[{"id":321390,"date":"2025-11-14T06:00:00","date_gmt":"2025-11-14T06:00:00","guid":{"rendered":"https:\/\/www.fujifilm-x.com\/?post_type=camera&#038;p=321390"},"modified":"2025-11-17T03:39:17","modified_gmt":"2025-11-17T03:39:17","slug":"simulator","status":"publish","type":"camera","link":"https:\/\/www.fujifilm-x.com\/it-it\/products\/cameras\/gfx-eterna-55\/simulator\/","title":{"rendered":"Simulator"},"content":{"rendered":"\n<h1 class=\"wp-block-heading hidden-heading\">Simulator<\/h1>\n\n\n\n<div class=\"wp-block-group alignfull is-style-default has-background is-layout-flow wp-block-group-is-layout-flow\" style=\"background-color:#161515;margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--80);padding-bottom:var(--wp--preset--spacing--60);padding-left:0\"><div id=\"fujifilm-simulator-app\" data-basepath=\"\/it-it\/products\/cameras\/gfx-eterna-55\/simulator\" data-product-slug=\"gfx-eterna-55\"><\/div>\n\n\n\n<div class=\"wp-block-group is-style-content-width-1260 is-layout-flow wp-block-group-is-layout-flow\" style=\"margin-top:var(--wp--preset--spacing--70);margin-bottom:var(--wp--preset--spacing--60);padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<p class=\"has-text-align-center has-white-color has-text-color has-link-color wp-elements-fe25f09da86f6fdd038abeb0b45edfb1\">Product simulator for demonstration purposes. <\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-link-color wp-elements-4cd1fd55367a0cd7e8293b5652706621\">Visuals, labels and behaviour may differ from the actual camera. <\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-link-color wp-elements-06c3a904b097bcd0268e50e2316ffcb1\">Features and specifications are&nbsp;subject to change without notice.<\/p>\n<\/div>\n<\/div>\n","protected":false},"author":8,"featured_media":321983,"parent":288639,"menu_order":0,"template":"","category":[],"products_category":[13941],"class_list":["post-321390","camera","type-camera","status-publish","has-post-thumbnail","hentry","products_category-simulator"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":[],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera\/321390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera"}],"about":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/types\/camera"}],"author":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/users\/8"}],"version-history":[{"count":0,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera\/321390\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera\/288639"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media\/321983"}],"wp:attachment":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media?parent=321390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/category?post=321390"},{"taxonomy":"products_category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/products_category?post=321390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":312137,"date":"2025-11-12T05:02:02","date_gmt":"2025-11-12T05:02:02","guid":{"rendered":"https:\/\/www.fujifilm-x.com\/?post_type=camera&#038;p=312137"},"modified":"2025-11-12T05:02:02","modified_gmt":"2025-11-12T05:02:02","slug":"gfx-eterna-55","status":"publish","type":"camera","link":"https:\/\/www.fujifilm-x.com\/it-it\/products\/cameras\/gfx-eterna-55\/","title":{"rendered":"GFX ETERNA 55"},"content":{"rendered":"\n<div class=\"wp-block-group alignfull is-layout-flow wp-block-group-is-layout-flow\">\n<h1 class=\"wp-block-heading hidden-heading\">GFX ETERNA 55<\/h1>\n\n\n\t<div id=\"block_593d58d4afd9813f7fa8f968824fac34\" class=\"wp-block wp-block-slider wp-block-slider--hero swiper alignfull\">\n\t\t<div class=\"swiper-wrapper\" data-settings='{\"autoplay\":false,\"autoplaySpeed\":\"5000\",\"speed\":500,\"effect\":\"fade\"}'>\n\t\t\t\n\t\t\t\t<div class=\"image-layer-container absolute top-0 left-0 right-0 z-10 pointer-events-none m-auto max-w-fujifilm w-full h-full py-8 md:py-12 px-5 md:px-8 h-mob-center h-center v-mob-top v-top\">\n\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"39\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/logo-eterna.png?width=768&amp;height=39\" class=\"attachment-medium_large size-medium_large\" alt=\"Image Logo\" loading=\"eager\" fetchpriority=\"high\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/logo-eterna.png?width=300&amp;height=15 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/logo-eterna.png?width=768&amp;height=39 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/logo-eterna.png?width=400&amp;height=20 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/logo-eterna.png?width=365&amp;height=18 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/logo-eterna.png?width=600&amp;height=30 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/logo-eterna.png?width=717&amp;height=36 717w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\n\t<figure class=\"swiper-slide\">\n\t\t<picture >\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"not all and (min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/banner-gfx-mobile.png?width=640&#038;height=854&#038;quality=85&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_1\" data-slider-device=\"mobile\"\t\t\t\t\/>\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/01_0133_newUI-min.jpg?width=2560&#038;height=980&#038;quality=85&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_1\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/01_0133_newUI-min.jpg?width=2560&#038;height=980&#038;quality=85&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"slide--container__img w-full object-cover position-mob-center position-center-bottom\"\t\t\t\t\t\t\t\t\talt=\"GFX ETERNA 55 Image\"\t\t\t\t\t\t\t\t\twidth=\"2560\"\t\t\t\t\t\t\t\t\theight=\"980\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_1\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t<\/figure>\n\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n\n\n<div class=\"wp-block-group alignfull fade-up-parallax has-black-background-color has-background is-layout-constrained wp-container-core-group-is-layout-fb24a776 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<div id=\"block_49e8b730cfc084c4282596d40f33fc6d\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_49e8b730cfc084c4282596d40f33fc6d.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_49e8b730cfc084c4282596d40f33fc6d.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-5ca99053 wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center custom-heading has-white-color has-text-color has-link-color wp-elements-f7f9c75c9d5b047c60609bbe861b373c\">ETERNA<sup>TM<\/sup><sub>&#8211;<\/sub> Legacy Reimagined for a New Era<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity faded-separator--orange\"\/>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-link-color wp-elements-1b87ba25cfcb53762c4a686a9b56b07d\">ETERNA \u2013 un nome che significa &#8220;eterno&#8221;.<br>Ci\u00f2 che un tempo viveva sulla celluloide ora ritorna nell&#8217;era digitale.<br>L&#8217;anima del cinema. Il passare del tempo. Colori che suscitano emozioni.<br>Vi presentiamo un nuovo tipo di macchina da presa cinematografica, creata per riflettere l&#8217;occhio e il cuore del creatore.<br>Intrisa della profonda saggezza senza tempo di Fujifilm, \u00e8 progettata per creare storie che superano la prova del tempo.<\/p>\n\n\n\n<div id=\"block_77f32c18e146bb2d17a1fd68670a1e2c\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_77f32c18e146bb2d17a1fd68670a1e2c.wp-block-spacer {\n        height: 60px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_77f32c18e146bb2d17a1fd68670a1e2c.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull is-style-content-width-1600 has-black-background-color has-background is-layout-constrained wp-container-core-group-is-layout-ccbce648 wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-fujifilm-youtube-modal alignfull product-youtube-mod\"><div class=\"block-video-player py-5 md:py-10\"><div class=\"max-w-[800px] m-auto w-full relative fade-up-parallax\"><div class=\"block-video-player__splash-img aspect-w-16 aspect-h-9 js-btn--modal-youtube\" data-id=\"rk9RHViSywY\"><img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/eterna-video-thumb-min.png\" alt=\"eterna-video-thumb-min\" loading=\"lazy\" data-recalc-dims=\"1\"\/><span class=\"play-button\"><\/span><\/div><\/div><div class=\"modal modal--youtube hidden\" data-id=\"rk9RHViSywY\"><div class=\"modal__content relative\"><button class=\"btn-modal-close\" data-id=\"rk9RHViSywY\"><span><\/span><span><\/span><\/button><figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\"><div id=\"player-rk9RHViSywY\" data-id=\"rk9RHViSywY\" class=\"youtube-iframe\"><\/div><\/div><\/figure><\/div><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull fade-up-parallax has-black-background-color has-background is-layout-constrained wp-container-core-group-is-layout-16140b61 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<div id=\"block_77f32c18e146bb2d17a1fd68670a1e2c\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_77f32c18e146bb2d17a1fd68670a1e2c.wp-block-spacer {\n        height: 60px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_77f32c18e146bb2d17a1fd68670a1e2c.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-9a69a910 wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center has-white-color has-text-color has-link-color wp-elements-8f8a8e5d7259f859da19469b0c655eeb\">Il sensore Large Format<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity faded-separator--orange\"\/>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-link-color wp-elements-ae86ce8b439d8afebc08ced88f23d6c8\">FUJIFILM GFX ETERNA 55 \u2013 Progettata per i registi, costruita attorno a un sensore Large Format<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-link-color wp-elements-9d880e5c15657fb82a3de2875d58e4f1\">Il cuore di GFX ETERNA 55 \u00e8 un potente sensore Large Format: 44&#215;33 mm (diagonale 55 mm), di gran lunga superiore al tradizionale sensore full-frame da 35mm.<br>La sua ampia superficie cattura la luce con dettagli sorprendenti, offrendo un&#8217;estetica cinematografica con caratteristiche di profondit\u00e0 di campo uniche che i formati standard semplicemente non possono replicare.<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-link-color wp-elements-e638e642aec1bc2348f66745d5ce70a2\">Gradazione tonale uniforme. Texture sottili che si nascondono nelle ombre. Atmosfera persistente nelle alte luci.<br>Ogni sfarfallio di luce, ogni sfumatura di tono: resa fedele, anche in condizioni di scarsa illuminazione, con un rumore notevolmente ridotto.<br>I toni della pelle vengono registrati con delicata precisione, preservandone la naturalezza.<\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-link-color wp-elements-af43c31cd3838e0997abc686a03fc7ef\">GFX ETERNA 55 \u00e8 pi\u00f9 di uno strumento. \u00c8 una fotocamera che consente ai registi di tornare all&#8217;essenza della narrazione visiva: il desiderio di parlare attraverso la luce.<\/p>\n\n\n\n<div id=\"block_fc2c5c7e5138153efa003bd6be0e9665\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_fc2c5c7e5138153efa003bd6be0e9665.wp-block-spacer {\n        height: 70px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_fc2c5c7e5138153efa003bd6be0e9665.wp-block-spacer {\n            height: 50px;       \n        }\n    }\n<\/style>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-black-background-color has-background is-layout-constrained wp-container-core-group-is-layout-10ae3479 wp-block-group-is-layout-constrained\" style=\"padding-right:0;padding-left:0\">\n<div class=\"wp-block-columns are-vertically-aligned-center has-spacing-none has-no-design is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40%\">\n<div class=\"wp-block-group fade-up-parallax is-layout-flow wp-block-group-is-layout-flow\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<h4 class=\"wp-block-heading has-text-align-center has-white-color has-text-color has-link-color wp-elements-0cef36e0a810f2780f49d6f0d9099179\">SENSOR SIZE<\/h4>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-white-color has-text-color has-link-color has-extra-large-font-size wp-elements-33b8685053522f5fc4227d5d76ad77b5\">43.8mm X 32.9mm<\/h2>\n\n\n\n<h5 class=\"wp-block-heading has-text-align-center has-white-color has-text-color has-link-color wp-elements-e98cd5ec0a7a17e2f8e366f136739483\">Approx. x1.7 the Size of Full Frame<\/h5>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:60%\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"744\" height=\"774\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/image_with_top_fade-min.png?width=744&#038;height=774\" alt=\"\" class=\"wp-image-288960\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/image_with_top_fade-min.png?width=744 744w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/image_with_top_fade-min.png?width=288&amp;height=300 288w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/image_with_top_fade-min.png?width=365&amp;height=380 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/image_with_top_fade-min.png?width=600&amp;height=624 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/image_with_top_fade-min.png?width=717&amp;height=746 717w\" sizes=\"auto, (max-width: 744px) 100vw, 744px\" data-recalc-dims=\"1\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull fade-up-parallax has-black-background-color has-background is-layout-constrained wp-container-core-group-is-layout-eaff47a1 wp-block-group-is-layout-constrained\" style=\"padding-top:0;padding-right:var(--wp--preset--spacing--50);padding-bottom:0;padding-left:var(--wp--preset--spacing--50)\">\n<div id=\"block_49e8b730cfc084c4282596d40f33fc6d\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_49e8b730cfc084c4282596d40f33fc6d.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_49e8b730cfc084c4282596d40f33fc6d.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-4f951bde wp-block-group-is-layout-constrained\"><div class=\"video-player-youtube alignfull is-style-burnt-orange wp-block-fujifilm-video-player-youtube\" id=\"block-6a046aa85ace1\" data-video-id=\"7-lwDhzC-rg\" data-youtube-url=\"https:\/\/youtu.be\/7-lwDhzC-rg?list=TLGGH5CBv9AogaowNTA5MjAyNQ\" data-autoplay=\"0\" data-muted=\"0\" data-loop=\"1\" data-playsinline=\"1\" data-controls=\"1\" data-ctrl-playpause=\"1\" data-ctrl-progress=\"1\" data-ctrl-mute=\"1\" data-ctrl-volume=\"1\" data-ctrl-captions=\"0\" data-scroll-sticky=\"0\" data-video-delay=\"500\" data-controls-always-visible=\"0\" data-show-related=\"0\" data-modest-branding=\"1\" data-lite-embed=\"1\" data-privacy-enhanced=\"1\" data-desktop-poster-xxl=\"https:\/\/i.ytimg.com\/vi\/7-lwDhzC-rg\/maxresdefault.jpg\" data-desktop-poster-xl=\"https:\/\/i.ytimg.com\/vi\/7-lwDhzC-rg\/maxresdefault.jpg\" data-desktop-poster-lg=\"https:\/\/i.ytimg.com\/vi\/7-lwDhzC-rg\/maxresdefault.jpg\" data-desktop-poster-md=\"https:\/\/i.ytimg.com\/vi\/7-lwDhzC-rg\/maxresdefault.jpg\" data-mobile-poster-md=\"https:\/\/i.ytimg.com\/vi\/7-lwDhzC-rg\/maxresdefault.jpg\" data-mobile-poster-sm=\"https:\/\/i.ytimg.com\/vi\/7-lwDhzC-rg\/maxresdefault.jpg\" data-mobile-poster-xs=\"https:\/\/i.ytimg.com\/vi\/7-lwDhzC-rg\/maxresdefault.jpg\">\n\t\t\n\t<div class=\"video-player-youtube__ctn\">\n\t\t\t\t\t\t<picture class=\"video-player-youtube__poster\">\n\t\t\t\t\t\t\t\t\t\t\t<source media=\"(max-width: 767px)\" srcset=\"https:\/\/i.ytimg.com\/vi\/7-lwDhzC-rg\/maxresdefault.jpg\" \/>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/i.ytimg.com\/vi\/7-lwDhzC-rg\/maxresdefault.jpg\" \/>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<img \n\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/vi\/7-lwDhzC-rg\/maxresdefault.jpg\"\n\t\t\t\t\t\talt=\"\"\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\tfetchpriority=\"auto\"\n\t\t\t\t\t\tclass=\"video-player-youtube__poster-img\"\n\t\t\t\t data-recalc-dims=\"1\"\t\/>\n\t\t\t\t<\/picture>\n\t\t\t\t\n\t\t<div class=\"video-player-youtube__video-ctn\"><\/div>\n\t\t\n\t\t\t\t\n\t\t\t\t\t<div class=\"video-player-youtube__video-controls\">\n\t\t\t\t\t\t\t\t\t<div class=\"video-player-youtube__play-pause-ctn\">\n\t\t\t\t\t\t<button \n\t\t\t\t\t\t\ttype=\"button\" \n\t\t\t\t\t\t\tclass=\"video-player-youtube__play-pause-btn\"\n\t\t\t\t\t\t\taria-label=\"Play video\"\n\t\t\t\t\t\t\tdata-playing=\"false\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t<svg class=\"video-player-youtube__play-icon\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\n\t\t\t\t\t\t\t\t<path d=\"M8 5v14l11-7z\" fill=\"currentColor\"\/>\n\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t<svg class=\"video-player-youtube__pause-icon\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" style=\"display: none;\">\n\t\t\t\t\t\t\t\t<path d=\"M6 19h4V5H6v14zm8-14v14h4V5h-4z\" fill=\"currentColor\"\/>\n\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"video-player-youtube__progress-ctn\">\n\t\t\t\t\t\t<div class=\"video-player-youtube__progress-bar\">\n\t\t\t\t\t\t\t<div class=\"video-player-youtube__progress-fill\"><\/div>\n\t\t\t\t\t\t\t<input\n\t\t\t\t\t\t\t\ttype=\"range\"\n\t\t\t\t\t\t\t\tclass=\"video-player-youtube__progress-input\"\n\t\t\t\t\t\t\t\tmin=\"0\"\n\t\t\t\t\t\t\t\tmax=\"1000\"\n\t\t\t\t\t\t\t\tvalue=\"0\"\n\t\t\t\t\t\t\t\taria-label=\"Video progress\"\n\t\t\t\t\t\t\t\trole=\"slider\"\n\t\t\t\t\t\t\t\taria-valuemin=\"0\"\n\t\t\t\t\t\t\t\taria-valuemax=\"1000\"\n\t\t\t\t\t\t\t\taria-valuenow=\"0\"\n\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"video-player-youtube__time-display\">\n\t\t\t\t\t\t\t<span class=\"video-player-youtube__current-time\">00:00<\/span>\n\t\t\t\t\t\t\t<span class=\"video-player-youtube__total-time\">00:00<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"video-player-youtube__volume-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"video-player-youtube__volume-ctn\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<button \n\t\t\t\t\t\t\t\t\t\ttype=\"button\" \n\t\t\t\t\t\t\t\t\t\tclass=\"video-player-youtube__mute-btn\"\n\t\t\t\t\t\t\t\t\t\taria-label=\"Mute video\"\n\t\t\t\t\t\t\t\t\t\tdata-muted=\"false\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t<svg class=\"video-player-youtube__volume-icon\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\">\n\t\t\t\t\t\t\t\t\t\t\t<path d=\"M11 5L6 9H2v6h4l5 4V5zM19 12c0-1.8-.9-3.3-2.3-4.2v8.4c1.4-.9 2.3-2.4 2.3-4.2zm2.3-6.7l-1.4 1.4C21.2 8.1 22 10 22 12s-.8 3.9-2.1 5.3l1.4 1.4C23 17 24 14.6 24 12s-1-5-2.7-6.7z\" fill=\"currentColor\"\/>\n\t\t\t\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t\t\t\t<svg class=\"video-player-youtube__mute-icon\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" style=\"display: none;\">\n\t\t\t\t\t\t\t\t\t\t\t<path d=\"M16.5 12l5-5-1.5-1.5L15 10.5 10 5.5 8.5 7l5 5-5 5 1.5 1.5 5-5 5 5 1.5-1.5-5-5zM11 5L6 9H2v6h4l5 4V5z\" fill=\"currentColor\"\/>\n\t\t\t\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"video-player-youtube__volume-slider-ctn\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"video-player-youtube__volume-fill\" style=\"width: 100%\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<input\n\t\t\t\t\t\t\t\t\t\t\ttype=\"range\"\n\t\t\t\t\t\t\t\t\t\t\tclass=\"video-player-youtube__volume-slider\"\n\t\t\t\t\t\t\t\t\t\t\tmin=\"0\"\n\t\t\t\t\t\t\t\t\t\t\tmax=\"100\"\n\t\t\t\t\t\t\t\t\t\t\tvalue=\"100\"\n\t\t\t\t\t\t\t\t\t\t\taria-label=\"Volume\"\n\t\t\t\t\t\t\t\t\t\t\trole=\"slider\"\n\t\t\t\t\t\t\t\t\t\t\taria-valuemin=\"0\"\n\t\t\t\t\t\t\t\t\t\t\taria-valuemax=\"100\"\n\t\t\t\t\t\t\t\t\t\t\taria-valuenow=\"100\"\n\t\t\t\t\t\t\t\t\t\t\tdisabled\n\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n<\/div>\n<\/div>\n\n\n\n<div id=\"block_49e8b730cfc084c4282596d40f33fc6d\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_49e8b730cfc084c4282596d40f33fc6d.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_49e8b730cfc084c4282596d40f33fc6d.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-black-background-color has-background is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group alignfull fade-up-parallax has-black-background-color has-background is-layout-constrained wp-container-core-group-is-layout-02f022fd wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-b5ae9130 wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center has-white-color has-text-color has-link-color wp-elements-26824ae3340b111a536fe28bab25d7ac\">The Fujifilm Look<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity faded-separator--orange\"\/>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-link-color wp-elements-00a53e874c28ecd8e464432b5fa02884\">Basato su oltre 90 anni di pionieristica esperienza nella scienza del colore delle pellicole Fujifilm, il sensore Large Format di GFX ETERNA 55 offre immagini digitali con la profondit\u00e0, il calore e le sfumature tradizionalmente riservate alla pellicola.<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-link-color wp-elements-8438725627de2579365d2d81d83f46a2\">GFX ETERNA 55 \u00e8 progettata per i registi che desiderano esprimere la propria visione con autenticit\u00e0 e impatto emotivo, creando non solo immagini, ma storie che risuonano.<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-green-dark-lime-color has-text-color has-link-color wp-elements-9355c07378186cab15a202f8ca285294\"><a href=\"http:\/\/www.fujifilm-x.com\/it-it\/support\/download\/technical-data\/\"><span style=\"text-decoration: underline;\">Learn more on GFX ETERNA 55 White Paper<\/span><\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-spacing-none has-no-design is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:60%\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1189\" height=\"583\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/Groupzxzxnew-min.png?width=1189&#038;height=583\" alt=\"\" class=\"wp-image-288959\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/Groupzxzxnew-min.png?width=1189 1189w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/Groupzxzxnew-min.png?width=300&amp;height=147 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/Groupzxzxnew-min.png?width=1024&amp;height=502 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/Groupzxzxnew-min.png?width=768&amp;height=377 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/Groupzxzxnew-min.png?width=400&amp;height=196 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/Groupzxzxnew-min.png?width=365&amp;height=179 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/Groupzxzxnew-min.png?width=600&amp;height=294 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/Groupzxzxnew-min.png?width=1152&amp;height=565 1152w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/Groupzxzxnew-min.png?width=717&amp;height=352 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/Groupzxzxnew-min.png?width=936&amp;height=459 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull fade-up-parallax has-black-background-color has-background is-layout-flow wp-block-group-is-layout-flow\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<div id=\"block_49e8b730cfc084c4282596d40f33fc6d\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_49e8b730cfc084c4282596d40f33fc6d.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_49e8b730cfc084c4282596d40f33fc6d.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-dd127765 wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center has-white-color has-text-color has-link-color wp-elements-846e3370c8e5242aaf8bf55c1a8c2af3\">Libera dai vincoli delle pellicole cinematografiche<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity faded-separator--orange\"\/>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-801f6f31 wp-block-group-is-layout-constrained\">\n<p class=\"has-text-align-center has-white-color has-text-color has-link-color wp-elements-7fe33e76492b988523d423bd6ab92589\">GFX ETERNA 55 offre 20 modalit\u00e0 di Simulazione Pellicola.<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-link-color wp-elements-c271c6c773ae9d3aed0282352ea0cc95\">Inoltre, utilizzando l&#8217;ampia gamma dinamica proprietaria Fujifilm e l&#8217;ampio gamut F-Log2 C\/F-Gamut C, i filmmaker possono accedere a dieci LUT di simulazione pellicola* realizzate da esperti che replicano le iconiche pellicole Fujifilm in formato digitale.<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-link-color wp-elements-be43f9f9c60597fd8d7fef7ae8f5692c\">Da Velvia e ASTIA a CLASSIC CHROME ed ETERNA, queste celebri pellicole rappresentano un potente strumento creativo di post-produzione, riaccendendo il caratteristico Memory Color da tempo ammirato in fotografia.<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-link-color wp-elements-8d5668e07e6b7283a5c02cd33ac061c1\">Questo va oltre la semplice correzione del colore.<br>\u00c8 una narrazione digitale intrisa della ricca tradizione e della profondit\u00e0 espressiva della pellicola analogica.<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-green-dark-lime-color has-text-color has-link-color wp-elements-2e908d778729ebf80101d9c378d3e9ba\"><a href=\"https:\/\/www.fujifilm-x.com\/it-it\/support\/download\/lut\/\"><span style=\"text-decoration: underline;\">Download the newly crafted Film Simulation LUTs<\/span><\/a><\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-link-color wp-elements-51144ed5d58a20868e24d7a446c65f7d\"><sub>*PROVIA\/Standard, Velvia\/Vivid, ASTIA\/Soft, Classic Chrome, REALA ACE, PRO Neg.Std, Classic Neg., ETERNA\/Cinema, ETERNA BLEACH BYPASS e ACROS<\/sub><\/p>\n<\/div>\n\n\n\n<div id=\"block_fc2c5c7e5138153efa003bd6be0e9665\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_fc2c5c7e5138153efa003bd6be0e9665.wp-block-spacer {\n        height: 70px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_fc2c5c7e5138153efa003bd6be0e9665.wp-block-spacer {\n            height: 50px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-ccbce648 wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns are-vertically-aligned-center has-spacing-extra-large has-no-design is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40%\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"814\" height=\"775\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/F-Log2C_A-0912-2-1-min.png?width=814&#038;height=775\" alt=\"\" class=\"wp-image-288957\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/F-Log2C_A-0912-2-1-min.png?width=814 814w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/F-Log2C_A-0912-2-1-min.png?width=300&amp;height=286 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/F-Log2C_A-0912-2-1-min.png?width=768&amp;height=731 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/F-Log2C_A-0912-2-1-min.png?width=315&amp;height=300 315w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/F-Log2C_A-0912-2-1-min.png?width=365&amp;height=348 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/F-Log2C_A-0912-2-1-min.png?width=600&amp;height=571 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/F-Log2C_A-0912-2-1-min.png?width=717&amp;height=683 717w\" sizes=\"auto, (max-width: 814px) 100vw, 814px\" data-recalc-dims=\"1\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:60%\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"775\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/F-log-curve_grey-min.png?width=1080&#038;height=775\" alt=\"\" class=\"wp-image-288956\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/F-log-curve_grey-min.png?width=1080 1080w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/F-log-curve_grey-min.png?width=300&amp;height=215 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/F-log-curve_grey-min.png?width=1024&amp;height=735 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/F-log-curve_grey-min.png?width=768&amp;height=551 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/F-log-curve_grey-min.png?width=400&amp;height=287 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/F-log-curve_grey-min.png?width=365&amp;height=262 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/F-log-curve_grey-min.png?width=600&amp;height=431 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/F-log-curve_grey-min.png?width=717&amp;height=515 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/F-log-curve_grey-min.png?width=936&amp;height=672 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div id=\"block_49e8b730cfc084c4282596d40f33fc6d\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_49e8b730cfc084c4282596d40f33fc6d.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_49e8b730cfc084c4282596d40f33fc6d.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull fade-up-parallax has-black-background-color has-background is-layout-flow wp-block-group-is-layout-flow\" style=\"border-bottom-color:var(--wp--preset--color--black);border-bottom-width:1px;padding-top:0;padding-bottom:0\">\t<div id=\"block_b93a81aa7153cbbe4ebdf7fa40febe4c\"\n\t\tclass=\"wp-block wp-block-slider wp-block-slider--swiper swiper alignfull\"\n\t\tdata-fixed-height=\"false\">\n\t\t<div class=\"swiper-wrapper\" data-settings='{\"autoplaySpeed\":\"5000\",\"speed\":500,\"slidesPerView\":1.1,\"spaceBetween\":20,\"navigation\":{\"nextEl\":\".swiper-button-next\",\"prevEl\":\".swiper-button-prev\"},\"scrollbar\":{\"el\":\".swiper-scrollbar\"},\"grabCursor\":true,\"breakpoints\":{\"640\":{\"slidesPerView\":2,\"spaceBetween\":32},\"1024\":{\"slidesPerView\":3,\"spaceBetween\":32}}}'>\n\t\t\t\t\t\t\t<div class=\"swiper-slide \">\n\t\t\t\t\t<div class=\"swiper-slide__inner text-white\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wp-block-youtube--modal js-btn--modal-youtube\" data-id=\"jZRxiuK8hOg\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/Group-min.jpg?width=1024&#038;height=768\" alt=\"YouTube Thumb\" width=\"576\" height=\"432\" loading\"lazy\" \/>\t\t\t\t\t\t\t\t\t<span class=\"play-button\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"h3 font-fjalla-one leading-snug font-normal block\">Filtro ND Variabile Elettronico<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ewa-rteLine\">GFX ETERNA 55 \u00e8 dotata di un filtro ND variabile elettronico integrato, progettato specificamente per il suo sensore Large Format. Con un intervallo da ND0,6 a 2,1, offre fino a sette stop di riduzione della luce con un controllo fluido e preciso, con incrementi fino a ND0,015. Grazie all&#8217;ingegneria di precisione proprietaria di Fujifilm, questo filtro consente regolazioni della densit\u00e0 fluide e altamente precise con una variazione minima del colore, anche durante la registrazione di filmati. Adattandosi istantaneamente alle mutevoli condizioni di illuminazione sul set, consente ai registi di impostare rapidamente l&#8217;esposizione desiderata, migliorando notevolmente l&#8217;efficienza.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide \">\n\t\t\t\t\t<div class=\"swiper-slide__inner text-white\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(max-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/image2-min.jpg?width=576&#038;height=432&#038;quality=80&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 641px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/image2-min.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/image2-min.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\" class=\"h-auto max-h-[432px] object-cover\" width=\"576\" height=\"432\" alt=\"Image\">\n\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"h3 font-fjalla-one leading-snug font-normal block\">Dual Base ISO<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ewa-rteLine\">Il sensore Large Format di GFX ETERNA 55, che misura 44&#215;33 mm, \u00e8 circa 1,7 volte pi\u00f9 grande di un tipico sensore full-frame. Il suo &#8220;dual base ISO&#8221; di 800 e 3200 massimizza le prestazioni, offrendo gradazioni tonali fluide ed eccezionali capacit\u00e0 di riduzione del rumore. Anche in condizioni di illuminazione difficili come ombre, controluce e scenari notturni, riduce al minimo il rumore digitale spesso associato a tali condizioni, registrando fedelmente l&#8217;atmosfera della scena. Il sensore di GFX ETERNA 55 \u00e8 destinato a diventare una nuova fonte di ispirazione per i registi.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide \">\n\t\t\t\t\t<div class=\"swiper-slide__inner text-white\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(max-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/07_t66-min.jpg?width=576&#038;height=432&#038;quality=80&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 641px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/07_t66-min.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/07_t66-min.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\" class=\"h-auto max-h-[432px] object-cover\" width=\"576\" height=\"432\" alt=\"Image\">\n\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"h3 font-fjalla-one leading-snug font-normal block\">Gamma Dinamica<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ewa-rteLine\">L&#8217;ampia gamma Log di GFX ETERNA 55, F-Log2 C, consente al sensore Large Format di raggiungere oltre 14 stop* di gamma dinamica. Dalle ombre profonde alle alte luci, registra le sottili sfumature di luce senza compromessi, consentendo regolazioni precise in linea con la visione creativa in post-produzione. In combinazione con la registrazione ad ampia gamma cromatica, questo apre possibilit\u00e0 praticamente illimitate di espressione in termini di colore e contrasto.<\/div>\n<p><sub>*Se registrato in F-Log2 C, secondo test interni Fujifilm.<\/sub><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide \">\n\t\t\t\t\t<div class=\"swiper-slide__inner text-white\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(max-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/image-min.jpg?width=576&#038;height=432&#038;quality=80&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 641px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/image-min.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/image-min.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\" class=\"h-auto max-h-[432px] object-cover\" width=\"576\" height=\"432\" alt=\"Image\">\n\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"h3 font-fjalla-one leading-snug font-normal block\">Filtro Ottico Passa-Basso<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ewa-rteLine\">Il sensore Large Format di GFX ETERNA 55 \u00e8 dotato di un filtro ottico passa-basso (OLPF) appositamente progettato e ottimizzato per le riprese cinematografiche. Utilizza un metodo di separazione a quattro punti che riduce efficacemente l&#8217;effetto moir\u00e9 e i falsi colori. Con un&#8217;attenzione particolare alla qualit\u00e0 dell&#8217;immagine morbida e raffinata richiesta dall&#8217;espressione cinematografica, GFX ETERNA 55 realizza filmati estremamente dettagliati che mantengono una piacevole fluidit\u00e0 senza un&#8217;eccessiva nitidezza.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide \">\n\t\t\t\t\t<div class=\"swiper-slide__inner text-white\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(max-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/Group-2-min.jpg?width=576&#038;height=432&#038;quality=80&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 641px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/Group-2-min.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/Group-2-min.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\" class=\"h-auto max-h-[432px] object-cover\" width=\"576\" height=\"432\" alt=\"Image\">\n\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"h3 font-fjalla-one leading-snug font-normal block\">Autofocus<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ewa-rteLine\">Con un obiettivo GF montato, GFX ETERNA 55 offre una messa a fuoco automatica estremamente precisa. L&#8217;algoritmo autofocus sfrutta la stessa tecnologia avanzata di FUJIFILM GFX100 II, utilizzando il rilevamento del soggetto basato sul deep learning per analizzare le scene in modo rapido e preciso. Ci\u00f2 consente di mantenere una messa a fuoco nitida, anche con la ridotta profondit\u00e0 di campo caratteristica del sensore Large Format. In abbinamento al nuovo FUJINON GF32-90mmT3.5 PZ OIS WR, si ottiene una maggiore flessibilit\u00e0 e reattivit\u00e0 sul set: un compagno indispensabile per qualsiasi filmmaker.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-navigation-wrapper\">\n\t\t\t\t<div class=\"swiper-navigation-wrapper__inner arrow-black\">\n\t\t\t\t\t\n<button class=\"swiper-button-prev \" type=\"button\">\n\t<span class=\"hidden sm:flex\">\n\t\t\t<span class=\"hidden\" aria-hidden=\"true\" focusable=\"false\">\n\t\t<svg class=\"\" id=\"svg-slick-left-arrow-svg\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 22\"><style>.s0{fill:none;stroke-linecap:round;stroke-linejoin:round}<\/style><path fill-rule=\"evenodd\" d=\"M10.1 19.3c-1.5-4.6-4.3-7.8-9-9 4.7-1.1 7.5-4.3 9-8.9\" class=\"s0\"\/><path fill-rule=\"evenodd\" d=\"M1.1 10.3h20.1\" class=\"s0\"\/><\/svg>\t<\/span>\n\t\t\t<svg class=\"svg-slick-left-arrow-svg \"\n\t\t width=\"24\" height=\"22\"\t\talt=\"Svg Slick Left Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-left-arrow-svg\"\n\t\t\t width=\"24\" height=\"22\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n\t<span class=\"flex sm:hidden\">\n\t\t\t\t<svg class=\"svg-slick-left-arrow-svg \"\n\t\t width=\"20\" height=\"18\"\t\talt=\"Svg Slick Left Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-left-arrow-svg\"\n\t\t\t width=\"20\" height=\"18\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n<\/button>\n<button class=\"swiper-button-next \" type=\"button\">\n\t<span class=\"hidden sm:flex\">\n\t\t\t<span class=\"hidden\" aria-hidden=\"true\" focusable=\"false\">\n\t\t<svg class=\"\" id=\"svg-slick-right-arrow-svg\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 22\"><style>.s0{fill:none;stroke-linecap:round;stroke-linejoin:round}<\/style><path fill-rule=\"evenodd\" d=\"M12.4 19.9c1.5-4.6 4.3-7.8 8.9-9-4.6-1.2-7.4-4.3-8.9-8.9\" class=\"s0\"\/><path fill-rule=\"evenodd\" d=\"M21.3 10.9h-20\" class=\"s0\"\/><\/svg>\t<\/span>\n\t\t\t<svg class=\"svg-slick-right-arrow-svg \"\n\t\t width=\"24\" height=\"22\"\t\talt=\"Svg Slick Right Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-right-arrow-svg\"\n\t\t\t width=\"24\" height=\"22\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n\t<span class=\"flex sm:hidden\">\n\t\t\t\t<svg class=\"svg-slick-right-arrow-svg \"\n\t\t width=\"20\" height=\"18\"\t\talt=\"Svg Slick Right Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-right-arrow-svg\"\n\t\t\t width=\"20\" height=\"18\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n<\/button>\n\t\t\t\t\t<div class=\"swiper-scrollbar scr-orange\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"modal modal--youtube hidden\" data-id=\"jZRxiuK8hOg\">\n\t\t\t\t<div class=\"modal__content relative\">\n\t\t\t\t\t<button class=\"btn-modal-close\" data-id=\"jZRxiuK8hOg\"><span><\/span><span><\/span><\/button>\n\t\t\t\t\t<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\">\n\t\t\t\t\t\t<div class=\"wp-block-embed__wrapper\">\n\t\t\t\t\t\t\t<div id=\"player-jZRxiuK8hOg\" data-id=\"jZRxiuK8hOg\" class=\"youtube-iframe\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/figure>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\n\n<div class=\"wp-block-group alignfull fade-up-parallax has-black-background-color has-background is-layout-constrained wp-container-core-group-is-layout-16140b61 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<div id=\"block_49e8b730cfc084c4282596d40f33fc6d\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_49e8b730cfc084c4282596d40f33fc6d.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_49e8b730cfc084c4282596d40f33fc6d.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-76fd4bc3 wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center has-white-color has-text-color has-link-color wp-elements-8fc5e93d9db548aaf15d33e868b04969\">Vari formati<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity faded-separator--orange\"\/>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-link-color wp-elements-85cb1f1d2b65d8103e38ae7c90f7e4b0\">GGFX ETERNA 55 supporta la registrazione Open Gate 4:3, sfruttando appieno l&#8217;ampia area di cattura del suo sensore Large Format.<br>Oltre agli obiettivi FUJINON GF e Premista, supporta anche la registrazione 8K\/4K DCI con obiettivi PL standard compatibili con il formato 35mm.<br>Inoltre, \u00e8 compatibile con obiettivi anamorfici e obiettivi in \u200b\u200bformato Super 35, consentendo ai registi di selezionare liberamente il campo visivo desiderato in base alla propria visione creativa.<br>Combinando la ricca espressione visiva unica di un sensore di grandi dimensioni con un&#8217;ampia compatibilit\u00e0 tra tipi di obiettivi e formati, questa camera diventa un potente strumento creativo, espandendo la libert\u00e0 cinematografica a nuovi livelli.<\/p>\n\n\n\n<div id=\"block_fc2c5c7e5138153efa003bd6be0e9665\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_fc2c5c7e5138153efa003bd6be0e9665.wp-block-spacer {\n        height: 70px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_fc2c5c7e5138153efa003bd6be0e9665.wp-block-spacer {\n            height: 50px;       \n        }\n    }\n<\/style>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull fade-up-parallax has-black-background-color has-background is-layout-constrained wp-container-core-group-is-layout-0ed1c277 wp-block-group-is-layout-constrained\" style=\"padding-bottom:var(--wp--preset--spacing--40)\">\t<div id=\"block_323095dbd802cafd9dbb65b86d75a1c3\" \n\tclass=\"wp-block block-aspect-ratio-tabs no-align \">\n\t\t<div class=\"image-container\">\n\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\tmedia=\"(max-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/sample2_GF-4-3-Open-Gate-min.png?width=640&#038;height=360&#038;quality=80&#038;sharpen=1\"\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\tmedia=\"(min-width: 641px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/sample2_GF-4-3-Open-Gate-min.png?width=2560&#038;height=1080&#038;quality=90&#038;sharpen=1\"\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t<img\n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/sample2_GF-4-3-Open-Gate-min.png?width=2560&#038;height=1080&#038;quality=90&#038;sharpen=1\"\t\t\t\tdata-selectable-id=\"0\" \n\t\t\t\tclass=\"image-slide active\"\n\t\t\t\t\/>\n\t\t\t<\/picture>\n\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\tmedia=\"(max-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/sample2_GF-DCI-min.png?width=640&#038;height=360&#038;quality=80&#038;sharpen=1\"\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\tmedia=\"(min-width: 641px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/sample2_GF-DCI-min.png?width=2560&#038;height=1080&#038;quality=90&#038;sharpen=1\"\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t<img\n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/sample2_GF-DCI-min.png?width=2560&#038;height=1080&#038;quality=90&#038;sharpen=1\"\t\t\t\tdata-selectable-id=\"1\" \n\t\t\t\tclass=\"image-slide \"\n\t\t\t\t\/>\n\t\t\t<\/picture>\n\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\tmedia=\"(max-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/sample2_Premista-DCI-min.png?width=640&#038;height=360&#038;quality=80&#038;sharpen=1\"\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\tmedia=\"(min-width: 641px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/sample2_Premista-DCI-min.png?width=2560&#038;height=1080&#038;quality=90&#038;sharpen=1\"\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t<img\n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/sample2_Premista-DCI-min.png?width=2560&#038;height=1080&#038;quality=90&#038;sharpen=1\"\t\t\t\tdata-selectable-id=\"2\" \n\t\t\t\tclass=\"image-slide \"\n\t\t\t\t\/>\n\t\t\t<\/picture>\n\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\tmedia=\"(max-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/sample2_35mm-DCI-min.png?width=640&#038;height=360&#038;quality=80&#038;sharpen=1\"\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\tmedia=\"(min-width: 641px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/sample2_35mm-DCI-min.png?width=2560&#038;height=1080&#038;quality=90&#038;sharpen=1\"\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t<img\n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/sample2_35mm-DCI-min.png?width=2560&#038;height=1080&#038;quality=90&#038;sharpen=1\"\t\t\t\tdata-selectable-id=\"3\" \n\t\t\t\tclass=\"image-slide \"\n\t\t\t\t\/>\n\t\t\t<\/picture>\n\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\tmedia=\"(max-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/sample2_8K-CDI-dot-by-dot-min.png?width=640&#038;height=360&#038;quality=80&#038;sharpen=1\"\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\tmedia=\"(min-width: 641px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/sample2_8K-CDI-dot-by-dot-min.png?width=2560&#038;height=1080&#038;quality=90&#038;sharpen=1\"\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t<img\n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/sample2_8K-CDI-dot-by-dot-min.png?width=2560&#038;height=1080&#038;quality=90&#038;sharpen=1\"\t\t\t\tdata-selectable-id=\"4\" \n\t\t\t\tclass=\"image-slide \"\n\t\t\t\t\/>\n\t\t\t<\/picture>\n\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\tmedia=\"(max-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/sample2_Super-35-DCI-min.png?width=640&#038;height=360&#038;quality=80&#038;sharpen=1\"\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\tmedia=\"(min-width: 641px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/sample2_Super-35-DCI-min.png?width=2560&#038;height=1080&#038;quality=90&#038;sharpen=1\"\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t<img\n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/sample2_Super-35-DCI-min.png?width=2560&#038;height=1080&#038;quality=90&#038;sharpen=1\"\t\t\t\tdata-selectable-id=\"5\" \n\t\t\t\tclass=\"image-slide \"\n\t\t\t\t\/>\n\t\t\t<\/picture>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"dropdown-button\">\n\t\t\t<span class=\"title\"><\/span>\n\t\t\t<div class=\"dropdown-arrows\"><\/div>\n\t\t<\/div>\n\t\t<div class=\"selectors\">\n\t\t\t\t\t\t\t\t<button data-selector-id=\"0\" class=\"selectors__label active\">GF 4:3 Open Gate<\/button>\n\t\t\t\t\t\t\t\t\t<button data-selector-id=\"1\" class=\"selectors__label \">GF DCI<\/button>\n\t\t\t\t\t\t\t\t\t<button data-selector-id=\"2\" class=\"selectors__label \">Premista DCI<\/button>\n\t\t\t\t\t\t\t\t\t<button data-selector-id=\"3\" class=\"selectors__label \">35mmDCI<\/button>\n\t\t\t\t\t\t\t\t\t<button data-selector-id=\"4\" class=\"selectors__label \">8K DCI, dot by dot<\/button>\n\t\t\t\t\t\t\t\t\t<button data-selector-id=\"5\" class=\"selectors__label \">Super 35 DCI<\/button>\n\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n\n\n<div class=\"wp-block-group alignfull fade-up-parallax has-black-background-color has-background is-layout-constrained wp-container-core-group-is-layout-16140b61 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<div id=\"block_49e8b730cfc084c4282596d40f33fc6d\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_49e8b730cfc084c4282596d40f33fc6d.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_49e8b730cfc084c4282596d40f33fc6d.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-9a69a910 wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center has-white-color has-text-color has-link-color wp-elements-ce8c4086945bcb5016bca42dafcae855\">Pronta per l&#8217;Anamorfico<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity faded-separator--orange\"\/>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-link-color wp-elements-f7965b4a92c5ec02921894667ea16987\">Il sensore 4:3 Large Format di GFX ETERNA 55 \u00e8 ideale per le qualit\u00e0 cinematografiche uniche degli obiettivi anamorfici.<br>Il rapporto di aspetto allungato, il bokeh ellittico e il flare orizzontale caratteristici di tali ottiche sono stati ampiamente adottati nel cinema per arricchire la narrazione.<br>GFX ETERNA 55 offre il monitoraggio del de-squeeze in tempo reale sul set, fornendo un&#8217;anteprima chiara e accurata durante le riprese.<br>Combinando l&#8217;ampio cerchio di immagine del sensore con le propriet\u00e0 distintive degli obiettivi anamorfici, GFX ETERNA 55 offre una profondit\u00e0 e una scalabilit\u00e0 al tuo output creativo senza precedenti.<\/p>\n\n\n\n<div id=\"block_fc2c5c7e5138153efa003bd6be0e9665\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_fc2c5c7e5138153efa003bd6be0e9665.wp-block-spacer {\n        height: 70px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_fc2c5c7e5138153efa003bd6be0e9665.wp-block-spacer {\n            height: 50px;       \n        }\n    }\n<\/style>\n<\/div>\n\n\n\n<div class=\"wp-block-group fade-up-parallax has-black-background-color has-background is-layout-constrained wp-container-core-group-is-layout-b9d88b67 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1713\" height=\"633\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/anamorphic-min.png?width=1713&#038;height=633\" alt=\"\" class=\"wp-image-288953\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/anamorphic-min.png?width=1713 1713w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/anamorphic-min.png?width=300&amp;height=111 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/anamorphic-min.png?width=1024&amp;height=378 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/anamorphic-min.png?width=768&amp;height=284 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/anamorphic-min.png?width=1536&amp;height=568 1536w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/anamorphic-min.png?width=400&amp;height=148 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/anamorphic-min.png?width=365&amp;height=135 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/anamorphic-min.png?width=600&amp;height=222 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/anamorphic-min.png?width=1152&amp;height=426 1152w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/anamorphic-min.png?width=717&amp;height=265 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/anamorphic-min.png?width=936&amp;height=346 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-white-color\"><sub><strong>\u00a9<\/strong>Oren Soffer<\/sub><\/mark><\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull fade-up-parallax has-black-background-color has-background is-layout-flow wp-block-group-is-layout-flow\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<div id=\"block_49e8b730cfc084c4282596d40f33fc6d\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_49e8b730cfc084c4282596d40f33fc6d.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_49e8b730cfc084c4282596d40f33fc6d.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-6fdff0fd wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center has-white-color has-text-color has-link-color wp-elements-73f932aa554e28713f072d3f93eec220\">Codec<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity faded-separator--orange\"\/>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-777d5bd5 wp-block-group-is-layout-constrained\">\n<p class=\"has-text-align-center has-white-color has-text-color has-link-color wp-elements-3a00af53a1cbaa6a6d1b0a8a5596e420\">ApApple ProRes HQ, rinomato per la sua affidabilit\u00e0 nei flussi di lavoro di post-produzione, \u00e8 il codec di registrazione principale di GFX ETERNA 55.<br>Offre un perfetto equilibrio tra fedelt\u00e0 delle immagini in alta qualit\u00e0 e prestazioni di editing affidabili, consentendo un flusso di lavoro fluido dal set alla finitura finale.<br>Con una copertura fino a 8K a 30fps, 4K a 60fps e FHD a 120fps, GFX ETERNA 55 registra la ricca gamma cromatica e tonale del suo sensore Large Format in formati ottimizzati per qualsiasi scenario.<br>Che si tratti di lungometraggi cinematografici, spot pubblicitari che richiedono frame rate flessibili o progetti artistici ad alta velocit\u00e0, la versatilit\u00e0 di GFX ETERNA 55 la rendono uno strumento ideale per tutti i generi.<\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-link-color wp-elements-13ccf5b4b6c29c9d17d121846c1a0522\"><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull fade-up-parallax has-black-background-color has-background is-layout-constrained wp-container-core-group-is-layout-16140b61 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<div id=\"block_31310a7930a4a0b08216ac304e0f034b\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_31310a7930a4a0b08216ac304e0f034b.wp-block-spacer {\n        height: 120px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_31310a7930a4a0b08216ac304e0f034b.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-1d6f4e6b wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center has-white-color has-text-color has-link-color wp-elements-7ee2dd65632833b6b215e881245f5d46\">Pronta per il Filmmaking<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity faded-separator--orange\"\/>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-link-color wp-elements-b7281f19c26183a48d4d79df76092209\">Un design che esalta la creativit\u00e0 di ogni regista.<br>Realizzata con un corpo in lega di magnesio, la camera coniuga leggerezza e portabilit\u00e0 con un&#8217;eccezionale resistenza.<br>Ogni dettaglio, dai connettori dei cavi alla disposizione dei pulsanti, fino all&#8217;impugnatura, \u00e8 stato meticolosamente realizzato per la massima praticit\u00e0 e robustezza.<br>La forma elegante e minimalista, ereditata dal sistema GFX, soddisfer\u00e0 sicuramente l&#8217;estetica pi\u00f9 esigente di qualsiasi utente.<\/p>\n\n\n\n<div id=\"block_fc2c5c7e5138153efa003bd6be0e9665\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_fc2c5c7e5138153efa003bd6be0e9665.wp-block-spacer {\n        height: 70px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_fc2c5c7e5138153efa003bd6be0e9665.wp-block-spacer {\n            height: 50px;       \n        }\n    }\n<\/style>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-black-background-color has-background is-layout-flow wp-block-group-is-layout-flow\">\n\t<div id=\"block_ae8edd56e7d5600491715cc4116f4a5b\" class=\"wp-block wp-block--film-continuous-parallax no-align px-0 block alignfull relative pointer-events-none\">\n\t\t<div class=\"w-full overflow-hidden m-auto block\">\n\t\t\t<div class=\"wp-block--film-continuous-parallax__inner\">\n\t\t\t\t<div class=\"images-container\">\n\t\t\t\t\t\t\t\t\t\t\t<picture class=\"relative block initial\" data-slides-per-row=\"2\">\n\t\t\t\t\t\t\t<source media=\"not all and (min-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/07_0353_newUI-1-min.jpg?width=640&#038;height=580&#038;quality=80&#038;sharpen=1\">\n\t\t\t\t\t\t\t<source media=\"(min-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/07_0353_newUI-1-min.jpg?width=768&#038;height=1024&#038;quality=80&#038;sharpen=1\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/07_0353_newUI-1-min.jpg?width=768&#038;height=1024&#038;quality=80&#038;sharpen=1\" class=\"block h-auto object-cover max-sm:aspect-2\/3 max-sm:max-h-[585px]\" width=\"768\" height=\"1024\" alt=\"Continuous Parallax Image 1\" loading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t<picture class=\"relative block initial\" data-slides-per-row=\"2\">\n\t\t\t\t\t\t\t<source media=\"not all and (min-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/05_0291_newUI-1-min.jpg?width=640&#038;height=580&#038;quality=80&#038;sharpen=1\">\n\t\t\t\t\t\t\t<source media=\"(min-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/05_0291_newUI-1-min.jpg?width=768&#038;height=1024&#038;quality=80&#038;sharpen=1\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/05_0291_newUI-1-min.jpg?width=768&#038;height=1024&#038;quality=80&#038;sharpen=1\" class=\"block h-auto object-cover max-sm:aspect-2\/3 max-sm:max-h-[585px]\" width=\"768\" height=\"1024\" alt=\"Continuous Parallax Image 2\" loading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t<picture class=\"relative block initial\" data-slides-per-row=\"2\">\n\t\t\t\t\t\t\t<source media=\"not all and (min-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/08_0391_newUI-min.jpg?width=640&#038;height=580&#038;quality=80&#038;sharpen=1\">\n\t\t\t\t\t\t\t<source media=\"(min-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/08_0391_newUI-min.jpg?width=768&#038;height=1024&#038;quality=80&#038;sharpen=1\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/08_0391_newUI-min.jpg?width=768&#038;height=1024&#038;quality=80&#038;sharpen=1\" class=\"block h-auto object-cover max-sm:aspect-2\/3 max-sm:max-h-[585px]\" width=\"768\" height=\"1024\" alt=\"Continuous Parallax Image 3\" loading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t<picture class=\"relative block initial\" data-slides-per-row=\"2\">\n\t\t\t\t\t\t\t<source media=\"not all and (min-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/11_0582_newUI-1-min.jpg?width=640&#038;height=580&#038;quality=80&#038;sharpen=1\">\n\t\t\t\t\t\t\t<source media=\"(min-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/11_0582_newUI-1-min.jpg?width=768&#038;height=1024&#038;quality=80&#038;sharpen=1\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/11_0582_newUI-1-min.jpg?width=768&#038;height=1024&#038;quality=80&#038;sharpen=1\" class=\"block h-auto object-cover max-sm:aspect-2\/3 max-sm:max-h-[585px]\" width=\"768\" height=\"1024\" alt=\"Continuous Parallax Image 4\" loading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull fade-up-parallax has-black-background-color has-background is-layout-flow wp-block-group-is-layout-flow\" style=\"border-bottom-color:var(--wp--preset--color--black);border-bottom-width:1px;padding-top:0;padding-bottom:0\">\n<div id=\"block_49e8b730cfc084c4282596d40f33fc6d\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_49e8b730cfc084c4282596d40f33fc6d.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_49e8b730cfc084c4282596d40f33fc6d.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-1d6f4e6b wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center has-white-color has-text-color has-link-color wp-elements-8a856aa4deb7e09cf820c36265eb4523\">Accessori in dotazione<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity faded-separator--orange\"\/>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div id=\"block_fc2c5c7e5138153efa003bd6be0e9665\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_fc2c5c7e5138153efa003bd6be0e9665.wp-block-spacer {\n        height: 70px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_fc2c5c7e5138153efa003bd6be0e9665.wp-block-spacer {\n            height: 50px;       \n        }\n    }\n<\/style>\n\n\n\t<div id=\"block_7b0dc37a9a813b0a4d43f9a0aeec9f5c\"\n\t\tclass=\"wp-block wp-block-slider wp-block-slider--swiper swiper alignfull\"\n\t\tdata-fixed-height=\"false\">\n\t\t<div class=\"swiper-wrapper\" data-settings='{\"autoplaySpeed\":\"5000\",\"speed\":500,\"slidesPerView\":1.1,\"spaceBetween\":20,\"navigation\":{\"nextEl\":\".swiper-button-next\",\"prevEl\":\".swiper-button-prev\"},\"scrollbar\":{\"el\":\".swiper-scrollbar\"},\"grabCursor\":true,\"breakpoints\":{\"640\":{\"slidesPerView\":2,\"spaceBetween\":32},\"1024\":{\"slidesPerView\":3,\"spaceBetween\":32}}}'>\n\t\t\t\t\t\t\t<div class=\"swiper-slide \">\n\t\t\t\t\t<div class=\"swiper-slide__inner text-white\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(max-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/pl-mount-min.jpg?width=576&#038;height=432&#038;quality=80&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 641px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/pl-mount-min.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/pl-mount-min.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\" class=\"h-auto max-h-[432px] object-cover\" width=\"576\" height=\"432\" alt=\"Image\">\n\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"h3 font-fjalla-one leading-snug font-normal block\">Adattatore PL Mount<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Oltre all&#8217;attacco G Mount standard, GFX ETERNA 55 \u00e8 dotata di un adattatore PL Mount, che consente l&#8217;utilizzo immediato di obiettivi con attacco PL senza la necessit\u00e0 di accessori aggiuntivi. L&#8217;essenza della fotocamera risiede nel rendere omaggio all&#8217;estetica creativa che gli obiettivi, compresi quelli anamorfici, conferiscono al tuo lavoro.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide \">\n\t\t\t\t\t<div class=\"swiper-slide__inner text-white\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(max-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/monitor-min.jpg?width=576&#038;height=432&#038;quality=80&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 641px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/monitor-min.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/monitor-min.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\" class=\"h-auto max-h-[432px] object-cover\" width=\"576\" height=\"432\" alt=\"Image\">\n\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"h3 font-fjalla-one leading-snug font-normal block\">Ampio schermo LCD da 5,0&quot;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Dotata di un display da 5,0&#8243;, questa telecamera vanta un pannello ad alta risoluzione con 6,22 milioni di punti, che semplifica notevolmente il controllo della messa a fuoco e della precisione del colore, fondamentali per le decisioni prese sul set. Con una luminosit\u00e0 di 2000 nit, lo schermo rimane nitido e visibile anche in condizioni di forte illuminazione esterna o di forte controluce. La latenza del display \u00e8 ridotta al minimo assoluto per un monitoraggio e un controllo della messa a fuoco fluidi in tempo reale, senza ritardi o frustrazioni. Inoltre, la tecnologia proprietaria di riproduzione del colore garantisce una resa cromatica fedele e uniforme, per una facile calibrazione che aiuta a mantenere l&#8217;integrit\u00e0 del colore durante la registrazione e la post-produzione.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide \">\n\t\t\t\t\t<div class=\"swiper-slide__inner text-white\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(max-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/handle-min.jpg?width=576&#038;height=432&#038;quality=80&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 641px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/handle-min.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/handle-min.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\" class=\"h-auto max-h-[432px] object-cover\" width=\"576\" height=\"432\" alt=\"Image\">\n\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"h3 font-fjalla-one leading-snug font-normal block\">Maniglia dedicata<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>\u00c8 inclusa un&#8217;impugnatura dedicata, progettata sia per la facilit\u00e0 d&#8217;uso che per le funzionalit\u00e0 avanzate. Sul lato dell&#8217;impugnatura \u00e8 presente una ghiera per il controllo di messa a fuoco, zoom o diaframma. Se abbinata a obiettivi a controllo elettronico, queste ghiera consente regolazioni fluide e precise per una messa a punto precisa in tempo reale. Spostando la ghiera sull&#8217;impostazione ND \u00e8 possibile regolare al volo la densit\u00e0 del filtro ND variabile elettronico. La base dell&#8217;impugnatura \u00e8 dotata di un sistema di guide scorrevoli, che consente di riposizionare rapidamente e senza sforzo il punto di bilanciamento per adattarsi alle variazioni del baricentro durante il montaggio di batterie o obiettivi.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\n\n<div class=\"wp-block-group alignfull fade-up-parallax has-black-background-color has-background is-layout-flow wp-block-group-is-layout-flow\" style=\"border-bottom-color:var(--wp--preset--color--black);border-bottom-width:1px;padding-top:0;padding-bottom:0\">\n<div id=\"block_49e8b730cfc084c4282596d40f33fc6d\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_49e8b730cfc084c4282596d40f33fc6d.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_49e8b730cfc084c4282596d40f33fc6d.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-1d6f4e6b wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center has-white-color has-text-color has-link-color wp-elements-479ad7ef8c29757e965a9503e72e39d5\">Funzionamento intuitivo<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity faded-separator--orange\"\/>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div id=\"block_fc2c5c7e5138153efa003bd6be0e9665\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_fc2c5c7e5138153efa003bd6be0e9665.wp-block-spacer {\n        height: 70px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_fc2c5c7e5138153efa003bd6be0e9665.wp-block-spacer {\n            height: 50px;       \n        }\n    }\n<\/style>\n\n\n\t<div id=\"block_ca4a703fa17cd27c1e986b0d6acaf301\"\n\t\tclass=\"wp-block wp-block-slider wp-block-slider--swiper swiper alignfull\"\n\t\tdata-fixed-height=\"false\">\n\t\t<div class=\"swiper-wrapper\" data-settings='{\"autoplaySpeed\":\"5000\",\"speed\":500,\"slidesPerView\":1.1,\"spaceBetween\":20,\"navigation\":{\"nextEl\":\".swiper-button-next\",\"prevEl\":\".swiper-button-prev\"},\"scrollbar\":{\"el\":\".swiper-scrollbar\"},\"grabCursor\":true,\"breakpoints\":{\"640\":{\"slidesPerView\":2,\"spaceBetween\":32},\"1024\":{\"slidesPerView\":3,\"spaceBetween\":32}}}'>\n\t\t\t\t\t\t\t<div class=\"swiper-slide \">\n\t\t\t\t\t<div class=\"swiper-slide__inner text-white\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(max-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/07_0353_newUI-1-min.jpg?width=576&#038;height=432&#038;quality=80&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 641px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/07_0353_newUI-1-min.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/07_0353_newUI-1-min.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\" class=\"h-auto max-h-[432px] object-cover\" width=\"576\" height=\"432\" alt=\"Image\">\n\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"h3 font-fjalla-one leading-snug font-normal block\">Doppio Schermo Laterale<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Per soddisfare le esigenze pratiche degli ambienti di ripresa, GFX ETERNA 55 \u00e8 dotata di schermi LCD indipendenti da 3,0&#8243; su entrambi i lati del corpo macchina. Questi display forniscono informazioni in tempo reale come stato di registrazione, esposizione, livelli audio e formati di registrazione, consentendo sia al direttore della fotografia che all&#8217;assistente di monitorare simultaneamente i dati essenziali, una soluzione perfetta per la collaborazione sul set.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide \">\n\t\t\t\t\t<div class=\"swiper-slide__inner text-white\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(max-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/13_0766-min.jpg?width=576&#038;height=432&#038;quality=80&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 641px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/13_0766-min.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/13_0766-min.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\" class=\"h-auto max-h-[432px] object-cover\" width=\"576\" height=\"432\" alt=\"Image\">\n\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"h3 font-fjalla-one leading-snug font-normal block\">Punti di montaggio degli accessori<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>La parte superiore del corpo macchina e l&#8217;impugnatura sono dotate di diverse filettature per accessori in due misure (1\/4&#8243;-20 e 3\/8&#8243;-16) per un facile fissaggio di accessori, tra cui monitor, microfoni e trasmettitori wireless. Questo design elimina la necessit\u00e0 di ulteriori rig aggiuntivi, semplificando il processo di installazione.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide \">\n\t\t\t\t\t<div class=\"swiper-slide__inner text-white\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(max-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/09_0462-min.jpg?width=576&#038;height=432&#038;quality=80&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 641px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/09_0462-min.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/09_0462-min.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\" class=\"h-auto max-h-[432px] object-cover\" width=\"576\" height=\"432\" alt=\"Image\">\n\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"h3 font-fjalla-one leading-snug font-normal block\">Porte di connessione<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Oltre ai terminali di uscita video 12G-SDI e HDMI, GFX ETERNA 55 \u00e8 dotata di un&#8217;ampia gamma di interfacce di livello professionale, tra cui GENLOCK, REMOTE, porta di alimentazione 12V CC e connettore LENS. Queste supportano configurazioni multi-camera, controllo esterno e alimentazione servo dell&#8217;obiettivo, consentendo sul set configurazioni di sistema flessibili. Inoltre, tutti i connettori sono protetti da robuste protezioni progettate per prevenire danni fisici.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide \">\n\t\t\t\t\t<div class=\"swiper-slide__inner text-white\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(max-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/08_0391_newUI-min.jpg?width=576&#038;height=432&#038;quality=80&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 641px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/08_0391_newUI-min.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/08_0391_newUI-min.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\" class=\"h-auto max-h-[432px] object-cover\" width=\"576\" height=\"432\" alt=\"Image\">\n\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"h3 font-fjalla-one leading-snug font-normal block\">Layout Pulsanti<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>I pulsanti di controllo sono disposti in modo intelligente per consentire un funzionamento fluido senza interrompere le riprese. Oltre a sette pulsanti personalizzabili, sono presenti un totale di 12 pulsanti integrati con l&#8217;interfaccia utente grafica su entrambi i monitor laterali.<br \/>\nQuesta configurazione consente un utilizzo intuitivo ed efficiente della telecamera, anche per operatori singoli.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide \">\n\t\t\t\t\t<div class=\"swiper-slide__inner text-white\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(max-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/06_0318-min.jpg?width=576&#038;height=432&#038;quality=80&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 641px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/06_0318-min.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/06_0318-min.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\" class=\"h-auto max-h-[432px] object-cover\" width=\"576\" height=\"432\" alt=\"Image\">\n\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"h3 font-fjalla-one leading-snug font-normal block\">Corpo Macchina Resistente alle Intemperie<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Oltre a offrire un&#8217;elevata qualit\u00e0 d&#8217;immagine e prestazioni superlative, GFX ETERNA 55 \u00e8 anche progettata per resistere ad ambienti difficili. L&#8217;intero corpo \u00e8 resistente alla polvere e all&#8217;acqua (ad eccezione del terminale di attacco della batteria V-Mount), rendendola affidabile per l&#8217;uso in condizioni difficili come luoghi polverosi o improvvisi cambiamenti meteorologici sui set in esterna.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-navigation-wrapper\">\n\t\t\t\t<div class=\"swiper-navigation-wrapper__inner arrow-black\">\n\t\t\t\t\t\n<button class=\"swiper-button-prev \" type=\"button\">\n\t<span class=\"hidden sm:flex\">\n\t\t\t\t<svg class=\"svg-slick-left-arrow-svg \"\n\t\t width=\"24\" height=\"22\"\t\talt=\"Svg Slick Left Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-left-arrow-svg\"\n\t\t\t width=\"24\" height=\"22\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n\t<span class=\"flex sm:hidden\">\n\t\t\t\t<svg class=\"svg-slick-left-arrow-svg \"\n\t\t width=\"20\" height=\"18\"\t\talt=\"Svg Slick Left Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-left-arrow-svg\"\n\t\t\t width=\"20\" height=\"18\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n<\/button>\n<button class=\"swiper-button-next \" type=\"button\">\n\t<span class=\"hidden sm:flex\">\n\t\t\t\t<svg class=\"svg-slick-right-arrow-svg \"\n\t\t width=\"24\" height=\"22\"\t\talt=\"Svg Slick Right Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-right-arrow-svg\"\n\t\t\t width=\"24\" height=\"22\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n\t<span class=\"flex sm:hidden\">\n\t\t\t\t<svg class=\"svg-slick-right-arrow-svg \"\n\t\t width=\"20\" height=\"18\"\t\talt=\"Svg Slick Right Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-right-arrow-svg\"\n\t\t\t width=\"20\" height=\"18\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n<\/button>\n\t\t\t\t\t<div class=\"swiper-scrollbar scr-orange\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\n<div id=\"block_49e8b730cfc084c4282596d40f33fc6d\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_49e8b730cfc084c4282596d40f33fc6d.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_49e8b730cfc084c4282596d40f33fc6d.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-black-background-color has-background is-layout-constrained wp-container-core-group-is-layout-1730dc24 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-9a69a910 wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center has-white-color has-text-color has-link-color wp-elements-32dfa131160a5745198eeb73e61a59fc\">Batteria &amp; Supporti di memoria<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity faded-separator--orange\"\/>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div id=\"block_fc2c5c7e5138153efa003bd6be0e9665\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_fc2c5c7e5138153efa003bd6be0e9665.wp-block-spacer {\n        height: 70px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_fc2c5c7e5138153efa003bd6be0e9665.wp-block-spacer {\n            height: 50px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-columns has-spacing-extra-large has-no-design fade-up-parallax is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:48%\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/10_0491-min.jpg?width=1000&#038;height=750\" alt=\"\" class=\"wp-image-288942\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/10_0491-min.jpg?width=1000 1000w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/10_0491-min.jpg?width=300&amp;height=225 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/10_0491-min.jpg?width=768&amp;height=576 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/10_0491-min.jpg?width=400&amp;height=300 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/10_0491-min.jpg?width=365&amp;height=274 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/10_0491-min.jpg?width=600&amp;height=450 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/10_0491-min.jpg?width=717&amp;height=538 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/10_0491-min.jpg?width=936&amp;height=702 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:52%\">\n<h3 class=\"wp-block-heading has-white-color has-text-color has-link-color wp-elements-1c807b6e81c870f6535877eed4f4e6f7\">Batteria<\/h3>\n\n\n\n<p class=\"has-white-color has-text-color has-link-color wp-elements-30c1e2c0e0bce7d280988166a7f81b8c\">GFX ETERNA 55 \u00e8 progettata per ospitare sia batterie V-Mount che NP-W235 di Fujifilm.<br>Utilizzando una batteria V-Mount come fonte di alimentazione principale, \u00e8 possibile montare contemporaneamente la batteria NP-W235, consentendo la sostituzione a caldo della batteria V-Mount senza interrompere l&#8217;alimentazione durante le riprese<em>1. Inoltre, la sola batteria NP-W235 offre circa 30 minuti<\/em>2 di funzionamento continuo, offrendo opzioni flessibili per riprese brevi o situazioni che richiedono un peso ridotto, come il montaggio su droni o gimbal.<\/p>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-white-color has-text-color has-link-color wp-elements-3fd8f7ea3a8dbdad77e85b639e68e5da\"><sub>*1 Non supportato durante la registrazione<br>*2 Ambiente con temperatura inferiore a 25 \u00b0C<\/sub><\/p>\n\n\n\n<div id=\"block_60d218753265e9c50180266152286f0f\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_60d218753265e9c50180266152286f0f.wp-block-spacer {\n        height: 30px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_60d218753265e9c50180266152286f0f.wp-block-spacer {\n            height: 20px;       \n        }\n    }\n<\/style>\n\n\n\n<h3 class=\"wp-block-heading has-white-color has-text-color has-link-color wp-elements-042de5bc240e904e6257d52b1d149143\">Supporto di memoria<\/h3>\n\n\n\n<p class=\"has-white-color has-text-color has-link-color wp-elements-bd5f2b6f729187613fc5b04999f518b7\">L&#8217;utilizzo di schede CFexpress Type B ad alta velocit\u00e0 come supporto di memoria principale offre prestazioni di registrazione fluide e stabili, in grado di gestire senza problemi filmati ad alta risoluzione 8K\/30p e formati ad alto bit-rate come ProRes HQ.<br>Inoltre, \u00e8 presente uno slot per scheda SD secondaria che consente la registrazione di backup sulla scheda SD quando si utilizza H.265.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div id=\"block_49e8b730cfc084c4282596d40f33fc6d\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_49e8b730cfc084c4282596d40f33fc6d.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_49e8b730cfc084c4282596d40f33fc6d.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull fade-up-parallax has-black-background-color has-background is-layout-constrained wp-container-core-group-is-layout-a2d7a1d0 wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--70);padding-right:var(--wp--preset--spacing--50);padding-bottom:var(--wp--preset--spacing--70);padding-left:var(--wp--preset--spacing--50)\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.fujifilm-x.com\/it-it\/filmmaking\/\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/Learn-More-1000-x-250-px-2-min-scaled.png?width=2560&#038;height=1024\" alt=\"\" class=\"wp-image-288961\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/Learn-More-1000-x-250-px-2-min-scaled.png?width=2560 2560w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/Learn-More-1000-x-250-px-2-min-scaled.png?width=300&amp;height=120 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/Learn-More-1000-x-250-px-2-min-scaled.png?width=1024&amp;height=410 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/Learn-More-1000-x-250-px-2-min-scaled.png?width=768&amp;height=307 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/Learn-More-1000-x-250-px-2-min-scaled.png?width=1536&amp;height=614 1536w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/Learn-More-1000-x-250-px-2-min-scaled.png?width=2048&amp;height=819 2048w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/Learn-More-1000-x-250-px-2-min-scaled.png?width=400&amp;height=160 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/Learn-More-1000-x-250-px-2-min-scaled.png?width=365&amp;height=146 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/Learn-More-1000-x-250-px-2-min-scaled.png?width=600&amp;height=240 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/Learn-More-1000-x-250-px-2-min-scaled.png?width=1152&amp;height=461 1152w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/Learn-More-1000-x-250-px-2-min-scaled.png?width=717&amp;height=287 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/Learn-More-1000-x-250-px-2-min-scaled.png?width=936&amp;height=374 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/a><\/figure>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-0740b621 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<figure class=\"wp-block-table alignwide has-none-or-default\"><table class=\"has-green-color has-text-color has-link-color has-fixed-layout\"><tbody><tr><td><strong>Model name<\/strong> <\/td><td>FUJIFILM GFX Eterna 55<\/td><\/tr><tr><td><strong>Declaration of Conformity<\/strong><\/td><td><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\"><a href=\"https:\/\/dl.fujifilm-x.com\/doc\/gfx-eterna-55_doc-iod.pdf\" target=\"_blank\" data-type=\"link\" data-id=\"https:\/\/dl.fujifilm-x.com\/global\/products\/cameras\/gfx100rf\/pdf\/gfx100rf_doc-ynd.pdf\" rel=\"noreferrer noopener\">View PDF<\/a><\/mark><\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n","protected":false},"author":269,"featured_media":288969,"parent":0,"menu_order":0,"template":"","category":[1006,13909,13910,1937,320],"products_category":[11636],"class_list":["post-312137","camera","type-camera","status-publish","has-post-thumbnail","hentry","category-cameras","category-gfx-series-filmmaking-camera","category-gfx-eterna-55","category-gfx-series","category-products","products_category-overview"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":[],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera\/312137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera"}],"about":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/types\/camera"}],"author":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/users\/269"}],"version-history":[{"count":0,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera\/312137\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media\/288969"}],"wp:attachment":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media?parent=312137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/category?post=312137"},{"taxonomy":"products_category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/products_category?post=312137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":315195,"date":"2025-10-27T08:26:57","date_gmt":"2025-10-27T08:26:57","guid":{"rendered":"https:\/\/www.fujifilm-x.com\/?post_type=camera&#038;p=315195"},"modified":"2025-10-27T08:27:10","modified_gmt":"2025-10-27T08:27:10","slug":"x-t30-iii","status":"publish","type":"camera","link":"https:\/\/www.fujifilm-x.com\/it-it\/products\/cameras\/x-t30-iii\/","title":{"rendered":"X-T30 III"},"content":{"rendered":"\n<h1 class=\"wp-block-heading hidden-heading\">X-T30 III<\/h1>\n\n\n\n<div class=\"wp-block-group alignfull x-t30-iii is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group alignfull top-section-tweaks is-layout-constrained wp-block-group-is-layout-constrained\">\t<div id=\"block_c70f2c3b693d1caeacb81b32377811fd\" class=\"wp-block wp-block-slider wp-block-slider--hero swiper alignfull\">\n\t\t<div class=\"swiper-wrapper\" data-settings='{\"autoplay\":false,\"autoplaySpeed\":\"5000\",\"speed\":500,\"effect\":\"fade\"}'>\n\t\t\t\n\t\t\t\t<div class=\"image-layer-container absolute top-0 left-0 right-0 z-10 pointer-events-none m-auto max-w-fujifilm w-full h-full py-8 md:py-12 px-5 md:px-8 h-mob-center h-left v-mob-bottom v-middle\">\n\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"88\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/t30iii_font-shiro-aee88977.png?width=768&amp;height=88\" class=\"attachment-medium_large size-medium_large\" alt=\"Image Logo\" loading=\"eager\" fetchpriority=\"high\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/t30iii_font-shiro-aee88977.png?width=300&amp;height=34 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/t30iii_font-shiro-aee88977.png?width=768&amp;height=88 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/t30iii_font-shiro-aee88977.png?width=400&amp;height=46 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/t30iii_font-shiro-aee88977.png?width=365&amp;height=42 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/t30iii_font-shiro-aee88977.png?width=600&amp;height=69 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/t30iii_font-shiro-aee88977.png?width=717&amp;height=82 717w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\n\t<figure class=\"swiper-slide\">\n\t\t<picture >\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"not all and (min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Mobile-Hero-Image_1-729585cd.jpg?width=640&#038;height=854&#038;quality=85&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_1\" data-slider-device=\"mobile\"\t\t\t\t\/>\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Hero-Image_1-4a00a532.jpg?width=2560&#038;height=980&#038;quality=85&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_1\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Hero-Image_1-4a00a532.jpg?width=2560&#038;height=980&#038;quality=85&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"slide--container__img w-full object-cover position-mob-center position-center\"\t\t\t\t\t\t\t\t\talt=\"X-T30 III Image\"\t\t\t\t\t\t\t\t\twidth=\"2560\"\t\t\t\t\t\t\t\t\theight=\"980\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_1\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t<\/figure>\n\t\t\t\t\n\t\t\t\t\n\t<figure class=\"swiper-slide\">\n\t\t<picture >\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"not all and (min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Mobile-Hero-Image_2-d8684e03.jpg?width=640&#038;height=854&#038;quality=85&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_2\" data-slider-device=\"mobile\"\t\t\t\t\/>\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Hero-Image_2-80515dcf.jpg?width=2560&#038;height=980&#038;quality=85&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_2\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Hero-Image_2-80515dcf.jpg?width=2560&#038;height=980&#038;quality=85&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"slide--container__img w-full object-cover position-mob-left-top position-left-top\"\t\t\t\t\t\t\t\t\talt=\"X-T30 III Image\"\t\t\t\t\t\t\t\t\twidth=\"2560\"\t\t\t\t\t\t\t\t\theight=\"980\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_2\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t<\/figure>\n\t\t\t\t\n\t\t\t\t\n\t<figure class=\"swiper-slide\">\n\t\t<picture >\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"not all and (min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Mobile-Hero-Image_3-8f70c964.jpg?width=640&#038;height=854&#038;quality=85&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_3\" data-slider-device=\"mobile\"\t\t\t\t\/>\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Hero-Image_3-9ec83354.jpg?width=2560&#038;height=980&#038;quality=85&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_3\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Hero-Image_3-9ec83354.jpg?width=2560&#038;height=980&#038;quality=85&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"slide--container__img w-full object-cover position-mob-left-top position-left-top\"\t\t\t\t\t\t\t\t\talt=\"X-T30 III Image\"\t\t\t\t\t\t\t\t\twidth=\"2560\"\t\t\t\t\t\t\t\t\theight=\"980\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_3\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t<\/figure>\n\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group fade-up-parallax is-layout-constrained wp-container-core-group-is-layout-2768c2ff wp-block-group-is-layout-constrained\">\n<div id=\"block_77b10ed2a71f61dfd6bf739dd9c78da1\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_77b10ed2a71f61dfd6bf739dd9c78da1.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_77b10ed2a71f61dfd6bf739dd9c78da1.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center parallax-item\">Your&nbsp;Story&nbsp;Starts Now<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity faded-separator parallax-item\"\/>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center\">Trasforma i momenti quotidiani in immagini straordinarie con FUJIFILM X-T30 III.<br>Compatta ma affidabile, si adatta perfettamente alla tua vita quotidiana, immortalando momenti fugaci come ricordi preziosi che custodirai a lungo.<\/p>\n\n\n\t<div id=\"block_2ee4f64d64a2c25ef9a4916b34c68b9e\" class=\"wp-block wp-block-slider wp-block-slider--three-cameras swiper no-align max-w-[880px] m-auto\">\n\t\t<div class=\"swiper-wrapper\" data-settings='{\"autoplay\":true,\"autoplaySpeed\":5000,\"speed\":500,\"slidesPerView\":1,\"centeredSlides\":true,\"breakpoints\":{\"640\":{\"slidesPerView\":3,\"centeredSlides\":false}}}'>\n\t\t\t\n\t<figure class=\"swiper-slide\">\n\t\t<picture >\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30\u2162_front_XC13-33_black-2da29f28-scaled.jpg?width=300&#038;height=197&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_1\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30\u2162_front_XC13-33_black-2da29f28-scaled.jpg?width=300&#038;height=197&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"h-auto px-4 md:px-8\"\t\t\t\t\t\t\t\t\talt=\"Camera Image 1\"\t\t\t\t\t\t\t\t\twidth=\"300\"\t\t\t\t\t\t\t\t\theight=\"197\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_1\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t<\/figure>\n\t\t\t\t\n\t<figure class=\"swiper-slide\">\n\t\t<picture >\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30\u2162_front_XC13-33_silver-23482ac5.jpg?width=300&#038;height=197&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_2\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30\u2162_front_XC13-33_silver-23482ac5.jpg?width=300&#038;height=197&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"h-auto px-4 md:px-8\"\t\t\t\t\t\t\t\t\talt=\"Camera Image 2\"\t\t\t\t\t\t\t\t\twidth=\"300\"\t\t\t\t\t\t\t\t\theight=\"197\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_2\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t<\/figure>\n\t\t\t\t\n\t<figure class=\"swiper-slide\">\n\t\t<picture >\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30\u2162_front_XC13-33_chacoalSilver-489958e1.jpg?width=300&#038;height=197&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_3\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30\u2162_front_XC13-33_chacoalSilver-489958e1.jpg?width=300&#038;height=197&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"h-auto px-4 md:px-8\"\t\t\t\t\t\t\t\t\talt=\"Camera Image 3\"\t\t\t\t\t\t\t\t\twidth=\"300\"\t\t\t\t\t\t\t\t\theight=\"197\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_3\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t<\/figure>\n\t\t\t\t   \n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n\n\n<div class=\"wp-block-fujifilm-youtube-modal alignfull product-youtube-mod has-white-background-color has-background\"><div class=\"block-video-player py-5 md:py-10\"><div class=\"max-w-[800px] m-auto w-full relative fade-up-parallax\"><div class=\"block-video-player__splash-img aspect-w-16 aspect-h-9 js-btn--modal-youtube\" data-id=\"5UPv6H4FnQg\"><img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_youtube-modal-3b168b0e.jpg\" alt=\"xt30iii_youtube-modal-3b168b0e\" loading=\"lazy\" data-recalc-dims=\"1\"\/><span class=\"play-button\"><\/span><\/div><\/div><div class=\"modal modal--youtube hidden\" data-id=\"5UPv6H4FnQg\"><div class=\"modal__content relative\"><button class=\"btn-modal-close\" data-id=\"5UPv6H4FnQg\"><span><\/span><span><\/span><\/button><figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\"><div id=\"player-5UPv6H4FnQg\" data-id=\"5UPv6H4FnQg\" class=\"youtube-iframe\"><\/div><\/div><\/figure><\/div><\/div><\/div><\/div>\n\n\n\n<div id=\"block_b2fd54d69cb326cdcbaef8787d9432c6\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_b2fd54d69cb326cdcbaef8787d9432c6.wp-block-spacer {\n        height: 54px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_b2fd54d69cb326cdcbaef8787d9432c6.wp-block-spacer {\n            height: 40px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group fade-up-parallax has-background is-layout-constrained wp-block-group-is-layout-constrained\" style=\"background-color:#e5e5e5\">\n<div class=\"wp-block-group group-single-col-content-grey padding-bottom-0 fade-up-parallax is-layout-constrained wp-container-core-group-is-layout-3e296035 wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center\">Quality Meets Control<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity faded-separator\"\/>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center\">X-T30 III \u00e8 dotata di un sensore X-Trans CMOS 4 retroilluminato da 26,1 megapixel e del processore di elaborazione delle immagini X-Processor 5.<br>Questa combinazione di qualit\u00e0 e velocit\u00e0 la rende perfetta per catturare i momenti quotidiani con dettagli straordinari.<\/p>\n<\/div>\n\n\n\n<div id=\"block_adc17f782168ad70b16c8294882f4c31\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_adc17f782168ad70b16c8294882f4c31.wp-block-spacer {\n        height: 40px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_adc17f782168ad70b16c8294882f4c31.wp-block-spacer {\n            height: 20px;       \n        }\n    }\n<\/style>\n\n\n\t<div id=\"block_d4ef8cfa3b73ec933a7c3f589f7bf129\" class=\"wp-block wp-block-slider wp-block-slider--full-width-caption swiper alignfull block relative overflow-hidden\">\n\t\t<div class=\"swiper-wrapper\" data-settings='{\"loop\":true,\"autoplay\":true,\"autoplaySpeed\":\"5000\",\"speed\":500,\"slidesPerView\":1,\"spaceBetween\":20,\"navigation\":{\"nextEl\":\".swiper-button-next\",\"prevEl\":\".swiper-button-prev\"},\"grabCursor\":true,\"breakpoints\":{\"768\":{\"spaceBetween\":32},\"1024\":{\"slidesPerView\":\"auto\",\"centeredSlides\":true,\"spaceBetween\":0}}}'>\n\t\t\t\t\t\t<div class=\"full-width-caption-slide--container swiper-slide\">\n\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__inner-content\">\n\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__image-container\">\n\t\t\t\t\t\t\t\n\t<figure class=\"swiper-slide__inner\">\n\t\t<picture class=\"aspect-ratio aspect-ratio--landscape\">\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Jon-Kerrin-a67c02d3-scaled.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_1\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Jon-Kerrin-a67c02d3-scaled.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"\"\t\t\t\t\t\t\t\t\talt=\"Image 1\"\t\t\t\t\t\t\t\t\twidth=\"800\"\t\t\t\t\t\t\t\t\theight=\"533\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_1\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t\t\t<figcaption class=\"text-extra-xs text-right mt-1.5 caption--landscape\">\n\t\t\t\t\u00a9Jon Kerrin\t\t\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"full-width-caption-slide--container swiper-slide\">\n\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__inner-content\">\n\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__image-container\">\n\t\t\t\t\t\t\t\n\t<figure class=\"swiper-slide__inner\">\n\t\t<picture class=\"aspect-ratio aspect-ratio--landscape\">\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30III_Jo-Howell-86278bfb.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_2\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30III_Jo-Howell-86278bfb.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"\"\t\t\t\t\t\t\t\t\talt=\"Image 2\"\t\t\t\t\t\t\t\t\twidth=\"800\"\t\t\t\t\t\t\t\t\theight=\"533\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_2\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t\t\t<figcaption class=\"text-extra-xs text-right mt-1.5 caption--landscape\">\n\t\t\t\t\u00a9Jo Howell\t\t\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"full-width-caption-slide--container swiper-slide\">\n\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__inner-content\">\n\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__image-container\">\n\t\t\t\t\t\t\t\n\t<figure class=\"swiper-slide__inner\">\n\t\t<picture class=\"aspect-ratio aspect-ratio--landscape\">\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Dong-Yuan-3c1455aa.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_3\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Dong-Yuan-3c1455aa.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"\"\t\t\t\t\t\t\t\t\talt=\"Image 3\"\t\t\t\t\t\t\t\t\twidth=\"800\"\t\t\t\t\t\t\t\t\theight=\"533\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_3\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t\t\t<figcaption class=\"text-extra-xs text-right mt-1.5 caption--landscape\">\n\t\t\t\t\u00a9Dong Yuan\t\t\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"full-width-caption-slide--container swiper-slide\">\n\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__inner-content\">\n\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__image-container\">\n\t\t\t\t\t\t\t\n\t<figure class=\"swiper-slide__inner\">\n\t\t<picture class=\"aspect-ratio aspect-ratio--landscape\">\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Elisa-Waves-a8b62b7c.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_4\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Elisa-Waves-a8b62b7c.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"\"\t\t\t\t\t\t\t\t\talt=\"Image 4\"\t\t\t\t\t\t\t\t\twidth=\"800\"\t\t\t\t\t\t\t\t\theight=\"533\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_4\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t\t\t<figcaption class=\"text-extra-xs text-right mt-1.5 caption--landscape\">\n\t\t\t\t\u00a9Elisa Waves\t\t\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"full-width-caption-slide--container swiper-slide\">\n\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__inner-content\">\n\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__image-container\">\n\t\t\t\t\t\t\t\n\t<figure class=\"swiper-slide__inner\">\n\t\t<picture class=\"aspect-ratio aspect-ratio--landscape\">\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Keiko-Watanabe-852045d6.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_5\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Keiko-Watanabe-852045d6.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"\"\t\t\t\t\t\t\t\t\talt=\"Image 5\"\t\t\t\t\t\t\t\t\twidth=\"800\"\t\t\t\t\t\t\t\t\theight=\"533\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_5\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t\t\t<figcaption class=\"text-extra-xs text-right mt-1.5 caption--landscape\">\n\t\t\t\t\u00a9Keiko Watanabe\t\t\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\n<button class=\"swiper-button-prev button-bg-transparent button-bg-transparent--black-arrow\" type=\"button\">\n\t<span class=\"hidden sm:flex\">\n\t\t\t\t<svg class=\"svg-slick-left-arrow-svg \"\n\t\t width=\"24\" height=\"22\"\t\talt=\"Svg Slick Left Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-left-arrow-svg\"\n\t\t\t width=\"24\" height=\"22\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n\t<span class=\"flex sm:hidden\">\n\t\t\t\t<svg class=\"svg-slick-left-arrow-svg \"\n\t\t width=\"20\" height=\"18\"\t\talt=\"Svg Slick Left Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-left-arrow-svg\"\n\t\t\t width=\"20\" height=\"18\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n<\/button>\n<button class=\"swiper-button-next button-bg-transparent button-bg-transparent--black-arrow\" type=\"button\">\n\t<span class=\"hidden sm:flex\">\n\t\t\t\t<svg class=\"svg-slick-right-arrow-svg \"\n\t\t width=\"24\" height=\"22\"\t\talt=\"Svg Slick Right Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-right-arrow-svg\"\n\t\t\t width=\"24\" height=\"22\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n\t<span class=\"flex sm:hidden\">\n\t\t\t\t<svg class=\"svg-slick-right-arrow-svg \"\n\t\t width=\"20\" height=\"18\"\t\talt=\"Svg Slick Right Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-right-arrow-svg\"\n\t\t\t width=\"20\" height=\"18\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n<\/button>\n\t<\/div>\n\t\n\n\n<div id=\"block_8b29aa0d2d0662ac953fb776dc7b058e\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_8b29aa0d2d0662ac953fb776dc7b058e.wp-block-spacer {\n        height: 54px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_8b29aa0d2d0662ac953fb776dc7b058e.wp-block-spacer {\n            height: 32px;       \n        }\n    }\n<\/style>\n<\/div>\n\n\n\n<div id=\"block_77b10ed2a71f61dfd6bf739dd9c78da1\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_77b10ed2a71f61dfd6bf739dd9c78da1.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_77b10ed2a71f61dfd6bf739dd9c78da1.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group  fade-up-parallax is-layout-constrained wp-container-core-group-is-layout-2768c2ff wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-1d6f4e6b wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center parallax-item\">Pocket Size, Classic Style<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity faded-separator parallax-item\"\/>\n<\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group alignfull is-layout-constrained wp-container-core-group-is-layout-741f6d8e wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<div class=\"wp-block-columns has-spacing-extra-large has-no-design fade-up-parallax is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column first-one is-layout-constrained wp-block-column-is-layout-constrained\">\n<figure class=\"wp-block-image alignwide size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"1667\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Size-3d04102b.jpg?width=2500&#038;height=1667\" alt=\"\" class=\"wp-image-314125\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Size-3d04102b.jpg?width=2500 2500w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Size-3d04102b.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Size-3d04102b.jpg?width=1024&amp;height=683 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Size-3d04102b.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Size-3d04102b.jpg?width=1536&amp;height=1024 1536w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Size-3d04102b.jpg?width=2048&amp;height=1366 2048w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Size-3d04102b.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Size-3d04102b.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Size-3d04102b.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Size-3d04102b.jpg?width=1152&amp;height=768 1152w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Size-3d04102b.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Size-3d04102b.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-bottom second-one is-content-justification-center is-layout-constrained wp-block-column-is-layout-constrained\">\n<h3 class=\"wp-block-heading mb-1.5\">Compatta e leggera<\/h3>\n\n\n\n<p>Con un peso di soli 378g*, X-T30 III pu\u00f2 essere portata a spalla o riposta in borsa, pronta per accompagnarti ovunque. Con le sue dimensioni compatte sar\u00e0 sempre a portata di mano, cos\u00ec sarai pronto a scattare istanti fantastici nel momento esatto in cui avvengono.<br><\/p>\n\n\n\n<p><sub>*Batteria e scheda di memoria incluse.<\/sub><\/p>\n<\/div>\n<\/div>\n\n\n\n<div id=\"block_a8e788005d7ff6921519b80ea93a548c\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_a8e788005d7ff6921519b80ea93a548c.wp-block-spacer {\n        height: 70px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_a8e788005d7ff6921519b80ea93a548c.wp-block-spacer {\n            height: 50px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-columns has-spacing-extra-large has-no-design fade-up-parallax is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-bottom second-one is-content-justification-center is-layout-constrained wp-block-column-is-layout-constrained\">\n<h3 class=\"wp-block-heading mb-1.5\">Design irresistibile<\/h3>\n\n\n\n<p>Ispirata all&#8217;eleganza delle classiche fotocamere a pellicola, X-T30 III presenta un design raffinato che vorrai sempre avere al tuo fianco. Il mirino centrale ti immerge in ogni scena, mentre l&#8217;impugnatura perfettamente sagomata \u00e8 cos\u00ec naturale che non vorrai mai pi\u00f9 lasciarla.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column first-one is-layout-constrained wp-block-column-is-layout-constrained\">\n<figure class=\"wp-block-image alignwide size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"1667\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Design-c0ca392e.jpg?width=2500&#038;height=1667\" alt=\"\" class=\"wp-image-314126\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Design-c0ca392e.jpg?width=2500 2500w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Design-c0ca392e.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Design-c0ca392e.jpg?width=1024&amp;height=683 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Design-c0ca392e.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Design-c0ca392e.jpg?width=1536&amp;height=1024 1536w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Design-c0ca392e.jpg?width=2048&amp;height=1366 2048w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Design-c0ca392e.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Design-c0ca392e.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Design-c0ca392e.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Design-c0ca392e.jpg?width=1152&amp;height=768 1152w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Design-c0ca392e.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Design-c0ca392e.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div id=\"block_77b10ed2a71f61dfd6bf739dd9c78da1\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_77b10ed2a71f61dfd6bf739dd9c78da1.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_77b10ed2a71f61dfd6bf739dd9c78da1.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group alignfull text-white has-background is-layout-flow wp-block-group-is-layout-flow\" style=\"background-color:#0f141c;padding-top:var(--wp--preset--spacing--70);padding-right:0;padding-bottom:var(--wp--preset--spacing--60);padding-left:0\">\n<div class=\"wp-block-group fade-up-parallax wp-block-group--with-learn-more wp-block-group--with-learn-more--white is-layout-constrained wp-container-core-group-is-layout-4ee83bb8 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<h2 class=\"wp-block-heading has-text-align-center\">Simulazione Pellicola<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity faded-separator\"\/>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center\">Le Simulazioni Pellicola sfruttano oltre 90 anni di esperienza Fujifilm nella scienza del colore, ricreando digitalmente look di ispirazione analogica per offrire risultati brillanti direttamente sulla fotocamera. La piastra superiore di X-T30 III ospita una ghiera personalizzabile di Simulazione Pellicola che consente di accedere rapidamente alle opzioni preferite, oppure di salvare e richiamare le proprie ricette di Simulazione Pellicola sulla ghiera FS1 &#8211; FS3.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-link-color wp-elements-957a6c4458cee633ad66d1eba88be436\" style=\"text-decoration:underline\"><a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/film-simulation\/\" data-type=\"link\" data-id=\"https:\/\/www.fujifilm-x.com\/global\/products\/film-simulation\/\" target=\"_blank\" rel=\"noreferrer noopener\">Scopri di pi\u00f9<\/a><\/p>\n<\/div>\n\n\n\n<div id=\"block_b0c4f03e6d0bb1b87837b18dd66b7d1a\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_b0c4f03e6d0bb1b87837b18dd66b7d1a.wp-block-spacer {\n        height: 50px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_b0c4f03e6d0bb1b87837b18dd66b7d1a.wp-block-spacer {\n            height: 30px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\">\n<div id=\"block_731733c03e33eda10546db79aaba0e1d\" class=\"wp-block wp-block-interactive-camera overflow-hidden  no-align\">\n\t<div class=\"interactive-camera__inner camera-model-x-t30iii\">\n\n\t\t<img decoding=\"async\" class=\"camera-frame\" src=\"http:\/\/www.fujifilm-x.com\/wp-content\/themes\/fujifilm\/dist\/images\/interactive-camera\/x-t30iii\/camera-frame.png\" loading=\"lazy\">\n\t\t<img decoding=\"async\" class=\"try-it\" src=\"http:\/\/www.fujifilm-x.com\/wp-content\/themes\/fujifilm\/dist\/images\/try-arrow.svg\" loading=\"lazy\">\n\t\t<div class=\"outter-ring\">\n\t\t\t<span class=\"inner-ring\">\n\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.fujifilm-x.com\/wp-content\/themes\/fujifilm\/dist\/images\/interactive-camera\/x-t30iii\/dial-inner.png\" loading=\"lazy\">\n\t\t\t<\/span>\n\t\t\t<img decoding=\"async\" class=\"outter-ring__img\" src=\"http:\/\/www.fujifilm-x.com\/wp-content\/themes\/fujifilm\/dist\/images\/interactive-camera\/x-t30iii\/dial-outer.png\" loading=\"lazy\">\n\t\t<\/div>\n\n\t\t<div class=\"photos\">\n\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"large-dial\">\n\t\t\t\t\t<div class=\"films\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"film film--active\" data-point=\"0,360,720,1080,1440,1800,2160,2520,2880\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2024\/04\/PROVIA-\u30b9\u30bf\u30f3\u30c0\u30fc\u30c9-2-1-1.png\" loading=\"lazy\" data-recalc-dims=\"1\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"film\" data-point=\"36,396,756,1116,1476,1836,2196,2556\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2024\/04\/velvia-1-1.png\" loading=\"lazy\" data-recalc-dims=\"1\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"film\" data-point=\"72,432,792,1152,1512,1872,2232,2592\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2024\/04\/ASTIA-\u30bd\u30d5\u30c8-2-1-1.png\" loading=\"lazy\" data-recalc-dims=\"1\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"film\" data-point=\"108,468,828,1188,1548,1908,2268,2628\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2024\/04\/classic-chrome-3.png\" loading=\"lazy\" data-recalc-dims=\"1\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"film\" data-point=\"144,504,864,1224,1584,1944,2304,2664\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2024\/04\/REALA-ACE-3.png\" loading=\"lazy\" data-recalc-dims=\"1\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"film\" data-point=\"180,540,900,1260,1620,1980,2340,2700\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2024\/04\/ACROS-3-1.png\" loading=\"lazy\" data-recalc-dims=\"1\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"film\" data-point=\"216,576,936,1296,1656,2016,2376,2736\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2024\/04\/classic-neg-2.png\" loading=\"lazy\" data-recalc-dims=\"1\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"film\" data-point=\"252,612,972,1332,1692,2052,2412,2772\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2024\/04\/PRO-Neg.-Hi-3-1.png\" loading=\"lazy\" data-recalc-dims=\"1\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"film\" data-point=\"288,648,1008,1368,1728,2088,2448,2808\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2024\/04\/neg.png\" loading=\"lazy\" data-recalc-dims=\"1\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"film\" data-point=\"324,684,1044,1404,1764,2124,2484,2844\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2024\/05\/ETERNA\u30d6\u30ea\u30fc\u30c1\u30d0\u30a4\u30d1\u30b9-2.png\" loading=\"lazy\" data-recalc-dims=\"1\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"dial-container\">\n\t\t\t\t\t\t<img decoding=\"async\" class=\"large-dial-img\" src=\"http:\/\/www.fujifilm-x.com\/wp-content\/themes\/fujifilm\/dist\/images\/interactive-camera\/x-t30iii\/large-dial-img.png\" loading=\"lazy\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<span class=\"sticky-center\"><\/span>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"photo photo--active\" data-point=\"0,360,720,1080,1440,1800,2160,2520,2880\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"235\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Provia-15c714bf-1.jpg?resize=417,235&amp;width=417&amp;height=235\" class=\"photo-img\" alt=\"\" \/>\t\t\t\t\t\t<span class=\"photo-tag\"><img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2024\/04\/PROVIA-STANDARD-1-1.png\" loading=\"lazy\" data-recalc-dims=\"1\"><\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"photo\" data-point=\"36,396,756,1116,1476,1836,2196,2556\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"235\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Velevia-45f97019.jpg?resize=417,235&amp;width=417&amp;height=235\" class=\"photo-img\" alt=\"\" \/>\t\t\t\t\t\t<span class=\"photo-tag\"><img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2024\/04\/Velvia-VIVID-1-1.png\" loading=\"lazy\" data-recalc-dims=\"1\"><\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"photo\" data-point=\"72,432,792,1152,1512,1872,2232,2592\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"235\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_ASTIA-63448590.jpg?resize=417,235&amp;width=417&amp;height=235\" class=\"photo-img\" alt=\"\" \/>\t\t\t\t\t\t<span class=\"photo-tag\"><img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2024\/04\/ASTIA-SOFT-1-1.png\" loading=\"lazy\" data-recalc-dims=\"1\"><\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"photo\" data-point=\"108,468,828,1188,1548,1908,2268,2628\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"235\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Classicshrome-9da90246.jpg?resize=417,235&amp;width=417&amp;height=235\" class=\"photo-img\" alt=\"\" \/>\t\t\t\t\t\t<span class=\"photo-tag\"><img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2024\/04\/CLASSIC-CHROME-2.png\" loading=\"lazy\" data-recalc-dims=\"1\"><\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"photo\" data-point=\"144,504,864,1224,1584,1944,2304,2664\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"235\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Realaace-81aeabdf.jpg?resize=417,235&amp;width=417&amp;height=235\" class=\"photo-img\" alt=\"\" \/>\t\t\t\t\t\t<span class=\"photo-tag\"><img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2024\/04\/REALA-ACE.png\" loading=\"lazy\" data-recalc-dims=\"1\"><\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"photo\" data-point=\"180,540,900,1260,1620,1980,2340,2700\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"235\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Across-dc89346d.jpg?resize=417,235&amp;width=417&amp;height=235\" class=\"photo-img\" alt=\"\" \/>\t\t\t\t\t\t<span class=\"photo-tag\"><img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2024\/04\/ACROS-1.png\" loading=\"lazy\" data-recalc-dims=\"1\"><\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"photo\" data-point=\"216,576,936,1296,1656,2016,2376,2736\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"235\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_FS1_Classicneg-899264cb.jpg?resize=417,235&amp;width=417&amp;height=235\" class=\"photo-img\" alt=\"\" \/>\t\t\t\t\t\t<span class=\"photo-tag\"><img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2024\/04\/CLASSIC-Neg-1.png\" loading=\"lazy\" data-recalc-dims=\"1\"><\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"photo\" data-point=\"252,612,972,1332,1692,2052,2412,2772\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"235\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_FS2_Proneghi-02f3b1f7.jpg?resize=417,235&amp;width=417&amp;height=235\" class=\"photo-img\" alt=\"\" \/>\t\t\t\t\t\t<span class=\"photo-tag\"><img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2024\/04\/PRO-Neg.-Hi.png\" loading=\"lazy\" data-recalc-dims=\"1\"><\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"photo\" data-point=\"288,648,1008,1368,1728,2088,2448,2808\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"235\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_FS3_Nostalgicneg-a8e13a9c.jpg?resize=417,235&amp;width=417&amp;height=235\" class=\"photo-img\" alt=\"\" \/>\t\t\t\t\t\t<span class=\"photo-tag\"><img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2024\/04\/NOSTALGIC-Neg.png\" loading=\"lazy\" data-recalc-dims=\"1\"><\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"photo\" data-point=\"324,684,1044,1404,1764,2124,2484,2844\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"235\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30-iii_film-Simulation_eterna-bleach-bypass-20fb0c41.jpg?resize=417,235&amp;width=417&amp;height=235\" class=\"photo-img\" alt=\"\" \/>\t\t\t\t\t\t<span class=\"photo-tag\"><img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2024\/05\/ETERNA-BLEACH-BYPASS.png\" loading=\"lazy\" data-recalc-dims=\"1\"><\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"q-info\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2024\/04\/Q-INFO-1.png\" loading=\"lazy\" data-recalc-dims=\"1\">\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t\t\t<div class=\"descriptions\">\n\t\t\t\t\t\t\t<div class=\"description description--active\" data-point=\"0,360,720,1080,1440,1800,2160,2520,2880\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"description-img-wrapper\">\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"description-img\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/provia.webp\" loading=\"lazy\" data-recalc-dims=\"1\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"description-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"description-title\">PROVIA\/STANDARD<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"description-text\">Basata sulla pellicola invertibile FUJICHROME PROVIA, progettata per l&#039;uso professionale, questa modalit\u00e0 di Simulazione Pellicola dalla riproduzione dei colori neutra \u00e8 adatta a tutti i tipi di soggetto.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"description\" data-point=\"36,396,756,1116,1476,1836,2196,2556\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"description-img-wrapper\">\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"description-img\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/velvia.webp\" loading=\"lazy\" data-recalc-dims=\"1\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"description-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"description-title\">VELVIA\/VIVID<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"description-text\">Basata su FUJICHROME Velvia, una pellicola invertibile ultra-vivida progettata per i professionisti, questa modalit\u00e0 di Simulazione Pellicola offre colori pi\u00f9 ricchi e contrastati rispetto alla PROVIA\/Standard. \u00c8 una delle preferite dai fotografi paesaggisti.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"description\" data-point=\"72,432,792,1152,1512,1872,2232,2592\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"description-img-wrapper\">\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"description-img\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/astia.webp\" loading=\"lazy\" data-recalc-dims=\"1\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"description-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"description-title\">ASTIA\/SOFT<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"description-text\">Basata sulla pellicola invertibile FUJICHROME ASTIA, progettata per i ritratti di moda, questa modalit\u00e0 privilegia la riproduzione fedele e morbida delle tonalit\u00e0 della pelle, riproducendo al contempo vividi cieli azzurri e vegetazione.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"description\" data-point=\"108,468,828,1188,1548,1908,2268,2628\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"description-img-wrapper\">\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"description-img\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/classicchrome.webp\" loading=\"lazy\" data-recalc-dims=\"1\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"description-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"description-title\">CLASSIC CHROME<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"description-text\">Progettata per riprodurre un aspetto simile alle riviste documentaristiche del XX secolo, la bassa saturazione e la gradazione tonale decisa nelle ombre di CLASSIC CHROME la rendono la scelta perfetta per la fotografia documentaristica con un tocco di realismo.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"description\" data-point=\"144,504,864,1224,1584,1944,2304,2664\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"description-img-wrapper\">\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"description-img\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2024\/05\/realaace-3.png\" loading=\"lazy\" data-recalc-dims=\"1\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"description-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"description-title\">REALA ACE<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"description-text\">Basata sulla pellicola REALA ACE, questa Simulazione Pellicola combina una fedele riproduzione dei colori con tonalit\u00e0 intense, rendendola adatta a tutti i soggetti e a tutte le situazioni.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"description\" data-point=\"180,540,900,1260,1620,1980,2340,2700\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"description-img-wrapper\">\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"description-img\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/acros.webp\" loading=\"lazy\" data-recalc-dims=\"1\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"description-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"description-title\">ACROS<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"description-text\">Basata su ACROS, una pellicola monocromatica nota per la sua grana finissima, questa modalit\u00e0 di Simulazione Pellicola offre ricchi dettagli nelle ombre e un&#039;eccellente nitidezza, aggiungendo comunque grana ad alti ISO e ricreando la straordinaria sensazione di trama del monocromatico.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"description\" data-point=\"216,576,936,1296,1656,2016,2376,2736\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"description-img-wrapper\">\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"description-img\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/classicneg.webp\" loading=\"lazy\" data-recalc-dims=\"1\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"description-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"description-title\">Classic Neg.<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"description-text\">Basata su SUPERIA, una pellicola negativa a colori amata da generazioni di fotografi, questa modalit\u00e0 di Simulazione Pellicola offre una gradazione tonale ad alto contrasto. Aggiunge profondit\u00e0 e definizione ai colori regolandone le tonalit\u00e0 nelle alte luci e nelle ombre, riducendone al contempo la saturazione.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"description\" data-point=\"252,612,972,1332,1692,2052,2412,2772\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"description-img-wrapper\">\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"description-img\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2024\/05\/proneghi-5.png\" loading=\"lazy\" data-recalc-dims=\"1\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"description-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"description-title\">PRO Neg. Hi<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"description-text\">Basata sulla PRO160NH, una pellicola negativa professionale a colori, questa simulazione pellicola presenta una gradazione tonale leggermente pi\u00f9 dura rispetto alla PRO Neg. Std. \u00c8 utilizzata principalmente nella fotografia di ritratto, dove l&#039;illuminazione non \u00e8 facilmente controllabile. Fornisce la giusta quantit\u00e0 di ombre anche in condizioni di illuminazione piatta.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"description\" data-point=\"288,648,1008,1368,1728,2088,2448,2808\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"description-img-wrapper\">\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"description-img\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/nostalgicneg.webp\" loading=\"lazy\" data-recalc-dims=\"1\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"description-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"description-title\">NOSTALGIC Neg.<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"description-text\">Progettata per ricreare l&#039;aspetto delle immagini contenute nei vecchi album fotografici, NOSTALGIC Neg. produce immagini con colori intensi nelle ombre e una tonalit\u00e0 morbida nei mezzi toni e nelle alte luci.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"description\" data-point=\"324,684,1044,1404,1764,2124,2484,2844\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"description-img-wrapper\">\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"description-img\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2024\/05\/eternabb-4.png\" loading=\"lazy\" data-recalc-dims=\"1\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"description-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"description-title\">ETERNA BLEACH BYPASS<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"description-text\">Questa simulazione di pellicola non si limita a manipolazioni basilari di contrasto, saturazione e tonalit\u00e0 tipiche del Bypass. \u00c8 stata sviluppata partendo dalla domanda: &quot;Come apparirebbe questa scena se fosse stata scattata ed elaborata con la rinomata pellicola cinematografica ETERNA?&quot; Il risultato \u00e8 un look distintivo, caratterizzato da bassa saturazione e alto contrasto, ideale per conferire un aspetto unico e cinematografico sia alle fotografie che ai video.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\n\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-background is-layout-flow wp-block-group-is-layout-flow\" style=\"background-color:#535762;padding-top:var(--wp--preset--spacing--70);padding-right:0;padding-bottom:var(--wp--preset--spacing--70);padding-left:0\">\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-5ca99053 wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center has-white-color has-text-color has-link-color wp-elements-9dc5e9c2a04afdebede662851e775098\">Your Images, Your Way<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity faded-separator\"\/>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-link-color wp-elements-1477f1325947ccb347377a71a532fe83\">Le immagini di qualit\u00e0 sono fatte di dettagli. Grazie a una serie di controlli creativi, X-T30 III ti consente di creare contenuti esattamente come li desideri.<\/p>\n<\/div>\n\n\n\n<div id=\"block_b0c4f03e6d0bb1b87837b18dd66b7d1a\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_b0c4f03e6d0bb1b87837b18dd66b7d1a.wp-block-spacer {\n        height: 50px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_b0c4f03e6d0bb1b87837b18dd66b7d1a.wp-block-spacer {\n            height: 30px;       \n        }\n    }\n<\/style>\n\n\n\t<div id=\"block_edefc80e86222e3c0a093790cded637b\" class=\"wp-block wp-block-slider wp-block-slider--rotate swiper alignfull block relative overflow-hidden\">\n\t\t<div class=\"swiper-wrapper\" data-settings='{\"loop\":true,\"autoplay\":true,\"autoplaySpeed\":\"5000\",\"speed\":500,\"slidesPerView\":1,\"spaceBetween\":20,\"navigation\":{\"nextEl\":\".swiper-button-next\",\"prevEl\":\".swiper-button-prev\"},\"grabCursor\":true,\"noSwipingSelector\":\".no-swiping\",\"breakpoints\":{\"768\":{\"spaceBetween\":32},\"1024\":{\"slidesPerView\":\"auto\",\"centeredSlides\":true,\"spaceBetween\":0}}}'>\n\t\t\t\t\t\t\t<div class=\"rotate-slide--container swiper-slide\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div id=\"effetto-grana\" class=\"flex flex-col justify-center\">\n\t\t\t\t\t\t\t<div class=\"img-comp-container__inner\">\n\t\t\t\t\t\t\t\t<div class=\"img-comp-container w-full relative overflow-hidden m-auto no-swiping\">\n\t\t\t\t\t\t\t\t\t<div class=\"img-comp-img w-full h-full overflow-hidden relative\">\n\t\t\t\t\t\t\t\t\t\t<img width=\"1000\" height=\"667\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Thanai-Manasathit_1_Grain-ON-bf2fca02.jpg?width=1000&amp;height=667\" class=\"w-full h-auto block object-left object-cover\" alt=\"Effetto Grana - Image Left 1\" loading=\"lazy\" decoding=\"async\" fetchpriority=\"low\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Thanai-Manasathit_1_Grain-ON-bf2fca02.jpg?width=1000 1000w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Thanai-Manasathit_1_Grain-ON-bf2fca02.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Thanai-Manasathit_1_Grain-ON-bf2fca02.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Thanai-Manasathit_1_Grain-ON-bf2fca02.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Thanai-Manasathit_1_Grain-ON-bf2fca02.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Thanai-Manasathit_1_Grain-ON-bf2fca02.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Thanai-Manasathit_1_Grain-ON-bf2fca02.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Thanai-Manasathit_1_Grain-ON-bf2fca02.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"img-comp-img top-0 img-comp-overlay w-1\/2 h-full overflow-hidden absolute\">\n\t\t\t\t\t\t\t\t\t\t<img width=\"1000\" height=\"667\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Thanai-Manasathit_1_Grain-Off-701746b3.jpg?width=1000&amp;height=667\" class=\"w-full h-auto block object-left object-cover\" alt=\"Effetto Grana - Image Right 1\" loading=\"lazy\" decoding=\"async\" fetchpriority=\"low\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Thanai-Manasathit_1_Grain-Off-701746b3.jpg?width=1000 1000w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Thanai-Manasathit_1_Grain-Off-701746b3.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Thanai-Manasathit_1_Grain-Off-701746b3.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Thanai-Manasathit_1_Grain-Off-701746b3.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Thanai-Manasathit_1_Grain-Off-701746b3.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Thanai-Manasathit_1_Grain-Off-701746b3.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Thanai-Manasathit_1_Grain-Off-701746b3.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Thanai-Manasathit_1_Grain-Off-701746b3.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"text-extra-xs text-right mt-1.5 text-white\">\n\t\t\t\t\t\t\t\t\t\t\u00a9Thanai Manasathit\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"flex flex-col justify-center mt-5 md:mt-8\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"main-title h3 h3\">Effetto Grana<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"main-paragraph\">Dalle texture pi\u00f9 delicate all&#039;aspetto granuloso delle tradizionali pellicole ad alta sensibilit\u00e0 ISO, con X-T30 III puoi aggiungere facilmente una grana naturale alle tue foto. Controlla l&#039;intensit\u00e0 e le dimensioni per ottenere la giusta quantit\u00e0 di trama su qualsiasi immagine.\r\n<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<style>\n\t\t\t\t\t\t\t\t#effetto-grana .img-comp-slider:before{content:\"Off\";}#effetto-grana .img-comp-slider:after{content:\"On\";}\t\t\t\t\t\t\t<\/style>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"rotate-slide--container swiper-slide\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div id=\"effetto-color-chrome\" class=\"flex flex-col justify-center\">\n\t\t\t\t\t\t\t<div class=\"img-comp-container__inner\">\n\t\t\t\t\t\t\t\t<div class=\"img-comp-container w-full relative overflow-hidden m-auto no-swiping\">\n\t\t\t\t\t\t\t\t\t<div class=\"img-comp-img w-full h-full overflow-hidden relative\">\n\t\t\t\t\t\t\t\t\t\t<img width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_NONKIT-JAMES_Color-Chrome-ON-d01476c4.jpg?width=1024&amp;height=682\" class=\"w-full h-auto block object-left object-cover\" alt=\"Effetto Color Chrome - Image Left 2\" loading=\"lazy\" decoding=\"async\" fetchpriority=\"low\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_NONKIT-JAMES_Color-Chrome-ON-d01476c4.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_NONKIT-JAMES_Color-Chrome-ON-d01476c4.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_NONKIT-JAMES_Color-Chrome-ON-d01476c4.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_NONKIT-JAMES_Color-Chrome-ON-d01476c4.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_NONKIT-JAMES_Color-Chrome-ON-d01476c4.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_NONKIT-JAMES_Color-Chrome-ON-d01476c4.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_NONKIT-JAMES_Color-Chrome-ON-d01476c4.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_NONKIT-JAMES_Color-Chrome-ON-d01476c4.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"img-comp-img top-0 img-comp-overlay w-1\/2 h-full overflow-hidden absolute\">\n\t\t\t\t\t\t\t\t\t\t<img width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_NONKIT-JAMES_Color-Chrome-OFF-9f17e8ac.jpg?width=1024&amp;height=682\" class=\"w-full h-auto block object-left object-cover\" alt=\"Effetto Color Chrome - Image Right 2\" loading=\"lazy\" decoding=\"async\" fetchpriority=\"low\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_NONKIT-JAMES_Color-Chrome-OFF-9f17e8ac.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_NONKIT-JAMES_Color-Chrome-OFF-9f17e8ac.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_NONKIT-JAMES_Color-Chrome-OFF-9f17e8ac.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_NONKIT-JAMES_Color-Chrome-OFF-9f17e8ac.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_NONKIT-JAMES_Color-Chrome-OFF-9f17e8ac.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_NONKIT-JAMES_Color-Chrome-OFF-9f17e8ac.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_NONKIT-JAMES_Color-Chrome-OFF-9f17e8ac.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_NONKIT-JAMES_Color-Chrome-OFF-9f17e8ac.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"text-extra-xs text-right mt-1.5 text-white\">\n\t\t\t\t\t\t\t\t\t\t\u00a9Tewter Thanawat\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"flex flex-col justify-center mt-5 md:mt-8\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"main-title h3 h3\">Effetto Color Chrome<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"main-paragraph\">Per soggetti molto saturi, l&#039;effetto Color Chrome aggiunge profondit\u00e0, dettaglio e vivacit\u00e0 in tre intensit\u00e0 ai toni del rosso, del verde o del giallo, laddove altrimenti i dettagli potrebbero andare persi. In alternativa, usa Color Chrome FX Blue per potenziare i toni blu nell&#039;immagine.\r\n<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<style>\n\t\t\t\t\t\t\t\t#effetto-color-chrome .img-comp-slider:before{content:\"Off\";}#effetto-color-chrome .img-comp-slider:after{content:\"On\";}\t\t\t\t\t\t\t<\/style>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"rotate-slide--container swiper-slide\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div id=\"chiarezza\" class=\"flex flex-col justify-center\">\n\t\t\t\t\t\t\t<div class=\"img-comp-container__inner\">\n\t\t\t\t\t\t\t\t<div class=\"img-comp-container w-full relative overflow-hidden m-auto no-swiping\">\n\t\t\t\t\t\t\t\t\t<div class=\"img-comp-img w-full h-full overflow-hidden relative\">\n\t\t\t\t\t\t\t\t\t\t<img width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Dong-Yuan_Clarity5-784ba87c.jpg?width=1024&amp;height=682\" class=\"w-full h-auto block object-left object-cover\" alt=\"Chiarezza - Image Left 3\" loading=\"lazy\" decoding=\"async\" fetchpriority=\"low\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Dong-Yuan_Clarity5-784ba87c.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Dong-Yuan_Clarity5-784ba87c.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Dong-Yuan_Clarity5-784ba87c.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Dong-Yuan_Clarity5-784ba87c.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Dong-Yuan_Clarity5-784ba87c.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Dong-Yuan_Clarity5-784ba87c.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Dong-Yuan_Clarity5-784ba87c.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Dong-Yuan_Clarity5-784ba87c.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"img-comp-img top-0 img-comp-overlay w-1\/2 h-full overflow-hidden absolute\">\n\t\t\t\t\t\t\t\t\t\t<img width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Dong-Yuan_Clarity-5-ff7e2f8f.jpg?width=1024&amp;height=682\" class=\"w-full h-auto block object-left object-cover\" alt=\"Chiarezza - Image Right 3\" loading=\"lazy\" decoding=\"async\" fetchpriority=\"low\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Dong-Yuan_Clarity-5-ff7e2f8f.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Dong-Yuan_Clarity-5-ff7e2f8f.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Dong-Yuan_Clarity-5-ff7e2f8f.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Dong-Yuan_Clarity-5-ff7e2f8f.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Dong-Yuan_Clarity-5-ff7e2f8f.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Dong-Yuan_Clarity-5-ff7e2f8f.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Dong-Yuan_Clarity-5-ff7e2f8f.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Dong-Yuan_Clarity-5-ff7e2f8f.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"text-extra-xs text-right mt-1.5 text-white\">\n\t\t\t\t\t\t\t\t\t\t\u00a9Dong Yuan\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"flex flex-col justify-center mt-5 md:mt-8\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"main-title h3 h3\">Chiarezza<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"main-paragraph\">Il controllo della Chiarezza consente di decidere se ricreare una scena con una elevata nitidezza, bordi definiti e contrasto migliorato, oppure con un effetto pi\u00f9 morbido. Con 11 livelli di controllo, \u00e8 facile adattarlo al tuo gusto e stile personale.\r\n<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<style>\n\t\t\t\t\t\t\t\t#chiarezza .img-comp-slider:before{content:\"-5\";}#chiarezza .img-comp-slider:after{content:\"+5\";}\t\t\t\t\t\t\t<\/style>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"rotate-slide--container swiper-slide\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div id=\"shift-bilanciamento-del-bianco\" class=\"flex flex-col justify-center\">\n\t\t\t\t\t\t\t<div class=\"img-default__inner\">\n\t\t\t\t\t\t\t\t<div class=\"img-comp-img w-full h-full overflow-hidden relative\">\n\t\t\t\t\t\t\t\t\t\n\t<figure class=\"swiper-slide__inner\">\n\t\t<picture >\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/image-20250520-044710-f065bcd4.png?width=0&#038;height=0&#038;quality=75&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_4\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/image-20250520-044710-f065bcd4.png?width=0&#038;height=0&#038;quality=75&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"w-full h-auto block object-left object-cover\"\t\t\t\t\t\t\t\t\talt=\"Shift Bilanciamento del Bianco - Image 4\"\t\t\t\t\t\t\t\t\twidth=\"\"\t\t\t\t\t\t\t\t\theight=\"\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_4\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"flex flex-col justify-center mt-5 md:mt-8\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"main-title h3\">Shift Bilanciamento del Bianco<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"main-paragraph\">Per il bilanciamento del bianco, scegli Auto, Personalizzato, Temperatura Colore o una serie di opzioni preimpostate. Il bilanciamento del bianco pu\u00f2 essere regolato con precisione nella funzione WB Shift con le coordinate di colore rosso (R) e blu (B).\r\n<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\n<button class=\"swiper-button-prev arrow-black\" type=\"button\">\n\t<span class=\"hidden sm:flex\">\n\t\t\t\t<svg class=\"svg-slick-left-arrow-svg \"\n\t\t width=\"24\" height=\"22\"\t\talt=\"Svg Slick Left Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-left-arrow-svg\"\n\t\t\t width=\"24\" height=\"22\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n\t<span class=\"flex sm:hidden\">\n\t\t\t\t<svg class=\"svg-slick-left-arrow-svg \"\n\t\t width=\"20\" height=\"18\"\t\talt=\"Svg Slick Left Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-left-arrow-svg\"\n\t\t\t width=\"20\" height=\"18\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n<\/button>\n<button class=\"swiper-button-next arrow-black\" type=\"button\">\n\t<span class=\"hidden sm:flex\">\n\t\t\t\t<svg class=\"svg-slick-right-arrow-svg \"\n\t\t width=\"24\" height=\"22\"\t\talt=\"Svg Slick Right Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-right-arrow-svg\"\n\t\t\t width=\"24\" height=\"22\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n\t<span class=\"flex sm:hidden\">\n\t\t\t\t<svg class=\"svg-slick-right-arrow-svg \"\n\t\t width=\"20\" height=\"18\"\t\talt=\"Svg Slick Right Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-right-arrow-svg\"\n\t\t\t width=\"20\" height=\"18\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n<\/button>\n\t<\/div>\n\t<\/div>\n\n\n\n<div class=\"wp-block-group alignfull is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group alignfull text-white has-background is-layout-flow wp-block-group-is-layout-flow\" style=\"background-color:#e5e5e5;padding-top:var(--wp--preset--spacing--70);padding-right:0;padding-bottom:var(--wp--preset--spacing--50);padding-left:0\">\n<h2 class=\"wp-block-heading has-text-align-center has-black-color has-text-color has-link-color wp-elements-89fca9eaef702258500a1eacc3fd6865\">Ricette Simulazione Pellicola<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity faded-separator\"\/>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-black-color has-text-color has-link-color wp-elements-328ad85138c2679a57ab517235691582\">Conserva i momenti preziosi con i tuoi colori e il tuo stile.<br>Crea i tuoi look personalizzati, salvali e richiamali all&#8217;istante con una semplice rotazione della manopola.<br>Usa le ricette per creare storie che non dimenticherai mai.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-fujifilm-youtube-modal alignfull product-youtube-mod has-background\" style=\"background-color:#e5e5e5\"><div class=\"block-video-player py-5 md:py-10\"><div class=\"max-w-[800px] m-auto w-full relative fade-up-parallax\"><div class=\"block-video-player__splash-img aspect-w-16 aspect-h-9 js-btn--modal-youtube\" data-id=\"AGN-DdFg0Rg\"><img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_fs-recipe-687b944c.jpeg\" alt=\"xt30iii_fs-recipe-687b944c\" loading=\"lazy\" data-recalc-dims=\"1\"\/><span class=\"play-button\"><\/span><\/div><\/div><div class=\"modal modal--youtube hidden\" data-id=\"AGN-DdFg0Rg\"><div class=\"modal__content relative\"><button class=\"btn-modal-close\" data-id=\"AGN-DdFg0Rg\"><span><\/span><span><\/span><\/button><figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\"><div id=\"player-AGN-DdFg0Rg\" data-id=\"AGN-DdFg0Rg\" class=\"youtube-iframe\"><\/div><\/div><\/figure><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-group group-single-col-content-white fade-up-parallax is-layout-constrained wp-container-core-group-is-layout-b5ae9130 wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center parallax-item\">Facile da usare<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity faded-separator parallax-item\"\/>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-spacing-extra-large has-no-design fade-up-parallax product-image-text-col is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column parallax-item is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_AUTO-Mode-Lever-8414ad6c.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-314155\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_AUTO-Mode-Lever-8414ad6c.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_AUTO-Mode-Lever-8414ad6c.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_AUTO-Mode-Lever-8414ad6c.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_AUTO-Mode-Lever-8414ad6c.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_AUTO-Mode-Lever-8414ad6c.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_AUTO-Mode-Lever-8414ad6c.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_AUTO-Mode-Lever-8414ad6c.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_AUTO-Mode-Lever-8414ad6c.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<div id=\"block_62270d910aa7bdc27f6286fda938d00a\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_62270d910aa7bdc27f6286fda938d00a.wp-block-spacer {\n        height: 16px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_62270d910aa7bdc27f6286fda938d00a.wp-block-spacer {\n            height: 10px;       \n        }\n    }\n<\/style>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\">Leva di Selezione Modalit\u00e0 Auto<\/h3>\n\n\n\n<p>Attivando la Leva di Selezione della Modalit\u00e0 Auto, X-T30 III seleziona automaticamente le migliori impostazioni di esposizione e messa a fuoco per ogni scena.<br>Riconosce il soggetto, lo segue e cattura il momento, occupandosi degli aspetti tecnici in modo che tu possa concentrarti sull&#8217;inquadratura perfetta.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column parallax-item is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_FLASH2-0512e948.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-314156\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_FLASH2-0512e948.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_FLASH2-0512e948.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_FLASH2-0512e948.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_FLASH2-0512e948.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_FLASH2-0512e948.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_FLASH2-0512e948.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_FLASH2-0512e948.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_FLASH2-0512e948.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<div id=\"block_62270d910aa7bdc27f6286fda938d00a\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_62270d910aa7bdc27f6286fda938d00a.wp-block-spacer {\n        height: 16px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_62270d910aa7bdc27f6286fda938d00a.wp-block-spacer {\n            height: 10px;       \n        }\n    }\n<\/style>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\">Flash integrato<\/h3>\n\n\n\n<p>Sapientemente integrato nel design del mirino centrale, il flash incorporato nella X-T30 III seleziona automaticamente la luminosit\u00e0 ottimale, illuminando delicatamente il soggetto anche in condizioni di scarsa illuminazione o in controluce.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-spacing-extra-large has-no-design fade-up-parallax product-image-text-col is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column parallax-item is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Dong-Yuan_Latest-AF-96033234.jpg?width=1024&#038;height=683\" alt=\"\" class=\"wp-image-314157\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Dong-Yuan_Latest-AF-96033234.jpg?width=1024&amp;height=683 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Dong-Yuan_Latest-AF-96033234.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Dong-Yuan_Latest-AF-96033234.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Dong-Yuan_Latest-AF-96033234.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Dong-Yuan_Latest-AF-96033234.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Dong-Yuan_Latest-AF-96033234.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Dong-Yuan_Latest-AF-96033234.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Dong-Yuan_Latest-AF-96033234.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\"><sub>\u00a9Dong Yuan<\/sub><\/figcaption><\/figure>\n\n\n\n<div id=\"block_62270d910aa7bdc27f6286fda938d00a\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_62270d910aa7bdc27f6286fda938d00a.wp-block-spacer {\n        height: 16px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_62270d910aa7bdc27f6286fda938d00a.wp-block-spacer {\n            height: 10px;       \n        }\n    }\n<\/style>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\">Avanzata Tecnologia AF<\/h3>\n\n\n\n<p>Dotata del pi\u00f9 recente algoritmo AF predittivo, X-T30 III segue senza sforzo i soggetti in movimento, anche in scenari a basso contrasto. Ci\u00f2 garantisce una messa a fuoco precisa non solo per i ritratti dinamici, ma anche per una variet\u00e0 di soggetti in rapido movimento, tra cui sport, animali e altro ancora.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column parallax-item is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Subject-Detection_Elke-Vogelsang-96c772bd.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-314158\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Subject-Detection_Elke-Vogelsang-96c772bd.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Subject-Detection_Elke-Vogelsang-96c772bd.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Subject-Detection_Elke-Vogelsang-96c772bd.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Subject-Detection_Elke-Vogelsang-96c772bd.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Subject-Detection_Elke-Vogelsang-96c772bd.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Subject-Detection_Elke-Vogelsang-96c772bd.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Subject-Detection_Elke-Vogelsang-96c772bd.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_Subject-Detection_Elke-Vogelsang-96c772bd.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\"><sub>\u00a9Elke Vogelsang<\/sub><\/figcaption><\/figure>\n\n\n\n<div id=\"block_62270d910aa7bdc27f6286fda938d00a\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_62270d910aa7bdc27f6286fda938d00a.wp-block-spacer {\n        height: 16px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_62270d910aa7bdc27f6286fda938d00a.wp-block-spacer {\n            height: 10px;       \n        }\n    }\n<\/style>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\">Autofocus a Rilevamento del Soggetto<\/h3>\n\n\n\n<p>X-T30 III utilizza l&#8217;AF con rilevamento del soggetto di X-Processor 5 per tracciare con precisione una vasta gamma di soggetti. Sviluppato utilizzando la tecnologia AI deep-learning, rileva animali, uccelli, auto, moto, biciclette, aerei, treni, insetti e droni.*<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-3cb5b2130c0789daf7780237a7df207c\"><sub>*Impostare l&#8217;IMPOSTAZIONE RILEVAMENTO SOGGETTO su UCCELLO per il rilevamento di insetti e su AEREO per il rilevamento di droni.<\/sub><\/p>\n<\/div>\n<\/div>\n\n\n\n<div id=\"block_b2fd54d69cb326cdcbaef8787d9432c6\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_b2fd54d69cb326cdcbaef8787d9432c6.wp-block-spacer {\n        height: 54px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_b2fd54d69cb326cdcbaef8787d9432c6.wp-block-spacer {\n            height: 40px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group alignfull fade-up-parallax has-background is-layout-constrained wp-container-core-group-is-layout-2768c2ff wp-block-group-is-layout-constrained\" style=\"background-color:#4b798f\">\n<div class=\"wp-block-group alignfull fade-up-parallax has-background is-layout-flow wp-block-group-is-layout-flow\" style=\"background-color:#4b798f;padding-top:0;padding-bottom:0\">\n<div id=\"block_d3cc8677cdbca53e435d69191d931e30\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_d3cc8677cdbca53e435d69191d931e30.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_d3cc8677cdbca53e435d69191d931e30.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-1d6f4e6b wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center has-white-color has-text-color has-link-color wp-elements-82424e35b7771f23b61fe66ace7b48c8\">Funzionoalit\u00e0 Video<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity faded-separator\"\/>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div id=\"block_e4954b1d78d9cc078ba279c3227bb8c9\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_e4954b1d78d9cc078ba279c3227bb8c9.wp-block-spacer {\n        height: 50px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_e4954b1d78d9cc078ba279c3227bb8c9.wp-block-spacer {\n            height: 30px;       \n        }\n    }\n<\/style>\n\n\n\t<div id=\"block_6fad6deea00d3b372baaff154997ab21\"\n\t\tclass=\"wp-block wp-block-slider wp-block-slider--swiper swiper alignfull\"\n\t\tdata-fixed-height=\"true\">\n\t\t<div class=\"swiper-wrapper\" data-settings='{\"autoplaySpeed\":\"5000\",\"speed\":500,\"slidesPerView\":1.1,\"spaceBetween\":20,\"navigation\":{\"nextEl\":\".swiper-button-next\",\"prevEl\":\".swiper-button-prev\"},\"scrollbar\":{\"el\":\".swiper-scrollbar\"},\"grabCursor\":true,\"breakpoints\":{\"640\":{\"slidesPerView\":2,\"spaceBetween\":32},\"1024\":{\"slidesPerView\":3,\"spaceBetween\":32}}}'>\n\t\t\t\t\t\t\t<div class=\"swiper-slide \">\n\t\t\t\t\t<div class=\"swiper-slide__inner text-white\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(max-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_6.2K-opengate-dd570afe-scaled.jpg?width=576&#038;height=432&#038;quality=80&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 641px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_6.2K-opengate-dd570afe-scaled.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/X-T30-III_6.2K-opengate-dd570afe-scaled.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\" class=\"h-auto max-h-[432px] object-cover\" width=\"576\" height=\"432\" alt=\"Image\">\n\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"h3 font-fjalla-one leading-snug font-normal block\">Comprehensive Video Features<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>X-T30 III supports internal 6.2K\/30p 4:2:2 10-bit recording. It also offers high-frame-rate video recording at 4K\/60p and 1080\/240p for outstanding slow-motion footage.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide \">\n\t\t\t\t\t<div class=\"swiper-slide__inner text-white\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(max-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/9_16_short_xt30iii-1-0eb136ff.jpg?width=576&#038;height=432&#038;quality=80&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 641px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/9_16_short_xt30iii-1-0eb136ff.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/9_16_short_xt30iii-1-0eb136ff.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\" class=\"h-auto max-h-[432px] object-cover\" width=\"576\" height=\"432\" alt=\"Image\">\n\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"h3 font-fjalla-one leading-snug font-normal block\">9:16 Short Movie Mode<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>X-T30 III also introduces a 9:16 Short Movie mode suited for short clips, optimized for platforms like YouTube or social media. Choose from durations of 15, 30, or 60 seconds while monitoring the remaining time directly on the screen during recording.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide \">\n\t\t\t\t\t<div class=\"swiper-slide__inner text-white\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(max-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Portrait-Enhancer-f9b6f0f9.jpg?width=576&#038;height=432&#038;quality=80&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 641px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Portrait-Enhancer-f9b6f0f9.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Portrait-Enhancer-f9b6f0f9.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\" class=\"h-auto max-h-[432px] object-cover\" width=\"576\" height=\"432\" alt=\"Image\">\n\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"h3 font-fjalla-one leading-snug font-normal block\">Portrait Enhancer<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Brightens and smoothens skin across three levels to deliver perfect portrait images.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide \">\n\t\t\t\t\t<div class=\"swiper-slide__inner text-white\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(max-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Subject-Tracking-30697e37.jpg?width=576&#038;height=432&#038;quality=80&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 641px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Subject-Tracking-30697e37.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_Subject-Tracking-30697e37.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\" class=\"h-auto max-h-[432px] object-cover\" width=\"576\" height=\"432\" alt=\"Image\">\n\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"h3 font-fjalla-one leading-snug font-normal block\">Subject Tracking<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>When using AF-C + Wide\/Tracking AF, select a subject to follow on the touchscreen, giving you accurate tracking even in scenes with multiple moving subjects.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide \">\n\t\t\t\t\t<div class=\"swiper-slide__inner text-white\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(max-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_DIS_-f59ab6f0.jpg?width=576&#038;height=432&#038;quality=80&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 641px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_DIS_-f59ab6f0.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_DIS_-f59ab6f0.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\" class=\"h-auto max-h-[432px] object-cover\" width=\"576\" height=\"432\" alt=\"Image\">\n\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"h3 font-fjalla-one leading-snug font-normal block\">Digital Image Stabilization<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>X-T30 III features digital image stabilization to manage camera shake during video recording, effectively reducing vibrations to deliver smooth, professional footage.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-navigation-wrapper\">\n\t\t\t\t<div class=\"swiper-navigation-wrapper__inner arrow-black\">\n\t\t\t\t\t\n<button class=\"swiper-button-prev \" type=\"button\">\n\t<span class=\"hidden sm:flex\">\n\t\t\t\t<svg class=\"svg-slick-left-arrow-svg \"\n\t\t width=\"24\" height=\"22\"\t\talt=\"Svg Slick Left Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-left-arrow-svg\"\n\t\t\t width=\"24\" height=\"22\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n\t<span class=\"flex sm:hidden\">\n\t\t\t\t<svg class=\"svg-slick-left-arrow-svg \"\n\t\t width=\"20\" height=\"18\"\t\talt=\"Svg Slick Left Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-left-arrow-svg\"\n\t\t\t width=\"20\" height=\"18\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n<\/button>\n<button class=\"swiper-button-next \" type=\"button\">\n\t<span class=\"hidden sm:flex\">\n\t\t\t\t<svg class=\"svg-slick-right-arrow-svg \"\n\t\t width=\"24\" height=\"22\"\t\talt=\"Svg Slick Right Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-right-arrow-svg\"\n\t\t\t width=\"24\" height=\"22\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n\t<span class=\"flex sm:hidden\">\n\t\t\t\t<svg class=\"svg-slick-right-arrow-svg \"\n\t\t width=\"20\" height=\"18\"\t\talt=\"Svg Slick Right Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-right-arrow-svg\"\n\t\t\t width=\"20\" height=\"18\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n<\/button>\n\t\t\t\t\t<div class=\"swiper-scrollbar scr-black\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\n<div id=\"block_d3cc8677cdbca53e435d69191d931e30\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_d3cc8677cdbca53e435d69191d931e30.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_d3cc8677cdbca53e435d69191d931e30.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull fade-up-parallax has-white-background-color has-background is-layout-flow wp-block-group-is-layout-flow\" style=\"padding-top:0;padding-bottom:0\">\n<div id=\"block_a8e788005d7ff6921519b80ea93a548c\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_a8e788005d7ff6921519b80ea93a548c.wp-block-spacer {\n        height: 70px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_a8e788005d7ff6921519b80ea93a548c.wp-block-spacer {\n            height: 50px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-1d6f4e6b wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center has-black-color has-text-color has-link-color wp-elements-898e33f2a3eb99c21505b6ac69e19e0f\">Smart Extras<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity faded-separator\"\/>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div id=\"block_a8e788005d7ff6921519b80ea93a548c\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_a8e788005d7ff6921519b80ea93a548c.wp-block-spacer {\n        height: 70px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_a8e788005d7ff6921519b80ea93a548c.wp-block-spacer {\n            height: 50px;       \n        }\n    }\n<\/style>\n\n\n\t<div id=\"block_7e2ead284b0088a8ea27b09ff09890a1\"\n\t\tclass=\"wp-block wp-block-slider wp-block-slider--swiper swiper alignfull\"\n\t\tdata-fixed-height=\"true\">\n\t\t<div class=\"swiper-wrapper\" data-settings='{\"autoplaySpeed\":\"5000\",\"speed\":500,\"slidesPerView\":1.1,\"spaceBetween\":20,\"navigation\":{\"nextEl\":\".swiper-button-next\",\"prevEl\":\".swiper-button-prev\"},\"scrollbar\":{\"el\":\".swiper-scrollbar\"},\"grabCursor\":true,\"breakpoints\":{\"640\":{\"slidesPerView\":2,\"spaceBetween\":32},\"1024\":{\"slidesPerView\":3,\"spaceBetween\":32}}}'>\n\t\t\t\t\t\t\t<div class=\"swiper-slide \">\n\t\t\t\t\t<div class=\"swiper-slide__inner text-black\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(max-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/XC13-33-Jonas-Rask-aec59cac.jpg?width=576&#038;height=432&#038;quality=80&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 641px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/XC13-33-Jonas-Rask-aec59cac.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/XC13-33-Jonas-Rask-aec59cac.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\" class=\"h-auto max-h-[432px] object-cover\" width=\"576\" height=\"432\" alt=\"Image\">\n\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"h3 font-fjalla-one leading-snug font-normal block\">XC13-33mmF3.5-6.3 OIS<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Abbinata all&#8217;obiettivo FUJINON XC13-33mmF3.5-6.3 OIS, lo zoom pi\u00f9 piccolo e leggero di Fujifilm, X-T30 III offre versatilit\u00e0 creativa, coprendo lunghezze focali dal grandangolo al normale.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/www.fujifilm-x.com\/it-it\/products\/lenses\/xc13-33mmf35-63-ois\/\" target=\"_blank\" class=\"text-xs sm:text-sm bold underline mt-3 block text-green\">Learn More<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide \">\n\t\t\t\t\t<div class=\"swiper-slide__inner text-black\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(max-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xapp-da38b712.jpg?width=576&#038;height=432&#038;quality=80&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 641px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xapp-da38b712.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xapp-da38b712.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\" class=\"h-auto max-h-[432px] object-cover\" width=\"576\" height=\"432\" alt=\"Image\">\n\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"h3 font-fjalla-one leading-snug font-normal block\">XApp<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>X-T30 III \u00e8 compatibile con l&#8217;app FUJIFILM XApp, che offre funzionalit\u00e0 avanzate e un facile trasferimento delle immagini. Permette di condividere rapidamente i file tra fotocamera e smartphone, oltre che a permettere di controllare la fotocamera da remoto.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/www.fujifilm-x.com\/it-it\/products\/software\/xapp\/\" target=\"_blank\" class=\"text-xs sm:text-sm bold underline mt-3 block text-green\">Learn More<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide \">\n\t\t\t\t\t<div class=\"swiper-slide__inner text-black\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(max-width: 640px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Instax-Print-Ryan-Tuttle-f31dccce.jpg?width=576&#038;height=432&#038;quality=80&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<source\n\t\t\t\t\t\t\t\t\t\tmedia=\"(min-width: 641px)\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Instax-Print-Ryan-Tuttle-f31dccce.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\"\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/Instax-Print-Ryan-Tuttle-f31dccce.jpg?width=576&#038;height=432&#038;quality=85&#038;sharpen=1\" class=\"h-auto max-h-[432px] object-cover\" width=\"576\" height=\"432\" alt=\"Image\">\n\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"h3 font-fjalla-one leading-snug font-normal block\">Stampa diretta con la serie instax\u2122 Link<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>X-T30 III supporta la stampa wireless diretta con stampanti selezionate della serie instax\u2122 Link*. I nuovi formati supportati per instax\u2122 mini, instax\u2122 SQUARE e instax\u2122 WIDE consentono agli utenti di passare agevolmente dalla creazione alla stampa e alla condivisione.<\/p>\n<p class=\"p1\"><sub><i>*Stampanti compatibili: instax mini Link 2\u2122, instax mini Link 3\u2122, instax SQUARE Link\u2122, instax Link WIDE\u2122.<\/i><\/sub><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/instax.com\/link_print\/en\/\" target=\"_blank\" class=\"text-xs sm:text-sm bold underline mt-3 block text-green\" rel=\"nofollow noopener\">Learn More<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-navigation-wrapper\">\n\t\t\t\t<div class=\"swiper-navigation-wrapper__inner arrow-white\">\n\t\t\t\t\t\n<button class=\"swiper-button-prev \" type=\"button\">\n\t<span class=\"hidden sm:flex\">\n\t\t\t\t<svg class=\"svg-slick-left-arrow-svg \"\n\t\t width=\"24\" height=\"22\"\t\talt=\"Svg Slick Left Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-left-arrow-svg\"\n\t\t\t width=\"24\" height=\"22\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n\t<span class=\"flex sm:hidden\">\n\t\t\t\t<svg class=\"svg-slick-left-arrow-svg \"\n\t\t width=\"20\" height=\"18\"\t\talt=\"Svg Slick Left Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-left-arrow-svg\"\n\t\t\t width=\"20\" height=\"18\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n<\/button>\n<button class=\"swiper-button-next \" type=\"button\">\n\t<span class=\"hidden sm:flex\">\n\t\t\t\t<svg class=\"svg-slick-right-arrow-svg \"\n\t\t width=\"24\" height=\"22\"\t\talt=\"Svg Slick Right Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-right-arrow-svg\"\n\t\t\t width=\"24\" height=\"22\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n\t<span class=\"flex sm:hidden\">\n\t\t\t\t<svg class=\"svg-slick-right-arrow-svg \"\n\t\t width=\"20\" height=\"18\"\t\talt=\"Svg Slick Right Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-right-arrow-svg\"\n\t\t\t width=\"20\" height=\"18\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n<\/button>\n\t\t\t\t\t<div class=\"swiper-scrollbar scr-green\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\n\n<div id=\"block_b2fd54d69cb326cdcbaef8787d9432c6\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_b2fd54d69cb326cdcbaef8787d9432c6.wp-block-spacer {\n        height: 54px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_b2fd54d69cb326cdcbaef8787d9432c6.wp-block-spacer {\n            height: 40px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group group-single-col-content-white is-layout-constrained wp-container-core-group-is-layout-2768c2ff wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-table has-none-or-default parallax-item alignnone\"><table class=\"has-green-color has-text-color has-link-color has-fixed-layout alignnone\"><tbody><tr><td><strong>Model<\/strong><\/td><td>FUJIFILM X-T30 III<\/td><\/tr><tr><td><strong>Declaration of conformity<\/strong><\/td><td><a href=\"https:\/\/dl.fujifilm-x.com\/doc\/x-t30-iii_doc-ssm.pdf\" data-type=\"link\" data-id=\"https:\/\/dl.fujifilm-x.com\/doc\/x-t30-iii_doc-ssm.pdf\">View PDF<\/a><\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n","protected":false},"author":269,"featured_media":314168,"parent":0,"menu_order":1975,"template":"","category":[1006,3211,320,1986,13936],"products_category":[11636],"class_list":["post-315195","camera","type-camera","status-publish","has-post-thumbnail","hentry","category-cameras","category-x-series-mirrorless","category-products","category-x-series","category-x-t30-iii","products_category-overview"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":[],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera\/315195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera"}],"about":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/types\/camera"}],"author":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/users\/269"}],"version-history":[{"count":0,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera\/315195\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media\/314168"}],"wp:attachment":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media?parent=315195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/category?post=315195"},{"taxonomy":"products_category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/products_category?post=315195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":314256,"date":"2025-10-23T05:00:00","date_gmt":"2025-10-23T05:00:00","guid":{"rendered":"https:\/\/www.fujifilm-x.com\/?post_type=camera&#038;p=314256"},"modified":"2025-10-23T05:09:01","modified_gmt":"2025-10-23T05:09:01","slug":"accessories","status":"publish","type":"camera","link":"https:\/\/www.fujifilm-x.com\/it-it\/products\/cameras\/x-t30-iii\/accessories\/","title":{"rendered":"Accessories \/ Software"},"content":{"rendered":"\n<div style=\"height:80px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center is-style-small-separator\">Accessories \/ Software<\/h1>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<!-- fragment (initial DATA ONLY  output) (language_code=unset, group=legacy_shortcodes_prod_accessories, key=prod_accessories_nav_314105, ttl=0s, full_key=:frag_cache:http:unset:legacy_shortcodes_prod_accessories:d2e117886483e1a87430cc5ad0fc8b59) --><!-- fragment (initial output) (language_code=it-it, group=legacy_shortcodes, key=prod_accessories_nav_314105, ttl=0s, full_key=:frag_cache:http:it-it:legacy_shortcodes:d2e117886483e1a87430cc5ad0fc8b59) --><style>\n\t.product-accessories-wrapper:not(.wp-block-sub-navigation) {\n\t\tmargin: auto;\n\t\tmax-width: 1600px;\n\t\tpadding-left: 1.25rem;\n\t\tpadding-right: 1.25rem;\n\t\twidth: 100%;\n\t}\n\n\tproduct-accessories-wrapper:not(.wp-block-sub-navigation) {\n\t\tmax-width: 820px;\n\t}\n\n\t@media (min-width: 768px) {\n\t\t.product-accessories-wrapper:not(.wp-block-sub-navigation) {\n\t\t\tpadding-left: 2rem;\n\t\t\tpadding-right: 2rem;\n\t\t}\n\t}\n\n\t.product-accessories-wrapper .headline.wp-block-heading.has-text-align-center {\n\t\tfont-family: Fjalla One, Oswald, Helvetica, sans-serif ;\n\t\tfont-size: 1.625rem ;\n\t\tfont-weight: 400 ;\n\t\tline-height: 2rem ;\n\t\tline-height: 1.25 ;\n\t\tmargin-bottom: 2rem ;\n\t\tscroll-margin-top: 7rem;\n\t}\n\n\t.product-accessories-wrapper .headline--title::after {\n\t\tbackground-color: currentColor;\n\t\tcontent: '';\n\t\tdisplay: block ;\n\t\theight: .125rem ;\n\t\tmargin: .75rem auto auto ;\n\t\twidth: 1.5rem;\n\t}\n\n\t@media (min-width: 640px) {\n\t\t.product-accessories-wrapper .headline.wp-block-heading.has-text-align-center {\n\t\t\tfont-size: 1.875rem ;\n\t\t\tline-height: 2.25rem;\n\t\t}\n\t}\n\n\t@media (min-width: 768px) {\n\t\t.product-accessories-wrapper .headline.wp-block-heading.has-text-align-center {\n\t\t\tfont-size: 3rem ;\n\t\t\tline-height: 1.15;\n\t\t}\n\t}\n\n\t.product-accessories-wrapper .wp-block-spacer {\n\t\tdisplay: block;\n\t\theight: 100px;\n\t}\n\n\t.product-accessories-wrapper .products__series {\n\t\tmargin-bottom: 70px;\n\t}\n\n\t@media (min-width: 1280px) {\n\t\t.product-accessories-wrapper .products__series--software .products__series_list li a {\n\t\t\tmin-height: 48px;\n\t\t}\n\t}\n\n\t.product-accessories-wrapper .products__series_list {\n\t\tdisplay: grid;\n\t\tgap: 20px;\n\t\tgrid-template-columns: repeat(2, minmax(0, 1fr));\n\t}\n\n\t@media (min-width: 768px) {\n\t\t.product-accessories-wrapper .products__series_list {\n\t\t\tgrid-template-columns: repeat(3, minmax(0, 1fr));\n\t\t}\n\t}\n\n\t@media (min-width: 1200px) {\n\t\t.product-accessories-wrapper .products__series_list {\n\t\t\tgap: 25px;\n\t\t\tgrid-template-columns: repeat(4, minmax(0, 1fr));\n\t\t}\n\t}\n\n\t.product-accessories-wrapper .products__series_list li>a {\n\t\t--tw-text-opacity: 1;\n\t\tcolor: rgb(0 0 0\/var(--tw-text-opacity));\n\t\tdisplay: block;\n\t\tfont-family: Noto Sans JP, Noto Sans, Helvetica, sans-serif;\n\t\tfont-size: .75rem;\n\t\tfont-weight: 700;\n\t\tline-height: 1rem;\n\t\tmargin-top: 10px;\n\t\ttext-decoration-line: none;\n\t}\n\n\t.product-accessories-wrapper .products__series_list li>a:hover {\n\t\tcolor: currentColor;\n\t\ttext-decoration-line: underline;\n\t}\n\n\t@media (min-width: 768px) {\n\t\t.product-accessories-wrapper .products__series_list li>a {\n\t\t\tfont-size: 1rem;\n\t\t\tline-height: 1.5rem;\n\t\t}\n\t}\n\n\t@media (min-width: 1280px) {\n\t\t.product-accessories-wrapper .products__series_list li>a {\n\t\t\tfont-size: 1.125rem;\n\t\t\tline-height: 1.5rem;\n\t\t}\n\t}\n\n\t.product-accessories-wrapper .products__series_list li img {\n\t\ttransition-duration: .2s;\n\t\ttransition-property: all;\n\t\ttransition-timing-function: cubic-bezier(.4, 0, .2, 1);\n\t\ttransition-timing-function: linear;\n\t}\n\n\t.product-accessories-wrapper .products__series_list li:hover>a {\n\t\ttext-decoration-line: underline;\n\t}\n\n\t.product-accessories-wrapper .products__series_list li:hover img {\n\t\t--tw-shadow: 0px 0px 20px rgba(0, 0, 0, .1);\n\t\t--tw-shadow-colored: 0px 0px 20px var(--tw-shadow-color);\n\t\tbox-shadow: var(--tw-ring-offset-shadow, 0 0 #0000), var(--tw-ring-shadow, 0 0 #0000), var(--tw-shadow);\n\t}\n\n\t.product-accessories-wrapper .products__series_list li .products__series_list_btn {\n\t\tdisplay: block;\n\t\tmargin-top: .625rem;\n\t}\n\n\t.product-accessories-wrapper .products__series_list li .products__series_list_btn a {\n\t\tbackground-color: rgb(20 165 143);\n\t\tcolor: rgb(255 255 255);\n\t\tdisplay: block;\n\t\tflex-grow: 1;\n\t\tfont-family: Fjalla One, Oswald, Helvetica, sans-serif;\n\t\tfont-size: .875rem;\n\t\tfont-weight: 400;\n\t\tline-height: 1.375rem;\n\t\tmargin-top: .625rem;\n\t\tpadding: .75rem;\n\t\ttext-align: center;\n\t\ttext-decoration-line: none;\n\t}\n\n\t.product-accessories-wrapper .products__series_list li .products__series_list_btn .wp_btn {\n\t\tdisplay: block;\n\t}\n\n\t.product-accessories-wrapper h2.headline {\n    \ttext-align: center;\n\t}\n\n\t.product-accessories-wrapper .headline,\n\t.product-accessories-wrapper  headline--minor {\n\t\tmargin-bottom: calc(1rem + 30px) ;\n\t}\n\n\t.product-accessories-wrapper  headline--minor {\n\t\tpadding-bottom: .5em;\n\t\tposition: relative;\n\t}\n\n\t.product-accessories-wrapper .headline--minor::before {\n\t\tbackground: #bfbfbf;\n\t\tbottom: -1px;\n\t\tcontent: \"\";\n\t\theight: 1px;\n\t\tleft: 0;\n\t\tposition: absolute;\n\t\twidth: 100%;\n\t}\n\n\t.product-accessories-wrapper .headline,\n\t.product-accessories-wrapper .headline--minor {\n\t\tmargin-bottom: calc(1rem + 30px) ;\n\t}\n\n\t.product-accessories-wrapper .headline--minor::after {\n\t\tbackground: #1b1b1b;\n\t\tbottom: -1px;\n\t\tcontent: \"\";\n\t\theight: 1px;\n\t\tleft: 0;\n\t\tposition: absolute;\n\t\twidth: 30%;\n\t}\n\n\t.product-accessories-wrapper .headline--minor {\n\t\tpadding-bottom: 0.5em;\n\t\tposition: relative;\n\t}\n\n\t.product-accessories-wrapper .headline--minor::before {\n\t\tcontent: \"\";\n\t\theight: 1px;\n\t\tbackground: #bfbfbf;\n\t\tposition: absolute;\n\t\tleft: 0;\n\t\twidth: 100%;\n\t\tbottom: -1px;\n\t}\n\n\t.product-accessories-wrapper .headline--minor::after {\n\t\tcontent: \"\";\n\t\theight: 1px;\n\t\tbackground: #1b1b1b;\n\t\tposition: absolute;\n\t\tleft: 0;\n\t\twidth: 30%;\n\t\tbottom: -1px;\n\t}\n\n\t@media screen and (max-width: 767px) {\n\n\t\t.product-accessories-wrapper .headline {\n\t\t\tposition: absolute;\n\t\t}\n\t}\n\t.product-accessories-wrapper .headline {\n\t\tmargin-top: 56px;\n\t}\n\t.product-accessories-wrapper .headline,\n\t.product-accessories-wrapper .headline--minor {\n\t\tmargin-bottom: calc(1rem + 30px);\n\t}\n<\/style>\n\n<section class=\"product-accessories-wrapper\">\n\t<section>\n\t\t\n\t\t\t\t\t\t<section class=\"products__series products__series--body-accessories\">\n\t\t\t\t<div class=\"inner\">\n\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"headline--minor\" id=\"body-accessories\">\n\t\t\t\t\t\t\tBody accessories\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t<ul class=\"products__series_list mt40\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/mic-st1\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2019\/10\/stereo-microphone_thum.jpg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/mic-st1\/\">\n\t\t\t\t\t\t\t\t\tStereo Microphone MIC-ST1\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/rr-100\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2019\/08\/remote-release-rr-100_thum-1.jpg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/rr-100\/\">\n\t\t\t\t\t\t\t\t\tRemote release RR-100\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/bcp-001\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2019\/10\/body-cap-bcp-001_thum.jpg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/bcp-001\/\">\n\t\t\t\t\t\t\t\t\tBody cap BCP-001\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/section>\n\t\t\n\t\t\t\t\t\t<section class=\"products__series products__series--lens-accessories\">\n\t\t\t\t<div class=\"inner\">\n\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"headline--minor\" id=\"lens-accessories\">\n\t\t\t\t\t\t\tLens accessories\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t<ul class=\"products__series_list mt40\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/m-mount-adapter\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2019\/10\/m-mount-adapter_thum.jpg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/m-mount-adapter\/\">\n\t\t\t\t\t\t\t\t\tFUJIFILM M MOUNT ADAPTER\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/mcex-11\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2019\/10\/mcex-11_thum.jpg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/mcex-11\/\">\n\t\t\t\t\t\t\t\t\tMacro extension tube MCEX-11\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/mcex-16\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2019\/10\/mcex-16_thum.jpg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/mcex-16\/\">\n\t\t\t\t\t\t\t\t\tMacro extension tube MCEX-16\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/section>\n\t\t\n\t\t\t\t\t\t<section class=\"products__series products__series--flash\">\n\t\t\t\t<div class=\"inner\">\n\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"headline--minor\" id=\"flash\">\n\t\t\t\t\t\t\tFlash\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t<ul class=\"products__series_list mt40\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/ef-x500\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2019\/10\/shoe-mount-flash-ef-x500_thum.jpg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/ef-x500\/\">\n\t\t\t\t\t\t\t\t\tShoe mount flash EF-X500\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/ef-x20\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2022\/05\/shoe-mount-flash-ef-x20.webp?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/ef-x20\/\">\n\t\t\t\t\t\t\t\t\tShoe mount flash EF-X20\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/ef-60\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2020\/07\/shoe-mount-flash-ef-60_thum.jpg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/ef-60\/\">\n\t\t\t\t\t\t\t\t\tFlash a slitta EF-60\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"products__series_list_btn\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wp_btn\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/eshop.fujifilm-x.com\/it\/fujifilm-flash-gun-ef-60.html\" target=\"self\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tAcquista ora\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wp_btn\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/shop\/\" target=\"self\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tTrova Rivenditore\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/ef-42\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2019\/10\/shoe-mount-flash-ef-42_thum.jpg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/ef-42\/\">\n\t\t\t\t\t\t\t\t\tShoe mount flash EF-42\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/ef-20\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2019\/10\/shoe-mount-flash-ef-20_thum.jpg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/ef-20\/\">\n\t\t\t\t\t\t\t\t\tShoe mount flash EF-20\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/ef-w1\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2020\/07\/wireless-commander_ef-w1_thum.jpg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/ef-w1\/\">\n\t\t\t\t\t\t\t\t\tWireless Commander EF-W1\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"products__series_list_btn\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wp_btn\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/eshop.fujifilm-x.com\/it\/fujifilm-wireless-commander-ef-w1.html\" target=\"self\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tAcquista ora\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wp_btn\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/shop\/\" target=\"self\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tTrova Rivenditore\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/section>\n\t\t\n\t\t\t\t\t\t<section class=\"products__series products__series--camera-cases\">\n\t\t\t\t<div class=\"inner\">\n\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"headline--minor\" id=\"camera-cases\">\n\t\t\t\t\t\t\tCamera cases\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t<ul class=\"products__series_list mt40\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/blc-xt10\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2019\/10\/leather-case-blc-xt10_thum.jpg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/blc-xt10\/\">\n\t\t\t\t\t\t\t\t\tLeather case BLC-XT10\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/section>\n\t\t\n\t\t\t\t\t\t<section class=\"products__series products__series--grip\">\n\t\t\t\t<div class=\"inner\">\n\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"headline--minor\" id=\"grip\">\n\t\t\t\t\t\t\tGrip\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t<ul class=\"products__series_list mt40\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/mhg-xt10\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2019\/10\/hand-grip-mhg-xt10_thum.jpg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/mhg-xt10\/\">\n\t\t\t\t\t\t\t\t\tHand grip MHG-XT10\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/tg-bt1\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2022\/11\/product-thum-tg-bt1.jpg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/tg-bt1\/\">\n\t\t\t\t\t\t\t\t\tTripod Grip TG-BT1\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/gb-001\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2019\/10\/grip-belt-gb-001_thum.jpg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/gb-001\/\">\n\t\t\t\t\t\t\t\t\tGrip belt GB-001\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/section>\n\t\t\n\t\t\t\t\t\t<section class=\"products__series products__series--power-supply\">\n\t\t\t\t<div class=\"inner\">\n\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"headline--minor\" id=\"power-supply\">\n\t\t\t\t\t\t\tPower supply\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t<ul class=\"products__series_list mt40\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/np-w126s\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2019\/10\/np-w126s_thum.jpg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/np-w126s\/\">\n\t\t\t\t\t\t\t\t\tLi-ion battery NP-W126S\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/bc-w126s\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2019\/08\/BC-W126S-Thumbnail.jpg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/bc-w126s\/\">\n\t\t\t\t\t\t\t\t\tBattery charger BC-W126S\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/section>\n\t\t\n\t\t\t\t\t\t\t<h2 class=\"headline\" id=\"software\">\n\t\t\t\t\tSoftware\t\t\t\t<\/h2>\n\t\t\t\t\t\t<section class=\"products__series products__series--software\">\n\t\t\t\t<div class=\"inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t<ul class=\"products__series_list mt40\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/software\/xapp\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2023\/05\/product-list-software-xapp.jpg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/software\/xapp\/\">\n\t\t\t\t\t\t\t\t\tFUJIFILM XApp\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/software\/capture-one\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2018\/02\/captureone-thumb-new-1.jpg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/software\/capture-one\/\">\n\t\t\t\t\t\t\t\t\tCapture One\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"products__series_list_btn\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wp_btn\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.captureone.com\/a\/explore-features\/fujifilm?utm_source=www.fujifilm-x.com&#038;utm_medium=referral&#038;utm_campaign=all_global_fujifilm_static_na&#038;utm_content=na&#038;_li=51e608ac4a7ad06642619e96918444a2\" target=\"self\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tDownload\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/software\/tether-app\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2024\/06\/FUJIFILM-TETHER-APP.jpeg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/software\/tether-app\/\">\n\t\t\t\t\t\t\t\t\tFUJIFILM TETHER APP\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/software\/raw-file-converter-ex-powered-by-silkypix\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2019\/02\/product-list-software-rfc.jpg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/software\/raw-file-converter-ex-powered-by-silkypix\/\">\n\t\t\t\t\t\t\t\t\tRAW FILE CONVERTER EX powered by SILKYPIX\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"products__series_list_btn\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wp_btn\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/support\/download\/software\/raw-file-converter-ex-powered-by-silkypix\/\"\n\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"self\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tDownload\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/software\/x-raw-studio\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2018\/02\/product-list-software-raw-studio-big.jpg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/software\/x-raw-studio\/\">\n\t\t\t\t\t\t\t\t\tFUJIFILM X RAW STUDIO\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"products__series_list_btn\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wp_btn\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/support\/download\/software\/x-raw-studio\/\"\n\t\t\t\t\t\t\t\t\t\t\t\t\ttarget=\"self\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tDownload\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/section>\n\t\t\t<\/section>\n<\/section>\n\n<!-- \/fragment (initial output) (language_code=it-it, group=legacy_shortcodes, key=prod_accessories_nav_314105, ttl=0s, full_key=:frag_cache:http:it-it:legacy_shortcodes:d2e117886483e1a87430cc5ad0fc8b59) --><!-- fragment (initial DATA ONLY  output) (language_code=unset, group=legacy_shortcodes_prod_accessories, key=prod_accessories_nav_314105, ttl=0s, full_key=:frag_cache:http:unset:legacy_shortcodes_prod_accessories:d2e117886483e1a87430cc5ad0fc8b59) -->\n","protected":false},"author":13,"featured_media":0,"parent":314105,"menu_order":0,"template":"","category":[],"products_category":[11685],"class_list":["post-314256","camera","type-camera","status-publish","hentry","products_category-accessories"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":[],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera\/314256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera"}],"about":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/types\/camera"}],"author":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/users\/13"}],"version-history":[{"count":0,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera\/314256\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera\/314105"}],"wp:attachment":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media?parent=314256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/category?post=314256"},{"taxonomy":"products_category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/products_category?post=314256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":314233,"date":"2025-10-23T05:00:00","date_gmt":"2025-10-23T05:00:00","guid":{"rendered":"https:\/\/www.fujifilm-x.com\/?post_type=camera&#038;p=314233"},"modified":"2025-10-23T05:08:15","modified_gmt":"2025-10-23T05:08:15","slug":"specifications","status":"publish","type":"camera","link":"https:\/\/www.fujifilm-x.com\/it-it\/products\/cameras\/x-t30-iii\/specifications\/","title":{"rendered":"Specifications"},"content":{"rendered":"<div class=\"camera-specifications\">\n\t\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Model Name<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">FUJIFILM X-T30 III<\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Lens Mount<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">FUJIFILM X mount<\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Image Sensor<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">23.5mm x 15.6mm (APS-C) X-Trans CMOS 4 with primary color filter<\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Number Of Effective Pixels<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">26.1 millions pixels<\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Sensor Cleaning System<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">Ultra Sonic Vibration<\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Image Processing Engine<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">X-Processor 5<\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-repeater-grid\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Storage Media<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\"><div>SD Card (-2GB)<\/div><div>SDHC Card (-32GB)<\/div><div>SDXC Card (-2TB)<\/div><div>UHS-I<\/div><div>*Please see the Fujifilm website (https:\/\/fujifilm-x.com\/support\/compatibility\/cameras\/) to check memory card compatibility.<\/div><\/div>\n\t<\/div><div class=\"camera-specifications__block specs-two-level file-format-of-still-image\">\n\t<h6>File Format Of Still Image<\/h6>\n\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">DCF<\/div><div class=\"col-span-6\">Compliant with Design rule for Camera File system (DCF2.0)<\/div><div class=\"col-span-2\">JPEG<\/div><div class=\"col-span-6\">Exif Ver.2.32<\/div><div class=\"col-span-2\">HEIF<\/div><div class=\"col-span-6\">4:2:2 10bit<\/div><div class=\"col-span-2\">RAW<\/div><div class=\"col-span-6\">14bit RAW (RAF original format)<\/div><div class=\"col-span-2\">TIFF<\/div><div class=\"col-span-6\">8bit \/ 16bit RGB (In-camera Raw Conversion Only)<\/div><div class=\"col-span-2\">Notes<\/div><div class=\"col-span-6\">*Exif 2.32 is a digital camera file format that contains a variety of shooting information for optimal printing<\/div>\n\t<\/div>\n<\/div>\t<div class=\"camera-specifications__block specs-three-level number-of-recorded-pixels\">\n\t\t<h6>Number Of Recorded Pixels<\/h6>\n\t\t<div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">[L]<\/div>\n\t<div class=\"col-span-6\"> 3:2: 6240 x 4160\r<br>16:9: 6240 x 3512\r<br>1:1: 4160 x 4160<\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">[M]<\/div>\n\t<div class=\"col-span-6\"> 3:2: 4416 x 2944\r<br>16:9: 4416 x 2488\r<br>1:1: 2944 x 2944<\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">[S]<\/div>\n\t<div class=\"col-span-6\"> 3:2: 3120 x 2080\r<br>16:9: 3120 x 1760\r<br>1:1: 2080 x 2080<\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">[instax]<\/div>\n\t<div class=\"col-span-6\"> instax mini: 1568 x 2080\r<br>instax SQUARE: 2080 x 2080\r<br>instax WIDE: 3120 x 1984<\/div><\/div>\n\t<\/div>\t<div class=\"camera-specifications__block specs-three-level panorama\">\n\t\t<h6>Panorama<\/h6>\n\t\t<div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">[L]<\/div>\n\t<div class=\"col-span-6\"> vertical: 2160 x 9600\r<br>horizontal: 9600 x 1440<\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">[M]<\/div>\n\t<div class=\"col-span-6\"> vertical: 2160 x 6400\r<br>horizontal: 6400 x 1440<\/div><\/div>\n\t<\/div>\t<div class=\"camera-specifications__block specs-three-level sensitivity\">\n\t\t<h6>Sensitivity<\/h6>\n\t\t<div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Still Image<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Standard Output<\/div>\n\t<div class=\"col-span-6\"><div>AUTO1<\/div><div>AUTO2<\/div><div>AUTO3<\/div><div>ISO160~12800 (1\/3 step)<\/div><\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Extended Output<\/div>\n\t<div class=\"col-span-6\"><div>ISO80<\/div><div>ISO100<\/div><div>ISO125<\/div><div>ISO25600<\/div><div>ISO51200<\/div><\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Movie<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Standard Output<\/div>\n\t<div class=\"col-span-6\"><div>AUTO<\/div><div>ISO160~12800 (1\/3 step)<\/div><\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Extended Output<\/div>\n\t<div class=\"col-span-6\"><div>ISO25600<\/div><\/div>\n<\/div><\/div><\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Exposure Control<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">TTL 256-zone metering\r<br>Multi\r<br>Spot\r<br>Average\r<br>Center Weighted<\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Exposure Mode<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">P (Program AE)\r<br>A (Aperture Priority AE)\r<br>S (Shutter Speed Priority AE)\r<br>M (Manual Exposure)<\/div>\n\t<\/div><div class=\"camera-specifications__block specs-two-level exposure-compensation\">\n\t<h6>Exposure Compensation<\/h6>\n\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">Still<\/div><div class=\"col-span-6\">-5.0EV~+5.0EV 1\/3EV step<\/div><div class=\"col-span-2\">Movie<\/div><div class=\"col-span-6\">-2.0EV~+2.0EV 1\/3EV step<\/div>\n\t<\/div>\n<\/div><div class=\"camera-specifications__block specs-two-level image-stabilizer\">\n\t<h6>Image Stabilizer<\/h6>\n\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">Digital Image Stabilization<\/div><div class=\"col-span-6\">Yes (movie mode only)<\/div><div class=\"col-span-2\">IS MODE BOOST<\/div><div class=\"col-span-6\">Yes (movie mode only)<\/div>\n\t<\/div>\n<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Shutter Type<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">Focal Plane Shutter<\/div>\n\t<\/div>\t<div class=\"camera-specifications__block specs-three-level shutter-speed\">\n\t\t<h6>Shutter Speed<\/h6>\n\t\t<div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Mechanical Shutter<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">P Mode<\/div>\n\t<div class=\"col-span-6\">30sec. to 1\/4000sec.<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">A Mode<\/div>\n\t<div class=\"col-span-6\">30sec. to 1\/4000sec.<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">S\/M Mode<\/div>\n\t<div class=\"col-span-6\">15min. to 1\/4000sec.<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Bulb<\/div>\n\t<div class=\"col-span-6\">up to 60min.<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Electronic Shutter<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">P Mode<\/div>\n\t<div class=\"col-span-6\">30sec. to 1\/32000sec.<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">A Mode<\/div>\n\t<div class=\"col-span-6\">30sec. to 1\/32000sec.<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">S\/M Mode<\/div>\n\t<div class=\"col-span-6\">15min. to 1\/32000sec.<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Bulb<\/div>\n\t<div class=\"col-span-6\">1sec. Fixed<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Electronic Front Curtain Shutter<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">P Mode<\/div>\n\t<div class=\"col-span-6\">30sec. to 1\/4000sec.<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">A Mode<\/div>\n\t<div class=\"col-span-6\">30sec. to 1\/4000sec.<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">S\/M Mode<\/div>\n\t<div class=\"col-span-6\">15min. to 1\/4000sec.<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Bulb<\/div>\n\t<div class=\"col-span-6\">up to 60min.<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Mechanical + Electronic Shutter<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">P Mode<\/div>\n\t<div class=\"col-span-6\">30sec. to 1\/32000sec.<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">A Mode<\/div>\n\t<div class=\"col-span-6\">30sec. to 1\/32000sec.<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">S\/M Mode<\/div>\n\t<div class=\"col-span-6\">15min. to 1\/32000sec.<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Bulb<\/div>\n\t<div class=\"col-span-6\">up to 60min.<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Notes<\/div>\n\t<div class=\"col-span-6\">*Mechanical shutter works until 1\/4000sec.<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">E-front + Mechanical Shutter<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">P Mode<\/div>\n\t<div class=\"col-span-6\">30sec. to 1\/4000sec.<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">A Mode<\/div>\n\t<div class=\"col-span-6\">30sec. to 1\/4000sec.<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">S\/M Mode<\/div>\n\t<div class=\"col-span-6\">15min. to 1\/4000sec.<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Bulb<\/div>\n\t<div class=\"col-span-6\">up to 60min.<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Notes<\/div>\n\t<div class=\"col-span-6\">*Electronic front curtain shutter works until 1\/2000sec.<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">E-front + Mechanical + Electronic Shutter<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">P Mode<\/div>\n\t<div class=\"col-span-6\">30sec. to 1\/32000sec.<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">A Mode<\/div>\n\t<div class=\"col-span-6\">30sec. to 1\/32000sec.<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">S\/M Mode<\/div>\n\t<div class=\"col-span-6\">15min. to 1\/32000sec.<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Bulb<\/div>\n\t<div class=\"col-span-6\">up to 60min.<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Notes<\/div>\n\t<div class=\"col-span-6\">*Electronic front curtain shutter works until 1\/2000sec, Mechanical shutter works until 1\/4000sec.\r<br>*The Electronic Shutter may not be suitable for fast-moving objects or handheld shooting. Flash can not be used.<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Movie<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">6.2K<\/div>\n\t<div class=\"col-span-6\">1\/4000sec. to 1\/24 sec.<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">4K\/DCI4K<\/div>\n\t<div class=\"col-span-6\">1\/4000sec. to 1\/24 sec.<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">FHD<\/div>\n\t<div class=\"col-span-6\">1\/4000sec. to 1\/24 sec.<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Notes<\/div>\n\t<div class=\"col-span-6\">*Cannot choose slower shutter speed than framerate.<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Synchronized Shutter Speed For Flash<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Mechanical Shutter<\/div>\n\t<div class=\"col-span-6\">1\/180sec. or slower<\/div>\n<\/div><\/div><\/div>\n\t<\/div>\t<div class=\"specs-continuous-shooting\">\n\t\t<h6>Continuous Shooting<\/h6>\n\t\t<div class=\"continuous-shooting-group\"><div class=\"continuous-shooting-heading\"><span>CH<\/strong><\/div>\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<span class=\"continuous-shooting-shutter\">Electronic Shutter<\/span>\n\t\t\tApprox. 30fps (1.25x Crop)\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">\n\t\t\t<div class=\"grid grid-cols-3\">\n\t\t\t\t<div>JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t128frames\n\t<\/div><div>Compressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t78frames\n\t<\/div><div>Lossless Compressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t46frames\n\t<\/div><div>Uncompressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t23frames\n\t<\/div><div>Compressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t32frames\n\t<\/div><div>Lossless Compressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t27frames\n\t<\/div><div>Uncompressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t21frames\n\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<span class=\"continuous-shooting-shutter\">Electronic Shutter<\/span>\n\t\t\tApprox. 20fps (1.25x Crop)\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">\n\t\t\t<div class=\"grid grid-cols-3\">\n\t\t\t\t<div>JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t141frames\n\t<\/div><div>Compressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t81frames\n\t<\/div><div>Lossless Compressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t47frames\n\t<\/div><div>Uncompressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t24frames\n\t<\/div><div>Compressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t46frames\n\t<\/div><div>Lossless Compressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t38frames\n\t<\/div><div>Uncompressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t21frames\n\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<span class=\"continuous-shooting-shutter\">Electronic Shutter<\/span>\n\t\t\tApprox. 10fps (1.25x Crop)\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">\n\t\t\t<div class=\"grid grid-cols-3\">\n\t\t\t\t<div>JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t204frames\n\t<\/div><div>Compressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t113frames\n\t<\/div><div>Lossless Compressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t57frames\n\t<\/div><div>Uncompressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t25frames\n\t<\/div><div>Compressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t66frames\n\t<\/div><div>Lossless Compressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t54frames\n\t<\/div><div>Uncompressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t22frames\n\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<span class=\"continuous-shooting-shutter\">Electronic Shutter<\/span>\n\t\t\tApprox. 20fps\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">\n\t\t\t<div class=\"grid grid-cols-3\">\n\t\t\t\t<div>JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t127frames\n\t<\/div><div>Compressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t60frames\n\t<\/div><div>Lossless Compressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t34frames\n\t<\/div><div>Uncompressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t23frames\n\t<\/div><div>Compressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t34frames\n\t<\/div><div>Lossless Compressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t26frames\n\t<\/div><div>Uncompressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t21frames\n\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<span class=\"continuous-shooting-shutter\">Electronic Shutter<\/span>\n\t\t\tApprox. 10fps\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">\n\t\t\t<div class=\"grid grid-cols-3\">\n\t\t\t\t<div>JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t155frames\n\t<\/div><div>Compressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t79frames\n\t<\/div><div>Lossless Compressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t41frames\n\t<\/div><div>Uncompressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t24frames\n\t<\/div><div>Compressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t48frames\n\t<\/div><div>Lossless Compressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t39frames\n\t<\/div><div>Uncompressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t22frames\n\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<span class=\"continuous-shooting-shutter\">Electronic Shutter<\/span>\n\t\t\tApprox. 8fps\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">\n\t\t\t<div class=\"grid grid-cols-3\">\n\t\t\t\t<div>JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t173frames\n\t<\/div><div>Compressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t82frames\n\t<\/div><div>Lossless Compressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t41frames\n\t<\/div><div>Uncompressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t25frames\n\t<\/div><div>Compressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t52frames\n\t<\/div><div>Lossless Compressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t37frames\n\t<\/div><div>Uncompressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t23frames\n\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<span class=\"continuous-shooting-shutter\">Electronic Shutter<\/span>\n\t\t\tApprox. 8.0fps\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">\n\t\t\t<div class=\"grid grid-cols-3\">\n\t\t\t\t<div>JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t173frames\n\t<\/div><div>Compressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t82frames\n\t<\/div><div>Lossless Compressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t38frames\n\t<\/div><div>Uncompressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t25frames\n\t<\/div><div>Compressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t52frames\n\t<\/div><div>Lossless Compressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t34frames\n\t<\/div><div>Uncompressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t23frames\n\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<span class=\"continuous-shooting-shutter\">Mechanical Shutter<\/span>\n\t\t\tApprox. 8fps\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">\n\t\t\t<div class=\"grid grid-cols-3\">\n\t\t\t\t<div>JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t173frames\n\t<\/div><div>Compressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t82frames\n\t<\/div><div>Lossless Compressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t38frames\n\t<\/div><div>Uncompressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t25frames\n\t<\/div><div>Compressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t52frames\n\t<\/div><div>Lossless Compressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t34frames\n\t<\/div><div>Uncompressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t23frames\n\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div><\/div><div class=\"continuous-shooting-group\"><div class=\"continuous-shooting-heading\"><span>CL<\/strong><\/div>\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<span class=\"continuous-shooting-shutter\">Mechanical Shutter<\/span>\n\t\t\tApprox. 5.0fps\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">\n\t\t\t<div class=\"grid grid-cols-3\">\n\t\t\t\t<div>JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t1000+frames\n\t<\/div><div>Compressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t163frames\n\t<\/div><div>Lossless Compressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t48frames\n\t<\/div><div>Uncompressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t27frames\n\t<\/div><div>Compressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t65frames\n\t<\/div><div>Lossless Compressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t39frames\n\t<\/div><div>Uncompressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t26frames\n\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<span class=\"continuous-shooting-shutter\">Mechanical Shutter<\/span>\n\t\t\tApprox. 4.0fps\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">\n\t\t\t<div class=\"grid grid-cols-3\">\n\t\t\t\t<div>JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t1000+frames\n\t<\/div><div>Compressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t1000+frames\n\t<\/div><div>Lossless Compressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t65frames\n\t<\/div><div>Uncompressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t28frames\n\t<\/div><div>Compressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t90frames\n\t<\/div><div>Lossless Compressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t51frames\n\t<\/div><div>Uncompressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t27frames\n\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<span class=\"continuous-shooting-shutter\">Mechanical Shutter<\/span>\n\t\t\tApprox. 3.0fps\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">\n\t\t\t<div class=\"grid grid-cols-3\">\n\t\t\t\t<div>JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t1000+frames\n\t<\/div><div>Compressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t1000+frames\n\t<\/div><div>Lossless Compressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t152frames\n\t<\/div><div>Uncompressed RAW<\/div>\t<div class=\"col-span-2\">\n\t\t38frames\n\t<\/div><div>Compressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t188frames\n\t<\/div><div>Lossless Compressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t62frames\n\t<\/div><div>Uncompressed RAW + JPEG<\/div>\t<div class=\"col-span-2\">\n\t\t33frames\n\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div><\/div><div class=\"continuous-shooting-group\"><div class=\"continuous-shooting-heading\"><span>Pre-shot<\/strong><\/div>\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<span class=\"continuous-shooting-shutter\">Electronic Shutter, 1.25 X Crop<\/span>\n\t\t\tApprox. 30fps (1.25x Crop)\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">\n\t\t\t<div class=\"grid grid-cols-3\">\n\t\t\t\t\t<div class=\"col-span-2\">\n\t\t30frames\n\t<\/div>\t<div class=\"col-span-2\">\n\t\t75frames\n\t<\/div>\t<div class=\"col-span-2\">\n\t\t105frames\n\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<span class=\"continuous-shooting-shutter\">Electronic Shutter, 1.25 X Crop<\/span>\n\t\t\tApprox. 20fps (1.25x Crop)\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">\n\t\t\t<div class=\"grid grid-cols-3\">\n\t\t\t\t\t<div class=\"col-span-2\">\n\t\t20frames\n\t<\/div>\t<div class=\"col-span-2\">\n\t\t576frames\n\t<\/div>\t<div class=\"col-span-2\">\n\t\t596frames\n\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<span class=\"continuous-shooting-shutter\">Electronic Shutter, 1.25 X Crop<\/span>\n\t\t\tApprox. 10fps (1.25x Crop)\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">\n\t\t\t<div class=\"grid grid-cols-3\">\n\t\t\t\t\t<div class=\"col-span-2\">\n\t\t10frames\n\t<\/div>\t<div class=\"col-span-2\">\n\t\t1000+frames\n\t<\/div>\t<div class=\"col-span-2\">\n\t\t1000+frames\n\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<span class=\"continuous-shooting-shutter\">Electronic Shutter, 1.25 X Crop<\/span>\n\t\t\tApprox. 8fps\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">\n\t\t\t<div class=\"grid grid-cols-3\">\n\t\t\t\t\t<div class=\"col-span-2\">\n\t\t8frames\n\t<\/div>\t<div class=\"col-span-2\">\n\t\t1000+frames\n\t<\/div>\t<div class=\"col-span-2\">\n\t\t1000+frames\n\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<span class=\"continuous-shooting-shutter\">Electronic Shutter<\/span>\n\t\t\tApprox. 20fps\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">\n\t\t\t<div class=\"grid grid-cols-3\">\n\t\t\t\t\t<div class=\"col-span-2\">\n\t\t20frames\n\t<\/div>\t<div class=\"col-span-2\">\n\t\t998frames\n\t<\/div>\t<div class=\"col-span-2\">\n\t\t1018frames\n\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<span class=\"continuous-shooting-shutter\">Electronic Shutter<\/span>\n\t\t\tApprox. 10fps\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">\n\t\t\t<div class=\"grid grid-cols-3\">\n\t\t\t\t\t<div class=\"col-span-2\">\n\t\t10frames\n\t<\/div>\t<div class=\"col-span-2\">\n\t\t1000+frames\n\t<\/div>\t<div class=\"col-span-2\">\n\t\t1000+frames\n\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div><\/div>\n\t\t\t\t<div class=\"grid grid-cols-8\">\n\t\t\t<div class=\"col-span-2\">Notes<\/div>\n\t\t\t<div class=\"col-span-6\">*No. of recordable frames are calculated based on a cold start<br \/>\r\n*Recordable frames depends on recording media<br \/>\r\n*Speed of continuous shooting depends on shooting environment and shooting frames<\/div>\n\t\t<\/div>\n\t<\/div><div class=\"camera-specifications__block specs-two-level drive-mode\">\n\t<h6>Drive Mode<\/h6>\n\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">AE Bracketing<\/div><div class=\"col-span-6\">2 frames\r<br>3 frames\r<br>5 frames\r<br>7 frames\r<br>9 frames\r<br>*by 1\/3EV step, up to \u00b13EV steps<\/div><div class=\"col-span-2\">Filmsimulation Bracketing<\/div><div class=\"col-span-6\">Any 3 types of film simulation selectable<\/div><div class=\"col-span-2\">Dynamic Range Bracketing<\/div><div class=\"col-span-6\">100%\r<br>200%\r<br>400%<\/div><div class=\"col-span-2\">ISO Sensitivity Bracketing<\/div><div class=\"col-span-6\">\u00b11\/3EV\r<br>\u00b12\/3EV\r<br>\u00b11EV<\/div><div class=\"col-span-2\">White Balance Bracketing<\/div><div class=\"col-span-6\">\u00b11\r<br>\u00b12\r<br>\u00b13<\/div><div class=\"col-span-2\">Focus Bracketing<\/div><div class=\"col-span-6\">AUTO\r<br>MANUAL<\/div><div class=\"col-span-2\">Multiple Exposure<\/div><div class=\"col-span-6\">Yes (Max. 9 frames)\r<br>Additive\r<br>Average\r<br>Bright\r<br>Dark<\/div><div class=\"col-span-2\">HDR Mode<\/div><div class=\"col-span-6\">AUTO\r<br>200%\r<br>400%\r<br>800%\r<br>800% +<\/div><div class=\"col-span-2\">Advanced Filter<\/div><div class=\"col-span-6\">Toy camera\r<br>Miniature\r<br>Pop color\r<br>High-key\r<br>Low-key\r<br>Dynamic tone\r<br>Soft focus\r<br>Partial color (Red \/ Orange \/ Yellow \/ Green \/ Blue \/ Purple)<\/div>\n\t<\/div>\n<\/div>\t<div class=\"camera-specifications__block specs-three-level focus\">\n\t\t<h6>Focus<\/h6>\n\t\t<div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Mode<\/div>\n\t<div class=\"col-span-6\"> Single AF\r<br>Continuous AF\r<br>MF<\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Type<\/div>\n\t<div class=\"col-span-6\"> Intelligent Hybrid AF (TTL contrast AF \/ TTL phase detection AF)<\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Low-light Performance<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Contrast<\/div>\n\t<div class=\"col-span-6\">-4.0EV\r<br>XF50mmF1.0 attached<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Phase Detection<\/div>\n\t<div class=\"col-span-6\">-7.0EV\r<br>XF50mmF1.0 attached<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">AF Frame Selection<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Single Point AF<\/div>\n\t<div class=\"col-span-6\">13&#215;9 \/ 25&#215;17 (Changeable size of AF frame)<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Zone AF<\/div>\n\t<div class=\"col-span-6\">3&#215;3 \/ 5&#215;5 \/ 7&#215;7 \/ Custom1-3 from 117 areas on 13\u00d79 grid<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Wide\/Tracking AF<\/div>\n\t<div class=\"col-span-6\">Yes (AF-S: Wide \/ AF-C: Tracking)<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">All<\/div>\n\t<div class=\"col-span-6\">Yes<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Face\/eye Detection<\/div>\n\t<div class=\"col-span-6\"> Yes<\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Subject Detection<\/div>\n\t<div class=\"col-span-6\"> Yes (Animal\/Bird\/Automobile\/Motorcycle&amp;Bike\/Airplane\/Train)<\/div><\/div>\n\t<\/div>\t<div class=\"camera-specifications__block specs-three-level flash\">\n\t\t<h6>Flash<\/h6>\n\t\t<div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Built-in Flash<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Built-in Flash<\/div>\n\t<div class=\"col-span-6\">Manual pop-up flash (Super Intelligent Flash)<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Guide Number<\/div>\n\t<div class=\"col-span-6\">approx. 7 (ISO200\u30fbm) \/ approx. 5 (ISO100\u30fbm)<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Sync. Mode<\/div>\n\t<div class=\"col-span-6\"><div>1st Curtain<\/div><div>2nd Curtain<\/div><\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Flash Mode<\/div>\n\t<div class=\"col-span-6\"><div>TTL (TTL AUTO \/ STANDARD \/ SLOW SYNC. )<\/div><div>MANUAL<\/div><div>COMMANDER<\/div><div>OFF<\/div><\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Shoe Mount Flash<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Sync. Mode<\/div>\n\t<div class=\"col-span-6\"><div>1st Curtain<\/div><div>2nd Curtain<\/div><div>AUTO FP (HSS)<\/div><\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Flash Mode<\/div>\n\t<div class=\"col-span-6\"><div>TTL (TTL AUTO \/ STANDARD \/ SLOW SYNC. )<\/div><div>MANUAL<\/div><div>MULTI *When EF-X500 is set<\/div><div>OFF<\/div><\/div>\n<\/div><\/div><\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Hot Shoe<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">Yes (Dedicated TTL Flash compatible)<\/div>\n\t<\/div>\t<div class=\"camera-specifications__block specs-three-level viewfinder\">\n\t\t<h6>Viewfinder<\/h6>\n\t\t<div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">EVF<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">EVF<\/div>\n\t<div class=\"col-span-6\">0.39 inch OLED Color Viewfinder\r<br>Approx. 2.36 million dots<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Coverage Of Viewing Area Vs. Capturing Area<\/div>\n\t<div class=\"col-span-6\">Approx. 100%<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Eyepoint<\/div>\n\t<div class=\"col-span-6\">Approx. 17.5mm (from the Rear End of the Camera&#8217;s Eyepiece)<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Diopter Adjustment<\/div>\n\t<div class=\"col-span-6\">-4~+2m-1<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Magnification<\/div>\n\t<div class=\"col-span-6\">0.62x with 50mm Lens (35mm Equivalent) at infinity and Diopter set to -1.0m-1<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Diagonal Angle Of View<\/div>\n\t<div class=\"col-span-6\"><div>approx. 31\u00b0 (Horizontal angle of view: approx. 26\u00b0 )<\/div><div>Built-In Eye Sensor<\/div><\/div>\n<\/div><\/div><\/div>\n\t<\/div>\t<div class=\"camera-specifications__block specs-three-level lcd-monitor\">\n\t\t<h6>LCD Monitor<\/h6>\n\t\t<div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">LCD Monitor<\/div>\n\t<div class=\"col-span-6\"> 3.0 inch Tilt-Type Touch Screen Color LCD Monitor<\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Aspect Ratio<\/div>\n\t<div class=\"col-span-6\"> 3:2<\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Dots<\/div>\n\t<div class=\"col-span-6\"> Approx. 1.62 million dots<\/div><\/div>\n\t<\/div><div class=\"camera-specifications__block specs-two-level touch-screen-mode\">\n\t<h6>Touch Screen Mode<\/h6>\n\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">Shooting Mode<\/div><div class=\"col-span-6\"><div>Shooting<\/div><div>AF<\/div><div>Focus Area<\/div><div>OFF<\/div><div>Double Tap Setting (ON\/OFF)<\/div><div>Touch Function Setting (ON\/OFF)<\/div><div>Touch Zoom (ON\/OFF)<\/div><div>EVF Touch Screen Area Setting<\/div><\/div><div class=\"col-span-2\">Playback Mode<\/div><div class=\"col-span-6\"><div>Swipe<\/div><div>Pinch-in \/ Pinch-out<\/div><div>Double-tap<\/div><div>Drag<\/div><\/div>\n\t<\/div>\n<\/div>\t<div class=\"camera-specifications__block specs-three-level movie-recording\">\n\t\t<h6>Movie Recording<\/h6>\n\t\t<div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">File Format<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">MOV<\/div>\n\t<div class=\"col-span-6\"><div>HEVC\/H.265, Linear PCM (Stereo sound 24bit \/ 48KHz sampling)<\/div><div>MPEG-4 AVC\/H.264, Linear PCM (Stereo sound 24bit \/ 48KHz sampling)<\/div><\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">MP4<\/div>\n\t<div class=\"col-span-6\">MPEG-4 AVC\/H.264, AAC<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Movie Compression<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\"><\/div>\n\t<div class=\"col-span-6\"><div>Long GOP<\/div><\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">6.2K(3:2)<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">File Size<\/div>\n\t<div class=\"col-span-6\">6240 x 4160<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Frame Rate<\/div>\n\t<div class=\"col-span-6\">29.97p\r<br>25p\r<br>24p\r<br>23.98p<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Bitrate<\/div>\n\t<div class=\"col-span-6\">200Mbps\r<br>100Mbps\r<br>50Mbps\r<br>25Mbps\r<br>8Mbps<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">DCI4K(17:9)<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">File Size<\/div>\n\t<div class=\"col-span-6\">4096 x 2160<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Frame Rate<\/div>\n\t<div class=\"col-span-6\">59.94p\r<br>50p\r<br>29.97p\r<br>25p\r<br>24p\r<br>23.98p<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Bitrate<\/div>\n\t<div class=\"col-span-6\">200Mbps\r<br>100Mbps\r<br>50Mbps\r<br>25Mbps\r<br>8Mbps<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">4K(16:9)<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">File Size<\/div>\n\t<div class=\"col-span-6\">3840 x 2160<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Frame Rate<\/div>\n\t<div class=\"col-span-6\">59.94p\r<br>50p\r<br>29.97p\r<br>25p\r<br>24p\r<br>23.98p<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Bitrate<\/div>\n\t<div class=\"col-span-6\">200Mbps\r<br>100Mbps\r<br>50Mbps\r<br>25Mbps\r<br>8Mbps<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Full HD(17:9)<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">File Size<\/div>\n\t<div class=\"col-span-6\">2048 x 1080<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Frame Rate<\/div>\n\t<div class=\"col-span-6\">59.94p\r<br>50p\r<br>29.97p\r<br>25p\r<br>24p\r<br>23.98p<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Bitrate<\/div>\n\t<div class=\"col-span-6\">200Mbps\r<br>100Mbps\r<br>50Mbps\r<br>25Mbps\r<br>8Mbps<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Full HD(16:9)<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">File Size<\/div>\n\t<div class=\"col-span-6\">1920 x 1080<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Frame Rate<\/div>\n\t<div class=\"col-span-6\">59.94p\r<br>50p\r<br>29.97p\r<br>25p\r<br>24p\r<br>23.98p<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Bitrate<\/div>\n\t<div class=\"col-span-6\">200Mbps\r<br>100Mbps\r<br>50Mbps\r<br>25Mbps\r<br>8Mbps<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Full HD(9:16)<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">File Size<\/div>\n\t<div class=\"col-span-6\">1080 x 1920<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Frame Rate<\/div>\n\t<div class=\"col-span-6\">29.97p\r<br>25p\r<br>24p\r<br>23.98p<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Bitrate<\/div>\n\t<div class=\"col-span-6\">200Mbps\r<br>100Mbps\r<br>50Mbps\r<br>25Mbps\r<br>8Mbps<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Full HD(17:9) High Speed Rec.<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">File Size<\/div>\n\t<div class=\"col-span-6\">2048 x 1080<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Frame Rate<\/div>\n\t<div class=\"col-span-6\">240p\r<br>200p\r<br>120p\r<br>100p<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Bitrate<\/div>\n\t<div class=\"col-span-6\">200Mbps (recording)<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Full HD(16:9) High Speed Rec.<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">File Size<\/div>\n\t<div class=\"col-span-6\">1920 x 1080<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Frame Rate<\/div>\n\t<div class=\"col-span-6\">240p\r<br>200p\r<br>120p\r<br>100p<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Bitrate<\/div>\n\t<div class=\"col-span-6\">200Mbps (recording)<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Notes<\/div>\n\t<div class=\"col-span-6\"> *For recording movies, use a SD memory card with UHS Speed Class 3 or higher.\r<br>*Selectable bitrate will be changed depends on the setting.\r<br>*Recording time can become short depending on the temperature and\/or shooting conditions<\/div><\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>AUTO Mode Setting<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">AUTO\r<br>Portrait\r<br>Portrait Enhancer\r<br>Landscape\r<br>Sport\r<br>Night\r<br>Night (Tripod)\r<br>Fireworks\r<br>Sunset\r<br>Snow\r<br>Beach\r<br>Underwater\r<br>Party\r<br>Flower\r<br>Text<\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-repeater-grid\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Film Simulation Mode<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\"><div>20 modes<\/div><div>PROVIA\/Standard<\/div><div>Velvia\/Vivid<\/div><div>ASTIA\/Soft<\/div><div>Classic Chrome<\/div><div>REALA ACE<\/div><div>PRO Neg.Hi<\/div><div>PRO Neg.Std<\/div><div>Classic Neg.<\/div><div>Nostalgic Neg.<\/div><div>ETERNA\/Cinema<\/div><div>ETERNA BLEACH BYPASS<\/div><div>ACROS<\/div><div>ACROS + Ye Filter<\/div><div>ACROS + R Filter<\/div><div>ACROS + G Filter<\/div><div>Black &amp; White<\/div><div>Black &amp; White + Ye Filter<\/div><div>Black &amp; White + R Filter<\/div><div>Black &amp; White + G Filter<\/div><div>Sepia<\/div><\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Monochromatic Color<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">Yes<\/div>\n\t<\/div><div class=\"camera-specifications__block specs-two-level grain-effect\">\n\t<h6>Grain Effect<\/h6>\n\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">Roughness<\/div><div class=\"col-span-6\">STRONG, WEAK, OFF<\/div><div class=\"col-span-2\">Size<\/div><div class=\"col-span-6\">LARGE, SMALL<\/div>\n\t<\/div>\n<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Color Chrome Effect<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">STRONG, WEAK, OFF<\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Color Chrome Blue<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">STRONG, WEAK, OFF<\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Portrait Enhancer Lv<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">STRONG, MEDIUM, WEAK, OFF<\/div>\n\t<\/div>\t<div class=\"camera-specifications__block specs-three-level dynamic-range-setting\">\n\t\t<h6>Dynamic Range Setting<\/h6>\n\t\t<div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Still<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Still<\/div>\n\t<div class=\"col-span-6\">AUTO \/ 100\uff05 \/ 200\uff05 \/ 400\uff05\u3000<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">ISO Restriction<\/div>\n\t<div class=\"col-span-6\">DR100%: No limit\u3001DR200%: ISO320 or more\u3001DR400%: ISO640 or more<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Movie<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Movie<\/div>\n\t<div class=\"col-span-6\">100\uff05 \/ 200\uff05 \/ 400\uff05\u3000<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">ISO Restriction<\/div>\n\t<div class=\"col-span-6\">DR100%: No limit\u3001DR200%: ISO320 or more\u3001DR400%: ISO640 or more<\/div>\n<\/div><\/div><\/div>\n\t<\/div>\t<div class=\"camera-specifications__block specs-three-level white-balance\">\n\t\t<h6>White Balance<\/h6>\n\t\t<div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Auto<\/div>\n\t<div class=\"col-span-6\"> White Priority\r<br>Auto\r<br>Ambience Priority<\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Custom<\/div>\n\t<div class=\"col-span-6\"> Custom1 &#8211; 3<\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Color Temperature Selection<\/div>\n\t<div class=\"col-span-6\"> 2500K~10000K<\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Preset<\/div>\n\t<div class=\"col-span-6\"> Daylight\r<br>Shade\r<br>Fluorescent Light-1\r<br>Fluorescent Light-2\r<br>Fluorescent Light-3\r<br>Incandescent Light\r<br>Underwater<\/div><\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Clarity Setting<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">\u00b15 steps<\/div>\n\t<\/div><div class=\"camera-specifications__block specs-two-level self-timer\">\n\t<h6>Self-timer<\/h6>\n\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">Still<\/div><div class=\"col-span-6\">10sec.\r<br>2sec.<\/div><div class=\"col-span-2\">Movie<\/div><div class=\"col-span-6\">10sec.\r<br>5sec.\r<br>3sec.<\/div>\n\t<\/div>\n<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Interval Timer Shooting<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">Yes (Setting : Interval, Number of shots, Starting time, Interval timer shooting exposure smoothing, Interval priority mode)<\/div>\n\t<\/div><div class=\"camera-specifications__block specs-two-level wireless-transmitter\">\n\t<h6>Wireless Transmitter<\/h6>\n\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">Standard<\/div><div class=\"col-span-6\">IEEE802.11b\/g\/n (standard wireless protocol)<\/div><div class=\"col-span-2\">Encryption<\/div><div class=\"col-span-6\">WPA2, WPA3<\/div><div class=\"col-span-2\">Access Mode<\/div><div class=\"col-span-6\">Infrastructure<\/div>\n\t<\/div>\n<\/div><div class=\"camera-specifications__block specs-two-level bluetooth\">\n\t<h6>Bluetooth\u00ae<\/h6>\n\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">Standartd<\/div><div class=\"col-span-6\">Bluetooth Ver. 5.2 (Bluetooth low energy)<\/div><div class=\"col-span-2\">Operating Frequency (Center Frequency)<\/div><div class=\"col-span-6\">2402\u301c2480MHz<\/div>\n\t<\/div>\n<\/div><div class=\"camera-specifications__block specs-two-level terminal\">\n\t<h6>Terminal<\/h6>\n\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">Digital Interface<\/div><div class=\"col-span-6\">USB Type-C USB 10Gbps<\/div><div class=\"col-span-2\">HDMI Output<\/div><div class=\"col-span-6\">HDMI Micro connector (Type D)<\/div><div class=\"col-span-2\">Others<\/div><div class=\"col-span-6\">\u00f82.5mm, stereo mini connector (Microphone &amp; Remote Release)\r<br>Hot shoe<\/div>\n\t<\/div>\n<\/div>\t<div class=\"camera-specifications__block specs-three-level power-supply\">\n\t\t<h6>Power Supply<\/h6>\n\t\t<div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Power Supply<\/div>\n\t<div class=\"col-span-6\"> NP-W126S Li-ion battery (included)<\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Battery Life For Still Images<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Economy Mode<\/div>\n\t<div class=\"col-span-6\">Approx. 425 frames<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Normal Mode<\/div>\n\t<div class=\"col-span-6\">Approx. 315 frames<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Notes<\/div>\n\t<div class=\"col-span-6\">*When XF35mmF1.4 R is set<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Actual Battery Life Of Movie Capture<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">6.2K<\/div>\n\t<div class=\"col-span-6\">Approx. 45min. (29.97p)<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">4K<\/div>\n\t<div class=\"col-span-6\">Approx. 40min. (59.94p)<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Full HD<\/div>\n\t<div class=\"col-span-6\">Approx. 45min. (59.94p), Approx. 50min. (120P)<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Notes<\/div>\n\t<div class=\"col-span-6\">*Face detection is set to OFF<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Continuance Battery Life Of Movie Capture<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">6.2K<\/div>\n\t<div class=\"col-span-6\">Approx. 65min. (29.97p)<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">4K<\/div>\n\t<div class=\"col-span-6\">Approx. 50min. (59.94p)<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Full HD<\/div>\n\t<div class=\"col-span-6\">Approx. 80min. (59.94p)<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Notes<\/div>\n\t<div class=\"col-span-6\">*Face detection is set to OFF<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Notes<\/div>\n\t<div class=\"col-span-6\"> *Approximate number of frames or movie recording time that can be taken with a fully-charged based on CIPA Standard.<\/div><\/div>\n\t<\/div>\t<div class=\"camera-specifications__block specs-three-level dimensions\">\n\t\t<h6>Dimensions<\/h6>\n\t\t<div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Width<\/div>\n\t<div class=\"col-span-6\"> 118.4mm<\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Height<\/div>\n\t<div class=\"col-span-6\"> 82.8mm<\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Depth<\/div>\n\t<div class=\"col-span-6\"> 46.8mm<\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">(Minimum Depth)<\/div>\n\t<div class=\"col-span-6\"> (31.9mm)<\/div><\/div>\n\t<\/div><div class=\"camera-specifications__block specs-two-level weight\">\n\t<h6>Weight<\/h6>\n\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">Including Battery And Memory Card<\/div><div class=\"col-span-6\">Approx. 378g<\/div><div class=\"col-span-2\">Excluding Battery And Memory Card<\/div><div class=\"col-span-6\">Approx. 329g<\/div>\n\t<\/div>\n<\/div><div class=\"camera-specifications__block specs-two-level operation-environment\">\n\t<h6>Operation Environment<\/h6>\n\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">Operating Temperature<\/div><div class=\"col-span-6\">0\u2103~+40\u2103<\/div><div class=\"col-span-2\">Operating Humidity<\/div><div class=\"col-span-6\">10%~80% (no condensation)<\/div>\n\t<\/div>\n<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Starting up period<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">Approx. 0.8sec.<\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Accessories Included<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">Li-ion battery NP-W126S\r<br>Headphone adapter\r<br>Shoulder strap\r<br>Body cap<\/div>\n\t<\/div><\/div>\n\n\n\n<div id=\"block_2f0749d6abb41ff880d3fc3bbd4d8cc5\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_2f0749d6abb41ff880d3fc3bbd4d8cc5.wp-block-spacer {\n        height: 30px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_2f0749d6abb41ff880d3fc3bbd4d8cc5.wp-block-spacer {\n            height: 0px;       \n        }\n    }\n<\/style>\n\n\n\n<h2 class=\"wp-block-heading\">Media Rec (SD memory card)<\/h2>\n\n\n\n<figure class=\"wp-block-table has-none-or-default alignnone\"><table><thead><tr><th>Resolution\/Aspect<\/th><th>Size<\/th><th>Frame rate<\/th><th>File format\/Compression<\/th><th>Bit rate*1<\/th><th>Bit depth<\/th><th>HDMI output Resolution(Frame rate)\/Sampling\/Bit depth<br> HDMI<\/th><th colspan=\"2\">Crop Magnification<\/th><\/tr><\/thead><tbody><tr><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td>DIS ON<\/td><td>DIS OFF<\/td><\/tr><tr><td><strong>6.2K 3:2<\/strong><\/td><td><strong>6240 x 4160<\/strong><\/td><td>29.97p<br>\n25.00p<br>\n24.00p<br>\n23.98p<\/td><td>H.265 Long GOP 4:2:2 MOV<br>\nH.265 Long GOP 4:2:0 MOV<\/td><td>200Mbps<br>\n100Mbps<br>\n50Mbps<br>\n25Mbps<br>\n8Mbps<\/td><td>10bit<\/td><td>FHD 4:2:2 10bit (H.265 Long GOP 4:2:2 MOV selected)*2*3<br>\n4K 4:2:2 10bit (H.265 Long GOP 4:2:0 MOV selected)*2*3<\/td><td>Not<br>possible<\/td><td>1.0x<\/td><\/tr><tr><td rowspan=\"2\"><strong>DCI4K 17:9<br>4K 16:9<\/strong><\/td><td rowspan=\"2\"><strong>4096 x 2160<br>3840 x 2160<\/strong><\/td><td rowspan=\"2\">59.94p<br>\n50.00p<br>\n29.97p<br>\n25.00p<br>\n24.00p<br>\n23.98p<\/td><td>H.265 Long GOP 4:2:2 MOV<br>H.265 Long GOP 4:2:0 MOV<\/td><td>200Mbps<br>\n100Mbps<br>\n50Mbps<br>\n25Mbps<br>\n8Mbps<\/td><td>10bit<\/td><td>DCI4K\/4K 4:2:2 10bit<\/td><td rowspan=\"2\">59.94p\/50.00p:1.22x<br>29.97p\/25.00p\/24.00p\/<br> 23.98p:1.32x<\/td><td rowspan=\"2\">59.94p\/50.00p:1.18x<br>29.97p\/25.00p\/24.00p\/<br> 23.98p:1.0x<\/td><\/tr><tr><td>H.264 Long GOP 4:2:0 MOV<br>H.264 Long GOP 4:2:0 MP4<\/td><td>200Mbps<br>\n100Mbps<br>\n50Mbps<br>\n25Mbps<br>\n8Mbps<\/td><td>8bit<\/td><td>DCI4K\/4K 4:2:2 8bit<\/td><\/tr><tr><td rowspan=\"2\"><strong>FHD 17:9<br>FHD 16:9<br>FHD 9:16<\/strong><\/td><td rowspan=\"2\"><strong>2048 x 1080<br>1920 x 1080<br>1080 x 1920<\/strong><\/td><td rowspan=\"2\">59.94p<br>50.00p<br>29.97p<br>25.00p<br>24.00p<br>23.98p<\/td><td>H.265 Long GOP 4:2:2 MOV<br>H.265 Long GOP 4:2:0 MOV<\/td><td>200Mbps<br>\n100Mbps<br>\n50Mbps<br>\n25Mbps<br>\n8Mbps<\/td><td>10bit<\/td><td>FHD 4:2:2 10bit*3<\/td><td rowspan=\"2\">1.32x<\/td><td rowspan=\"2\">1.0x<\/td><\/tr><tr><td>H.264 Long GOP 4:2:0 MOV<br>H.264 Long GOP 4:2:0 MP4<\/td><td>200Mbps<br>\n100Mbps<br>\n50Mbps<br>\n25Mbps<br>\n8Mbps<\/td><td>8bit<\/td><td>FHD 4:2:2 8bit*3<\/td><\/tr><tr><td rowspan=\"2\"><strong>High speed<br>FHD 17:9<br>FHD 16:9<\/strong><\/td><td rowspan=\"2\"><strong>2048 x 1080<br>1920 x 1080<\/strong><\/td><td rowspan=\"2\">240fps(4\u00d7\/8\u00d7\/10\u00d7)<br>200fps(4\u00d7\/8\u00d7)<br>120p (2x\/4x\/5x)<br>100p (2x\/4x)<\/td><td>H.265 Long GOP 4:2:2 MOV<br>H.265 Long GOP 4:2:0 MOV<\/td><td>200Mbps (when recording)<\/td><td>10bit<\/td><td>FHD(59.94p) 4:2:2 10bit*4<\/td><td rowspan=\"2\">Not<br>possible<\/td><td rowspan=\"2\">1.29x<\/td><\/tr><tr><td>H.264 Long GOP 4:2:0 MOV<br>H.264 Long GOP 4:2:0 MP4<\/td><td>200Mbps (when recording)<\/td><td>8bit<\/td><td>FHD(59.94p) 4:2:2 8bit*4<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div id=\"block_2f0749d6abb41ff880d3fc3bbd4d8cc5\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_2f0749d6abb41ff880d3fc3bbd4d8cc5.wp-block-spacer {\n        height: 30px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_2f0749d6abb41ff880d3fc3bbd4d8cc5.wp-block-spacer {\n            height: 0px;       \n        }\n    }\n<\/style>\n\n\n\n<h2 class=\"wp-block-heading\">HDMI Output<\/h2>\n\n\n\n<figure class=\"wp-block-table has-none-or-default alignnone\"><table><thead><tr><th>Resolution\/Aspect<\/th><th>Size<\/th><th>Frame rate<\/th><th>HDMI output Resolution\/Sampling\/Bit depth<\/th><th colspan=\"2\">Crop Magnification<\/th><\/tr><\/thead><tbody><tr><td><\/td><td><\/td><td><\/td><td><\/td><td>DIS ON<\/td><td>DIS OFF<\/td><\/tr><tr><td><strong>6.2K 3:2<\/strong><\/td><td><strong>6240 x 4160<\/strong><\/td><td>29.97p<br>25.00p<br>24.00p<br>23.98p<\/td><td>FHD 4:2:2 10bit*2*3<\/td><td>Not<br>\npossible<\/td><td>1.0x<\/td><\/tr><tr><td><strong>DCI4K 17:9<br>4K 16:9<\/strong><\/td><td><strong>4096 x 2160<br>3840 x 2160<\/strong><\/td><td>59.94p<br>50.00p<br>29.97p<br>25.00p<br>24.00p<br>23.98p<\/td><td>DCI4K\/4K 4:2:2 10bit<\/td><td>59.94p\/50.00p:1.22x<br>\n29.97p\/25.00p\/24.00p\/<br>\n23.98p:1.32x<\/td><td>59.94p\/50.00p:1.18x<br>\n29.97p\/25.00p\/24.00p\/<br>\n23.98p:1.0x<\/td><\/tr><tr><td><strong>FHD 17:9<br>FHD 16:9<\/strong><\/td><td><strong>2048 x 1080<br>1920 x 1080<\/strong><\/td><td>59.94p<br>50.00p<br>29.97p<br>25.00p<br>24.00p<br>23.98p<\/td><td>FHD 4:2:2 10bit<\/td><td>1.32x<\/td><td>1.0x<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div id=\"block_2f0749d6abb41ff880d3fc3bbd4d8cc5\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_2f0749d6abb41ff880d3fc3bbd4d8cc5.wp-block-spacer {\n        height: 30px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_2f0749d6abb41ff880d3fc3bbd4d8cc5.wp-block-spacer {\n            height: 0px;       \n        }\n    }\n<\/style>\n\n\n\n<h2 class=\"wp-block-heading\">HDMI Output (High speed REC HDMI ONLY\uff09<\/h2>\n\n\n\n<figure class=\"wp-block-table has-none-or-default alignnone\"><table><thead><tr><th>Resolution\/Aspect<\/th><th>Size<\/th><th>Frame rate<\/th><th>HDMI output Resolution(Frame rate)\/Sampling\/Bit depth<\/th><th colspan=\"2\">Crop Magnification<\/th><\/tr><\/thead><tbody><tr><td><\/td><td><\/td><td><\/td><td><\/td><td>DIS ON<\/td><td>DIS OFF<\/td><\/tr><tr><td><strong>FHD 16:9<\/strong><\/td><td><strong>1920 x 1080<\/strong><\/td><td>120p<br>100p<\/td><td>FHD(120p\/100p) 4:2:2 10bit<\/td><td>Not<br>possible<\/td><td>1.29x<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div id=\"block_2f0749d6abb41ff880d3fc3bbd4d8cc5\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_2f0749d6abb41ff880d3fc3bbd4d8cc5.wp-block-spacer {\n        height: 30px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_2f0749d6abb41ff880d3fc3bbd4d8cc5.wp-block-spacer {\n            height: 0px;       \n        }\n    }\n<\/style>\n\n\n\n<h2 class=\"wp-block-heading\">HDMI RAW Output<\/h2>\n\n\n\n<figure class=\"wp-block-table has-none-or-default alignnone\"><table><thead><tr><th>Resolution\/Aspect<\/th><th>Size<\/th><th>Frame rate<\/th><th>Bit depth<\/th><th colspan=\"2\">Crop Magnification<\/th><\/tr><\/thead><tbody><tr><td><\/td><td><\/td><td><\/td><td><\/td><td>DIS ON<\/td><td>DIS OFF<\/td><\/tr><tr><td><strong>6.2K 3:2<\/strong><\/td><td><strong>6240 x 4160<\/strong><\/td><td>29.97p<br>25.00p<br>24.00p<br>23.98p<\/td><td>12bit<\/td><td>Not<br>possible<\/td><td>1.0x<\/td><\/tr><tr><td><strong>5.2K 16:9<\/strong><\/td><td><strong>5232 x 2944<\/strong><\/td><td>59.94p<br>50.00p<br>29.97p<br>25.00p<br>24.00p<br>23.98p<\/td><td>12bit<\/td><td>Not<br>possible<\/td><td>1.19x<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div id=\"block_8a3130a6be41ef326b7c5f9dc195cee7\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_8a3130a6be41ef326b7c5f9dc195cee7.wp-block-spacer {\n        height: 70px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_8a3130a6be41ef326b7c5f9dc195cee7.wp-block-spacer {\n            height: 0px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group has-light-gray-background-color has-background is-layout-flow wp-block-group-is-layout-flow\" style=\"padding-top:var(--wp--preset--spacing--20);padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0\">\n<ul class=\"wp-block-list\">\n<li>*1 Bit rate will be changed depend on the subject<\/li>\n\n\n\n<li>*2 The resolution from HDMI output is different from selected setting<\/li>\n\n\n\n<li>*3 When the aspect ratio is not 16:9, the image is output in 16:9 with a black band<\/li>\n\n\n\n<li>*4 The frame rate from HDMI output is different from selected setting<\/li>\n<\/ul>\n<\/div>\n","protected":false},"author":13,"featured_media":0,"parent":314105,"menu_order":0,"template":"","category":[],"products_category":[11538],"class_list":["post-314233","camera","type-camera","status-publish","hentry","products_category-specifications"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":[],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera\/314233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera"}],"about":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/types\/camera"}],"author":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/users\/13"}],"version-history":[{"count":0,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera\/314233\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera\/314105"}],"wp:attachment":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media?parent=314233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/category?post=314233"},{"taxonomy":"products_category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/products_category?post=314233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":314215,"date":"2025-10-23T05:00:00","date_gmt":"2025-10-23T05:00:00","guid":{"rendered":"https:\/\/www.fujifilm-x.com\/?post_type=camera&#038;p=314215"},"modified":"2025-10-23T05:10:12","modified_gmt":"2025-10-23T05:10:12","slug":"gallery","status":"publish","type":"camera","link":"https:\/\/www.fujifilm-x.com\/it-it\/products\/cameras\/x-t30-iii\/gallery\/","title":{"rendered":"Gallery"},"content":{"rendered":"\n<div style=\"height:80px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center is-style-small-separator\">Gallery<\/h1>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-2a7b38d8 wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns has-spacing-extra-large has-no-design  product-image-text-col is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div id=\"block_260120e2ca1d93d56d96eb396c0c0ade\" class=\"wp-block block-gallery-modal flex flex-col align-center\">\n    <div class=\"w-full aspect-3\/2 bg-gray-400 flex flex-col align-items items-center mb-4 relative\">\n        <img  width=\"683\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Keiko-Watanabe-2a0706c4-scaled.jpg?width=683&amp;height=1024\" class=\"w-full h-full object-contain aspect-3\/2\" alt=\"\" loading=\"eager\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Keiko-Watanabe-2a0706c4-scaled.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Keiko-Watanabe-2a0706c4-scaled.jpg?width=683&amp;height=1024 683w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Keiko-Watanabe-2a0706c4-scaled.jpg?width=365&amp;height=548 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Keiko-Watanabe-2a0706c4-scaled.jpg?width=600&amp;height=900 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Keiko-Watanabe-2a0706c4-scaled.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Keiko-Watanabe-2a0706c4-scaled.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/>        <div class=\"attachment-caption w-full text-xs text-center text-white absolute bottom-4 left-0 z-[5]\">\n            \u00a9Keiko Watanabe        <\/div>\n    <\/div>\n    <button data-target=\"modalblock_260120e2ca1d93d56d96eb396c0c0ade\" class=\"openBtn border border-black mx-auto font-fjalla-one py-2 px-6\">\n         View larger image    <\/button>\n    <div id=\"modalblock_260120e2ca1d93d56d96eb396c0c0ade\" class=\"lightbox hidden fixed z-50 left-0 top-0 w-full h-full overflow-hidden\">\n        <span class=\"close\">&times;<\/span>\n        <img decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Keiko-Watanabe-2a0706c4-scaled.jpg?width=683&amp;height=1024\" class=\"lightbox-content object-contain m-auto\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Keiko-Watanabe-2a0706c4-scaled.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Keiko-Watanabe-2a0706c4-scaled.jpg?width=683&amp;height=1024 683w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Keiko-Watanabe-2a0706c4-scaled.jpg?width=365&amp;height=548 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Keiko-Watanabe-2a0706c4-scaled.jpg?width=600&amp;height=900 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Keiko-Watanabe-2a0706c4-scaled.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Keiko-Watanabe-2a0706c4-scaled.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/>        <div class=\"zoom-in\">+<\/div>\n        <div class=\"zoom-out\">&#8211;<\/div>\n        <div class=\"fullscreen\">[ ]<\/div>\n    <\/div>\n<\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-table has-none-or-default alignnone\"><table><tbody><tr><td><strong>Shooting Mode<\/strong><br><strong>Image Size<br>Sensitivity<br>Aperture<br>Shutter Speed<br><strong>White Balance<\/strong><\/strong><br><strong>Lens<\/strong><\/td><td>Aperture-Priority<br>2000 x 3000<br>ISO640<br>F16<br>1\/500<br>AUTO<br>XC13-33mmF3.5-6.3 OIS<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div id=\"block_0468f7dc8e9530ba1b173e8f92106dee\" class=\"wp-block block-gallery-modal flex flex-col align-center\">\n    <div class=\"w-full aspect-3\/2 bg-gray-400 flex flex-col align-items items-center mb-4 relative\">\n        <img decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Elisa-Waves-404c1600-scaled.jpg?width=683&amp;height=1024\" class=\"w-full h-full object-contain aspect-3\/2\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Elisa-Waves-404c1600-scaled.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Elisa-Waves-404c1600-scaled.jpg?width=683&amp;height=1024 683w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Elisa-Waves-404c1600-scaled.jpg?width=365&amp;height=548 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Elisa-Waves-404c1600-scaled.jpg?width=600&amp;height=900 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Elisa-Waves-404c1600-scaled.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Elisa-Waves-404c1600-scaled.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/>        <div class=\"attachment-caption w-full text-xs text-center text-white absolute bottom-4 left-0 z-[5]\">\n            \u00a9Elisa Waves        <\/div>\n    <\/div>\n    <button data-target=\"modalblock_0468f7dc8e9530ba1b173e8f92106dee\" class=\"openBtn border border-black mx-auto font-fjalla-one py-2 px-6\">\n         View larger image    <\/button>\n    <div id=\"modalblock_0468f7dc8e9530ba1b173e8f92106dee\" class=\"lightbox hidden fixed z-50 left-0 top-0 w-full h-full overflow-hidden\">\n        <span class=\"close\">&times;<\/span>\n        <img decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Elisa-Waves-404c1600-scaled.jpg?width=683&amp;height=1024\" class=\"lightbox-content object-contain m-auto\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Elisa-Waves-404c1600-scaled.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Elisa-Waves-404c1600-scaled.jpg?width=683&amp;height=1024 683w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Elisa-Waves-404c1600-scaled.jpg?width=365&amp;height=548 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Elisa-Waves-404c1600-scaled.jpg?width=600&amp;height=900 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Elisa-Waves-404c1600-scaled.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Elisa-Waves-404c1600-scaled.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/>        <div class=\"zoom-in\">+<\/div>\n        <div class=\"zoom-out\">&#8211;<\/div>\n        <div class=\"fullscreen\">[ ]<\/div>\n    <\/div>\n<\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-table has-none-or-default alignnone\"><table><tbody><tr><td><strong>Shooting Mode<\/strong><br><strong>Image Size<br>Sensitivity<br>Aperture<br>Shutter Speed<br><strong>White Balance<\/strong><\/strong><br><strong>Lens<\/strong><\/td><td>Manual<br>2000 x 3000<br>ISO8000<br>F4<br>1\/320<br>Manual<br>XF16-55mmF2.8 R LM WR II<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-spacing-extra-large has-no-design  product-image-text-col is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div id=\"block_2182e8b9717f0839107844f57428c65e\" class=\"wp-block block-gallery-modal flex flex-col align-center\">\n    <div class=\"w-full aspect-3\/2 bg-gray-400 flex flex-col align-items items-center mb-4 relative\">\n        <img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jo-Howell-88b51034-scaled.jpg?width=1024&amp;height=683\" class=\"w-full h-full object-contain aspect-3\/2\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jo-Howell-88b51034-scaled.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jo-Howell-88b51034-scaled.jpg?width=1024&amp;height=683 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jo-Howell-88b51034-scaled.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jo-Howell-88b51034-scaled.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jo-Howell-88b51034-scaled.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jo-Howell-88b51034-scaled.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jo-Howell-88b51034-scaled.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jo-Howell-88b51034-scaled.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>        <div class=\"attachment-caption w-full text-xs text-center text-white absolute bottom-4 left-0 z-[5]\">\n            \u00a9Jo Howell        <\/div>\n    <\/div>\n    <button data-target=\"modalblock_2182e8b9717f0839107844f57428c65e\" class=\"openBtn border border-black mx-auto font-fjalla-one py-2 px-6\">\n         View larger image    <\/button>\n    <div id=\"modalblock_2182e8b9717f0839107844f57428c65e\" class=\"lightbox hidden fixed z-50 left-0 top-0 w-full h-full overflow-hidden\">\n        <span class=\"close\">&times;<\/span>\n        <img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jo-Howell-88b51034-scaled.jpg?width=1024&amp;height=683\" class=\"lightbox-content object-contain m-auto\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jo-Howell-88b51034-scaled.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jo-Howell-88b51034-scaled.jpg?width=1024&amp;height=683 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jo-Howell-88b51034-scaled.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jo-Howell-88b51034-scaled.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jo-Howell-88b51034-scaled.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jo-Howell-88b51034-scaled.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jo-Howell-88b51034-scaled.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jo-Howell-88b51034-scaled.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>        <div class=\"zoom-in\">+<\/div>\n        <div class=\"zoom-out\">&#8211;<\/div>\n        <div class=\"fullscreen\">[ ]<\/div>\n    <\/div>\n<\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-table has-none-or-default alignnone\"><table><tbody><tr><td><strong>Shooting Mode<\/strong><br><strong>Image Size<br>Sensitivity<br>Aperture<br>Shutter Speed<br><strong>White Balance<\/strong><\/strong><br><strong>Lens<\/strong><\/td><td>Manual<br>3000 x 2000<br>ISO1250<br>F3.2<br>1\/1000<br>Manual<br>XF50-140mmF2.8 R LM OIS WR<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div id=\"block_deec5b1ebc315a0275c5845b19430979\" class=\"wp-block block-gallery-modal flex flex-col align-center\">\n    <div class=\"w-full aspect-3\/2 bg-gray-400 flex flex-col align-items items-center mb-4 relative\">\n        <img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Dong-Yuan-42cf7ba9-scaled.jpg?width=1024&amp;height=683\" class=\"w-full h-full object-contain aspect-3\/2\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Dong-Yuan-42cf7ba9-scaled.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Dong-Yuan-42cf7ba9-scaled.jpg?width=1024&amp;height=683 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Dong-Yuan-42cf7ba9-scaled.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Dong-Yuan-42cf7ba9-scaled.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Dong-Yuan-42cf7ba9-scaled.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Dong-Yuan-42cf7ba9-scaled.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Dong-Yuan-42cf7ba9-scaled.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Dong-Yuan-42cf7ba9-scaled.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>        <div class=\"attachment-caption w-full text-xs text-center text-white absolute bottom-4 left-0 z-[5]\">\n            \u00a9Dong Yuan        <\/div>\n    <\/div>\n    <button data-target=\"modalblock_deec5b1ebc315a0275c5845b19430979\" class=\"openBtn border border-black mx-auto font-fjalla-one py-2 px-6\">\n         View larger image    <\/button>\n    <div id=\"modalblock_deec5b1ebc315a0275c5845b19430979\" class=\"lightbox hidden fixed z-50 left-0 top-0 w-full h-full overflow-hidden\">\n        <span class=\"close\">&times;<\/span>\n        <img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Dong-Yuan-42cf7ba9-scaled.jpg?width=1024&amp;height=683\" class=\"lightbox-content object-contain m-auto\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Dong-Yuan-42cf7ba9-scaled.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Dong-Yuan-42cf7ba9-scaled.jpg?width=1024&amp;height=683 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Dong-Yuan-42cf7ba9-scaled.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Dong-Yuan-42cf7ba9-scaled.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Dong-Yuan-42cf7ba9-scaled.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Dong-Yuan-42cf7ba9-scaled.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Dong-Yuan-42cf7ba9-scaled.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Dong-Yuan-42cf7ba9-scaled.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>        <div class=\"zoom-in\">+<\/div>\n        <div class=\"zoom-out\">&#8211;<\/div>\n        <div class=\"fullscreen\">[ ]<\/div>\n    <\/div>\n<\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-table has-none-or-default alignnone\"><table><tbody><tr><td><strong>Shooting Mode<\/strong><br><strong>Image Size<br>Sensitivity<br>Aperture<br>Shutter Speed<br><strong>White Balance<\/strong><\/strong><br><strong>Lens<\/strong><\/td><td>Aperture-Priority<br>3000 x 2000<br>ISO12800<br>F8<br>1\/100<br>AUTO<br>XF16-55mmF2.8 R LM WR II<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-spacing-extra-large has-no-design  product-image-text-col is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div id=\"block_23707dd6b81f498083ee244a8222bfef\" class=\"wp-block block-gallery-modal flex flex-col align-center\">\n    <div class=\"w-full aspect-3\/2 bg-gray-400 flex flex-col align-items items-center mb-4 relative\">\n        <img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jon-Kerrin-8463064a-scaled.jpg?width=1024&amp;height=683\" class=\"w-full h-full object-contain aspect-3\/2\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jon-Kerrin-8463064a-scaled.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jon-Kerrin-8463064a-scaled.jpg?width=1024&amp;height=683 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jon-Kerrin-8463064a-scaled.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jon-Kerrin-8463064a-scaled.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jon-Kerrin-8463064a-scaled.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jon-Kerrin-8463064a-scaled.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jon-Kerrin-8463064a-scaled.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jon-Kerrin-8463064a-scaled.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>        <div class=\"attachment-caption w-full text-xs text-center text-white absolute bottom-4 left-0 z-[5]\">\n            \u00a9Jon Kerrin        <\/div>\n    <\/div>\n    <button data-target=\"modalblock_23707dd6b81f498083ee244a8222bfef\" class=\"openBtn border border-black mx-auto font-fjalla-one py-2 px-6\">\n         View larger image    <\/button>\n    <div id=\"modalblock_23707dd6b81f498083ee244a8222bfef\" class=\"lightbox hidden fixed z-50 left-0 top-0 w-full h-full overflow-hidden\">\n        <span class=\"close\">&times;<\/span>\n        <img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jon-Kerrin-8463064a-scaled.jpg?width=1024&amp;height=683\" class=\"lightbox-content object-contain m-auto\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jon-Kerrin-8463064a-scaled.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jon-Kerrin-8463064a-scaled.jpg?width=1024&amp;height=683 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jon-Kerrin-8463064a-scaled.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jon-Kerrin-8463064a-scaled.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jon-Kerrin-8463064a-scaled.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jon-Kerrin-8463064a-scaled.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jon-Kerrin-8463064a-scaled.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jon-Kerrin-8463064a-scaled.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>        <div class=\"zoom-in\">+<\/div>\n        <div class=\"zoom-out\">&#8211;<\/div>\n        <div class=\"fullscreen\">[ ]<\/div>\n    <\/div>\n<\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-table has-none-or-default alignnone\"><table><tbody><tr><td><strong>Shooting Mode<\/strong><br><strong>Image Size<br>Sensitivity<br>Aperture<br>Shutter Speed<br><strong>White Balance<\/strong><\/strong><br><strong>Lens<\/strong><\/td><td>Manual<br>3000 x 2000<br>ISO160<br>F11<br>1.5<br>AUTO<br>XF150-600mmF5.6-8 R LM OIS WR<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div id=\"block_0180d32f0110c0df6d7a46a1ba842418\" class=\"wp-block block-gallery-modal flex flex-col align-center\">\n    <div class=\"w-full aspect-3\/2 bg-gray-400 flex flex-col align-items items-center mb-4 relative\">\n        <img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jonas-Dyhr-Rask-28ff322d-scaled.jpg?width=1024&amp;height=683\" class=\"w-full h-full object-contain aspect-3\/2\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jonas-Dyhr-Rask-28ff322d-scaled.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jonas-Dyhr-Rask-28ff322d-scaled.jpg?width=1024&amp;height=683 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jonas-Dyhr-Rask-28ff322d-scaled.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jonas-Dyhr-Rask-28ff322d-scaled.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jonas-Dyhr-Rask-28ff322d-scaled.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jonas-Dyhr-Rask-28ff322d-scaled.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jonas-Dyhr-Rask-28ff322d-scaled.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jonas-Dyhr-Rask-28ff322d-scaled.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>        <div class=\"attachment-caption w-full text-xs text-center text-white absolute bottom-4 left-0 z-[5]\">\n            \u00a9Jonas Dyhr Rask        <\/div>\n    <\/div>\n    <button data-target=\"modalblock_0180d32f0110c0df6d7a46a1ba842418\" class=\"openBtn border border-black mx-auto font-fjalla-one py-2 px-6\">\n         View larger image    <\/button>\n    <div id=\"modalblock_0180d32f0110c0df6d7a46a1ba842418\" class=\"lightbox hidden fixed z-50 left-0 top-0 w-full h-full overflow-hidden\">\n        <span class=\"close\">&times;<\/span>\n        <img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jonas-Dyhr-Rask-28ff322d-scaled.jpg?width=1024&amp;height=683\" class=\"lightbox-content object-contain m-auto\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jonas-Dyhr-Rask-28ff322d-scaled.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jonas-Dyhr-Rask-28ff322d-scaled.jpg?width=1024&amp;height=683 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jonas-Dyhr-Rask-28ff322d-scaled.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jonas-Dyhr-Rask-28ff322d-scaled.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jonas-Dyhr-Rask-28ff322d-scaled.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jonas-Dyhr-Rask-28ff322d-scaled.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jonas-Dyhr-Rask-28ff322d-scaled.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/10\/xt30iii_gallery_Jonas-Dyhr-Rask-28ff322d-scaled.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>        <div class=\"zoom-in\">+<\/div>\n        <div class=\"zoom-out\">&#8211;<\/div>\n        <div class=\"fullscreen\">[ ]<\/div>\n    <\/div>\n<\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-table has-none-or-default alignnone\"><table><tbody><tr><td><strong>Shooting Mode<\/strong><br><strong>Image Size<br>Sensitivity<br>Aperture<br>Shutter Speed<br><strong>White Balance<\/strong><\/strong><br><strong>Lens<\/strong><\/td><td>Manual<br>3000 x 2000<br>ISO3200<br>F6.3<br>1\/125<br>Manual<br>XC13-33mmF3.5-6.3 OIS<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p><\/p>\n","protected":false},"author":13,"featured_media":0,"parent":314105,"menu_order":0,"template":"","category":[],"products_category":[11587],"class_list":["post-314215","camera","type-camera","status-publish","hentry","products_category-sample-images"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":[],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera\/314215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera"}],"about":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/types\/camera"}],"author":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/users\/13"}],"version-history":[{"count":0,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera\/314215\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera\/314105"}],"wp:attachment":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media?parent=314215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/category?post=314215"},{"taxonomy":"products_category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/products_category?post=314215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":288670,"date":"2025-09-11T01:00:00","date_gmt":"2025-09-11T01:00:00","guid":{"rendered":"https:\/\/www.fujifilm-x.com\/?post_type=camera&#038;p=288670"},"modified":"2025-09-10T08:16:54","modified_gmt":"2025-09-10T08:16:54","slug":"product-views","status":"publish","type":"camera","link":"https:\/\/www.fujifilm-x.com\/it-it\/products\/cameras\/gfx-eterna-55\/product-views\/","title":{"rendered":"Product Views"},"content":{"rendered":"\n<div style=\"height:80px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center is-style-small-separator\">Product Views<\/h1>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group alignwide is-layout-constrained wp-container-core-group-is-layout-00475714 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-7a8ecd1d wp-block-group-is-layout-constrained\">\t<div id=\"block_09086002a2b26a68d07e37b657ac9fef\" class=\"wp-block wp-block-slider wp-block-slider--product-views swiper alignfull\">\n\t\t<div class=\"swiper-wrapper\" data-settings='{\"loop\":true,\"autoplay\":false,\"autoplaySpeed\":\"5000\",\"speed\":500,\"spaceBetween\":20,\"slidesPerView\":1,\"grabCursor\":true,\"navigation\":{\"nextEl\":\".swiper-button-next\",\"prevEl\":\".swiper-button-prev\"},\"breakpoints\":{\"640\":{\"spaceBetween\":32}}}'>\n\t\t\t\n\t<figure class=\"swiper-slide\">\n\t\t<picture >\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/1-GFX_ETERNA_front_CMOS-min-scaled.jpg?width=600&#038;height=600&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_1\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/1-GFX_ETERNA_front_CMOS-min-scaled.jpg?width=600&#038;height=600&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"h-auto max-h-[600px] object-contain\"\t\t\t\t\t\t\t\t\talt=\"Image 1\"\t\t\t\t\t\t\t\t\twidth=\"600\"\t\t\t\t\t\t\t\t\theight=\"600\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_1\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t<\/figure>\n\t\t\t\t\n\t<figure class=\"swiper-slide\">\n\t\t<picture >\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/2-GFX_ETERNA_left_CMOS-min-scaled.jpg?width=600&#038;height=600&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_2\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/2-GFX_ETERNA_left_CMOS-min-scaled.jpg?width=600&#038;height=600&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"h-auto max-h-[600px] object-contain\"\t\t\t\t\t\t\t\t\talt=\"Image 2\"\t\t\t\t\t\t\t\t\twidth=\"600\"\t\t\t\t\t\t\t\t\theight=\"600\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_2\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t<\/figure>\n\t\t\t\t\n\t<figure class=\"swiper-slide\">\n\t\t<picture >\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/3-GFX_ETERNA_back-min-scaled.jpg?width=600&#038;height=600&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_3\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/3-GFX_ETERNA_back-min-scaled.jpg?width=600&#038;height=600&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"h-auto max-h-[600px] object-contain\"\t\t\t\t\t\t\t\t\talt=\"Image 3\"\t\t\t\t\t\t\t\t\twidth=\"600\"\t\t\t\t\t\t\t\t\theight=\"600\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_3\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t<\/figure>\n\t\t\t\t\n\t<figure class=\"swiper-slide\">\n\t\t<picture >\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/4-GFX_ETERNA_back_NoCap-min-scaled.jpg?width=600&#038;height=600&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_4\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/4-GFX_ETERNA_back_NoCap-min-scaled.jpg?width=600&#038;height=600&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"h-auto max-h-[600px] object-contain\"\t\t\t\t\t\t\t\t\talt=\"Image 4\"\t\t\t\t\t\t\t\t\twidth=\"600\"\t\t\t\t\t\t\t\t\theight=\"600\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_4\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t<\/figure>\n\t\t\t\t\n\t<figure class=\"swiper-slide\">\n\t\t<picture >\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/5-GFX_ETERNA_right_CMOS-min-scaled.jpg?width=600&#038;height=600&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_5\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/5-GFX_ETERNA_right_CMOS-min-scaled.jpg?width=600&#038;height=600&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"h-auto max-h-[600px] object-contain\"\t\t\t\t\t\t\t\t\talt=\"Image 5\"\t\t\t\t\t\t\t\t\twidth=\"600\"\t\t\t\t\t\t\t\t\theight=\"600\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_5\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t<\/figure>\n\t\t\t\t\n\t<figure class=\"swiper-slide\">\n\t\t<picture >\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/6-GFX_ETERNA_top_CMOS-min-scaled.jpg?width=600&#038;height=600&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_6\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/6-GFX_ETERNA_top_CMOS-min-scaled.jpg?width=600&#038;height=600&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"h-auto max-h-[600px] object-contain\"\t\t\t\t\t\t\t\t\talt=\"Image 6\"\t\t\t\t\t\t\t\t\twidth=\"600\"\t\t\t\t\t\t\t\t\theight=\"600\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_6\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t<\/figure>\n\t\t\t\t\n\t<figure class=\"swiper-slide\">\n\t\t<picture >\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/7-GFX_ETERNA_bottom-min-scaled.jpg?width=600&#038;height=600&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_7\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/7-GFX_ETERNA_bottom-min-scaled.jpg?width=600&#038;height=600&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"h-auto max-h-[600px] object-contain\"\t\t\t\t\t\t\t\t\talt=\"Image 7\"\t\t\t\t\t\t\t\t\twidth=\"600\"\t\t\t\t\t\t\t\t\theight=\"600\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_7\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t<\/figure>\n\t\t\t\t\n\t<figure class=\"swiper-slide\">\n\t\t<picture >\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/8-GFX_ETERNA_frontNANAMEue_CMOS-min-scaled.jpg?width=600&#038;height=600&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_8\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/8-GFX_ETERNA_frontNANAMEue_CMOS-min-scaled.jpg?width=600&#038;height=600&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"h-auto max-h-[600px] object-contain\"\t\t\t\t\t\t\t\t\talt=\"Image 8\"\t\t\t\t\t\t\t\t\twidth=\"600\"\t\t\t\t\t\t\t\t\theight=\"600\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_8\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t<\/figure>\n\t\t\t\t\n\t<figure class=\"swiper-slide\">\n\t\t<picture >\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/9-GFX_ETERNA_leftNANAME_CMOS-min-scaled.jpg?width=600&#038;height=600&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_9\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/9-GFX_ETERNA_leftNANAME_CMOS-min-scaled.jpg?width=600&#038;height=600&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"h-auto max-h-[600px] object-contain\"\t\t\t\t\t\t\t\t\talt=\"Image 9\"\t\t\t\t\t\t\t\t\twidth=\"600\"\t\t\t\t\t\t\t\t\theight=\"600\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_9\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t<\/figure>\n\t\t\t\t\n\t<figure class=\"swiper-slide\">\n\t\t<picture >\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/10-GFX_ETERNA_leftNANAME_GF32-90_grip_monitorUE-min.jpg?width=600&#038;height=600&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_10\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/10-GFX_ETERNA_leftNANAME_GF32-90_grip_monitorUE-min.jpg?width=600&#038;height=600&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"h-auto max-h-[600px] object-contain\"\t\t\t\t\t\t\t\t\talt=\"Image 10\"\t\t\t\t\t\t\t\t\twidth=\"600\"\t\t\t\t\t\t\t\t\theight=\"600\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_10\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t<\/figure>\n\t\t\t\t\n\t<figure class=\"swiper-slide\">\n\t\t<picture >\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/11-GFX_ETERNA_leftNANAME_GF32-90_grip_monitorYOKO-min.jpg?width=600&#038;height=600&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_11\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/11-GFX_ETERNA_leftNANAME_GF32-90_grip_monitorYOKO-min.jpg?width=600&#038;height=600&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"h-auto max-h-[600px] object-contain\"\t\t\t\t\t\t\t\t\talt=\"Image 11\"\t\t\t\t\t\t\t\t\twidth=\"600\"\t\t\t\t\t\t\t\t\theight=\"600\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_11\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t<\/figure>\n\t\t\t\t\n\t<figure class=\"swiper-slide\">\n\t\t<picture >\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/12-GFX_ETERNA_left_GF32-90_grip_monitorUE-min.jpg?width=600&#038;height=600&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_12\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/12-GFX_ETERNA_left_GF32-90_grip_monitorUE-min.jpg?width=600&#038;height=600&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"h-auto max-h-[600px] object-contain\"\t\t\t\t\t\t\t\t\talt=\"Image 12\"\t\t\t\t\t\t\t\t\twidth=\"600\"\t\t\t\t\t\t\t\t\theight=\"600\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_12\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t<\/figure>\n\t\t\t\t\n\t<figure class=\"swiper-slide\">\n\t\t<picture >\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/13-GFX_ETERNA_left_GF32-90_grip_monitorYOKO-min.jpg?width=600&#038;height=600&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_13\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/09\/13-GFX_ETERNA_left_GF32-90_grip_monitorYOKO-min.jpg?width=600&#038;height=600&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"h-auto max-h-[600px] object-contain\"\t\t\t\t\t\t\t\t\talt=\"Image 13\"\t\t\t\t\t\t\t\t\twidth=\"600\"\t\t\t\t\t\t\t\t\theight=\"600\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_13\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t<\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\n<button class=\"swiper-button-prev arrow-white\" type=\"button\">\n\t<span class=\"hidden sm:flex\">\n\t\t\t\t<svg class=\"svg-slick-left-arrow-svg \"\n\t\t width=\"24\" height=\"22\"\t\talt=\"Svg Slick Left Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-left-arrow-svg\"\n\t\t\t width=\"24\" height=\"22\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n\t<span class=\"flex sm:hidden\">\n\t\t\t\t<svg class=\"svg-slick-left-arrow-svg \"\n\t\t width=\"20\" height=\"18\"\t\talt=\"Svg Slick Left Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-left-arrow-svg\"\n\t\t\t width=\"20\" height=\"18\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n<\/button>\n<button class=\"swiper-button-next arrow-white\" type=\"button\">\n\t<span class=\"hidden sm:flex\">\n\t\t\t\t<svg class=\"svg-slick-right-arrow-svg \"\n\t\t width=\"24\" height=\"22\"\t\talt=\"Svg Slick Right Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-right-arrow-svg\"\n\t\t\t width=\"24\" height=\"22\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n\t<span class=\"flex sm:hidden\">\n\t\t\t\t<svg class=\"svg-slick-right-arrow-svg \"\n\t\t width=\"20\" height=\"18\"\t\talt=\"Svg Slick Right Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-right-arrow-svg\"\n\t\t\t width=\"20\" height=\"18\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n<\/button>\n\t<\/div>\n\t<\/div>\n<\/div>\n","protected":false},"author":13,"featured_media":0,"parent":288639,"menu_order":0,"template":"","category":[],"products_category":[11587],"class_list":["post-288670","camera","type-camera","status-publish","hentry","products_category-sample-images"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":[],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera\/288670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera"}],"about":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/types\/camera"}],"author":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/users\/13"}],"version-history":[{"count":0,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera\/288670\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera\/288639"}],"wp:attachment":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media?parent=288670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/category?post=288670"},{"taxonomy":"products_category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/products_category?post=288670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":288664,"date":"2025-09-11T01:00:00","date_gmt":"2025-09-11T01:00:00","guid":{"rendered":"https:\/\/www.fujifilm-x.com\/?post_type=camera&#038;p=288664"},"modified":"2025-09-10T08:18:04","modified_gmt":"2025-09-10T08:18:04","slug":"accessories","status":"publish","type":"camera","link":"https:\/\/www.fujifilm-x.com\/it-it\/products\/cameras\/gfx-eterna-55\/accessories\/","title":{"rendered":"Accessories \/ Software"},"content":{"rendered":"\n<div style=\"height:80px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center is-style-small-separator\">Accessories \/ Software<\/h1>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<!-- fragment (initial DATA ONLY  output) (language_code=unset, group=legacy_shortcodes_prod_accessories, key=prod_accessories_nav_288639, ttl=0s, full_key=:frag_cache:http:unset:legacy_shortcodes_prod_accessories:4c1401fbb52d010def95f0e3f2438ef0) --><!-- fragment (initial output) (language_code=it-it, group=legacy_shortcodes, key=prod_accessories_nav_288639, ttl=0s, full_key=:frag_cache:http:it-it:legacy_shortcodes:4c1401fbb52d010def95f0e3f2438ef0) --><style>\n\t.product-accessories-wrapper:not(.wp-block-sub-navigation) {\n\t\tmargin: auto;\n\t\tmax-width: 1600px;\n\t\tpadding-left: 1.25rem;\n\t\tpadding-right: 1.25rem;\n\t\twidth: 100%;\n\t}\n\n\tproduct-accessories-wrapper:not(.wp-block-sub-navigation) {\n\t\tmax-width: 820px;\n\t}\n\n\t@media (min-width: 768px) {\n\t\t.product-accessories-wrapper:not(.wp-block-sub-navigation) {\n\t\t\tpadding-left: 2rem;\n\t\t\tpadding-right: 2rem;\n\t\t}\n\t}\n\n\t.product-accessories-wrapper .headline.wp-block-heading.has-text-align-center {\n\t\tfont-family: Fjalla One, Oswald, Helvetica, sans-serif ;\n\t\tfont-size: 1.625rem ;\n\t\tfont-weight: 400 ;\n\t\tline-height: 2rem ;\n\t\tline-height: 1.25 ;\n\t\tmargin-bottom: 2rem ;\n\t\tscroll-margin-top: 7rem;\n\t}\n\n\t.product-accessories-wrapper .headline--title::after {\n\t\tbackground-color: currentColor;\n\t\tcontent: '';\n\t\tdisplay: block ;\n\t\theight: .125rem ;\n\t\tmargin: .75rem auto auto ;\n\t\twidth: 1.5rem;\n\t}\n\n\t@media (min-width: 640px) {\n\t\t.product-accessories-wrapper .headline.wp-block-heading.has-text-align-center {\n\t\t\tfont-size: 1.875rem ;\n\t\t\tline-height: 2.25rem;\n\t\t}\n\t}\n\n\t@media (min-width: 768px) {\n\t\t.product-accessories-wrapper .headline.wp-block-heading.has-text-align-center {\n\t\t\tfont-size: 3rem ;\n\t\t\tline-height: 1.15;\n\t\t}\n\t}\n\n\t.product-accessories-wrapper .wp-block-spacer {\n\t\tdisplay: block;\n\t\theight: 100px;\n\t}\n\n\t.product-accessories-wrapper .products__series {\n\t\tmargin-bottom: 70px;\n\t}\n\n\t@media (min-width: 1280px) {\n\t\t.product-accessories-wrapper .products__series--software .products__series_list li a {\n\t\t\tmin-height: 48px;\n\t\t}\n\t}\n\n\t.product-accessories-wrapper .products__series_list {\n\t\tdisplay: grid;\n\t\tgap: 20px;\n\t\tgrid-template-columns: repeat(2, minmax(0, 1fr));\n\t}\n\n\t@media (min-width: 768px) {\n\t\t.product-accessories-wrapper .products__series_list {\n\t\t\tgrid-template-columns: repeat(3, minmax(0, 1fr));\n\t\t}\n\t}\n\n\t@media (min-width: 1200px) {\n\t\t.product-accessories-wrapper .products__series_list {\n\t\t\tgap: 25px;\n\t\t\tgrid-template-columns: repeat(4, minmax(0, 1fr));\n\t\t}\n\t}\n\n\t.product-accessories-wrapper .products__series_list li>a {\n\t\t--tw-text-opacity: 1;\n\t\tcolor: rgb(0 0 0\/var(--tw-text-opacity));\n\t\tdisplay: block;\n\t\tfont-family: Noto Sans JP, Noto Sans, Helvetica, sans-serif;\n\t\tfont-size: .75rem;\n\t\tfont-weight: 700;\n\t\tline-height: 1rem;\n\t\tmargin-top: 10px;\n\t\ttext-decoration-line: none;\n\t}\n\n\t.product-accessories-wrapper .products__series_list li>a:hover {\n\t\tcolor: currentColor;\n\t\ttext-decoration-line: underline;\n\t}\n\n\t@media (min-width: 768px) {\n\t\t.product-accessories-wrapper .products__series_list li>a {\n\t\t\tfont-size: 1rem;\n\t\t\tline-height: 1.5rem;\n\t\t}\n\t}\n\n\t@media (min-width: 1280px) {\n\t\t.product-accessories-wrapper .products__series_list li>a {\n\t\t\tfont-size: 1.125rem;\n\t\t\tline-height: 1.5rem;\n\t\t}\n\t}\n\n\t.product-accessories-wrapper .products__series_list li img {\n\t\ttransition-duration: .2s;\n\t\ttransition-property: all;\n\t\ttransition-timing-function: cubic-bezier(.4, 0, .2, 1);\n\t\ttransition-timing-function: linear;\n\t}\n\n\t.product-accessories-wrapper .products__series_list li:hover>a {\n\t\ttext-decoration-line: underline;\n\t}\n\n\t.product-accessories-wrapper .products__series_list li:hover img {\n\t\t--tw-shadow: 0px 0px 20px rgba(0, 0, 0, .1);\n\t\t--tw-shadow-colored: 0px 0px 20px var(--tw-shadow-color);\n\t\tbox-shadow: var(--tw-ring-offset-shadow, 0 0 #0000), var(--tw-ring-shadow, 0 0 #0000), var(--tw-shadow);\n\t}\n\n\t.product-accessories-wrapper .products__series_list li .products__series_list_btn {\n\t\tdisplay: block;\n\t\tmargin-top: .625rem;\n\t}\n\n\t.product-accessories-wrapper .products__series_list li .products__series_list_btn a {\n\t\tbackground-color: rgb(20 165 143);\n\t\tcolor: rgb(255 255 255);\n\t\tdisplay: block;\n\t\tflex-grow: 1;\n\t\tfont-family: Fjalla One, Oswald, Helvetica, sans-serif;\n\t\tfont-size: .875rem;\n\t\tfont-weight: 400;\n\t\tline-height: 1.375rem;\n\t\tmargin-top: .625rem;\n\t\tpadding: .75rem;\n\t\ttext-align: center;\n\t\ttext-decoration-line: none;\n\t}\n\n\t.product-accessories-wrapper .products__series_list li .products__series_list_btn .wp_btn {\n\t\tdisplay: block;\n\t}\n\n\t.product-accessories-wrapper h2.headline {\n    \ttext-align: center;\n\t}\n\n\t.product-accessories-wrapper .headline,\n\t.product-accessories-wrapper  headline--minor {\n\t\tmargin-bottom: calc(1rem + 30px) ;\n\t}\n\n\t.product-accessories-wrapper  headline--minor {\n\t\tpadding-bottom: .5em;\n\t\tposition: relative;\n\t}\n\n\t.product-accessories-wrapper .headline--minor::before {\n\t\tbackground: #bfbfbf;\n\t\tbottom: -1px;\n\t\tcontent: \"\";\n\t\theight: 1px;\n\t\tleft: 0;\n\t\tposition: absolute;\n\t\twidth: 100%;\n\t}\n\n\t.product-accessories-wrapper .headline,\n\t.product-accessories-wrapper .headline--minor {\n\t\tmargin-bottom: calc(1rem + 30px) ;\n\t}\n\n\t.product-accessories-wrapper .headline--minor::after {\n\t\tbackground: #1b1b1b;\n\t\tbottom: -1px;\n\t\tcontent: \"\";\n\t\theight: 1px;\n\t\tleft: 0;\n\t\tposition: absolute;\n\t\twidth: 30%;\n\t}\n\n\t.product-accessories-wrapper .headline--minor {\n\t\tpadding-bottom: 0.5em;\n\t\tposition: relative;\n\t}\n\n\t.product-accessories-wrapper .headline--minor::before {\n\t\tcontent: \"\";\n\t\theight: 1px;\n\t\tbackground: #bfbfbf;\n\t\tposition: absolute;\n\t\tleft: 0;\n\t\twidth: 100%;\n\t\tbottom: -1px;\n\t}\n\n\t.product-accessories-wrapper .headline--minor::after {\n\t\tcontent: \"\";\n\t\theight: 1px;\n\t\tbackground: #1b1b1b;\n\t\tposition: absolute;\n\t\tleft: 0;\n\t\twidth: 30%;\n\t\tbottom: -1px;\n\t}\n\n\t@media screen and (max-width: 767px) {\n\n\t\t.product-accessories-wrapper .headline {\n\t\t\tposition: absolute;\n\t\t}\n\t}\n\t.product-accessories-wrapper .headline {\n\t\tmargin-top: 56px;\n\t}\n\t.product-accessories-wrapper .headline,\n\t.product-accessories-wrapper .headline--minor {\n\t\tmargin-bottom: calc(1rem + 30px);\n\t}\n<\/style>\n\n<section class=\"product-accessories-wrapper\">\n\t<section>\n\t\t\n\t\t\t\t\t\t<section class=\"products__series products__series--body-accessories\">\n\t\t\t\t<div class=\"inner\">\n\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"headline--minor\" id=\"body-accessories\">\n\t\t\t\t\t\t\tBody accessories\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t<ul class=\"products__series_list mt40\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/view-camera-adapter-g\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2019\/10\/view-camera-adapter-g_thum.jpg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/view-camera-adapter-g\/\">\n\t\t\t\t\t\t\t\t\tVIEW CAMERA ADAPTER G\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/rr-100\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2019\/08\/remote-release-rr-100_thum-1.jpg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/rr-100\/\">\n\t\t\t\t\t\t\t\t\tRemote release RR-100\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/bcp-002\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2019\/10\/body-cap-bcp-002_thum.jpg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/bcp-002\/\">\n\t\t\t\t\t\t\t\t\tBody cap BCP-002\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/section>\n\t\t\n\t\t\t\t\t\t<section class=\"products__series products__series--lens-accessories\">\n\t\t\t\t<div class=\"inner\">\n\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"headline--minor\" id=\"lens-accessories\">\n\t\t\t\t\t\t\tLens accessories\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t<ul class=\"products__series_list mt40\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/h-mount-adapter-g\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2019\/10\/h-mount-adapter-g_thum-1.jpg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/h-mount-adapter-g\/\">\n\t\t\t\t\t\t\t\t\tH MOUNT ADAPTER G\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/mcex-18g-wr\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2019\/10\/mcex-18g-wr_thum.jpg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/mcex-18g-wr\/\">\n\t\t\t\t\t\t\t\t\tMacro extension tube MCEX-18G WR\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/mcex-45g-wr\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2019\/10\/mcex-45g-wr_thum.jpg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/mcex-45g-wr\/\">\n\t\t\t\t\t\t\t\t\tMacro extension tube MCEX-45G WR\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/section>\n\t\t\n\t\t\t\t\t\t<section class=\"products__series products__series--power-supply\">\n\t\t\t\t<div class=\"inner\">\n\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"headline--minor\" id=\"power-supply\">\n\t\t\t\t\t\t\tPower supply\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t<ul class=\"products__series_list mt40\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/np-w235\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2020\/02\/np-w235_thum.jpg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/np-w235\/\">\n\t\t\t\t\t\t\t\t\tLi-ion battery NP-W235\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<div class=\"card-media-thumbnail relative\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/bc-w235\/\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2020\/02\/bc-w235_thum.jpg?width=480&#038;height=480\">\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/accessories\/bc-w235\/\">\n\t\t\t\t\t\t\t\t\tDual battery charger BC-W235\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/section>\n\t\t\t<\/section>\n<\/section>\n\n<!-- \/fragment (initial output) (language_code=it-it, group=legacy_shortcodes, key=prod_accessories_nav_288639, ttl=0s, full_key=:frag_cache:http:it-it:legacy_shortcodes:4c1401fbb52d010def95f0e3f2438ef0) --><!-- fragment (initial DATA ONLY  output) (language_code=unset, group=legacy_shortcodes_prod_accessories, key=prod_accessories_nav_288639, ttl=0s, full_key=:frag_cache:http:unset:legacy_shortcodes_prod_accessories:4c1401fbb52d010def95f0e3f2438ef0) -->\n","protected":false},"author":13,"featured_media":0,"parent":288639,"menu_order":0,"template":"","category":[],"products_category":[11685],"class_list":["post-288664","camera","type-camera","status-publish","hentry","products_category-accessories"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":[],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera\/288664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera"}],"about":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/types\/camera"}],"author":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/users\/13"}],"version-history":[{"count":0,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera\/288664\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera\/288639"}],"wp:attachment":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media?parent=288664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/category?post=288664"},{"taxonomy":"products_category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/products_category?post=288664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":288659,"date":"2025-09-11T01:00:00","date_gmt":"2025-09-11T01:00:00","guid":{"rendered":"https:\/\/www.fujifilm-x.com\/?post_type=camera&#038;p=288659"},"modified":"2025-09-10T08:17:11","modified_gmt":"2025-09-10T08:17:11","slug":"specifications","status":"publish","type":"camera","link":"https:\/\/www.fujifilm-x.com\/it-it\/products\/cameras\/gfx-eterna-55\/specifications\/","title":{"rendered":"Specifications"},"content":{"rendered":"<div class=\"camera-specifications\">\n\t\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Model Name<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">FUJIFILM GFX ETERNA 55<\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Lens Mount<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">FUJIFILM G mount<\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Image Sensor<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">43.8mm\u00d732.9mm GFX 102MP CMOS II HS with primary color filter<\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Number Of Pixels<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">102 million pixels<\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>ND Filter<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">Electronic Variable ND Filter, 0.6(ND4)\uff5e2.1(ND128)<\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Gamma<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">Film Simulation \/ F-Log2 \/ F-Log2 C \/ F-Log \/ HLG<\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>LUT Setting<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">Up to 16 3D-LUT files can be saved on the camera. Supported cube sizes (17\/33\/65). File names support up to 48 characters.<\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Cooling Fan Setting<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">AUTO1 \/ AUTO2 \/ HIGH \/ LOW<\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Sensor Cleaning System<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">Ultra Sonic Vibration<\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Image Processing Engine<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">X-Processor 5<\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-repeater-grid\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Storage Media<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\"><div>SD Card (-2GB)<\/div><div>SDHC Card (-32GB)<\/div><div>SDXC Card (-2TB)<\/div><div>UHS-I<\/div><div>UHS-II<\/div><div>Video Speed Class V90<\/div><div>CFexpress Type B Card (-2TB)<\/div><div>SSD (-2TB)<\/div><div>*Please see the Fujifilm website (https:\/\/fujifilm-x.com\/support\/compatibility\/cameras\/) to check memory card compatibility.<\/div><\/div>\n\t<\/div>\t<div class=\"camera-specifications__block specs-three-level sensitivity\">\n\t\t<h6>Sensitivity<\/h6>\n\t\t<div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Movie<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Standard Output<\/div>\n\t<div class=\"col-span-6\"><div>AUTO<\/div><div>ISO400\uff5e12800 (1\/3 step)<\/div><\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Extended Output<\/div>\n\t<div class=\"col-span-6\"><div>ISO100~ISO320 (1\/3 step)<\/div><div>ISO25600<\/div><\/div>\n<\/div><\/div><\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Exposure Control<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">TTL 256-zone metering\r<br>Multi\r<br>Spot\r<br>Average\r<br>Center Weighted<\/div>\n\t<\/div><div class=\"camera-specifications__block specs-two-level exposure-compensation\">\n\t<h6>Exposure Compensation<\/h6>\n\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">Movie<\/div><div class=\"col-span-6\">-2.0EV~+2.0EV (1\/4EV step)<\/div>\n\t<\/div>\n<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Dynamic Range<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">14+Stop (F-Log2 \/ F-Log2 C)<\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Shutter speed \/ Shutter angle<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">1\/8 sec~1\/8000 sec, 5.6\u00b0~ 360\u00b0<\/div>\n\t<\/div>\t<div class=\"camera-specifications__block specs-three-level focus\">\n\t\t<h6>Focus<\/h6>\n\t\t<div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Mode<\/div>\n\t<div class=\"col-span-6\"> Continuous AF\r<br>MF<\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Type<\/div>\n\t<div class=\"col-span-6\"> Intelligent Hybrid AF (TTL contrast AF \/ TTL phase detection AF)<\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Low-light Performance<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Contrast<\/div>\n\t<div class=\"col-span-6\">-0.7EV\r<br>GF80mmF1.7 attached<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Phase Detection<\/div>\n\t<div class=\"col-span-6\">-3.7EV\r<br>GF80mmF1.7 attached<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">AF Frame Selection<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Single Point AF<\/div>\n\t<div class=\"col-span-6\">13&#215;9 \/ 25&#215;17 (Changeable size of AF frame)<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Wide\/Tracking AF<\/div>\n\t<div class=\"col-span-6\">AF: MULTI \/ TRACKING \/ AREA<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Face\/eye Detection<\/div>\n\t<div class=\"col-span-6\"> Yes<\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Subject Detection<\/div>\n\t<div class=\"col-span-6\"> Yes (FACE\/Animal\/Bird\/Automobile\/Motorcycle&amp;Bike\/Airplane\/Train)<\/div><\/div>\n\t<\/div><div class=\"camera-specifications__block specs-two-level side-monitor\">\n\t<h6>Side monitor<\/h6>\n\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\"><\/div><div class=\"col-span-6\">3.0 inch Touch Screen Color LCD Monitor<\/div><div class=\"col-span-2\">Aspect Ratio<\/div><div class=\"col-span-6\">3:2<\/div><div class=\"col-span-2\">Dots<\/div><div class=\"col-span-6\">Approx. 1.04 million dots<\/div>\n\t<\/div>\n<\/div>\t<div class=\"camera-specifications__block specs-three-level movie-recording\">\n\t\t<h6>Movie Recording<\/h6>\n\t\t<div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">File Format<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">MXF, MOV<\/div>\n\t<div class=\"col-span-6\"><div>Apple ProRes 422 HQ, Linear PCM (Stereo sound 24bit \/ 48KHz sampling)<\/div><div>Apple ProRes 422, Linear PCM (Stereo sound 24bit \/ 48KHz sampling)<\/div><div>Apple ProRes 422 LT, Linear PCM (Stereo sound 24bit \/ 48KHz sampling)<\/div><div>HEVC\/H.265, Linear PCM (Stereo sound 24bit \/ 48KHz sampling)<\/div><\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Movie Compression<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\"><\/div>\n\t<div class=\"col-span-6\"><div>All Intra<\/div><\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\"><\/div>\n\t<div class=\"col-span-6\"><div>Long GOP<\/div><\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Project FPS<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Frame Rate<\/div>\n\t<div class=\"col-span-6\">59.94P\r<br>50P\r<br>48P\r<br>47.95P\r<br>29.97P\r<br>25P\r<br>24P\r<br>23.98P<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">8K(17:9)<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">File Size<\/div>\n\t<div class=\"col-span-6\">8192 x 4320<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Frame Rate<\/div>\n\t<div class=\"col-span-6\">24p\r<br>23.98p\r<br>22p<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Bitrate<\/div>\n\t<div class=\"col-span-6\">720Mbps\r<br>360Mbps\r<br>200Mbps\r<br>100Mbps\r<br>50Mbps\r<br>All Intra: Only available at 720 Mbps and 360 Mbps<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">8K(16:9)<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">File Size<\/div>\n\t<div class=\"col-span-6\">7680 x 4320<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Frame Rate<\/div>\n\t<div class=\"col-span-6\">29.97p\r<br>25p\r<br>24p\r<br>23.98p\r<br>22p<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Bitrate<\/div>\n\t<div class=\"col-span-6\">720Mbps\r<br>360Mbps\r<br>200Mbps\r<br>100Mbps\r<br>50Mbps\r<br>All Intra: Only available at 720 Mbps and 360 Mbps<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">8K(2.76:1)<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">File Size<\/div>\n\t<div class=\"col-span-6\">8192 x 2968<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Frame Rate<\/div>\n\t<div class=\"col-span-6\">24p\r<br>23.98p\r<br>22p<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Bitrate<\/div>\n\t<div class=\"col-span-6\">720Mbps\r<br>360Mbps\r<br>200Mbps\r<br>100Mbps\r<br>50Mbps\r<br>All Intra: Only available at 720 Mbps and 360 Mbps<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">6.3K(16:9)<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">File Size<\/div>\n\t<div class=\"col-span-6\">6382&#215;3590<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Frame Rate<\/div>\n\t<div class=\"col-span-6\">29.97p\r<br>25p\r<br>24p\r<br>23.98p\r<br>22p<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Bitrate<\/div>\n\t<div class=\"col-span-6\">720Mbps\r<br>360Mbps\r<br>200Mbps\r<br>100Mbps\r<br>50Mbps\r<br>All Intra:Only available at 720 Mbps and 360 Mbps<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">5.8K(2.39:1)<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">File Size<\/div>\n\t<div class=\"col-span-6\">5824&#215;2436<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Frame Rate<\/div>\n\t<div class=\"col-span-6\">29.97p\r<br>25p\r<br>24p\r<br>23.98p\r<br>22p<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Bitrate<\/div>\n\t<div class=\"col-span-6\">720Mbps\r<br>360Mbps\r<br>200 Mbps\r<br>100Mbps\r<br>50Mbps\r<br>All Intra: Only available at 720 Mbps and 360 Mbps<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">5.4K(17:9)<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">File Size<\/div>\n\t<div class=\"col-span-6\">5440 x 2868<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Frame Rate<\/div>\n\t<div class=\"col-span-6\">29.97p\r<br>25p\r<br>24p\r<br>23.98p\r<br>22p<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Bitrate<\/div>\n\t<div class=\"col-span-6\">720Mbps\r<br>360Mbps\r<br>200Mbps\r<br>100Mbps\r<br>50Mbps\r<br>All Intra: Only available at 720 Mbps and 360 Mbps<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">4.8K(3:2)<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">File Size<\/div>\n\t<div class=\"col-span-6\">4776 x 3184<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Frame Rate<\/div>\n\t<div class=\"col-span-6\">24p\r<br>23.98p\r<br>22p<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Bitrate<\/div>\n\t<div class=\"col-span-6\">720Mbps\r<br>360Mbps\r<br>200Mbps\r<br>100Mbps\r<br>50Mbps\r<br>All Intra: Only available at 720 Mbps and 360 Mbps<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">4.8K(16:9)<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">File Size<\/div>\n\t<div class=\"col-span-6\">4776 x 2688<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Frame Rate<\/div>\n\t<div class=\"col-span-6\">29.97p\r<br>25p\r<br>24p\r<br>23.98p\r<br>22p<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Bitrate<\/div>\n\t<div class=\"col-span-6\">720Mbps\r<br>360Mbps\r<br>200Mbps\r<br>100Mbps\r<br>50Mbps\r<br>All Intra: Only available at 720 Mbps and 360 Mbps<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">4.6K(1.38:1)<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">File Size<\/div>\n\t<div class=\"col-span-6\">4664 x 3380<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Frame Rate<\/div>\n\t<div class=\"col-span-6\">24p\r<br>23.98p\r<br>22p<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Bitrate<\/div>\n\t<div class=\"col-span-6\">720Mbps\r<br>360Mbps\r<br>200Mbps\r<br>100Mbps\r<br>50Mbps\r<br>All Intra: Only available at 720 Mbps and 360 Mbps<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">4K(1.195:1)<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">File Size<\/div>\n\t<div class=\"col-span-6\">4040&#215;3380<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Frame Rate<\/div>\n\t<div class=\"col-span-6\">24p\r<br>23.98p\r<br>22p<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Bitrate<\/div>\n\t<div class=\"col-span-6\">720Mbps\r<br>360Mbps\r<br>200Mbps\r<br>100Mbps\r<br>50Mbps\r<br>All Intra:Only available at 720 Mbps and 360 Mbps<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">DCI4K(17:9)<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">File Size<\/div>\n\t<div class=\"col-span-6\">4096 x 2160<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Frame Rate<\/div>\n\t<div class=\"col-span-6\">59.94p\r<br>50p\r<br>48p\r<br>47.95\r<br>29.97p\r<br>25p\r<br>24p\r<br>23.98p\r<br>22p<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Bitrate<\/div>\n\t<div class=\"col-span-6\">720Mbps\r<br>360Mbps\r<br>200Mbps\r<br>100Mbps\r<br>50Mbps\r<br>All Intra: Only available at 720 Mbps and 360 Mbps<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">4K(16:9)<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">File Size<\/div>\n\t<div class=\"col-span-6\">3840 x 2160<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Frame Rate<\/div>\n\t<div class=\"col-span-6\">59.94p\r<br>50p\r<br>48p\r<br>47.95p\r<br>29.97p\r<br>25p\r<br>24p\r<br>23.98p\r<br>22p<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Bitrate<\/div>\n\t<div class=\"col-span-6\">720Mbps\r<br>360Mbps\r<br>200Mbps\r<br>100Mbps\r<br>50Mbps\r<br>All Intra: Only available at 720 Mbps and 360 Mbps<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">4K(4:3)<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">File Size<\/div>\n\t<div class=\"col-span-6\">3840&#215;2880<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Frame Rate<\/div>\n\t<div class=\"col-span-6\">48p\r<br>47.95p\r<br>29.97p\r<br>25p\r<br>24p\r<br>23.98p\r<br>22p<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Bitrate<\/div>\n\t<div class=\"col-span-6\">720Mbps\r<br>360Mbps\r<br>200Mbps\r<br>100Mbps\r<br>50Mbps\r<br>All Intra: Only available at 720 Mbps and 360 Mbps<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Full HD(17:9)<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">File Size<\/div>\n\t<div class=\"col-span-6\">2048 x 1080<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Frame Rate<\/div>\n\t<div class=\"col-span-6\">119.8p\r<br>100p\r<br>59.94p\r<br>50p\r<br>48p\r<br>47.95p\r<br>29.97p\r<br>25p\r<br>24p\r<br>23.98p\r<br>22p<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Bitrate<\/div>\n\t<div class=\"col-span-6\">720Mbps\r<br>360Mbps\r<br>200Mbps\r<br>100Mbps\r<br>50Mbps\r<br>All Intra: Only available at 720 Mbps and 360 Mbps<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Full HD(16:9)<\/div>\n\t<div class=\"col-span-6\"> <div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">File Size<\/div>\n\t<div class=\"col-span-6\">1920 x 1080<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Frame Rate<\/div>\n\t<div class=\"col-span-6\">119.8p\r<br>100p\r<br>59.94p\r<br>50p\r<br>48p\r<br>47.95p\r<br>29.97p\r<br>25p\r<br>24p\r<br>23.98p\r<br>22p<\/div>\n<\/div><div class=\"grid grid-cols-8\">\n\t<div class=\"col-span-2\">Bitrate<\/div>\n\t<div class=\"col-span-6\">720Mbps\r<br>360Mbps\r<br>200Mbps\r<br>100Mbps\r<br>50Mbps\r<br>All Intra: Only available at 720 Mbps and 360 Mbps<\/div>\n<\/div><\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Proxy<\/div>\n\t<div class=\"col-span-6\"> H.264, ProRes Proxy, OFF<\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Notes<\/div>\n\t<div class=\"col-span-6\"> *Selectable mode will be changed depending on the &#8220;Image Format&#8221; setting.\r<br>*For recording movies, use a CFexpress Type B card or SD memory card with UHS Speed Class 3 or higher.\r<br>*For recording movies in 360Mbps, use a CFexpress Type B card or SD memory card with Video Speed Class 60 or higher.\r<br>*For recording movies in 720Mbps, use a CFexpress Type B card or SD memory card with Video Speed Class 90 or higher.\r<br>*PROJECT FPS cannot be set above the maximum RECORDING FPS.\r<br>*Selectable bitrate will be changed depends on the setting.\r<br>*Apple ProRes codec can be only recorded to CFexpress Type B card\r<br>*Bitrate for Apple ProRes codec is not selectable.\r<br>*Recording time can become short depending on the temperature and\/or shooting conditions<\/div><\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-repeater-grid\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Film Simulation Mode<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\"><div>20 modes<\/div><div>PROVIA\/Standard<\/div><div>Velvia\/Vivid<\/div><div>ASTIA\/Soft<\/div><div>Classic Chrome<\/div><div>REALA ACE<\/div><div>PRO Neg.Hi<\/div><div>PRO Neg.Std<\/div><div>Classic Neg.<\/div><div>Nostalgic Neg.<\/div><div>ETERNA\/Cinema<\/div><div>ETERNA BLEACH BYPASS<\/div><div>ACROS<\/div><div>ACROS + Ye Filter<\/div><div>ACROS + R Filter<\/div><div>ACROS + G Filter<\/div><div>Black &amp; White<\/div><div>Black &amp; White + Ye Filter<\/div><div>Black &amp; White + R Filter<\/div><div>Black &amp; White + G Filter<\/div><div>Sepia<\/div><\/div>\n\t<\/div>\t<div class=\"camera-specifications__block specs-three-level white-balance\">\n\t\t<h6>White Balance<\/h6>\n\t\t<div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Auto<\/div>\n\t<div class=\"col-span-6\"> White Priority\r<br>Auto\r<br>Ambience Priority<\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Custom<\/div>\n\t<div class=\"col-span-6\"> Custom<\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Color Temperature Selection<\/div>\n\t<div class=\"col-span-6\"> 2000K~11000K,CC(-16.00~+16.00)<\/div><\/div>\n\t<\/div><div class=\"camera-specifications__block specs-two-level wireless-transmitter\">\n\t<h6>Wireless Transmitter<\/h6>\n\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">Standard<\/div><div class=\"col-span-6\">IEEE802.11a\/b\/g\/n\/ac (standard wireless protocol)<\/div><div class=\"col-span-2\">Encryption<\/div><div class=\"col-span-6\">WPA2, WPA3<\/div><div class=\"col-span-2\">Access Mode<\/div><div class=\"col-span-6\">Infrastructure mode<\/div>\n\t<\/div>\n<\/div><div class=\"camera-specifications__block specs-two-level bluetooth\">\n\t<h6>Bluetooth\u00ae<\/h6>\n\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">Standartd<\/div><div class=\"col-span-6\">Bluetooth Ver. 4.2 (Bluetooth low energy)<\/div><div class=\"col-span-2\">Operating Frequency (Center Frequency)<\/div><div class=\"col-span-6\">2402\u301c2480MHz<\/div>\n\t<\/div>\n<\/div><div class=\"camera-specifications__block specs-two-level terminal\">\n\t<h6>Terminal<\/h6>\n\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">Digital Interface<\/div><div class=\"col-span-6\">USB Type-C\u00ae<\/div><div class=\"col-span-2\">HDMI Output<\/div><div class=\"col-span-6\">HDMI OUT connector (Type A)<\/div><div class=\"col-span-2\">LAN Terminal<\/div><div class=\"col-span-6\">LAN connector  1000BASE-T\u3001100BASE-TX\u300110BASE-T<\/div><div class=\"col-span-2\">Others<\/div><div class=\"col-span-6\">\u00f83.5mm,stereo mini connector (Microphone)\r<br>\u00f83.5mm, stereo mini connector (Headphone)\r<br>\u00f82.5mm,connector (Remote Release )\r<br>TC IN\/TC OUT connector\r<br>GenLock connector\r<br>12G SDI OUT connector:max 4K59.94p 12G\/6G\/3G\r<br>LENS connector(12-pin) :Power supply 14V-0.5A\r<br>V-mount battery attachment terminal \r<br>Handle connection terminal\r<br>DC OUT 12V connector :2-pin LEMO :12V 3A\r<br>LCD monitor cable connector\r<br>DC IN connector:4-pin for AC-15VS<\/div>\n\t<\/div>\n<\/div>\t<div class=\"camera-specifications__block specs-three-level power-supply\">\n\t\t<h6>Power Supply<\/h6>\n\t\t<div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Power Supply<\/div>\n\t<div class=\"col-span-6\"> NP-W235 Li-ion battery (included)\r<br>DC IN:AC-15VS AC power adapter (included)\r<br>V-mount battery<\/div><\/div>\n\t<\/div>\t<div class=\"camera-specifications__block specs-three-level dimensions\">\n\t\t<h6>Dimensions<\/h6>\n\t\t<div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Width<\/div>\n\t<div class=\"col-span-6\"> 110.8mm<\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Height<\/div>\n\t<div class=\"col-span-6\"> 138.2mm<\/div><\/div><div class=\"camera-specifications__block grid grid-cols-8\">\n\t<div class=\"col-span-2\">Depth<\/div>\n\t<div class=\"col-span-6\"> 176.8mm<\/div><\/div>\n\t<\/div><div class=\"camera-specifications__block specs-two-level weight\">\n\t<h6>Weight<\/h6>\n\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">Excluding Battery And Memory Card<\/div><div class=\"col-span-6\">Approx. 2.0kg<\/div>\n\t<\/div>\n<\/div><div class=\"camera-specifications__block specs-two-level operation-environment\">\n\t<h6>Operation Environment<\/h6>\n\t<div class=\"grid grid-cols-8\">\n\t\t<div class=\"col-span-2\">Operating Temperature<\/div><div class=\"col-span-6\">-10\u2103\uff5e+40\u2103<\/div><div class=\"col-span-2\">Operating Humidity<\/div><div class=\"col-span-6\">10% &#8211; 80% (no condensation)<\/div>\n\t<\/div>\n<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Power Consumption<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">Standard power consumption\uff1a21W\r<br>With lens, 4K 16:9, 59.94P, ProRes HQ, cooling fan Auto1,\r<br>excluding accessories other than the LCD monitor and handle.\r<br>Maximum power consumption\uff1a49W\r<br>With lens, 4K 16:9, 59.94P, ProRes HQ, cooling fan High,\r<br>including accessories, DC OUT 12V not connected.<\/div>\n\t<\/div>\t<div class=\"camera-specifications__block grid grid-cols-8 specs-single\">\n\t\t<div class=\"col-span-2\">\n\t\t\t<h6>Accessories Included<\/h6>\n\t\t<\/div>\n\t\t<div class=\"col-span-6\">Li-ion battery NP-W235\r<br>AC power adapter AC-15VS\r<br>AC cable\r<br>Body cap\r<br>Handle\r<br>LCD Monitor\r<br>LCD Monitor hood\r<br>LCD attachment\r<br>PL-Mount Adapter<\/div>\n\t<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"author":13,"featured_media":0,"parent":288639,"menu_order":0,"template":"","category":[],"products_category":[11538],"class_list":["post-288659","camera","type-camera","status-publish","hentry","products_category-specifications"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":[],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera\/288659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera"}],"about":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/types\/camera"}],"author":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/users\/13"}],"version-history":[{"count":0,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera\/288659\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera\/288639"}],"wp:attachment":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media?parent=288659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/category?post=288659"},{"taxonomy":"products_category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/products_category?post=288659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":277947,"date":"2025-06-15T02:40:18","date_gmt":"2025-06-15T02:40:18","guid":{"rendered":"https:\/\/www.fujifilm-x.com\/?post_type=camera&#038;p=277947"},"modified":"2025-06-16T01:09:39","modified_gmt":"2025-06-16T01:09:39","slug":"x-e5","status":"publish","type":"camera","link":"https:\/\/www.fujifilm-x.com\/it-it\/products\/cameras\/x-e5\/","title":{"rendered":"X-E5"},"content":{"rendered":"\n<h1 class=\"wp-block-heading hidden-heading\">X-E5<\/h1>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\t<div id=\"block_54e6a73d0fa81d1c423660f31daa2076\" class=\"wp-block wp-block-slider wp-block-slider--hero swiper alignfull\">\n\t\t<div class=\"swiper-wrapper\" data-settings='{\"autoplay\":false,\"autoplaySpeed\":\"5000\",\"speed\":500,\"effect\":\"fade\"}'>\n\t\t\t\n\t\t\t\t<div class=\"image-layer-container absolute top-0 left-0 right-0 z-10 pointer-events-none m-auto max-w-fujifilm w-full h-full py-8 md:py-12 px-5 md:px-8 h-mob-center h-center v-mob-middle v-middle\">\n\t\t\t\t\t<img decoding=\"async\" width=\"249\" height=\"44\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/x-e5logo-ef75c1dd-bd31-4f9e-8fe2-ac3f4e329bb0.png?width=249&amp;height=44\" class=\"attachment-medium_large size-medium_large\" alt=\"Image Logo\" loading=\"eager\" fetchpriority=\"high\" \/>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\n\t<figure class=\"swiper-slide\">\n\t\t<picture >\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"not all and (min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Top-Image_mobile-2ec9d737-e8a0-4295-8a61-ba7e76914f24.png?width=640&#038;height=854&#038;quality=85&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_1\" data-slider-device=\"mobile\"\t\t\t\t\/>\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_top-image-a4ee0239-e593-4069-b764-5194a60f66e9.webp?width=2560&#038;height=980&#038;quality=85&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_1\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_top-image-a4ee0239-e593-4069-b764-5194a60f66e9.webp?width=2560&#038;height=980&#038;quality=85&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"slide--container__img w-full object-cover position-mob-center position-center-bottom\"\t\t\t\t\t\t\t\t\talt=\"X-E5 Image\"\t\t\t\t\t\t\t\t\twidth=\"2560\"\t\t\t\t\t\t\t\t\theight=\"980\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_1\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t<\/figure>\n\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n\n\n<div id=\"block_7e7207a995b745e5f74fe9e3d08ae3db\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_7e7207a995b745e5f74fe9e3d08ae3db.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_7e7207a995b745e5f74fe9e3d08ae3db.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group alignfull fade-up-parallax is-layout-constrained wp-container-core-group-is-layout-49dd7d7c wp-block-group-is-layout-constrained\" style=\"padding-top:0;padding-right:var(--wp--preset--spacing--50);padding-bottom:0;padding-left:var(--wp--preset--spacing--50)\">\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-1d6f4e6b wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center\">The Refined Classic<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity faded-separator\"\/>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<p class=\"has-text-align-center\">Un classico moderno non pu\u00f2 limitarsi a replicare il passato, n\u00e9 tantomeno ignorarlo. Deve raccoglierne l\u2019eredit\u00e0, innovandone i concetti senza mai tradirne l\u2019essenza. FUJIFILM X-E5 incarna il significato di un classico moderno, combinando un design sofisticato ed elegante con controlli analogici che sanno ispirare le menti creative.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><\/p>\n<\/div>\n\n\n\n<div id=\"block_7e7207a995b745e5f74fe9e3d08ae3db\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_7e7207a995b745e5f74fe9e3d08ae3db.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_7e7207a995b745e5f74fe9e3d08ae3db.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group alignfull has-background is-layout-flow wp-block-group-is-layout-flow\" style=\"background:linear-gradient(45deg,rgb(164,175,187) 0%,rgb(205,214,221) 55%)\">\n<div class=\"banner-parallax-container relative overflow-hidden w-full p-0\">\n\t<div id=\"block_22fe3ee5459b9a2433a193fca5f818bf\"\n\t\tclass=\"wp-block block-banner-parallax h-full w-full py-16 md:py-24 overflow-hidden px-5 md:px-8 relative\"\n\t\tstyle=\"background-image:url(https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_overlay-parallax-image-clipped2c2743e7-78a0-4653-921a-404c3f06174.png?width=1613&#038;height=827)\">\n\t\t\t<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div id=\"block_3715d7c663d0d3748d92f36abf8cfd76\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_3715d7c663d0d3748d92f36abf8cfd76.wp-block-spacer {\n        height: 60px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_3715d7c663d0d3748d92f36abf8cfd76.wp-block-spacer {\n            height: 38px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-fujifilm-youtube-modal alignfull product-youtube-mod\"><div class=\"block-video-player py-5 md:py-10\"><div class=\"max-w-[800px] m-auto w-full relative fade-up-parallax\"><div class=\"block-video-player__splash-img aspect-w-16 aspect-h-9 js-btn--modal-youtube\" data-id=\"hDczjEDMB9Q\"><img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_youtube-thumbnail-469b300f-5531-4936-9f64-e4b5a1471d5c.webp\" alt=\"X-E5_youtube-thumbnail-469b300f-5531-4936-9f64-e4b5a1471d5c\" loading=\"lazy\" data-recalc-dims=\"1\"\/><span class=\"play-button\"><\/span><\/div><\/div><div class=\"modal modal--youtube hidden\" data-id=\"hDczjEDMB9Q\"><div class=\"modal__content relative\"><button class=\"btn-modal-close\" data-id=\"hDczjEDMB9Q\"><span><\/span><span><\/span><\/button><figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\"><div id=\"player-hDczjEDMB9Q\" data-id=\"hDczjEDMB9Q\" class=\"youtube-iframe\"><\/div><\/div><\/figure><\/div><\/div><\/div><\/div>\n\n\n\n<div id=\"block_3715d7c663d0d3748d92f36abf8cfd76\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_3715d7c663d0d3748d92f36abf8cfd76.wp-block-spacer {\n        height: 60px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_3715d7c663d0d3748d92f36abf8cfd76.wp-block-spacer {\n            height: 38px;       \n        }\n    }\n<\/style>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull fade-up-parallax is-layout-flow wp-block-group-is-layout-flow\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-6fdff0fd wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center\">Design<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity faded-separator\"\/>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<p class=\"has-text-align-center\">Realizzata interamente in alluminio lavorato, la piastra superiore conserva l&#8217;essenza di una fotocamera classica con il suo design minimal.<br>Questo aspetto straordinario si unisce a una maneggevolezza tattile per creare una fotocamera piacevole da usare.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull is-layout-constrained wp-container-core-group-is-layout-741f6d8e wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<div id=\"block_ead3b654b9f3b4d71596ad149deff960\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_ead3b654b9f3b4d71596ad149deff960.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_ead3b654b9f3b4d71596ad149deff960.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-columns has-spacing-extra-large has-no-design fade-up-parallax is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column first-one is-layout-constrained wp-block-column-is-layout-constrained\">\n<figure class=\"wp-block-image alignwide size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1689\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_top-plate-f8f35542-3e8c-49cc-97cb-c96185f7ca47.webp?width=2560&#038;height=1689\" alt=\"\" class=\"wp-image-276808\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_top-plate-f8f35542-3e8c-49cc-97cb-c96185f7ca47.webp?width=2560 2560w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_top-plate-f8f35542-3e8c-49cc-97cb-c96185f7ca47.webp?width=300&amp;height=198 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_top-plate-f8f35542-3e8c-49cc-97cb-c96185f7ca47.webp?width=1024&amp;height=676 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_top-plate-f8f35542-3e8c-49cc-97cb-c96185f7ca47.webp?width=768&amp;height=507 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_top-plate-f8f35542-3e8c-49cc-97cb-c96185f7ca47.webp?width=1536&amp;height=1013 1536w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_top-plate-f8f35542-3e8c-49cc-97cb-c96185f7ca47.webp?width=2048&amp;height=1351 2048w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_top-plate-f8f35542-3e8c-49cc-97cb-c96185f7ca47.webp?width=400&amp;height=264 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_top-plate-f8f35542-3e8c-49cc-97cb-c96185f7ca47.webp?width=365&amp;height=241 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_top-plate-f8f35542-3e8c-49cc-97cb-c96185f7ca47.webp?width=600&amp;height=396 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_top-plate-f8f35542-3e8c-49cc-97cb-c96185f7ca47.webp?width=1152&amp;height=760 1152w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_top-plate-f8f35542-3e8c-49cc-97cb-c96185f7ca47.webp?width=717&amp;height=473 717w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-bottom second-one is-content-justification-center is-layout-constrained wp-block-column-is-layout-constrained\">\n<h2 class=\"wp-block-heading mb-1.5\">Piastra superiore in alluminio lavorato<\/h2>\n\n\n\n<p>La piastra superiore che \u00e8 ricavata da un unico pezzo di metallo, non solo esalta il design e la sensazione tattile di FUJIFILM X-E5, ma migliora anche la funzionalit\u00e0 della ghiera. Inoltre, la finitura anodizzata conferisce al corpo macchina un&#8217;estetica raffinata e di alta qualit\u00e0.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div id=\"block_ead3b654b9f3b4d71596ad149deff960\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_ead3b654b9f3b4d71596ad149deff960.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_ead3b654b9f3b4d71596ad149deff960.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-columns has-spacing-extra-large has-no-design fade-up-parallax is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-bottom second-one is-content-justification-center is-layout-constrained wp-block-column-is-layout-constrained\">\n<h2 class=\"wp-block-heading mb-1.5\">Nuova ghiera Simulazione Pellicola<\/h2>\n\n\n\n<p>La ghiera di Simulazione Pellicola di nuova concezione presenta un indicatore visivo intagliato con precisione che riduce al minimo lo spazio tra la ghiera e il corpo macchina per una finitura impeccabile. Inoltre, \u00e8 possibile impostare singolarmente la Simulazione Pellicola e le impostazioni di qualit\u00e0 dell&#8217;immagine sulle posizioni FS1-FS3, consentendo di salvare le proprie ricette FS.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column first-one is-layout-constrained wp-block-column-is-layout-constrained\">\n<figure class=\"wp-block-image alignwide size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1690\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_film-simulation-dial-0ed1fdf8-3002-40b0-ba76-ded161d2feee.webp?width=2560&#038;height=1690\" alt=\"\" class=\"wp-image-276805\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_film-simulation-dial-0ed1fdf8-3002-40b0-ba76-ded161d2feee.webp?width=2560 2560w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_film-simulation-dial-0ed1fdf8-3002-40b0-ba76-ded161d2feee.webp?width=300&amp;height=198 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_film-simulation-dial-0ed1fdf8-3002-40b0-ba76-ded161d2feee.webp?width=1024&amp;height=676 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_film-simulation-dial-0ed1fdf8-3002-40b0-ba76-ded161d2feee.webp?width=768&amp;height=507 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_film-simulation-dial-0ed1fdf8-3002-40b0-ba76-ded161d2feee.webp?width=1536&amp;height=1014 1536w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_film-simulation-dial-0ed1fdf8-3002-40b0-ba76-ded161d2feee.webp?width=2048&amp;height=1352 2048w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_film-simulation-dial-0ed1fdf8-3002-40b0-ba76-ded161d2feee.webp?width=400&amp;height=264 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_film-simulation-dial-0ed1fdf8-3002-40b0-ba76-ded161d2feee.webp?width=365&amp;height=241 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_film-simulation-dial-0ed1fdf8-3002-40b0-ba76-ded161d2feee.webp?width=600&amp;height=396 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_film-simulation-dial-0ed1fdf8-3002-40b0-ba76-ded161d2feee.webp?width=1152&amp;height=761 1152w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_film-simulation-dial-0ed1fdf8-3002-40b0-ba76-ded161d2feee.webp?width=717&amp;height=473 717w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div id=\"block_ead3b654b9f3b4d71596ad149deff960\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_ead3b654b9f3b4d71596ad149deff960.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_ead3b654b9f3b4d71596ad149deff960.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-columns has-spacing-extra-large has-no-design fade-up-parallax is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column first-one is-layout-constrained wp-block-column-is-layout-constrained\">\n<figure class=\"wp-block-image alignwide size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1689\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_detail-27ab76b1-ae4d-4e58-80e0-01c1f3e6eacf.webp?width=2560&#038;height=1689\" alt=\"\" class=\"wp-image-276803\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_detail-27ab76b1-ae4d-4e58-80e0-01c1f3e6eacf.webp?width=2560 2560w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_detail-27ab76b1-ae4d-4e58-80e0-01c1f3e6eacf.webp?width=300&amp;height=198 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_detail-27ab76b1-ae4d-4e58-80e0-01c1f3e6eacf.webp?width=1024&amp;height=676 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_detail-27ab76b1-ae4d-4e58-80e0-01c1f3e6eacf.webp?width=768&amp;height=507 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_detail-27ab76b1-ae4d-4e58-80e0-01c1f3e6eacf.webp?width=1536&amp;height=1013 1536w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_detail-27ab76b1-ae4d-4e58-80e0-01c1f3e6eacf.webp?width=2048&amp;height=1351 2048w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_detail-27ab76b1-ae4d-4e58-80e0-01c1f3e6eacf.webp?width=400&amp;height=264 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_detail-27ab76b1-ae4d-4e58-80e0-01c1f3e6eacf.webp?width=365&amp;height=241 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_detail-27ab76b1-ae4d-4e58-80e0-01c1f3e6eacf.webp?width=600&amp;height=396 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_detail-27ab76b1-ae4d-4e58-80e0-01c1f3e6eacf.webp?width=1152&amp;height=760 1152w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_detail-27ab76b1-ae4d-4e58-80e0-01c1f3e6eacf.webp?width=717&amp;height=473 717w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-bottom second-one is-content-justification-center is-layout-constrained wp-block-column-is-layout-constrained\">\n<h2 class=\"wp-block-heading mb-1.5\">Padroneggiare i dettagli<\/h2>\n\n\n\n<p>La raffinatezza \u00e8 al centro di ogni aspetto del design di FUJIFILM X-E5. Il mirino e il comando di regolazione diottrica, ad esempio, si integrano perfettamente nel corpo macchina, mentre il pulsante Bluetooth sulla base della fotocamera richiama l&#8217;aspetto del pulsante di riavvolgimento di una classica macchina fotografica a pellicola.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div id=\"block_ead3b654b9f3b4d71596ad149deff960\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_ead3b654b9f3b4d71596ad149deff960.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_ead3b654b9f3b4d71596ad149deff960.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group fade-up-parallax is-layout-flow wp-block-group-is-layout-flow\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-1d6f4e6b wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center\">The Joy of Photography<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity faded-separator\"\/>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<p class=\"has-text-align-center\">FUJIFILM X-E5 non \u00e8 solo bella.<br>Offre anche un mirino mozzafiato e comandi analogici intuitivi<br>Questa \u00e8 una fotocamera progettata per regalare gioia alla tua creativit\u00e0.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><\/p>\n\n\n\n<p class=\"has-text-align-center\"><\/p>\n<\/div>\n\n\n\n<div id=\"block_ead3b654b9f3b4d71596ad149deff960\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_ead3b654b9f3b4d71596ad149deff960.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_ead3b654b9f3b4d71596ad149deff960.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group alignfull is-layout-constrained wp-container-core-group-is-layout-741f6d8e wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<div class=\"wp-block-columns has-spacing-extra-large has-no-design fade-up-parallax is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column first-one is-layout-constrained wp-block-column-is-layout-constrained\">\n<figure class=\"wp-block-image alignwide size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"960\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Classic-Display-87a3119f-3316-43c4-a0df-7fc8b065c07b.webp?width=1280&#038;height=960\" alt=\"\" class=\"wp-image-276802\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Classic-Display-87a3119f-3316-43c4-a0df-7fc8b065c07b.webp?width=1280 1280w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Classic-Display-87a3119f-3316-43c4-a0df-7fc8b065c07b.webp?width=300&amp;height=225 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Classic-Display-87a3119f-3316-43c4-a0df-7fc8b065c07b.webp?width=1024&amp;height=768 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Classic-Display-87a3119f-3316-43c4-a0df-7fc8b065c07b.webp?width=768&amp;height=576 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Classic-Display-87a3119f-3316-43c4-a0df-7fc8b065c07b.webp?width=400&amp;height=300 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Classic-Display-87a3119f-3316-43c4-a0df-7fc8b065c07b.webp?width=365&amp;height=274 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Classic-Display-87a3119f-3316-43c4-a0df-7fc8b065c07b.webp?width=600&amp;height=450 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Classic-Display-87a3119f-3316-43c4-a0df-7fc8b065c07b.webp?width=1152&amp;height=864 1152w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Classic-Display-87a3119f-3316-43c4-a0df-7fc8b065c07b.webp?width=717&amp;height=538 717w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-bottom second-one is-content-justification-center is-layout-constrained wp-block-column-is-layout-constrained\">\n<h2 class=\"wp-block-heading mb-1.5\">Nuova modalit\u00e0 Classic Display<\/h2>\n\n\n\n<p>La nuova modalit\u00e0 Classic Display* nel mirino offre un&#8217;immagine nitida con le informazioni chiave nella parte inferiore dell&#8217;inquadratura. In combinazione con un design che consente di utilizzare le ghiere e la leva con una sola mano, \u00e8 possibile immergersi nella creazione di immagini guardando nell&#8217;oculare del mirino.<\/p>\n\n\n\n<p><sub>*Disponibile solo su EVF<\/sub><\/p>\n<\/div>\n<\/div>\n\n\n\n<div id=\"block_ead3b654b9f3b4d71596ad149deff960\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_ead3b654b9f3b4d71596ad149deff960.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_ead3b654b9f3b4d71596ad149deff960.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-columns has-spacing-extra-large has-no-design fade-up-parallax is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-bottom second-one is-content-justification-center is-layout-constrained wp-block-column-is-layout-constrained\">\n<h2 class=\"wp-block-heading mb-1.5\">Modalit\u00e0 Surround View<\/h2>\n\n\n\n<p>La leva di controllo anteriore di FUJIFILM X-E5 consente di accedere alla funzione Surround View, che mostra con un\u2019area semitrasparente, o con una cornice, l&#8217;area esterna all&#8217;inquadratura. Questo offre un&#8217;esperienza simile a quella di un OVF, consentendo di vedere oltre l&#8217;inquadratura del mirino elettronico, in modo da poter monitorare la scena circostante.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column first-one is-layout-constrained wp-block-column-is-layout-constrained\">\n<figure class=\"wp-block-image alignwide size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"960\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Surround-View-Mode-8f747cd3-5816-46d7-bd6e-15b37b4b108a.webp?width=1440&#038;height=960\" alt=\"\" class=\"wp-image-276806\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Surround-View-Mode-8f747cd3-5816-46d7-bd6e-15b37b4b108a.webp?width=1440 1440w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Surround-View-Mode-8f747cd3-5816-46d7-bd6e-15b37b4b108a.webp?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Surround-View-Mode-8f747cd3-5816-46d7-bd6e-15b37b4b108a.webp?width=1024&amp;height=683 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Surround-View-Mode-8f747cd3-5816-46d7-bd6e-15b37b4b108a.webp?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Surround-View-Mode-8f747cd3-5816-46d7-bd6e-15b37b4b108a.webp?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Surround-View-Mode-8f747cd3-5816-46d7-bd6e-15b37b4b108a.webp?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Surround-View-Mode-8f747cd3-5816-46d7-bd6e-15b37b4b108a.webp?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Surround-View-Mode-8f747cd3-5816-46d7-bd6e-15b37b4b108a.webp?width=1152&amp;height=768 1152w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Surround-View-Mode-8f747cd3-5816-46d7-bd6e-15b37b4b108a.webp?width=717&amp;height=478 717w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div id=\"block_ead3b654b9f3b4d71596ad149deff960\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_ead3b654b9f3b4d71596ad149deff960.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_ead3b654b9f3b4d71596ad149deff960.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-columns has-spacing-extra-large has-no-design fade-up-parallax is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column first-one is-layout-constrained wp-block-column-is-layout-constrained\">\n<figure class=\"wp-block-image alignwide size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Evolved-Mobility_KV-d097b463-4bcb-4691-95e4-70f109d8844b.webp?width=1620&#038;height=1080\" alt=\"\" class=\"wp-image-276804\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Evolved-Mobility_KV-d097b463-4bcb-4691-95e4-70f109d8844b.webp?width=1620 1620w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Evolved-Mobility_KV-d097b463-4bcb-4691-95e4-70f109d8844b.webp?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Evolved-Mobility_KV-d097b463-4bcb-4691-95e4-70f109d8844b.webp?width=1024&amp;height=683 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Evolved-Mobility_KV-d097b463-4bcb-4691-95e4-70f109d8844b.webp?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Evolved-Mobility_KV-d097b463-4bcb-4691-95e4-70f109d8844b.webp?width=1536&amp;height=1024 1536w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Evolved-Mobility_KV-d097b463-4bcb-4691-95e4-70f109d8844b.webp?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Evolved-Mobility_KV-d097b463-4bcb-4691-95e4-70f109d8844b.webp?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Evolved-Mobility_KV-d097b463-4bcb-4691-95e4-70f109d8844b.webp?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Evolved-Mobility_KV-d097b463-4bcb-4691-95e4-70f109d8844b.webp?width=1152&amp;height=768 1152w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/X-E5_Evolved-Mobility_KV-d097b463-4bcb-4691-95e4-70f109d8844b.webp?width=717&amp;height=478 717w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-bottom second-one is-content-justification-center is-layout-constrained wp-block-column-is-layout-constrained\">\n<h2 class=\"wp-block-heading mb-1.5\">Mobilit\u00e0 evoluta<\/h2>\n\n\n\n<p>Pur mantenendo dimensioni simili al modello predecessore, X-E5 \u00e8 la prima fotocamera della serie a essere dotata di un potente meccanismo IBIS a cinque assi che offre fino a 7,0 stop al centro e 6,0 stop in periferia*. Questo la rende una fotocamera &#8220;da portare con s\u00e9 ogni giorno&#8221;, comoda e adattabile anche agli scenari pi\u00f9 impegnativi.<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><sub>*In base agli standard CIPA 2024. Prestazioni di correzione di imbardata\/beccheggio\/rollio con obiettivo FUJINON XF35mmF1.4 R (venduto separatamente) <\/sub><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div id=\"block_7e7207a995b745e5f74fe9e3d08ae3db\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_7e7207a995b745e5f74fe9e3d08ae3db.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_7e7207a995b745e5f74fe9e3d08ae3db.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group alignfull fade-up-parallax is-layout-constrained wp-container-core-group-is-layout-0740b621 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-1d6f4e6b wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center\">See More, Tell More<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity faded-separator\"\/>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<p class=\"has-text-align-center\">Un design sofisticato.<br>Comandi intuitivi che ti mantengono immerso nella creazione delle immagini.<br>Dimensioni compatte che si adattano perfettamente alla tua mano.<br>Con FUJIFILM X-E5, scoprirai pi\u00f9 storie.<br>Racconta queste storie con la straordinaria qualit\u00e0 d&#8217;immagine della nostra tecnologia di quinta generazione.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><\/p>\n\n\n\n<p class=\"has-text-align-center\"><\/p>\n<\/div>\n\n\n\n<div id=\"block_7e7207a995b745e5f74fe9e3d08ae3db\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_7e7207a995b745e5f74fe9e3d08ae3db.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_7e7207a995b745e5f74fe9e3d08ae3db.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group alignfull px-6 md:px-8 is-layout-constrained wp-container-core-group-is-layout-c493854b wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns has-spacing-extra-large has-no-design fade-up-parallax full-height-col is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column tech-module parallax-item has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"background-color:#0f141c\">\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2024\/05\/x-trans-5-1024x74-1-1.png\" alt=\"\" class=\"wp-image-117705\" style=\"width:380px\" data-recalc-dims=\"1\"\/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center has-white-color has-text-color has-link-color wp-elements-f82f2b88c129d827d9f2787fc557f5fc\">High-Resolution 40.2MP BSI Imaging Sensor<\/h4>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2024\/05\/x-trans-4.png\" alt=\"\" class=\"wp-image-117612\" style=\"width:280px\" data-recalc-dims=\"1\"\/><\/figure>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-link-color wp-elements-707799f33f76a5769c7d2ef089f14d84\">The high-resolution 40.2MP X-Trans CMOS 5 HR sensor has an enhanced image-processing algorithm that boosts resolution without compromising the signal-to-noise ratio, delivering astonishing image quality.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-container-core-buttons-is-layout-6b4e3324 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-100\"><a class=\"wp-block-button__link has-white-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/x-trans-cmos\/\" style=\"background:linear-gradient(90deg,rgb(255,255,255) 0%,rgb(0,0,0) 100%)\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-white-color\">Learn more<\/mark><\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column tech-module parallax-item has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"background-color:#0f141c\">\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2024\/05\/x-processor-5-1024x101-1-1.png\" alt=\"\" class=\"wp-image-117706\" style=\"width:292px\" data-recalc-dims=\"1\"\/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center has-white-color has-text-color has-link-color wp-elements-85fc8167f8759533a177d24405a65381\">Twice the processing speed of X-Processor 4<\/h4>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2024\/05\/x-processor-3.png\" alt=\"\" class=\"wp-image-117611\" style=\"width:280px\" data-recalc-dims=\"1\"\/><\/figure>\n\n\n\n<p class=\"has-white-color has-text-color has-link-color wp-elements-c645e628e62f8fbab9d9726851472d16\"><\/p>\n\n\n\n<div class=\"wp-block-columns has-spacing-none has-no-design  tech-feature-table is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center has-white-color has-text-color has-link-color wp-elements-365f233b78d3d35c9fc9cfbb51124cb2\">AI processing technology<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center has-white-color has-text-color has-link-color wp-elements-8775cc289ef0f34ba48a562014d0be1f\">Next generation HEIF image file format<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center has-white-color has-text-color has-link-color wp-elements-acab9be2bc92b3c6ece41f88291baf7e\">Reduced power consumption<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div id=\"block_7e7207a995b745e5f74fe9e3d08ae3db\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_7e7207a995b745e5f74fe9e3d08ae3db.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_7e7207a995b745e5f74fe9e3d08ae3db.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group alignfull is-layout-constrained wp-container-core-group-is-layout-741f6d8e wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<div class=\"wp-block-columns has-spacing-extra-large has-no-design fade-up-parallax is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-bottom second-one is-content-justification-center is-layout-constrained wp-block-column-is-layout-constrained\">\n<h2 class=\"wp-block-heading mb-1.5\">Sensibilit\u00e0 Nativa ISO 125<\/h2>\n\n\n\n<p>Il sensore X-Trans CMOS 5 HR di FUJIFILM X-E5 presenta una struttura dei pixel migliorata e ad alta efficienza luminosa. Questo consente di raggiungere un ISO nativo inferiore di 125, disponibile solo come opzione estesa sul modello precedente.<\/p>\n\n\n\n<div id=\"block_b0db025402e24bf2aa56e376dec1caba\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_b0db025402e24bf2aa56e376dec1caba.wp-block-spacer {\n        height: 24px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_b0db025402e24bf2aa56e376dec1caba.wp-block-spacer {\n            height: 0px;       \n        }\n    }\n<\/style>\n<\/div>\n\n\n\n<div class=\"wp-block-column first-one is-layout-constrained wp-block-column-is-layout-constrained\">\n<figure class=\"wp-block-image alignwide size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/ISO125_Derrick-Ong-scaled.jpg?width=2560&#038;height=1707\" alt=\"\" class=\"wp-image-276350\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/ISO125_Derrick-Ong-scaled.jpg?width=2560 2560w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/ISO125_Derrick-Ong-scaled.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/ISO125_Derrick-Ong-scaled.jpg?width=1024&amp;height=683 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/ISO125_Derrick-Ong-scaled.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/ISO125_Derrick-Ong-scaled.jpg?width=1536&amp;height=1024 1536w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/ISO125_Derrick-Ong-scaled.jpg?width=2048&amp;height=1365 2048w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/ISO125_Derrick-Ong-scaled.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/ISO125_Derrick-Ong-scaled.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/ISO125_Derrick-Ong-scaled.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/ISO125_Derrick-Ong-scaled.jpg?width=1152&amp;height=768 1152w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/ISO125_Derrick-Ong-scaled.jpg?width=717&amp;height=478 717w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\"><sub>\u00a9Derrick Ong<\/sub><\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div id=\"block_ead3b654b9f3b4d71596ad149deff960\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_ead3b654b9f3b4d71596ad149deff960.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_ead3b654b9f3b4d71596ad149deff960.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-columns has-spacing-extra-large has-no-design fade-up-parallax is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column first-one is-layout-constrained wp-block-column-is-layout-constrained\">\n<figure class=\"wp-block-image alignwide size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1921\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/SN-Level_Low-Light-Power_Luo-Fei-scaled.jpg?width=2560&#038;height=1921\" alt=\"\" class=\"wp-image-276346\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/SN-Level_Low-Light-Power_Luo-Fei-scaled.jpg?width=2560 2560w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/SN-Level_Low-Light-Power_Luo-Fei-scaled.jpg?width=300&amp;height=225 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/SN-Level_Low-Light-Power_Luo-Fei-scaled.jpg?width=1024&amp;height=769 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/SN-Level_Low-Light-Power_Luo-Fei-scaled.jpg?width=768&amp;height=576 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/SN-Level_Low-Light-Power_Luo-Fei-scaled.jpg?width=1536&amp;height=1153 1536w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/SN-Level_Low-Light-Power_Luo-Fei-scaled.jpg?width=2048&amp;height=1537 2048w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/SN-Level_Low-Light-Power_Luo-Fei-scaled.jpg?width=400&amp;height=300 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/SN-Level_Low-Light-Power_Luo-Fei-scaled.jpg?width=365&amp;height=274 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/SN-Level_Low-Light-Power_Luo-Fei-scaled.jpg?width=600&amp;height=450 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/SN-Level_Low-Light-Power_Luo-Fei-scaled.jpg?width=1152&amp;height=865 1152w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/SN-Level_Low-Light-Power_Luo-Fei-scaled.jpg?width=717&amp;height=538 717w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\"><sub>\u00a9Luo Fei<\/sub><\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-bottom second-one is-content-justification-center is-layout-constrained wp-block-column-is-layout-constrained\">\n<h2 class=\"wp-block-heading mb-1.5\">S\/N Level &amp; Low-Light Power<\/h2>\n\n\n\n<p>Il sensore X-Trans CMOS 5 HR ad alta risoluzione da 40,2 MP \u00e8 dotato di un algoritmo di elaborazione delle immagini migliorato che migliora la risoluzione senza compromettere il rapporto segnale\/rumore. Una qualit\u00e0 d&#8217;immagine straordinaria nel palmo della tua mano.<\/p>\n\n\n\n<div id=\"block_b0db025402e24bf2aa56e376dec1caba\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_b0db025402e24bf2aa56e376dec1caba.wp-block-spacer {\n        height: 24px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_b0db025402e24bf2aa56e376dec1caba.wp-block-spacer {\n            height: 0px;       \n        }\n    }\n<\/style>\n<\/div>\n<\/div>\n\n\n\n<div id=\"block_ead3b654b9f3b4d71596ad149deff960\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_ead3b654b9f3b4d71596ad149deff960.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_ead3b654b9f3b4d71596ad149deff960.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-columns has-spacing-extra-large has-no-design fade-up-parallax is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-bottom second-one is-content-justification-center is-layout-constrained wp-block-column-is-layout-constrained\">\n<h2 class=\"wp-block-heading mb-1.5\">Algoritmo AF aggiornato<\/h2>\n\n\n\n<p>FUJIFILM X-E5 integra un algoritmo predittivo dell&#8217;autofocus di alto livello per una messa a fuoco affidabile anche durante la ripresa di soggetti in continuo movimento. I miglioramenti dell&#8217;autofocus sono particolarmente evidenti in AF Zona e in situazioni a basso contrasto.<\/p>\n\n\n\n<div id=\"block_b0db025402e24bf2aa56e376dec1caba\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_b0db025402e24bf2aa56e376dec1caba.wp-block-spacer {\n        height: 24px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_b0db025402e24bf2aa56e376dec1caba.wp-block-spacer {\n            height: 0px;       \n        }\n    }\n<\/style>\n<\/div>\n\n\n\n<div class=\"wp-block-column first-one is-layout-constrained wp-block-column-is-layout-constrained\">\n<figure class=\"wp-block-image alignwide size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Updated-AF-Algorithm_Luo-Fei-scaled.jpg?width=2560&#038;height=1707\" alt=\"\" class=\"wp-image-276343\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Updated-AF-Algorithm_Luo-Fei-scaled.jpg?width=2560 2560w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Updated-AF-Algorithm_Luo-Fei-scaled.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Updated-AF-Algorithm_Luo-Fei-scaled.jpg?width=1024&amp;height=683 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Updated-AF-Algorithm_Luo-Fei-scaled.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Updated-AF-Algorithm_Luo-Fei-scaled.jpg?width=1536&amp;height=1024 1536w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Updated-AF-Algorithm_Luo-Fei-scaled.jpg?width=2048&amp;height=1365 2048w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Updated-AF-Algorithm_Luo-Fei-scaled.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Updated-AF-Algorithm_Luo-Fei-scaled.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Updated-AF-Algorithm_Luo-Fei-scaled.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Updated-AF-Algorithm_Luo-Fei-scaled.jpg?width=1152&amp;height=768 1152w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Updated-AF-Algorithm_Luo-Fei-scaled.jpg?width=717&amp;height=478 717w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\"><sub>\u00a9Luo Fei<\/sub><\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div id=\"block_ead3b654b9f3b4d71596ad149deff960\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_ead3b654b9f3b4d71596ad149deff960.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_ead3b654b9f3b4d71596ad149deff960.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-columns has-spacing-extra-large has-no-design fade-up-parallax is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column first-one is-layout-constrained wp-block-column-is-layout-constrained\">\n<figure class=\"wp-block-image alignwide size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/AI-AF_Dawn-Eagleton-scaled.jpg?width=2560&#038;height=1707\" alt=\"\" class=\"wp-image-276361\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/AI-AF_Dawn-Eagleton-scaled.jpg?width=2560 2560w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/AI-AF_Dawn-Eagleton-scaled.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/AI-AF_Dawn-Eagleton-scaled.jpg?width=1024&amp;height=683 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/AI-AF_Dawn-Eagleton-scaled.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/AI-AF_Dawn-Eagleton-scaled.jpg?width=1536&amp;height=1024 1536w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/AI-AF_Dawn-Eagleton-scaled.jpg?width=2048&amp;height=1365 2048w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/AI-AF_Dawn-Eagleton-scaled.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/AI-AF_Dawn-Eagleton-scaled.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/AI-AF_Dawn-Eagleton-scaled.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/AI-AF_Dawn-Eagleton-scaled.jpg?width=1152&amp;height=768 1152w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/AI-AF_Dawn-Eagleton-scaled.jpg?width=717&amp;height=478 717w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\"><sub>\u00a9Dawn Eagleton<\/sub><\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-bottom second-one is-content-justification-center is-layout-constrained wp-block-column-is-layout-constrained\">\n<h2 class=\"wp-block-heading mb-1.5\">Autofocus a Rilevamento del Soggetto<\/h2>\n\n\n\n<p>FUJIFILM X-E5 utilizza l&#8217;AF con rilevamento del soggetto di X-Processor 5 per inseguire con precisione una vasta gamma di soggetti. Sviluppato utilizzando la tecnologia di intelligenza artificiale deep-learning, rileva animali, uccelli, auto, moto, biciclette, aerei, treni, insetti e droni.*<\/p>\n\n\n\n<p><sub>*Impostare IMPOSTAZIONI DI RILEVAMENTO SOGGETTO su UCCELLO per il rilevamento di insetti e AEREO per il rilevamento di droni<\/sub><\/p>\n\n\n\n<div id=\"block_a2d4901f2b0a983141401ea4f923af17\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_a2d4901f2b0a983141401ea4f923af17.wp-block-spacer {\n        height: 28px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_a2d4901f2b0a983141401ea4f923af17.wp-block-spacer {\n            height: 0px;       \n        }\n    }\n<\/style>\n<\/div>\n<\/div>\n\n\n\n<div id=\"block_ead3b654b9f3b4d71596ad149deff960\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_ead3b654b9f3b4d71596ad149deff960.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_ead3b654b9f3b4d71596ad149deff960.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull text-white has-background is-layout-flow wp-block-group-is-layout-flow\" style=\"background-color:#0f141c;padding-top:var(--wp--preset--spacing--70);padding-right:0;padding-bottom:var(--wp--preset--spacing--70);padding-left:0\">\n<div class=\"wp-block-group fade-up-parallax wp-block-group--with-learn-more wp-block-group--with-learn-more--white is-layout-constrained wp-container-core-group-is-layout-4ee83bb8 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<h2 class=\"wp-block-heading has-text-align-center\">Simulazione Pellicola<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity faded-separator\"\/>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center\">Le 20 modalit\u00e0 di Simulazione Pellicola offerte da FUJIFILM X-E5, inclusa REALA ACE, sfruttano 90 anni di esperienza nella scienza colore di Fujifilm.<br>Scopri di pi\u00f9.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-link-color wp-elements-9f772a48ded743e1708849ee784ee2d3\" style=\"text-decoration:underline\"><a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/film-simulation\/\" target=\"_blank\" data-type=\"link\" data-id=\"https:\/\/www.fujifilm-x.com\/global\/products\/film-simulation\/\" rel=\"noreferrer noopener\">Learn more about Film Simulations<\/a><\/p>\n<\/div>\n\n\n\n<div id=\"block_3b780c2d0bf9ca3273200cbeb5523aed\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_3b780c2d0bf9ca3273200cbeb5523aed.wp-block-spacer {\n        height: 50px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_3b780c2d0bf9ca3273200cbeb5523aed.wp-block-spacer {\n            height: 30px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group fade-up-parallax is-layout-constrained wp-container-core-group-is-layout-d2968217 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1716\" height=\"650\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/03\/19.1film-simulaions.png?width=1716&#038;height=650\" alt=\"\" class=\"wp-image-264039\" style=\"object-fit:cover\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/03\/19.1film-simulaions.png?width=1716 1716w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/03\/19.1film-simulaions.png?width=300&amp;height=114 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/03\/19.1film-simulaions.png?width=1024&amp;height=388 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/03\/19.1film-simulaions.png?width=768&amp;height=291 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/03\/19.1film-simulaions.png?width=1536&amp;height=582 1536w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/03\/19.1film-simulaions.png?width=400&amp;height=152 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/03\/19.1film-simulaions.png?width=365&amp;height=138 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/03\/19.1film-simulaions.png?width=600&amp;height=227 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/03\/19.1film-simulaions.png?width=1152&amp;height=436 1152w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/03\/19.1film-simulaions.png?width=717&amp;height=272 717w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n<\/div>\n\n\n\n<div id=\"block_3b780c2d0bf9ca3273200cbeb5523aed\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_3b780c2d0bf9ca3273200cbeb5523aed.wp-block-spacer {\n        height: 50px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_3b780c2d0bf9ca3273200cbeb5523aed.wp-block-spacer {\n            height: 30px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group alignfull h-screen is-layout-constrained wp-block-group-is-layout-constrained\">\t<div id=\"block_7316d8f84d12b830bfe209705b8c24b6\" class=\"wp-block wp-block-slider wp-block-slider--full-width-caption swiper alignfull block relative overflow-hidden\">\n\t\t<div class=\"swiper-wrapper\" data-settings='{\"loop\":true,\"autoplay\":true,\"autoplaySpeed\":\"5000\",\"speed\":500,\"slidesPerView\":1,\"spaceBetween\":20,\"navigation\":{\"nextEl\":\".swiper-button-next\",\"prevEl\":\".swiper-button-prev\"},\"grabCursor\":true,\"breakpoints\":{\"768\":{\"spaceBetween\":32},\"1024\":{\"slidesPerView\":\"auto\",\"centeredSlides\":true,\"spaceBetween\":0}}}'>\n\t\t\t\t\t\t<div class=\"full-width-caption-slide--container swiper-slide\">\n\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__inner-content\">\n\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__image-container\">\n\t\t\t\t\t\t\t\n\t<figure class=\"swiper-slide__inner\">\n\t\t<picture class=\"aspect-ratio aspect-ratio--landscape\">\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Provia_Zao-Yanming-scaled.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_1\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Provia_Zao-Yanming-scaled.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"\"\t\t\t\t\t\t\t\t\talt=\"Image 1\"\t\t\t\t\t\t\t\t\twidth=\"800\"\t\t\t\t\t\t\t\t\theight=\"533\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_1\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t\t\t<figcaption class=\"text-extra-xs text-right mt-1.5 caption--landscape\">\n\t\t\t\t\u00a9Zao Yanming\t\t\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"150\" height=\"150\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/provia.webp?resize=150,150&amp;width=150&amp;height=150\" class=\"w-auto h-auto max-h-[90px] md:max-h-[130px] flex-shrink-0\" alt=\"\" loading=\"lazy\" decoding=\"async\" fetchpriority=\"low\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/provia.webp?width=150&amp;height=150 150w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/provia.webp?width=80&amp;height=80 80w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__content--inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"mb-1\">PROVIA\/STANDARD<\/h3>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Basata sulla pellicola invertibile FUJICHROME PROVIA, progettata per l&#8217;uso professionale, questa modalit\u00e0 di Simulazione Pellicola grazie alla sua riproduzione neutra dei colori, \u00e8 adatta a tutti i tipi di soggetto.<\/p>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"full-width-caption-slide--container swiper-slide\">\n\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__inner-content\">\n\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__image-container\">\n\t\t\t\t\t\t\t\n\t<figure class=\"swiper-slide__inner\">\n\t\t<picture class=\"aspect-ratio aspect-ratio--landscape\">\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Velvia_Yukio-Uchida.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_2\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Velvia_Yukio-Uchida.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"\"\t\t\t\t\t\t\t\t\talt=\"Image 2\"\t\t\t\t\t\t\t\t\twidth=\"800\"\t\t\t\t\t\t\t\t\theight=\"533\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_2\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t\t\t<figcaption class=\"text-extra-xs text-right mt-1.5 caption--landscape\">\n\t\t\t\t\u00a9Yukio Uchida\t\t\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"150\" height=\"150\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/velvia.webp?resize=150,150&amp;width=150&amp;height=150\" class=\"w-auto h-auto max-h-[90px] md:max-h-[130px] flex-shrink-0\" alt=\"\" loading=\"lazy\" decoding=\"async\" fetchpriority=\"low\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/velvia.webp?width=150&amp;height=150 150w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/velvia.webp?width=80&amp;height=80 80w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__content--inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"mb-1\">VELVIA\/VIVID<\/h3>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Basata su FUJICHROME Velvia, una pellicola invertibile ultra-vivida progettata per i professionisti, questa modalit\u00e0 di Simulazione Pellicola offre colori pi\u00f9 ricchi e contrastati rispetto alla PROVIA\/STANDARD. \u00c8 una delle preferite dai fotografi paesaggisti.<\/p>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"full-width-caption-slide--container swiper-slide\">\n\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__inner-content\">\n\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__image-container\">\n\t\t\t\t\t\t\t\n\t<figure class=\"swiper-slide__inner\">\n\t\t<picture class=\"aspect-ratio aspect-ratio--landscape\">\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Astia_Yukio-Uchida.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_3\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Astia_Yukio-Uchida.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"\"\t\t\t\t\t\t\t\t\talt=\"Image 3\"\t\t\t\t\t\t\t\t\twidth=\"800\"\t\t\t\t\t\t\t\t\theight=\"533\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_3\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t\t\t<figcaption class=\"text-extra-xs text-right mt-1.5 caption--landscape\">\n\t\t\t\t\u00a9Yukio Uchida\t\t\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"150\" height=\"150\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/astia.webp?resize=150,150&amp;width=150&amp;height=150\" class=\"w-auto h-auto max-h-[90px] md:max-h-[130px] flex-shrink-0\" alt=\"\" loading=\"lazy\" decoding=\"async\" fetchpriority=\"low\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/astia.webp?width=150&amp;height=150 150w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/astia.webp?width=80&amp;height=80 80w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__content--inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"mb-1\">ASTIA\/SOFT<\/h3>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Basata sulla pellicola invertibile FUJICHROME ASTIA, progettata per i ritratti di moda, questa modalit\u00e0 privilegia la riproduzione fedele e morbida delle tonalit\u00e0 della pelle, ritraendo al contempo cieli blu vividi e vegetazione.<\/p>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"full-width-caption-slide--container swiper-slide\">\n\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__inner-content\">\n\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__image-container\">\n\t\t\t\t\t\t\t\n\t<figure class=\"swiper-slide__inner\">\n\t\t<picture class=\"aspect-ratio aspect-ratio--landscape\">\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Pro-Neg.-Std_Xu-Huanxing.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_4\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Pro-Neg.-Std_Xu-Huanxing.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"\"\t\t\t\t\t\t\t\t\talt=\"Image 4\"\t\t\t\t\t\t\t\t\twidth=\"800\"\t\t\t\t\t\t\t\t\theight=\"533\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_4\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t\t\t<figcaption class=\"text-extra-xs text-right mt-1.5 caption--landscape\">\n\t\t\t\t\u00a9Xu Huanxing\t\t\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"150\" height=\"150\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/pronegstd-9.png?resize=150,150&amp;width=150&amp;height=150\" class=\"w-auto h-auto max-h-[90px] md:max-h-[130px] flex-shrink-0\" alt=\"\" loading=\"lazy\" decoding=\"async\" fetchpriority=\"low\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/pronegstd-9.png?width=150&amp;height=150 150w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/pronegstd-9.png?width=80&amp;height=80 80w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__content--inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"mb-1\">PRO Neg. Std<\/h3>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Basata su PRO160NS, una pellicola negativa a colori per professionisti, questa modalit\u00e0 di Simulazione Pellicola offre una gradazione tonale morbida e un&#8217;eccellente riproduzione dell&#8217;incarnato. Ideale per la fotografia di ritratti con un&#8217;illuminazione attentamente controllata. La tonalit\u00e0 neutra si adatta bene alla post-produzione.<\/p>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"full-width-caption-slide--container swiper-slide\">\n\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__inner-content\">\n\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__image-container\">\n\t\t\t\t\t\t\t\n\t<figure class=\"swiper-slide__inner\">\n\t\t<picture class=\"aspect-ratio aspect-ratio--landscape\">\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/CC_Yukio-Uchida.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_5\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/CC_Yukio-Uchida.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"\"\t\t\t\t\t\t\t\t\talt=\"Image 5\"\t\t\t\t\t\t\t\t\twidth=\"800\"\t\t\t\t\t\t\t\t\theight=\"533\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_5\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t\t\t<figcaption class=\"text-extra-xs text-right mt-1.5 caption--landscape\">\n\t\t\t\t\u00a9Yukio Uchida\t\t\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"150\" height=\"150\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/classicchrome.webp?resize=150,150&amp;width=150&amp;height=150\" class=\"w-auto h-auto max-h-[90px] md:max-h-[130px] flex-shrink-0\" alt=\"\" loading=\"lazy\" decoding=\"async\" fetchpriority=\"low\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/classicchrome.webp?width=150&amp;height=150 150w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/classicchrome.webp?width=80&amp;height=80 80w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__content--inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"mb-1\">CLASSIC CHROME<\/h3>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Progettata per riprodurre un aspetto simile alle riviste documentaristiche del XX secolo, Classic Chrome, grazie alla bassa saturazione e alla gradazione tonale decisa nelle ombre, \u00e8 la scelta perfetta per la fotografia documentaristica con un tocco di realismo.<\/p>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"full-width-caption-slide--container swiper-slide\">\n\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__inner-content\">\n\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__image-container\">\n\t\t\t\t\t\t\t\n\t<figure class=\"swiper-slide__inner\">\n\t\t<picture class=\"aspect-ratio aspect-ratio--landscape\">\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/CN_Breyer_Melissa-scaled.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_6\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/CN_Breyer_Melissa-scaled.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"\"\t\t\t\t\t\t\t\t\talt=\"Image 6\"\t\t\t\t\t\t\t\t\twidth=\"800\"\t\t\t\t\t\t\t\t\theight=\"533\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_6\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t\t\t<figcaption class=\"text-extra-xs text-right mt-1.5 caption--landscape\">\n\t\t\t\t\u00a9Melissa Breyer\t\t\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"150\" height=\"150\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/classicneg.webp?resize=150,150&amp;width=150&amp;height=150\" class=\"w-auto h-auto max-h-[90px] md:max-h-[130px] flex-shrink-0\" alt=\"\" loading=\"lazy\" decoding=\"async\" fetchpriority=\"low\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/classicneg.webp?width=150&amp;height=150 150w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/classicneg.webp?width=80&amp;height=80 80w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__content--inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"mb-1\">CLASSIC Neg.<\/h3>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Basata su SUPERIA, una pellicola negativa a colori amata da generazioni di fotografi, questa modalit\u00e0 di Simulazione Pellicola offre una gradazione tonale ad alto contrasto. Aggiunge profondit\u00e0 e definizione ai colori regolandone le tonalit\u00e0 nelle alte luci e nelle ombre, riducendone al contempo la saturazione.<\/p>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"full-width-caption-slide--container swiper-slide\">\n\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__inner-content\">\n\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__image-container\">\n\t\t\t\t\t\t\t\n\t<figure class=\"swiper-slide__inner\">\n\t\t<picture class=\"aspect-ratio aspect-ratio--landscape\">\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/NN_Derrick-Ong-scaled.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_7\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/NN_Derrick-Ong-scaled.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"\"\t\t\t\t\t\t\t\t\talt=\"Image 7\"\t\t\t\t\t\t\t\t\twidth=\"800\"\t\t\t\t\t\t\t\t\theight=\"533\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_7\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t\t\t<figcaption class=\"text-extra-xs text-right mt-1.5 caption--landscape\">\n\t\t\t\t\u00a9Derrick Ong\t\t\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"150\" height=\"150\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/nostalgicneg.webp?resize=150,150&amp;width=150&amp;height=150\" class=\"w-auto h-auto max-h-[90px] md:max-h-[130px] flex-shrink-0\" alt=\"\" loading=\"lazy\" decoding=\"async\" fetchpriority=\"low\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/nostalgicneg.webp?width=150&amp;height=150 150w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/nostalgicneg.webp?width=80&amp;height=80 80w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__content--inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"mb-1\">NOSTALGIC Neg.<\/h3>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Progettata per ricreare l&#8217;aspetto delle immagini contenute nei vecchi album fotografici, NOSTALGIC Neg. produce immagini con colori intensi nelle ombre e una tonalit\u00e0 morbida nei mezzitoni e nelle luci.<\/p>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"full-width-caption-slide--container swiper-slide\">\n\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__inner-content\">\n\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__image-container\">\n\t\t\t\t\t\t\t\n\t<figure class=\"swiper-slide__inner\">\n\t\t<picture class=\"aspect-ratio aspect-ratio--landscape\">\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/RA_Zao-Yanming-scaled.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_8\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/RA_Zao-Yanming-scaled.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"\"\t\t\t\t\t\t\t\t\talt=\"Image 8\"\t\t\t\t\t\t\t\t\twidth=\"800\"\t\t\t\t\t\t\t\t\theight=\"533\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_8\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t\t\t<figcaption class=\"text-extra-xs text-right mt-1.5 caption--landscape\">\n\t\t\t\t\u00a9Zao Yanming\t\t\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"150\" height=\"150\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/realaace-5.png?resize=150,150&amp;width=150&amp;height=150\" class=\"w-auto h-auto max-h-[90px] md:max-h-[130px] flex-shrink-0\" alt=\"\" loading=\"lazy\" decoding=\"async\" fetchpriority=\"low\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/realaace-5.png?width=150&amp;height=150 150w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/realaace-5.png?width=80&amp;height=80 80w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__content--inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"mb-1\">REALA ACE<\/h3>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Basata su REALA ACE, questa ventesima Simulazione Pellicola unisce una fedele riproduzione dei colori a tonalit\u00e0 decise, rendendola adatta a tutti i soggetti e a tutte le situazioni.<\/p>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"full-width-caption-slide--container swiper-slide\">\n\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__inner-content\">\n\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__image-container\">\n\t\t\t\t\t\t\t\n\t<figure class=\"swiper-slide__inner\">\n\t\t<picture class=\"aspect-ratio aspect-ratio--landscape\">\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/ACROS_Derrick-Ong-scaled.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_9\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/ACROS_Derrick-Ong-scaled.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"\"\t\t\t\t\t\t\t\t\talt=\"Image 9\"\t\t\t\t\t\t\t\t\twidth=\"800\"\t\t\t\t\t\t\t\t\theight=\"533\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_9\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t\t\t<figcaption class=\"text-extra-xs text-right mt-1.5 caption--landscape\">\n\t\t\t\t\u00a9Derrick Ong\t\t\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"150\" height=\"150\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/acros.webp?resize=150,150&amp;width=150&amp;height=150\" class=\"w-auto h-auto max-h-[90px] md:max-h-[130px] flex-shrink-0\" alt=\"\" loading=\"lazy\" decoding=\"async\" fetchpriority=\"low\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/acros.webp?width=150&amp;height=150 150w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/acros.webp?width=80&amp;height=80 80w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wp-block-slider--full-width-caption__content--inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"mb-1\">ACROS<\/h3>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Basata su ACROS, una pellicola monocromatica nota per la sua grana super fine, questa modalit\u00e0 di Simulazione Pellicola garantisce ricchi dettagli nelle ombre e un&#8217;eccellente nitidezza, aggiungendo comunque grana ad alti ISO e ricreando la straordinaria sensazione materica del monocromatico.<\/p>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\n<button class=\"swiper-button-prev button-bg-white\" type=\"button\">\n\t<span class=\"hidden sm:flex\">\n\t\t\t\t<svg class=\"svg-slick-left-arrow-svg \"\n\t\t width=\"24\" height=\"22\"\t\talt=\"Svg Slick Left Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-left-arrow-svg\"\n\t\t\t width=\"24\" height=\"22\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n\t<span class=\"flex sm:hidden\">\n\t\t\t\t<svg class=\"svg-slick-left-arrow-svg \"\n\t\t width=\"20\" height=\"18\"\t\talt=\"Svg Slick Left Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-left-arrow-svg\"\n\t\t\t width=\"20\" height=\"18\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n<\/button>\n<button class=\"swiper-button-next button-bg-white\" type=\"button\">\n\t<span class=\"hidden sm:flex\">\n\t\t\t\t<svg class=\"svg-slick-right-arrow-svg \"\n\t\t width=\"24\" height=\"22\"\t\talt=\"Svg Slick Right Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-right-arrow-svg\"\n\t\t\t width=\"24\" height=\"22\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n\t<span class=\"flex sm:hidden\">\n\t\t\t\t<svg class=\"svg-slick-right-arrow-svg \"\n\t\t width=\"20\" height=\"18\"\t\talt=\"Svg Slick Right Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-right-arrow-svg\"\n\t\t\t width=\"20\" height=\"18\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n<\/button>\n\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-background is-layout-flow wp-block-group-is-layout-flow\" style=\"background-color:#737d7d;padding-top:var(--wp--preset--spacing--70);padding-right:0;padding-bottom:var(--wp--preset--spacing--70);padding-left:0\">\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-5ca99053 wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center has-white-color has-text-color has-link-color wp-elements-73b1d5ceef83b77203d66eafb61d8b43\">Your Film, Your Story<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity faded-separator\"\/>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-link-color wp-elements-d99f3f08c112a618b44ef5a2ba4e59a5\">Aggiungi un tocco personale a ogni immagine che scatti. La ghiera Simulazione Pellicola di FUJIFILM X-E5 offre le posizioni FS1, FS2 e FS3, permettendoti di personalizzare e salvare le tue ricette FS.<\/p>\n<\/div>\n\n\n\n<div id=\"block_3b780c2d0bf9ca3273200cbeb5523aed\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_3b780c2d0bf9ca3273200cbeb5523aed.wp-block-spacer {\n        height: 50px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_3b780c2d0bf9ca3273200cbeb5523aed.wp-block-spacer {\n            height: 30px;       \n        }\n    }\n<\/style>\n\n\n\t<div id=\"block_d7a997c8837f6da15f7fc85554847563\" class=\"wp-block wp-block-slider wp-block-slider--rotate swiper alignfull block relative overflow-hidden\">\n\t\t<div class=\"swiper-wrapper\" data-settings='{\"loop\":true,\"autoplay\":true,\"autoplaySpeed\":\"5000\",\"speed\":500,\"slidesPerView\":1,\"spaceBetween\":20,\"navigation\":{\"nextEl\":\".swiper-button-next\",\"prevEl\":\".swiper-button-prev\"},\"grabCursor\":true,\"noSwipingSelector\":\".no-swiping\",\"breakpoints\":{\"768\":{\"spaceBetween\":32},\"1024\":{\"slidesPerView\":\"auto\",\"centeredSlides\":true,\"spaceBetween\":0}}}'>\n\t\t\t\t\t\t\t<div class=\"rotate-slide--container swiper-slide\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div id=\"grain-effect\" class=\"flex flex-col justify-center\">\n\t\t\t\t\t\t\t<div class=\"img-comp-container__inner\">\n\t\t\t\t\t\t\t\t<div class=\"img-comp-container w-full relative overflow-hidden m-auto no-swiping\">\n\t\t\t\t\t\t\t\t\t<div class=\"img-comp-img w-full h-full overflow-hidden relative\">\n\t\t\t\t\t\t\t\t\t\t<img width=\"1024\" height=\"683\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/GRAIN-ON-scaled.jpg?width=1024&amp;height=683\" class=\"w-full h-auto block object-left object-cover\" alt=\"Grain Effect - Image Left 1\" loading=\"lazy\" decoding=\"async\" fetchpriority=\"low\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/GRAIN-ON-scaled.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/GRAIN-ON-scaled.jpg?width=1024&amp;height=683 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/GRAIN-ON-scaled.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/GRAIN-ON-scaled.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/GRAIN-ON-scaled.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/GRAIN-ON-scaled.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/GRAIN-ON-scaled.jpg?width=717&amp;height=478 717w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"img-comp-img top-0 img-comp-overlay w-1\/2 h-full overflow-hidden absolute\">\n\t\t\t\t\t\t\t\t\t\t<img width=\"1024\" height=\"683\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/GRAIN-OFF-scaled.jpg?width=1024&amp;height=683\" class=\"w-full h-auto block object-left object-cover\" alt=\"Grain Effect - Image Right 1\" loading=\"lazy\" decoding=\"async\" fetchpriority=\"low\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/GRAIN-OFF-scaled.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/GRAIN-OFF-scaled.jpg?width=1024&amp;height=683 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/GRAIN-OFF-scaled.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/GRAIN-OFF-scaled.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/GRAIN-OFF-scaled.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/GRAIN-OFF-scaled.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/GRAIN-OFF-scaled.jpg?width=717&amp;height=478 717w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"text-extra-xs text-right mt-1.5 text-white\">\n\t\t\t\t\t\t\t\t\t\t\u00a9Bao Zoan\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"flex flex-col justify-center mt-5 md:mt-8\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"main-title h3 h3\">Grain Effect<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"main-paragraph\">Dalle texture pi\u00f9 delicate all&#039;aspetto granuloso delle pellicole tradizionali ad alti ISO, con FUJIFILM X-E5 puoi aggiungere facilmente una grana dall&#039;aspetto naturale alle tue foto. Controlla l&#039;intensit\u00e0 e le dimensioni per ottenere la giusta quantit\u00e0 di texture su qualsiasi immagine.<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<style>\n\t\t\t\t\t\t\t\t#grain-effect .img-comp-slider:before{content:\"Off\";}#grain-effect .img-comp-slider:after{content:\"On\";}\t\t\t\t\t\t\t<\/style>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"rotate-slide--container swiper-slide\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div id=\"color-chrome-effect\" class=\"flex flex-col justify-center\">\n\t\t\t\t\t\t\t<div class=\"img-comp-container__inner\">\n\t\t\t\t\t\t\t\t<div class=\"img-comp-container w-full relative overflow-hidden m-auto no-swiping\">\n\t\t\t\t\t\t\t\t\t<div class=\"img-comp-img w-full h-full overflow-hidden relative\">\n\t\t\t\t\t\t\t\t\t\t<img width=\"1024\" height=\"683\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Color-Chrome-Effect_ON.jpg?width=1024&amp;height=683\" class=\"w-full h-auto block object-left object-cover\" alt=\"Color Chrome Effect - Image Left 2\" loading=\"lazy\" decoding=\"async\" fetchpriority=\"low\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Color-Chrome-Effect_ON.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Color-Chrome-Effect_ON.jpg?width=1024&amp;height=683 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Color-Chrome-Effect_ON.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Color-Chrome-Effect_ON.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Color-Chrome-Effect_ON.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Color-Chrome-Effect_ON.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Color-Chrome-Effect_ON.jpg?width=717&amp;height=478 717w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"img-comp-img top-0 img-comp-overlay w-1\/2 h-full overflow-hidden absolute\">\n\t\t\t\t\t\t\t\t\t\t<img width=\"1024\" height=\"683\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Color-Chrome-Effect_OFF.jpg?width=1024&amp;height=683\" class=\"w-full h-auto block object-left object-cover\" alt=\"Color Chrome Effect - Image Right 2\" loading=\"lazy\" decoding=\"async\" fetchpriority=\"low\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Color-Chrome-Effect_OFF.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Color-Chrome-Effect_OFF.jpg?width=1024&amp;height=683 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Color-Chrome-Effect_OFF.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Color-Chrome-Effect_OFF.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Color-Chrome-Effect_OFF.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Color-Chrome-Effect_OFF.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Color-Chrome-Effect_OFF.jpg?width=717&amp;height=478 717w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"text-extra-xs text-right mt-1.5 text-white\">\n\t\t\t\t\t\t\t\t\t\t\u00a9Derrick Ong\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"flex flex-col justify-center mt-5 md:mt-8\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"main-title h3 h3\">Color Chrome Effect<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"main-paragraph\">Per soggetti molto saturi, l&#039;effetto Color Chrome aggiunge profondit\u00e0, dettaglio e vivacit\u00e0 in tre intensit\u00e0 ai toni del rosso, del verde o del giallo, dove altrimenti i dettagli andrebbero persi. Oppure usa Color Chrome FX Blue per enfatizzare i toni blu di un&#039;immagine.<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<style>\n\t\t\t\t\t\t\t\t#color-chrome-effect .img-comp-slider:before{content:\"Off\";}#color-chrome-effect .img-comp-slider:after{content:\"On\";}\t\t\t\t\t\t\t<\/style>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"rotate-slide--container swiper-slide\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div id=\"chiarezza\" class=\"flex flex-col justify-center\">\n\t\t\t\t\t\t\t<div class=\"img-comp-container__inner\">\n\t\t\t\t\t\t\t\t<div class=\"img-comp-container w-full relative overflow-hidden m-auto no-swiping\">\n\t\t\t\t\t\t\t\t\t<div class=\"img-comp-img w-full h-full overflow-hidden relative\">\n\t\t\t\t\t\t\t\t\t\t<img width=\"1024\" height=\"683\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Clarity_5_Luo-Fei.jpg?width=1024&amp;height=683\" class=\"w-full h-auto block object-left object-cover\" alt=\"Chiarezza - Image Left 3\" loading=\"lazy\" decoding=\"async\" fetchpriority=\"low\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Clarity_5_Luo-Fei.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Clarity_5_Luo-Fei.jpg?width=1024&amp;height=683 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Clarity_5_Luo-Fei.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Clarity_5_Luo-Fei.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Clarity_5_Luo-Fei.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Clarity_5_Luo-Fei.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Clarity_5_Luo-Fei.jpg?width=717&amp;height=478 717w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"img-comp-img top-0 img-comp-overlay w-1\/2 h-full overflow-hidden absolute\">\n\t\t\t\t\t\t\t\t\t\t<img width=\"1024\" height=\"683\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Clarity_-5_Luo-Fei.jpg?width=1024&amp;height=683\" class=\"w-full h-auto block object-left object-cover\" alt=\"Chiarezza - Image Right 3\" loading=\"lazy\" decoding=\"async\" fetchpriority=\"low\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Clarity_-5_Luo-Fei.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Clarity_-5_Luo-Fei.jpg?width=1024&amp;height=683 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Clarity_-5_Luo-Fei.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Clarity_-5_Luo-Fei.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Clarity_-5_Luo-Fei.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Clarity_-5_Luo-Fei.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Clarity_-5_Luo-Fei.jpg?width=717&amp;height=478 717w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"text-extra-xs text-right mt-1.5 text-white\">\n\t\t\t\t\t\t\t\t\t\t\u00a9Luo Fei\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"flex flex-col justify-center mt-5 md:mt-8\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"main-title h3 h3\">Chiarezza<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"main-paragraph\">Il controllo Chiarezza permette di scegliere se ricreare una scena con una nitidezza elevata, definendo i bordi e aumentando il contrasto, oppure con un tocco pi\u00f9 morbido. Con 11 livelli di controllo, \u00e8 facile personalizzarlo in base al tuo gusto e stile personale.<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<style>\n\t\t\t\t\t\t\t\t#chiarezza .img-comp-slider:before{content:\"-5\";}#chiarezza .img-comp-slider:after{content:\"+5\";}\t\t\t\t\t\t\t<\/style>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"rotate-slide--container swiper-slide\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div id=\"smooth-skin-effect\" class=\"flex flex-col justify-center\">\n\t\t\t\t\t\t\t<div class=\"img-default__inner\">\n\t\t\t\t\t\t\t\t<div class=\"img-comp-img w-full h-full overflow-hidden relative\">\n\t\t\t\t\t\t\t\t\t\n\t<figure class=\"swiper-slide__inner\">\n\t\t<picture >\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/SSK_Cen-Baolan.jpg?width=0&#038;height=0&#038;quality=75&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_4\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/SSK_Cen-Baolan.jpg?width=0&#038;height=0&#038;quality=75&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"w-full h-auto block object-left object-cover\"\t\t\t\t\t\t\t\t\talt=\"Smooth Skin Effect - Image 4\"\t\t\t\t\t\t\t\t\twidth=\"\"\t\t\t\t\t\t\t\t\theight=\"\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_4\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"text-extra-xs text-right mt-1.5 text-white\">\n\t\t\t\t\t\t\t\t\t\t\t\u00a9Cen Baolan\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"flex flex-col justify-center mt-5 md:mt-8\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"main-title h3\">Smooth Skin Effect<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"main-paragraph\">Ideale per i ritratti, questa funzione leviga la texture della pelle per un incarnato pi\u00f9 valorizzante.<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"rotate-slide--container swiper-slide\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div id=\"white-balance-shift\" class=\"flex flex-col justify-center\">\n\t\t\t\t\t\t\t<div class=\"img-default__inner\">\n\t\t\t\t\t\t\t\t<div class=\"img-comp-img w-full h-full overflow-hidden relative\">\n\t\t\t\t\t\t\t\t\t\n\t<figure class=\"swiper-slide__inner\">\n\t\t<picture >\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/image-20250520-044710.png?width=0&#038;height=0&#038;quality=75&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_5\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/image-20250520-044710.png?width=0&#038;height=0&#038;quality=75&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"w-full h-auto block object-left object-cover\"\t\t\t\t\t\t\t\t\talt=\"White Balance Shift - Image 5\"\t\t\t\t\t\t\t\t\twidth=\"\"\t\t\t\t\t\t\t\t\theight=\"\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_5\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"flex flex-col justify-center mt-5 md:mt-8\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"main-title h3\">White Balance Shift<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"main-paragraph\">Per il bilanciamento del bianco, scegli Auto, Personalizzato, Temperatura Colore o una serie di opzioni preimpostate. Il bilanciamento del bianco pu\u00f2 essere regolato con precisione nella funzione WB Shift con le coordinate di colore rosso (R) e blu (B).<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\n<button class=\"swiper-button-prev arrow-black\" type=\"button\">\n\t<span class=\"hidden sm:flex\">\n\t\t\t\t<svg class=\"svg-slick-left-arrow-svg \"\n\t\t width=\"24\" height=\"22\"\t\talt=\"Svg Slick Left Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-left-arrow-svg\"\n\t\t\t width=\"24\" height=\"22\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n\t<span class=\"flex sm:hidden\">\n\t\t\t\t<svg class=\"svg-slick-left-arrow-svg \"\n\t\t width=\"20\" height=\"18\"\t\talt=\"Svg Slick Left Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-left-arrow-svg\"\n\t\t\t width=\"20\" height=\"18\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n<\/button>\n<button class=\"swiper-button-next arrow-black\" type=\"button\">\n\t<span class=\"hidden sm:flex\">\n\t\t\t\t<svg class=\"svg-slick-right-arrow-svg \"\n\t\t width=\"24\" height=\"22\"\t\talt=\"Svg Slick Right Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-right-arrow-svg\"\n\t\t\t width=\"24\" height=\"22\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n\t<span class=\"flex sm:hidden\">\n\t\t\t\t<svg class=\"svg-slick-right-arrow-svg \"\n\t\t width=\"20\" height=\"18\"\t\talt=\"Svg Slick Right Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-right-arrow-svg\"\n\t\t\t width=\"20\" height=\"18\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n<\/button>\n\t<\/div>\n\t<\/div>\n\n\n\n<div id=\"block_7e7207a995b745e5f74fe9e3d08ae3db\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_7e7207a995b745e5f74fe9e3d08ae3db.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_7e7207a995b745e5f74fe9e3d08ae3db.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group alignfull fade-up-parallax is-layout-flow wp-block-group-is-layout-flow\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-e5e2ce42 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-1d6f4e6b wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center\">Funzionalit\u00e0 video<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity faded-separator\"\/>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<p class=\"has-text-align-center\">Il corpo compatto e leggero di FUJIFILM X-E5 supporta la registrazione interna su una scheda SD a 6,2K\/30p 4:2:2 a 10 bit, nonch\u00e9 4K\/60p e 1080\/240p di alta qualit\u00e0.<\/p>\n<\/div>\n\n\n\n<div id=\"block_3b780c2d0bf9ca3273200cbeb5523aed\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_3b780c2d0bf9ca3273200cbeb5523aed.wp-block-spacer {\n        height: 50px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_3b780c2d0bf9ca3273200cbeb5523aed.wp-block-spacer {\n            height: 30px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-5ca99053 wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Video-Recording_thumbnail.webp?width=1024&#038;height=576\" alt=\"\" class=\"wp-image-276327\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Video-Recording_thumbnail.webp?width=1024 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Video-Recording_thumbnail.webp?width=300&amp;height=169 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Video-Recording_thumbnail.webp?width=768&amp;height=432 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Video-Recording_thumbnail.webp?width=400&amp;height=225 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Video-Recording_thumbnail.webp?width=365&amp;height=205 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Video-Recording_thumbnail.webp?width=600&amp;height=338 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Video-Recording_thumbnail.webp?width=417&amp;height=235 417w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Video-Recording_thumbnail.webp?width=717&amp;height=403 717w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div id=\"block_7e7207a995b745e5f74fe9e3d08ae3db\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_7e7207a995b745e5f74fe9e3d08ae3db.wp-block-spacer {\n        height: 100px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_7e7207a995b745e5f74fe9e3d08ae3db.wp-block-spacer {\n            height: 70px;       \n        }\n    }\n<\/style>\n\n\n\n<div class=\"wp-block-group alignfull is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group fade-up-parallax is-layout-constrained wp-container-core-group-is-layout-4ee83bb8 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<h2 class=\"wp-block-heading has-text-align-center has-black-color has-text-color has-link-color wp-elements-1687b9b24e7fed497882b914b88a26da\">Complete Your Creative Setup<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity faded-separator\"\/>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div id=\"block_3b780c2d0bf9ca3273200cbeb5523aed\" aria-hidden=\"true\" class=\"wp-block-spacer custom-responsive\"><\/div>\n\n<style>\n    #block_3b780c2d0bf9ca3273200cbeb5523aed.wp-block-spacer {\n        height: 50px;       \n    }\n    @media screen and (max-width: 767px) {\n        #block_3b780c2d0bf9ca3273200cbeb5523aed.wp-block-spacer {\n            height: 30px;       \n        }\n    }\n<\/style>\n\n\n\t<div id=\"block_114146ff229cf4b7e79dc6360034349a\" class=\"wp-block wp-block-slider wp-block-slider--image-and-content swiper block-overlay-content-slider--black fade-up-parallax alignfull block relative overflow-hidden\">\n\t\t<div class=\"swiper-wrapper\" data-settings='{\"loop\":true,\"autoplay\":false,\"autoplaySpeed\":\"5000\",\"speed\":500,\"slidesPerView\":1,\"spaceBetween\":20,\"navigation\":{\"nextEl\":\".swiper-button-next\",\"prevEl\":\".swiper-button-prev\"},\"grabCursor\":true,\"centeredSlides\":true,\"breakpoints\":{\"768\":{\"slidesPerView\":\"auto\",\"spaceBetween\":32},\"1024\":{\"slidesPerView\":\"auto\",\"spaceBetween\":0}}}'>\n\t\t\t\t\t\t\t<div class=\"image-and-content-slide--container swiper-slide\">\n\t\t\t\t\t<div class=\"image-and-content-slide--container__inner\">\n\t\t\t\t\t\t<div class=\"main-img-container\">\n\t\t\t\t\t\t\t\n\t<figure class=\"swiper-slide__inner\">\n\t\t<picture >\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/x-app-20495723.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_1\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/x-app-20495723.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"w-full h-auto aspect-3\/2 object-cover main-img\"\t\t\t\t\t\t\t\t\talt=\"Image Column 1\"\t\t\t\t\t\t\t\t\twidth=\"800\"\t\t\t\t\t\t\t\t\theight=\"533\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_1\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"main-content flex md:flex-row items-start md:items-end gap-4 md:gap-6\">\n\t\t\t\t\t\t\t\t<div class=\"block\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"main-content__title\">XApp<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"main-content__inner\">\n\t\t\t\t\t\t\t\t\t\t\t<p>FUJIFILM X-E5 \u00e8 compatibile con FUJIFILM XApp, che offre funzionalit\u00e0 aggiuntive e semplifica il trasferimento delle immagini al tuo smartphone. I file possono essere condivisi rapidamente tra X-E5 e il tuo smartphone, mentre l&#8217;app gratuita consente anche il controllo remoto della fotocamera.<\/p>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/software\/xapp\" target=\"_blank\" class=\"text-xs sm:text-sm bold underline mt-3 block text-green\">Learn more about XApp.<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"image-and-content-slide--container swiper-slide\">\n\t\t\t\t\t<div class=\"image-and-content-slide--container__inner\">\n\t\t\t\t\t\t<div class=\"main-img-container\">\n\t\t\t\t\t\t\t\n\t<figure class=\"swiper-slide__inner\">\n\t\t<picture >\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Frame.io-Camera-to-Cloud_2-scaled.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_2\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/Frame.io-Camera-to-Cloud_2-scaled.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"w-full h-auto aspect-3\/2 object-cover main-img\"\t\t\t\t\t\t\t\t\talt=\"Image Column 2\"\t\t\t\t\t\t\t\t\twidth=\"800\"\t\t\t\t\t\t\t\t\theight=\"533\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_2\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"main-content flex md:flex-row items-start md:items-end gap-4 md:gap-6\">\n\t\t\t\t\t\t\t\t<div class=\"block\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"main-content__title\">Frame.io Camera to Cloud<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"main-content__inner\">\n\t\t\t\t\t\t\t\t\t\t\t<p>Crea, condividi e collabora in un istante con la tecnologia nativa Frame.io Camera to Cloud di FUJIFILM X-E5. Connettiti in modalit\u00e0 wireless a una connessione internet attiva, autenticati su Frame.io e inizia a caricare foto e video nell&#8217;istante della creazione.<\/p>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"image-and-content-slide--container swiper-slide\">\n\t\t\t\t\t<div class=\"image-and-content-slide--container__inner\">\n\t\t\t\t\t\t<div class=\"main-img-container\">\n\t\t\t\t\t\t\t\n\t<figure class=\"swiper-slide__inner\">\n\t\t<picture >\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/dont-just-take-give-scaled.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_3\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/dont-just-take-give-scaled.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"w-full h-auto aspect-3\/2 object-cover main-img\"\t\t\t\t\t\t\t\t\talt=\"Image Column 3\"\t\t\t\t\t\t\t\t\twidth=\"800\"\t\t\t\t\t\t\t\t\theight=\"533\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_3\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"main-content flex md:flex-row items-start md:items-end gap-4 md:gap-6\">\n\t\t\t\t\t\t\t\t<div class=\"block\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"main-content__title\">don&#8217;t just take, give.\u2122<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"main-content__inner\">\n\t\t\t\t\t\t\t\t\t\t\t<p>Condividi le tue immagini collegandoti in modalit\u00e0 wireless e stampando su stampanti selezionate della serie instax\u2122 Link.* FUJIFILM X-E5 si collega direttamente, senza bisogno di un app.<\/p>\n<p class=\"p1\"><sub>*instax mini Link 3\u2122 \/ instax mini Link 2\u2122 \/ instax Link WIDE\u2122 <span class=\"s1\">&#8211; ciascuna venduta separatamente<\/span><\/sub><\/p>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"image-and-content-slide--container swiper-slide\">\n\t\t\t\t\t<div class=\"image-and-content-slide--container__inner\">\n\t\t\t\t\t\t<div class=\"main-img-container\">\n\t\t\t\t\t\t\t\n\t<figure class=\"swiper-slide__inner\">\n\t\t<picture >\n\t\t\t\t\t\t\t<source \n\t\t\t\tmedia=\"(min-width: 640px)\" \t\t\t\tsrcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/XF23mmF2.8-R-WR.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\t\t\t\t data-slider-slide=\"slide_4\" data-slider-device=\"desktop\"\t\t\t\t\/>\n\t\t\t\t\t\t<img \n\t\t\t\tsrc=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/06\/XF23mmF2.8-R-WR.jpg?width=800&#038;height=533&#038;quality=80&#038;sharpen=1\"\n\t\t\t\t\t\t\t\t\tclass=\"w-full h-auto aspect-3\/2 object-cover main-img\"\t\t\t\t\t\t\t\t\talt=\"Image Column 4\"\t\t\t\t\t\t\t\t\twidth=\"800\"\t\t\t\t\t\t\t\t\theight=\"533\"\t\t\t\t\t\t\t\t\tdata-slider-slide=\"slide_4\"\t\t\t\t\t\t\t\t\tdata-slider-device=\"desktop\"\t\t\t\t\t\t\tloading=\"lazy\" fetchpriority=\"low\" data-on-dom-ready=\"preload\" data-on-dom-ready-delay=\"300\" \/>\n\t\t<\/picture>\n\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"main-content flex md:flex-row items-start md:items-end gap-4 md:gap-6\">\n\t\t\t\t\t\t\t\t<div class=\"block\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"main-content__title\">XF23mmF2.8 R WR<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"main-content__inner\">\n\t\t\t\t\t\t\t\t\t\t\t<p>Con una lunghezza focale equivalente a 35mm, il nuovo obiettivo pancake FUJINON XF23mmF2.8 R WR pesa solo 90g. Montato su FUJIFILM X-E5, crea un dispositivo compatto e raffinato.<\/p>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/lenses\/xf23mmf28-r-wr\/\" target=\"_blank\" class=\"text-xs sm:text-sm bold underline mt-3 block text-green\">Per maggiori dettagli, clicca qui.<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\n<button class=\"swiper-button-prev arrow-black\" type=\"button\">\n\t<span class=\"hidden sm:flex\">\n\t\t\t\t<svg class=\"svg-slick-left-arrow-svg \"\n\t\t width=\"24\" height=\"22\"\t\talt=\"Svg Slick Left Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-left-arrow-svg\"\n\t\t\t width=\"24\" height=\"22\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n\t<span class=\"flex sm:hidden\">\n\t\t\t\t<svg class=\"svg-slick-left-arrow-svg \"\n\t\t width=\"20\" height=\"18\"\t\talt=\"Svg Slick Left Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-left-arrow-svg\"\n\t\t\t width=\"20\" height=\"18\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n<\/button>\n<button class=\"swiper-button-next arrow-black\" type=\"button\">\n\t<span class=\"hidden sm:flex\">\n\t\t\t\t<svg class=\"svg-slick-right-arrow-svg \"\n\t\t width=\"24\" height=\"22\"\t\talt=\"Svg Slick Right Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-right-arrow-svg\"\n\t\t\t width=\"24\" height=\"22\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n\t<span class=\"flex sm:hidden\">\n\t\t\t\t<svg class=\"svg-slick-right-arrow-svg \"\n\t\t width=\"20\" height=\"18\"\t\talt=\"Svg Slick Right Arrow Svg\"\n\t\trole=\"img\">\n\t\t\t<use href=\"#svg-slick-right-arrow-svg\"\n\t\t\t width=\"20\" height=\"18\"\t\t\t><\/use>\n\t\t<\/svg>\n\t\t<\/span>\n<\/button>\n\t<\/div>\n\t<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-0740b621 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<figure class=\"wp-block-table alignwide has-none-or-default\"><table class=\"has-green-color has-text-color has-link-color has-fixed-layout\"><tbody><tr><td><strong>Model name<\/strong> <\/td><td>FUJIFILM X-E5<\/td><\/tr><tr><td><strong>Declaration of Conformity<\/strong><\/td><td><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\"><a href=\"https:\/\/dl.fujifilm-x.com\/doc\/x-e5_doc-rse.pdf\" target=\"_blank\" data-type=\"link\" data-id=\"https:\/\/dl.fujifilm-x.com\/doc\/x-hf1_doc-mmt.pdf\" rel=\"noreferrer noopener\">View PDF<\/a><\/mark><\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n","protected":false},"author":251,"featured_media":276312,"parent":0,"menu_order":2550,"template":"","category":[1006,3211,320,1986,13898],"products_category":[11636],"class_list":["post-277947","camera","type-camera","status-publish","has-post-thumbnail","hentry","category-cameras","category-x-series-mirrorless","category-products","category-x-series","category-x-e5","products_category-overview"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":[],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera\/277947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera"}],"about":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/types\/camera"}],"author":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/users\/251"}],"version-history":[{"count":0,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/camera\/277947\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media\/276312"}],"wp:attachment":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media?parent=277947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/category?post=277947"},{"taxonomy":"products_category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/products_category?post=277947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}]