[{"id":357050,"date":"2026-05-03T01:18:20","date_gmt":"2026-05-03T01:18:20","guid":{"rendered":"https:\/\/www.fujifilm-x.com\/?post_type=story&#038;p=357050"},"modified":"2026-05-03T01:18:25","modified_gmt":"2026-05-03T01:18:25","slug":"acros-fs-recipe-x-rober-tomas","status":"publish","type":"story","link":"https:\/\/www.fujifilm-x.com\/it-it\/stories\/acros-fs-recipe-x-rober-tomas\/","title":{"rendered":"ACROS\u00a0FS RECIPE\u00a0x\u00a0Rober Tom\u00e1s"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>Fotografare con ACROS+ R, la bellezza della semplicit\u00e0<\/strong><\/h2>\n\n\n\n<p>Quando penso alla fotografia, penso a come trarre il massimo dalla vita osservandola in modo personale e diverso. Non voglio che la realt\u00e0 mi sfugga senza fermarsi; voglio immortalarla a modo mio. FUJIFILM X-E5 \u00e8 senza dubbio una fotocamera che si avvicina molto a questo modo di pensare. \u00c8 discreta, compatta, leggera. Non \u00e8 intimidatoria n\u00e9 distrae. Ha proprio ci\u00f2 che serve per concentrarsi su ci\u00f2 che conta: godersi ci\u00f2 che si ha davanti e immortalarlo. Se la si abbina alle riprese in ACROS+ R, tutto scorre.<\/p>\n\n\n\n<p>In un mondo saturo di immagini esagerate ed effetti bizzarri, lavorare in bianco e nero con un tocco e un carattere diversi \u00e8 quasi una decisione coraggiosa. \u00c8 pensare in modo diverso. \u00c8 tornare all&#8217;essenza. Lavorare con JPG direttamente dalla fotocamera con una linea retta basata su ACROS+ R permette di catturare una grande ricchezza tonale con un contrasto molto bello e intenso.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_02.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-351083\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_02.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_02.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_02.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_02.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_02.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_02.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_02.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_02.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_03.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-351084\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_03.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_03.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_03.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_03.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_03.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_03.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_03.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_03.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p>La semplicit\u00e0 \u00e8 potere. E il contrasto, se usato bene, non \u00e8 solo uno strumento visivo, ma un modo per raccontare la propria realt\u00e0. Ecco perch\u00e9 mi piace aggiungere un po\u2019 pi\u00f9 di contrasto alla base ACROS+ R. Nella mia FS RECIPE, applico +1 al parametro HIGHLIGHTS e nel parametro SHADOWS. Mi piace che le foto in bianco e nero conservino una certa memoria del filtro rosso, quindi conferisco ad ACROS una leggera deviazione verso il caldo. Per il resto, questa Simulazione Pellicola funziona in modo fantastico con i toni di grigio, conferendo un&#8217;impressione cinematografica molto interessante.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_04.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-351085\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_04.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_04.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_04.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_04.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_04.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_04.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_04.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_04.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p>Questa Simulazione Pellicola trasforma la citt\u00e0 in uno scenario quasi senza tempo, dove luce e ombra recitano un ruolo fondamentale. La luce cruda di mezzogiorno si trasforma in pennellate intense. Le ombre di un portone assumono un&#8217;aria misteriosa. Il contrasto offerto dal filtro rosso esalta ogni scatto, ogni texture, e conferisce a ogni foto maggior volume. Tuttavia, non dimenticate che le ombre manterranno sempre alcuni dettagli, e questo \u00e8 un vantaggio dell&#8217;utilizzo di ACROS+ R: si mantiene un contrasto che conferisce corpo alla foto con una luce dura, ma senza perdere i neri, tenendo sotto controllo le alte luci.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_05.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-351086\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_05.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_05.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_05.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_05.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_05.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_05.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_05.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_05.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p>La cosa migliore \u00e8 che \u00e8 gi\u00e0 tutto pronto. Basta guardare nel mirino, inquadrare e scattare. La foto \u00e8 pronta e, una volta trasferite dalla scheda di memoria, le immagini sono pronte per essere visualizzate, senza bisogno di ulteriori ritocchi. Personalmente, mi piacciono le foto che hanno un certo carattere. Non ho bisogno della perfezione; ho bisogno che trasmettano emozioni. Lavorare esclusivamente con ACROS+ R mi ha portato a concentrarmi maggiormente su un tipo diverso di fotografia, qualcosa di pi\u00f9 riflessivo e ponderato.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_06.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-351087\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_06.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_06.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_06.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_06.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_06.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_06.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_06.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_06.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p>Nella mia fotografia quotidiana cerco i colori, i volti, le espressioni e gli attimi. Questa volta, concentrandomi sul bianco e nero e riuscendo a cogliere tanta ricchezza nelle sfumature di grigio, mi \u00e8 sembrato di scattare con una fotocamera analogica. Ho fotografato da un punto di vista pi\u00f9 intimo e sereno, catturando texture, ricordi e sensazioni della mia casa, dei miei viaggi e del mio lavoro. Avere le foto pronte cos\u00ec rapidamente e con tanta facilit\u00e0 \u00e8 stato divertente e mi ha permesso di riscoprire un altro tipo di fotografia.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_07.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-351088\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_07.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_07.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_07.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_07.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_07.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_07.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_07.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/03\/ES_Rober-Tomas_ACROS_07.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Scopri la mia FS Recipe:<\/h3>\n\n\n\n<p><strong>FILM SIMULATION: <\/strong>ACROS+ R<br><strong>MONOCHROMATIC COLOR: <\/strong>WC +1, MG 0<br><strong>GRAIN EFFECT: <\/strong>WEAK, SMALL<br><strong>CHROME EFFECT COLOR: <\/strong>OFF<br><strong>COLOR CHROME FX BLUE: <\/strong>OFF<br><strong>SMOOTH SKIN EFFECT:<\/strong> 0<br><strong>WHITE BALANCE: <\/strong>AUTO \/ R 0, B 0<br><strong>DYNAMIC RANGE: <\/strong>D200<br><strong>D RANGE PRIORITY: <\/strong>OFF<br><strong>TONE CURVE : <\/strong>H +1, S +1<br><strong>COLOR:<\/strong> 0<br><strong>SHARPNESS:<\/strong> &#8211;<br><strong>HIG ISO NR:<\/strong> &#8211;<br><strong>CLARITY: <\/strong>0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fotografare con ACROS+ R, la bellezza della semplicit\u00e0 Quando penso alla fotografia, penso a come trarre il massimo dalla vita osservandola in modo personale e diverso. Non voglio che la realt\u00e0 mi sfugga senza fermarsi; voglio immortalarla a modo mio. FUJIFILM X-E5 \u00e8 senza dubbio una fotocamera che si avvicina molto a questo modo di [&hellip;]<\/p>\n","protected":false},"author":269,"featured_media":351082,"template":"","category":[13929,2084,1006,1202,13607,1055,3211,3309,320,3162,1986,565,13898,13899],"post_tag":[],"class_list":["post-357050","story","type-story","status-publish","has-post-thumbnail","hentry","category-acros-r-filter","category-be-inspired","category-cameras","category-category","category-film-simulation","category-lenses","category-x-series-mirrorless","category-x-mount-prime","category-products","category-x-mount","category-x-series","category-stories","category-x-e5","category-xf23mmf28-r-wr"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 14:55:34","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/story\/357050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/story"}],"about":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/types\/story"}],"author":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/users\/269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media\/351082"}],"wp:attachment":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media?parent=357050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/category?post=357050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/post_tag?post=357050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":357049,"date":"2026-04-30T08:18:03","date_gmt":"2026-04-30T08:18:03","guid":{"rendered":"https:\/\/www.fujifilm-x.com\/?post_type=story&#038;p=357049"},"modified":"2026-04-30T08:18:08","modified_gmt":"2026-04-30T08:18:08","slug":"acros-fs-recipe-x-ben-savage","status":"publish","type":"story","link":"https:\/\/www.fujifilm-x.com\/it-it\/stories\/acros-fs-recipe-x-ben-savage\/","title":{"rendered":"ACROS\u00a0FS RECIPE\u00a0x\u00a0Ben Savage"},"content":{"rendered":"\n<p>Come fotografo che vive in un mondo pieno di colori, spesso \u00e8 gratificante eliminare quell\u2019elemento dall\u2019equazione quando si scattano le foto. Scattare in bianco e nero permette di concentrarsi sulla luce, sulla composizione e sull\u2019emozione che si cerca di trasmettere con un\u2019immagine.<\/p>\n\n\n\n<p>Girando per Sydney con la ricetta personalizzata \u201cShadow Play FS RECIPE\u201d impostato sulla ghiera dedicata di FUJIFILM X-E5, mi sono subito reso conto di quanto la citt\u00e0 apparisse diversa una volta eliminato il colore. Grazie ad ACROS, le scene quotidiane sono diventate senza tempo, dal prendere il traghetto per la citt\u00e0 o anche solo passeggiare per Bondi. Scattare in bianco e nero ti fa rallentare. Ti costringe a notare il modo in cui la luce cade in diversi momenti della giornata e le forme che vengono create dalla citt\u00e0.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_02.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-349054\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_02.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_02.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_02.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_02.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_02.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_02.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_02.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_02.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p>Nei ritratti, le modifiche che ho apportato alla FS RECIPE hanno dato davvero il meglio di s\u00e9. L&#8217;attenuazione del parametro HIGHLIGHTS  (-2) e il contrasto introdotto nel parametro SHADOWS (+1) hanno conferito profondit\u00e0 al soggetto, mantenendo al contempo un&#8217;atmosfera delicata. Senza il colore, ho potuto concentrarmi sull&#8217;espressione, cercare composizioni interessanti e focalizzarmi sul rapporto tra il soggetto e la citt\u00e0 o la natura.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_03.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-349055\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_03.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_03.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_03.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_03.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_03.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_03.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_03.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_03.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p>La serie si \u00e8 rapidamente incentrata sui contrasti. Lo SMOOTH SKIN EFFECT (STRONG) contrapposto ai dettagli nitidi delle foglie di palma. Il gioco di contrasti tra l&#8217;architettura di Sydney e le oasi di natura sparse qua e l\u00e0. Uno dei miei scatti preferiti ritrae l&#8217;Harbour Bridge, le cui linee sono ammorbidite dalle palme in primo piano. \u00c8 un&#8217;immagine che pu\u00f2 appartenere solo a questa citt\u00e0, dove struttura e natura convivono in cos\u00ec stretta sintonia.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_04.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-349056\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_04.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_04.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_04.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_04.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_04.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_04.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_04.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_04.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p>Ci\u00f2 che mi ha colpito di pi\u00f9 \u00e8 stato il modo in cui la luce del tramonto, che di solito appare calda e dorata, ha assunto un carattere misterioso e suggestivo una volta immortalata in bianco e nero.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_05.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-349057\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_05.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_05.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_05.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_05.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_05.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_05.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_05.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_05.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p>Di notte, la ricetta \u00e8 stata nuovamente modificata. Abbassando la riduzione del rumore ad alto ISO (HIGH ISO NR), ho lasciato che la grana naturale venisse in primo piano man mano che l&#8217;ISO aumentava. \u00c8 stato proprio qui che la base ACROS ha davvero dimostrato la sua forza. La grana non sembrava rumore digitale. Aggiungeva consistenza, atmosfera e peso alle ombre. Le luci della citt\u00e0 brillavano, mentre lo skyline si stagliava in tonalit\u00e0 che sembrano senza tempo. La citt\u00e0 \u00e8 diventata pi\u00f9 misteriosa, pi\u00f9 cinematografica, quasi come se stesse rivelando un lato che non si nota alla luce del giorno.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_06.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-349058\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_06.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_06.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_06.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_06.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_06.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_06.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_06.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_06.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p>Ci\u00f2 che mi \u00e8 piaciuto di pi\u00f9 di questo progetto \u00e8 stato il modo in cui mi ha fatto vedere Sydney con occhi nuovi. Ho trascorso gli ultimi due anni qui, esplorando la citt\u00e0 e le spiagge innumerevoli volte, ma eliminando il colore e perfezionando la Simulazione Pellicola ACROS ho dato a questi luoghi familiari una nuova energia. La fotografia non riguarda solo ci\u00f2 che si inserisce nell\u2019inquadratura, ma anche la prospettiva che si sceglie di adottare. Un cambiamento nelle ombre, una piccola regolazione del contrasto o persino la scelta di vedere in bianco e nero possono ridefinire completamente l\u2019atmosfera di un luogo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_07.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-349059\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_07.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_07.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_07.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_07.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_07.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_07.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_07.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_07.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p>Lavorare entro i limiti di una singola Simulazione Pellicola mi ha anche stimolato dal punto di vista creativo. Attenendomi ad un&#8217;unica FS Recipe, non mi sono lasciato distrarre dalle infinite possibilit\u00e0. Al contrario, ho riposto fiducia nel processo e ho puntato sulla coerenza. Questo ha conferito alla serie un senso di coesione, pur spaziando tra ritratti, paesaggi, natura e dettagli architettonici. Ogni fotogramma sembra far parte della stessa storia.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_08.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-349061\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_08.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_08.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_08.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_08.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_08.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_08.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_08.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_08.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p>Alla fine, non si trattava di cercare la ricetta perfetta per la Simulazione Pellicola. Si trattava piuttosto di rallentare, prestare attenzione e trovare il legame tra la citt\u00e0 e la natura. La Simulazione Pellicola ACROS \u00e8 sempre stata una delle mie preferite, ma personalizzarla per questo progetto l\u2019ha resa pi\u00f9 intima. \u00c8 diventata pi\u00f9 di una semplice impostazione. \u00c8 diventata un modo di vedere, un modo di tradurre in fotografie il modo in cui vivo Sydney.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_09.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-349060\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_09.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_09.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_09.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_09.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_09.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_09.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_09.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/AU_Ben-Savage_ACROS_09.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p>Spero che queste immagini riflettano quell\u2019equilibrio: non solo lo skyline o i simboli di Sydney, ma anche i luoghi pi\u00f9 tranquilli dove le foglie delle palme si intrecciano con gli edifici, dove le ombre si allungano sul marciapiede e dove le persone si ritrovano incorniciate tra la natura e la citt\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Come fotografo che vive in un mondo pieno di colori, spesso \u00e8 gratificante eliminare quell\u2019elemento dall\u2019equazione quando si scattano le foto. Scattare in bianco e nero permette di concentrarsi sulla luce, sulla composizione e sull\u2019emozione che si cerca di trasmettere con un\u2019immagine. Girando per Sydney con la ricetta personalizzata \u201cShadow Play FS RECIPE\u201d impostato sulla [&hellip;]<\/p>\n","protected":false},"author":269,"featured_media":349053,"template":"","category":[13920,2084,1006,1202,13607,1055,3211,3309,320,3162,1986,565,13898,13899],"post_tag":[],"class_list":["post-357049","story","type-story","status-publish","has-post-thumbnail","hentry","category-acros","category-be-inspired","category-cameras","category-category","category-film-simulation","category-lenses","category-x-series-mirrorless","category-x-mount-prime","category-products","category-x-mount","category-x-series","category-stories","category-x-e5","category-xf23mmf28-r-wr"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 14:55:34","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/story\/357049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/story"}],"about":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/types\/story"}],"author":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/users\/269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media\/349053"}],"wp:attachment":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media?parent=357049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/category?post=357049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/post_tag?post=357049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":355887,"date":"2026-04-24T00:55:31","date_gmt":"2026-04-24T00:55:31","guid":{"rendered":"https:\/\/www.fujifilm-x.com\/?post_type=story&#038;p=355887"},"modified":"2026-04-24T00:55:39","modified_gmt":"2026-04-24T00:55:39","slug":"imparare-con-la-pratica-fotografia-di-paesaggi-con-andy-mumford","status":"publish","type":"story","link":"https:\/\/www.fujifilm-x.com\/it-it\/stories\/imparare-con-la-pratica-fotografia-di-paesaggi-con-andy-mumford\/","title":{"rendered":"Imparare con la pratica: Fotografia di paesaggi con Andy Mumford"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Il fotografo di paesaggi Andy Mumford ci parla di attrezzatura, tecnica e ci d\u00e0 consigli per le immagini<\/h2>\n\n\n\n<p>Attualmente, Andy Mumford potrebbe stare nella soleggiata Lisbona, ma la sua attivit\u00e0 lo ha portato negli angoli pi\u00f9 remoti del mondo. Fotografo esperto di paesaggi e viaggi, Andy \u00e8 anche un appassionato insegnante di fotografia che condivide la sua esperienza con creativi agli inizi nell\u2019ambito di vari workshop.<\/p>\n\n\n\n<p>\u201cLa gente tende ad avvicinarsi alla fotografia di paesaggi per due motivi\u201d, esordisce. \u201cPu\u00f2 essere perch\u00e9 sono davvero interessati alla fotografia e alle fotocamere, oppure perch\u00e9, come me, sono cresciuti in un ambiente in cui l\u2019escursionismo e la natura erano elementi centrali.<\/p>\n\n\n\n<p>\u201cFin da giovane, ho sempre fatto un sacco di campeggio con i miei genitori, oltre a escursioni nel Peak District. Stare a contatto con la natura mi \u00e8 sempre piaciuto. Per me \u00e8 tutta una questione di sensazioni, di come ti fa sentire stare in un determinato posto. La fotografia \u00e8 semplicemente un modo per immortalare quella percezione\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_01-1024x683.jpg?width=1024&#038;height=683\" alt=\"\" class=\"wp-image-354177\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_01.jpg?width=1024&amp;height=683 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_01.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_01.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_01.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_01.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_01.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\">Foto 2019 \u00a9 Andy Mumford | FUJIFILM X-T3 and FUJINON XF10-24mmF4 R OIS, 1\/125 s a F9, ISO 160<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Prova ed errore<\/h2>\n\n\n\n<p>Come ci ha spiegato con assoluta sincerit\u00e0, i primi tentativi di Andy di fotografare paesaggi non erano particolarmente buoni. Ma invece di scoraggiarsi, ha cercato di capire cosa rendesse alcune foto migliori di altre.<\/p>\n\n\n\n<p>\u201cRicordo che da bambino, quando andavamo in vacanza, usavamo una macchina fotografica a pellicola. Quando portavi a sviluppare le foto, c\u2019era questa espressione: \u201cQuesta \u00e8 venuta bene, questa non \u00e8 venuta\u201d. Ma non avevo mai fatto una riflessione su cosa volesse dire\u201d, ricorda Andy. \u201cChe caratteristiche ha una foto ben riuscita? E quali misteri si nascondono dietro il risultato? Cosa la faceva risultare sfocata o sovraesposta?<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_02-768x1024.jpg?width=768&#038;height=1024\" alt=\"\" class=\"wp-image-354178\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_02.jpg?width=768&amp;height=1024 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_02.jpg?width=225&amp;height=300 225w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_02.jpg?width=640&amp;height=854 640w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_02.jpg?width=717&amp;height=956 717w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\">Foto 2019 \u00a9 Andy Mumford | FUJIFILM X-T3 and FUJINON XF10-24mmF4 R OIS, 1\/30 s a F8, ISO 160<\/figcaption><\/figure>\n\n\n\n<p>\u201cHo cominciato a indagare e a capire perch\u00e9 alcune foto mi piacevano mentre altre erano terribili, cos\u00ec mi sono unito ai primi gruppi fotografici online\u201d. Da l\u00ec ho imparato tantissimo e in breve sono diventato ossessionato dal perfezionare ogni scatto: lunghe esposizioni, l\u2019attesa della golden hour, e cose del genere. Sono un autodidatta, ma \u00e8 nato tutto principalmente dall\u2019amore per stare all\u2019aria aperta, nella natura\u201d.<\/p>\n\n\n\n<p>Questo amore per la natura fa s\u00ec che il fulcro della fotografia di Andy sia trasmettere l\u2019anima di un luogo, pi\u00f9 che offrire una semplice rappresentazione documentaristica del paesaggio.<\/p>\n\n\n\n<p>\u201cIl punto non \u00e8 fotografare il posto\u201d, riflette. \u201cLa questione \u00e8 immortalare le sensazioni che il luogo ti fa provare. L\u2019obiettivo finale di qualsiasi foto \u00e8 questo, specialmente per quanto riguarda la fotografia di paesaggi\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_03-768x1024.jpg?width=768&#038;height=1024\" alt=\"\" class=\"wp-image-354179\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_03.jpg?width=768&amp;height=1024 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_03.jpg?width=225&amp;height=300 225w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_03.jpg?width=640&amp;height=854 640w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_03.jpg?width=717&amp;height=956 717w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\">Foto 2020 \u00a9 Andy Mumford | FUJIFILM X-T3 and FUJINON XF10-24mmF4 R OIS, 25\u00a0s a F9, ISO 160<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Creare un\u2019atmosfera<\/h2>\n\n\n\n<p>\u201cNon sono ossessionato dalla perfezione tecnica. Mi preoccupavo molto di correggere le parti sovraesposte di una fotografia e cose del genere, ma quando acquisisci pi\u00f9 sicurezza, impari a valorizzare le imperfezioni\u201d, spiega Andy.<\/p>\n\n\n\n<p>\u201cAd esempio, magari sto fotografando una scena in cui nel cielo non c\u2019\u00e8 niente. In molti posti in cui lavoro, come la Namibia, i cieli sono spesso completamente vuoti. Questo vuol dire che, fondamentalmente, non \u00e8 un elemento interessante nella fotografia\u201d, osserva. \u201cIn questi casi, quello che puoi fare \u00e8 bruciare il cielo e renderlo bianco e velato\u201d.<\/p>\n\n\n\n<p>Sebbene sia possibile modificare e fare esperimenti con gli aspetti tecnici, Andy sostiene che a livello di composizione le basi debbano essere solide. \u201cLa composizione deve risultare armoniosa\u201d, afferma. \u201cCi sono infiniti tipi di regole per la composizione, ma alla fin fine si tratta di creare qualcosa di equilibrato a livello visivo. Il modo in cui convivono i diversi elementi deve essere armonioso\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_04-683x1024.jpg?width=683&#038;height=1024\" alt=\"\" class=\"wp-image-354180\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_04.jpg?width=683&amp;height=1024 683w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_04.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_04.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_04.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\">Foto 2017 \u00a9 Andy Mumford | FUJIFILM X-T2 and FUJINON XF10-24mmF4 R OIS, 1\/6\u00a0s a F11, ISO 200<\/figcaption><\/figure>\n\n\n\n<p>Una delle caratteristiche fondamentali, eppure pi\u00f9 difficili da definire, di una grande foto \u00e8 l\u2019atmosfera. \u201cLa differenza tra una buona foto e una foto eccellente \u00e8 l\u2019atmosfera\u201d, continua Andy. \u201cPer ottenerla, servono le condizioni giuste, il che significa che, in parte, \u00e8 una questione di fortuna.<\/p>\n\n\n\n<p>\u201cMan mano che progredivo, ho escogitato modi per affrontare il maltempo e la luce piatta per trovare o creare l\u2019atmosfera, sia sottoesponendo sia usando livelli pi\u00f9 elevati di contrasto in post-produzione. L\u2019atmosfera \u00e8 un elemento necessario per migliorare un\u2019immagine. \u00c8 talmente importante che anche le persone che non hanno una comprensione tecnica o un interesse per la fotografia la noteranno e saranno in grado di provare qualcosa guardando la foto\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_05-1024x683.jpg?width=1024&#038;height=683\" alt=\"\" class=\"wp-image-354181\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_05.jpg?width=1024&amp;height=683 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_05.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_05.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_05.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_05.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_05.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\">Foto 2019 \u00a9 Andy Mumford | FUJIFILM X-T3 and FUJINON XF10-24mmF4 R OIS, 1\/60\u00a0s a F8, ISO 160<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Elementi di spontaneit\u00e0<\/h2>\n\n\n\n<p>Nel mondo della fotografia di paesaggi, la pianificazione \u00e8 fondamentale, spiega Andy: \u201cHo un collega con cui lavoro che non apprezza le immagini spontanee. Passa cos\u00ec tanto tempo a controllare le previsioni meteorologiche e a consultare Google Earth che la sua soddisfazione deriva dal fatto che tutto vada come aveva previsto\u201d.<\/p>\n\n\n\n<p>Nonostante anche il lavoro di Andy si basi su una meticolosa pianificazione, lui \u00e8 molto pi\u00f9 propenso a lasciare spazio agli imprevisti. \u201cDi solito c\u2019\u00e8 un elemento che non ti aspetti di vedere. Sai che la luce reagir\u00e0 in un certo modo, ma certe condizioni possono illuminare una parte della scena che non ti aspettavi, quindi devi essere flessibile e pronto ad adattarti.<\/p>\n\n\n\n<p>\u201cIn genere, in un\u2019immagine, potresti avere un elemento in primo piano a 6 metri da te, mentre il tuo soggetto potrebbe essere a chilometri di distanza. Tra il primo piano e lo sfondo, pu\u00f2 succedere di tutto. Magari l\u2019elemento in primo piano non \u00e8 illuminato, mentre lo sfondo \u00e8 molto ben illuminato a causa di un varco tra le nuvole o di una circostanza che non sei stato in grado di prevedere.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_06-1024x683.jpg?width=1024&#038;height=683\" alt=\"\" class=\"wp-image-354182\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_06.jpg?width=1024&amp;height=683 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_06.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_06.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_06.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_06.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_06.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\">Foto 2023 \u00a9 Andy Mumford | FUJIFILM X-T5 and FUJINON XF70-300mmF4-5.6 R LM OIS WR, 1\/2000\u00a0s a F6.4, ISO 640<\/figcaption><\/figure>\n\n\n\n<p>\u201cIn questo caso, potresti togliere l\u2019ottica grandangolare e utilizzare, per esempio, un&#8217;ottica <a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/lenses\/xf70-300mmf4-56-r-lm-ois-wr\/\" target=\"_blank\" rel=\"noreferrer noopener\">FUJINON XF70-300mmF4-5.6 R LM OIS WR<\/a> per eliminare il primo piano, definire il paesaggio in lontananza e iniziare a comporre in modo diverso.<\/p>\n\n\n\n<p>\u201cSe penso al mio portfolio, molte immagini sono pianificate: andiamo, aspettiamo che arrivi la luce prevista e poi facciamo lo scatto. Ma anche facendo cos\u00ec, c\u2019\u00e8 spesso un elemento di ricerca di un particolare primo piano che funzioni con lo sfondo che abbiamo gi\u00e0 studiato, oppure la luce si comporter\u00e0 inaspettatamente. Pensi semplicemente: \u2018OK, funzioner\u00e0.\u2019\u201d<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_07-1024x640.jpg?width=1024&#038;height=640\" alt=\"\" class=\"wp-image-354183\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_07.jpg?width=1024&amp;height=640 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_07.jpg?width=300&amp;height=188 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_07.jpg?width=768&amp;height=480 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_07.jpg?width=400&amp;height=250 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_07.jpg?width=717&amp;height=448 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_07.jpg?width=936&amp;height=585 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\">Foto 2023 \u00a9 Andy Mumford | FUJIFILM X-T5 and FUJINON XF70-300mmF4-5.6 R LM OIS WR, 1\/15\u00a0s a F5.6, ISO 160<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">L\u2019attrezzatura per la fotografia di paesaggi usata da Andy<\/h2>\n\n\n\n<p>Per realizzare determinate sessioni di fotografia pu\u00f2 essere necessario camminare a lungo, perci\u00f2 Andy deve arrivare a un compromesso tra portabilit\u00e0 e qualit\u00e0 ottica quando seleziona l\u2019attrezzatura. \u201cLe fotocamere e le ottiche sono davvero incredibili rispetto a quando ho iniziato 15-20 anni fa\u201d, sottolinea. \u201cSiamo veramente fortunati. In generale, gli obiettivi di alta qualit\u00e0 sono pi\u00f9 pesanti, quindi uso il <a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/gfx-series\/\" target=\"_blank\" rel=\"noreferrer noopener\">Sistema GFX<\/a> se voglio dare la priorit\u00e0 alla qualit\u00e0.<\/p>\n\n\n\n<p>\u201cSe propendo per la portabilit\u00e0, invece, uso <a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/cameras\/x-t5\/\" target=\"_blank\" rel=\"noreferrer noopener\">FUJIFILM X-T5<\/a>. Gli obiettivi meno costosi di Fujifilm, quelli che non sono proprio il top di gamma, sono perfetti per le mie esigenze. In genere, invece di portare i migliori obiettivi a focale fissa, che sono pi\u00f9 nitidi, e gli zoom a F2.8, uso quelli un po\u2019 pi\u00f9 leggeri.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_08-683x1024.jpg?width=683&#038;height=1024\" alt=\"\" class=\"wp-image-354184\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_08.jpg?width=683&amp;height=1024 683w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_08.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_08.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_08.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\">Foto 2023 \u00a9 Andy Mumford | FUJIFILM X-T5 and FUJINON XF70-300mmF4-5.6 R LM OIS WR, 1\/40 s a F6.4, ISO 640<\/figcaption><\/figure>\n\n\n\n<p>\u201cPorto sempre con me uno zoom grandangolare, qualcosa come <a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/lenses\/xf10-24mmf4-r-ois-wr\/\" target=\"_blank\" rel=\"noreferrer noopener\">FUJINON XF10-24mmF4 R OIS WR<\/a>, e un teleobiettivo con zoom, come XF70-300mmF4-5.6 R LM OIS WR. E, inoltre, user\u00f2 uno zoom standard. Di solito prediligo  <a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/lenses\/xf16-50mmf28-48-r-lm-wr\/\" target=\"_blank\" rel=\"noreferrer noopener\">FUJINON XF16-50mmF2.8-4.8 R LM WR<\/a>. \u00c8 un\u2019ottica fantastica e pesa solo 240\u00a0g. In aggiunta, non manca mai XF70-300mmF4-5.6, che pesa solo 580\u00a0g. Cos\u00ec hai un set-up leggero con una copertura straordinaria.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/eshop.fujifilm-x.com\/it\/promozioni.html\" target=\"_blank\" rel=\"noreferrer noopener\">SCOPRI LE PROMOZIONI<\/a><\/div>\n<\/div>\n\n\n\n<p>\u201cNon considero necessario usare le ottiche pi\u00f9 nitide in assoluto. Se lo facessi, userei zoom come <a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/lenses\/xf50-140mmf28-r-lm-ois-wr\/\" target=\"_blank\" rel=\"noreferrer noopener\">FUJINON XF50-140mmF2.8 R LM OIS WR<\/a>, <a href=\"https:\/\/www.fujifilm-x.com\/it-it\/products\/lenses\/xf16-55mmf28-r-lm-wr-ii\/\">XF16-55mmF2.8 R LM WR II<\/a> e <a href=\"hhttps:\/\/www.fujifilm-x.com\/it-it\/products\/lenses\/xf8-16mmf28-r-lm-wr\/\" target=\"_blank\" rel=\"noreferrer noopener\">XF8-16mmF2.8 R LM WR<\/a>. Si tratta di ottiche incredibili con apertura fissa a F2.8, ma pi\u00f9 pesanti.<\/p>\n\n\n\n<p>\u201cLa maggior parte delle persone non noter\u00e0 mai quella percentuale extra di nitidezza nei miei lavori. Potrei notarlo io se ingrandisco le immagini al 100%, ma per quanto riguarda le stampe che vendo o le fotografie che realizzo per le campagne online, non vedrai la differenza\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_09-683x1024.jpg?width=683&#038;height=1024\" alt=\"\" class=\"wp-image-354185\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_09.jpg?width=683&amp;height=1024 683w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_09.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_09.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_09.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\">Foto 2019 \u00a9 Andy Mumford | FUJIFILM X-T3 and FUJINON XF10-24mmF4 R OIS, 30\u00a0s a F13, ISO 160<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Come migliorare i tuoi paesaggi<\/h2>\n\n\n\n<p>Nonostante avere l\u2019attrezzatura adatta al lavoro sia importante, Andy ritiene che non sia un fattore determinante per i fotografi di paesaggi alle prime armi. \u201cNon fissarti su questo\u201d, suggerisce. \u201c\u00c8 pi\u00f9 importante migliorare come fotografo.<\/p>\n\n\n\n<p>\u201cIl golfista Gary Player una volta disse: \u2018Pi\u00f9 mi alleno, pi\u00f9 sono fortunato\u2019. Pi\u00f9 esci, pi\u00f9 \u00e8 probabile imbatterti in luoghi in cui hai la possibilit\u00e0 di scattare buone foto. \u201cNon c\u2019\u00e8 bisogno di andare lontano\u201d, aggiunge Andy. \u201cLa maggior parte delle nozioni che ho imparato da autodidatta proviene dagli scatti della costa vicino a Lisbona, a 45&nbsp;minuti da dove vivo. La gran parte delle persone vive a breve distanza in auto da una qualche spazio naturale.<\/p>\n\n\n\n<p>\u201cL\u2019importante \u00e8 uscire in orari un po\u2019 scomodi. Alzarsi all\u2019alba, quando fa freddo, non piace a nessuno. Se sei ancora fuori al calar del sole \u00e8 possibile che tu finisca per cenare molto tardi. Ma il gioco vale assolutamente la candela\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_10-768x1024.jpg?width=768&#038;height=1024\" alt=\"\" class=\"wp-image-354186\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_10.jpg?width=768&amp;height=1024 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_10.jpg?width=225&amp;height=300 225w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_10.jpg?width=640&amp;height=854 640w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Andy-Mumford-X-Story_10.jpg?width=717&amp;height=956 717w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\">Foto 2023 \u00a9 Andy Mumford | FUJIFILM X-T5 and FUJINON XF150-600mmF5.6-8 R LM OIS WR, 1\/800\u00a0s a F7.1, ISO 1000<\/figcaption><\/figure>\n\n\n\n<p>Per migliorare, per\u00f2, non \u00e8 sufficiente la semplice creazione di foto. Bisogna riflettere sul proprio lavoro, \u00e8 una parte fondamentale del processo, suggerisce Andy. \u201cDevi anche essere critico a livello compositivo. Al giorno d\u2019oggi, con le fotocamere moderne, ottenere l\u2019esposizione e la messa a fuoco corrette \u00e8 relativamente facile. La composizione, per\u00f2, \u00e8 estremamente complessa da capire.<\/p>\n\n\n\n<p>\u201c\u00c8 la cosa pi\u00f9 difficile da insegnare. \u00c8 come cercare di insegnare a qualcuno perch\u00e9 un determinato arrangiamento musicale crea una melodia piacevole, ma cambiando l\u2019ordine delle note suona male. \u00c8 una sensazione che avvertiamo quasi senza rendercene conto. Perch\u00e9 certe forme ci sembrano attraenti? Perch\u00e9 un albero solitario \u00e8 pi\u00f9 piacevole esteticamente di cinque alberi? Devi fare pratica e continuare ad analizzare criticamente le tue foto per scoprire cosa funziona e cosa non funziona\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il fotografo di paesaggi Andy Mumford ci parla di attrezzatura, tecnica e ci d\u00e0 consigli per le immagini Attualmente, Andy Mumford potrebbe stare nella soleggiata Lisbona, ma la sua attivit\u00e0 lo ha portato negli angoli pi\u00f9 remoti del mondo. Fotografo esperto di paesaggi e viaggi, Andy \u00e8 anche un appassionato insegnante di fotografia che condivide [&hellip;]<\/p>\n","protected":false},"author":269,"featured_media":354187,"template":"","category":[2084,1006,1202,1055,3211,320,3162,1986,565,7180,8503,9140,9238,9189,3358],"post_tag":[],"class_list":["post-355887","story","type-story","status-publish","has-post-thumbnail","hentry","category-be-inspired","category-cameras","category-category","category-lenses","category-x-series-mirrorless","category-products","category-x-mount","category-x-series","category-stories","category-x-t5","category-xf10-24mmf4-r-ois","category-xf10-24mmf4-r-ois-wr","category-xf150-600mmf5-6-8-r-lm-ois-wr","category-xf70-300mmf4-5-6-r-lm-ois-wr","category-zoom"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 14:55:34","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/story\/355887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/story"}],"about":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/types\/story"}],"author":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/users\/269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media\/354187"}],"wp:attachment":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media?parent=355887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/category?post=355887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/post_tag?post=355887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":354458,"date":"2026-04-20T02:14:59","date_gmt":"2026-04-20T02:14:59","guid":{"rendered":"https:\/\/www.fujifilm-x.com\/?post_type=story&#038;p=354458"},"modified":"2026-04-20T02:17:19","modified_gmt":"2026-04-20T02:17:19","slug":"malta-archive-project","status":"publish","type":"story","link":"https:\/\/www.fujifilm-x.com\/it-it\/stories\/malta-archive-project\/","title":{"rendered":"Guardians of Memory: FUJIFILM GFX System preserves the Cultural Heritage of MALTA"},"content":{"rendered":"\n<p>The Maltese Islands are a living museum \u2014 their streets and landscapes rich with millennia of human endeavour, collective memory, and visual history. Central to understanding this cultural tapestry are the photographic archives that document Malta\u2019s past: the evocative images of the <strong>Richard Ellis Archive<\/strong>, the official record holdings of the <strong>National Archives of Malta<\/strong>, and the meticulously curated collections of the <strong>Malta Image Preservation Archive (<a href=\"https:\/\/mipa.com.mt\/\" data-type=\"link\" data-id=\"https:\/\/mipa.com.mt\/\" rel=\"nofollow noopener\" target=\"_blank\">MIPA<\/a>)<\/strong>. These priceless materials \u2014 fragile, deteriorating, and often unique \u2014 demand preservation that is both technically rigorous and respectful of their heritage value. In response to that challenge, digital photography is no longer just a convenience tool: it has become a preservation imperative.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"387\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_02.jpg?width=1024&#038;height=387\" alt=\"\" class=\"wp-image-354459\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_02.jpg?width=1024&amp;height=387 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_02.jpg?width=300&amp;height=113 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_02.jpg?width=768&amp;height=290 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_02.jpg?width=400&amp;height=151 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_02.jpg?width=365&amp;height=138 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_02.jpg?width=600&amp;height=227 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_02.jpg?width=717&amp;height=271 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_02.jpg?width=936&amp;height=353 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p><strong>The largest online repository of archival photographic history material pertaining to Malta, the Malta Image Preservation Archive (<a href=\"https:\/\/mipa.com.mt\/\" data-type=\"link\" data-id=\"https:\/\/mipa.com.mt\/\" rel=\"nofollow noopener\" target=\"_blank\">MIPA<\/a>), uses FUJIFILM GFX camera systems exclusively to digitise all archival material.<\/strong><\/p>\n\n\n\n<p><strong>The Digital Imperative in Cultural Heritage<br><\/strong>Photographic prints, negatives, and transparencies are vulnerable to time. Silver mirroring, physical abrasions, and chemical degradation progressively obscure detail and diminish informational content. Digitisation not only stabilises the present state of these objects but also creates a durable surrogate that can be studied, shared, and safeguarded for future generations. But digitisation is only as good as the technology used to capture it.<\/p>\n\n\n\n<p>For cultural heritage institutions \u2014 especially those tasked with archiving national memory \u2014 the technical criteria for digitisation are exacting. Accurate tonal reproduction, high resolution, minimal noise, and faithful colour rendition are essential if digital surrogates are to be trustworthy representations of the originals. Enter Fujifilm\u2019s large-format digital systems: the <strong>FUJIFILM GFX100S and GFX100 II.<\/strong><\/p>\n\n\n\n<p><strong>FUJIFILM GFX: Large-format for Maximum Fidelity<br><\/strong>At the heart of both the FUJIFILM GFX100S and the GFX100 II is a <strong>102-megapixel large-format CMOS sensor<\/strong> \u2014 significantly larger than the typical 35 mm full-frame sensor. This increased sensor area translates directly into higher native resolution, finer tonal gradation, and enhanced dynamic range. For archival digitisation work, this means micro-texture \u2014 the subtle interplay of grain, detail, and shadow \u2014 is resolved with remarkable clarity.<\/p>\n\n\n\n<p><strong>Technical strengths that matter for heritage work include:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>High Resolution and Detail Capture<\/strong><br>The 102 MP sensor captures extraordinarily fine detail, enabling archival masters that can be used for large-format reproduction without loss of fidelity.<\/li>\n\n\n\n<li><strong>Dynamic Range and Tonal Depth<\/strong><br>Both systems deliver approximately 14+ stops of dynamic range. This allows archivists to preserve detail in highlights and shadows \u2014 crucial for aged or unevenly processed originals.<\/li>\n\n\n\n<li><strong>Colour Accuracy and Reproducibility<\/strong><br>Fujifilm\u2019s color science, combined with high-bit RAW capture, ensures faithful rendering of subtle hues in historical documents, delicate tonality in early black-and-white photography, and the varied palette of colour emulsions.<\/li>\n\n\n\n<li><strong>Low Noise and High ISO Integrity<\/strong><br>Even at lower light levels often encountered in archive studios, the sensor\u2019s performance maintains clarity with minimal noise \u2014 a valuable asset when copying old negatives that cannot be aggressively illuminated.<\/li>\n\n\n\n<li><strong>Stability and Workflow Efficiency<\/strong><br>The GFX systems\u2019 ergonomic design, weather-sealed bodies, and reliable autofocus \u2014 often paired with high-quality FUJINON GF Lenses \u2014 streamline extended digitisation sessions, reducing operator fatigue and improving output consistency.<\/li>\n<\/ul>\n\n\n\n<p>Between the <strong>GFX100S<\/strong> \u2014 a more compact, cost-efficient medium-format solution \u2014 and the <strong>GFX100 II<\/strong> \u2014 boasting enhanced processing speed, refined autofocus, and improved handling \u2014 heritage digitisation programmes gain flexibility without compromising image quality. Using the two FUJIFIILM GFX bodies provided by Ciancio 1913 Co. Ltd. Malta, as well as the FUJINON GF32-64mmF4 R LM WR and GF120mmF4 R LM OIS WR MACRO ensured a complete two camera system suitable for digitising all sizes of artifacts, prints and negatives from 35mm all the way to A0 size, up to 400-megapixels in size.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"876\" height=\"1024\" data-id=\"354460\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_03.jpg?width=876&#038;height=1024\" alt=\"\" class=\"wp-image-354460\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_03.jpg?width=876&amp;height=1024 876w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_03.jpg?width=257&amp;height=300 257w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_03.jpg?width=768&amp;height=898 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_03.jpg?width=365&amp;height=427 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_03.jpg?width=600&amp;height=702 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_03.jpg?width=717&amp;height=839 717w\" sizes=\"auto, (max-width: 876px) 100vw, 876px\" data-recalc-dims=\"1\" \/><\/figure>\n<\/figure>\n\n\n\n<p><strong>Photo captured by Richard Ellis of the bow view of HMS Vulcan, in drydock August 1897, digitised from the 12 x 10 inch gelatin glass plate negative using FUJIFILM GFX100S and FUJINON GF32-64mmF4 R LM WR. Courtesy of the Richard Ellis Archive.<\/strong><\/p>\n\n\n\n<p><strong>Digitising the Maltese Photographic Legacy<br><\/strong>Institutions such as the <strong>National Archives of Malta<\/strong> hold official records that chronicle civic life, public works, and national development. Their photographic collections, including those of Guido Stilon and Sigrid Neubert, digitised using FUJIFILM GFX systems, trace Malta\u2019s evolving identity. The <strong>Richard Ellis Archive<\/strong> contains evocative imagery that is both documentary and artistic, capturing people, places, and narratives seldom preserved elsewhere. Meanwhile, the <strong>Malta Image Preservation Archive<\/strong> acts as a custodian for thousands of community-sourced and professional images \u2014 each one a thread in the visual history of the islands, such as the collections of David Wrightson and Gerald Formosa.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"716\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_04.jpg?width=1024&#038;height=716\" alt=\"\" class=\"wp-image-354461\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_04.jpg?width=1024&amp;height=716 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_04.jpg?width=300&amp;height=210 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_04.jpg?width=768&amp;height=537 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_04.jpg?width=400&amp;height=280 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_04.jpg?width=365&amp;height=255 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_04.jpg?width=600&amp;height=419 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_04.jpg?width=717&amp;height=501 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_04.jpg?width=936&amp;height=654 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p><strong>Guido Stilon\u2019s Exacta camera, digitised using FUJIFILM GFX 100 II and FUJINON GF120mmF4 R LM OIS WR Macro. Courtesy of MIPA.<\/strong><\/p>\n\n\n\n<p>Using FUJIFILM GFX systems in these contexts means:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Producing high-resolution digital masters suitable for long-term storage and access.<\/li>\n\n\n\n<li>Delivering images that support research, publication, and exhibition without risking damage to the originals.<\/li>\n\n\n\n<li>Enabling digital preservation workflows that align with international standards for archival imaging.<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-columns has-spacing-none has-no-design is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_05.jpg?width=819&#038;height=1024\" alt=\"\" class=\"wp-image-354462\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_05.jpg?width=819&amp;height=1024 819w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_05.jpg?width=240&amp;height=300 240w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_05.jpg?width=768&amp;height=960 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_05.jpg?width=365&amp;height=456 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_05.jpg?width=600&amp;height=750 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_05.jpg?width=717&amp;height=896 717w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" data-recalc-dims=\"1\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_06.jpg?width=819&#038;height=1024\" alt=\"\" class=\"wp-image-354463\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_06.jpg?width=819&amp;height=1024 819w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_06.jpg?width=240&amp;height=300 240w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_06.jpg?width=768&amp;height=960 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_06.jpg?width=365&amp;height=456 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_06.jpg?width=600&amp;height=750 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_06.jpg?width=717&amp;height=896 717w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" data-recalc-dims=\"1\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"793\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_08_add.jpg?width=793&#038;height=1024\" alt=\"\" class=\"wp-image-354889\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_08_add.jpg?width=793&amp;height=1024 793w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_08_add.jpg?width=232&amp;height=300 232w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_08_add.jpg?width=768&amp;height=992 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_08_add.jpg?width=365&amp;height=471 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_08_add.jpg?width=600&amp;height=775 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_08_add.jpg?width=717&amp;height=926 717w\" sizes=\"auto, (max-width: 793px) 100vw, 793px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p><strong>Two milestone publications produced using the material digitised using FUJIFILM GFX equipment, namely <em>100 Years of Photography in Malta, 1839\u20131939<\/em> and <em>Victorian Malta<\/em>, both published in 2025. Courtesy of the author, Dr Charles Paul Azzopardi &amp; Midsea Books.<\/strong><\/p>\n\n\n\n<p>By digitising such holdings with technical precision and archival integrity, these institutions ensure Malta\u2019s visual heritage remains accessible to researchers, educators, and the public \u2014 not just today, but for generations to come. This has already resulted in the publication of several milestone landmark publications documenting Maltese photographic history, such as the de facto encyclopaedia of Maltese photographic history, <em>100 Years of Photography in Malta, 1839\u20131939<\/em> (published in 2025 and already sold out), as well as the milestone exhibit documenting the 150th anniversary of the Richard Ellis Archive in 2022.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"150 | Richard Ellis | Exhibition Promo | 2022\/2023\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/odNsyVxzIc0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>150 \u2013 Ellis curator vignette<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_07.jpg?width=1024&#038;height=683\" alt=\"\" class=\"wp-image-354464\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_07.jpg?width=1024&amp;height=683 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_07.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_07.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_07.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_07.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_07.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_07.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/Malta_GFX-Project_07.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p><strong>The installation of the 150 \u2013 Ellis exhibit in 2022 commemorated the 150<sup>th<\/sup> anniversary of the Richard Ellis Archive. All the material for the exhibit was digitised using FUJIFILM GFX100S and  FUJINON GF32-64mmF4 R LM WR in a 400-megapixel multi-shot modality. Courtesy of the Richard Ellis Archive.<\/strong><\/p>\n\n\n\n<p><strong>The Broader Cultural Impact<br><\/strong>Preserving Malta\u2019s photographic heritage through digitisation does more than safeguard images: it nurtures collective memory. Digitised archives become platforms for exploration, education, and interpretation. They empower scholars to conduct comparative research, allow communities to rediscover their past, and support cultural tourism with authentic visual narratives grounded in history.<\/p>\n\n\n\n<p>As Malta embraces digital preservation, the choice of equipment matters. The FUIFILM GFX 100S and GFX100 II offer the combination of resolution, fidelity, and reliability needed for archival excellence. In the meticulous work of capturing the nuances of a nation\u2019s visual record, these cameras are not just tools \u2014 they are partners in the stewardship of cultural memory.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.maltarti.tv\/portfolio\/100-years-of-photography\" rel=\"nofollow noopener\" target=\"_blank\">https:\/\/www.maltarti.tv\/portfolio\/100-years-of-photography<\/a><br><em>100 Years of Photography in Malta, 1839\u20131939 featurette<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>The Maltese Islands are a living museum \u2014 their streets and landscapes rich with millennia of human endeavour, collective memory, and visual history. Central to understanding this cultural tapestry are the photographic archives that document Malta\u2019s past: the evocative images of the Richard Ellis Archive, the official record holdings of the National Archives of Malta, [&hellip;]<\/p>\n","protected":false},"author":135,"featured_media":354465,"template":"","category":[2084,1006,1202,3113,10365,10806,1937,10267,3505,565],"post_tag":[],"class_list":["post-354458","story","type-story","status-publish","has-post-thumbnail","hentry","category-be-inspired","category-cameras","category-category","category-g-mount","category-gf120mmf4-r-lm-ois-wr-macro","category-gf32-64mmf4-r-lm-wr","category-gfx-series","category-gfx100-ii","category-g-mount-prime","category-stories"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 14:55:35","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/story\/354458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/story"}],"about":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/types\/story"}],"author":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/users\/135"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media\/354465"}],"wp:attachment":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media?parent=354458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/category?post=354458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/post_tag?post=354458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":355260,"date":"2026-04-15T00:51:06","date_gmt":"2026-04-15T00:51:06","guid":{"rendered":"https:\/\/www.fujifilm-x.com\/?post_type=story&#038;p=355260"},"modified":"2026-04-15T00:51:12","modified_gmt":"2026-04-15T00:51:12","slug":"acros-fs-recipe-x-alex-liverani","status":"publish","type":"story","link":"https:\/\/www.fujifilm-x.com\/it-it\/stories\/acros-fs-recipe-x-alex-liverani\/","title":{"rendered":"ACROS FS RECIPE\u00a0x\u00a0Alex Liverani"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong><strong>ACROS, sogni ad occhi aperti<\/strong><\/strong><\/h2>\n\n\n\n<p>&#8220;Credo non ci sia cosa che ami di pi\u00f9 della fotografia, ma in questo legame viscerale, totalizzante\u00a0 e indissolubile, l\u2019aspetto che meno apprezzo di questa professione, \u00e8 certamente la fase della post-produzione. Sono fotografo di professione da oltre 20 anni ma, nei ritagli di tempo tra un lavoro commissionato e l\u2019altro, quando posso finalmente dedicarmi alla mia fotografia, sento proprio un bisogno di semplicit\u00e0, di immediatezza e di istantaneit\u00e0, tutti aspetti per\u00f2 che in nessun modo, devono inficiare sulla qualit\u00e0 del lavoro stesso.<\/p>\n\n\n\n<p>Utilizzo Fujifilm dal 2016, e qui potrei elencare un\u2019infinit\u00e0 di motivi per cui mi sono legato agli strumenti di questo brand, ma credo che siano state le simulazioni pellicola, a farmi innamorare perdutamente.<\/p>\n\n\n\n<p>Sebbene lavori spesso con la fotografia a colori, a volte sento ancora il bisogno di visualizzare l&#8217;ambiente circostante in bianco e nero, per sentirmi pi\u00f9 vicino ai maestri che mi hanno ispirato e che hanno fondato le origini della fotografia di strada nella storia della fotografia, ma anche per riprodurre una sorta di atmosfera onirica e surreale.&#8221;<\/p>\n\n\n\n<div class=\"wp-block-columns has-spacing-none has-no-design is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_02.jpg?width=682&#038;height=1024\" alt=\"\" class=\"wp-image-349712\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_02.jpg?width=682&amp;height=1024 682w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_02.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_02.jpg?width=365&amp;height=548 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_02.jpg?width=600&amp;height=900 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_02.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_02.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_03.jpg?width=682&#038;height=1024\" alt=\"\" class=\"wp-image-349713\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_03.jpg?width=682&amp;height=1024 682w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_03.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_03.jpg?width=365&amp;height=548 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_03.jpg?width=600&amp;height=900 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_03.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_03.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p>&#8220;Con estrema semplicit\u00e0, con la nuova <a href=\"https:\/\/eshop.fujifilm-x.com\/it\/fujifilm-x-e5.html\" data-type=\"link\" data-id=\"https:\/\/eshop.fujifilm-x.com\/it\/fujifilm-x-e5.html\" target=\"_blank\" rel=\"noreferrer noopener\">FUJIFILM X-E5<\/a>, ruoto la ghiera delle simulazioni pellicola fino a trovare la \u201cA\u201d di ACROS, e il mio sguardo si trasforma all\u2019istante in un vero e proprio sogno ad occhi aperti.<br>Lo sguardo, attravero il mirino della fotocamera, mi proietta su una visione del mondo senza tempo, con la profondit\u00e0 e la brillantezza che rimanda all\u2019eleganza e alla gravit\u00e0 delle pregiate stampe all\u2019alogenuro d\u2019argento. Un bianco e nero essenziale, un linguaggio profondo, sensuale e contemporaneo ma allo stesso tempo legato al passato, una visione perfetta per trasformare la vita quotidiana in poesia visiva.&#8221;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"697\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_04.jpg?width=697&#038;height=1024\" alt=\"\" class=\"wp-image-349714\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_04.jpg?width=697&amp;height=1024 697w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_04.jpg?width=204&amp;height=300 204w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_04.jpg?width=365&amp;height=536 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_04.jpg?width=600&amp;height=881 600w\" sizes=\"auto, (max-width: 697px) 100vw, 697px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p>&#8220;ACROS \u00e8 la Simulazione Pellicola ideale per le composizioni minimali e contemplative, dove la perfezione spaziale incontra la presenza silenziosa della figura umana, in una visiona onirica e metafisica, che rimanda alle pitture di Giorgio de Chirico. Le scene sembrano dipinte, evocano un senso di mistero, inquietudine e straniamento, una simulazione adatta ad evidenziare la consistenza dei materiali, esaltando tutte le sfumature di luce sulle varie superfici.<\/p>\n\n\n\n<p>Per questo progetto in particolare, oltre ad aver scelto di scattare con ACROS selezionando il filtro G, ho modificato le impostazioni di scatto andando a creare una nuova ricetta che ho chiamato METAPHYSICAL NOIR.<br><br>Nella fotografia analogica su pellicola, era pratica comune realizzare fotografie in bianco e nero applicando un filtro colorato davanti all&#8217;obiettivo.&#8221;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_05.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-349715\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_05.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_05.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_05.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_05.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_05.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_05.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_05.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_05.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p>&#8220;Oggi tutto \u00e8 pi\u00f9 semplice, cos\u00ec attivando il filtro colorato che preferiamo nella fotografia digitale, le Simulazioni Pellicola di Fujifilm continuano questa pratica in una veste contemporanea e immediata. Ho attivato il filtro G, Green particolarmente adatto anche per i ritratti. Riduce i toni rossi della pelle e scurisce le labbra, contribuendo a rendere naturale il resto del viso. A differenza della fotografia analogica, dove non \u00e8 possibile verificare l&#8217;effetto in tempo reale, filtri digitali come le Simulazioni Pellicola sono istantanei, visualizzabili direttamente dalla fotocamera. Utilizzando il mirino elettronico per previsualizzare l&#8217;effetto, abbiamo la possibilit\u00e0 di scegliere la Simulazione Pellicola che preferiamo.&#8221;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_06.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-349716\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_06.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_06.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_06.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_06.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_06.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_06.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_06.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_06.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p>&#8220;La mia ricetta Metaphysical Noir \u00e8 molto semplice, ma spesso la semplicit\u00e0 \u00e8 anche sinonimo di efficacia. Per un mio personale gusto estetico ho anche agito sull\u2019effetto grana selezionando una durezza \u201cdebole\u201d e una dimensione \u201cpiccola\u201d della grana stessa. La grana contribuisce a rendere l\u2019immagine con un retrogusto vintage, ma allo stesso tempo non voglio diventi troppo invasiva, questa opzione individuata, credo sia un ottimo compromesso.&#8221;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_07.jpg?width=576&#038;height=1024\" alt=\"\" class=\"wp-image-349717\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_07.jpg?width=576&amp;height=1024 576w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_07.jpg?width=169&amp;height=300 169w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_07.jpg?width=365&amp;height=649 365w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p>&#8220;Le uniche altre modifiche alla ricetta, le ho effettuate agendo nella sezione \u201cCurva Tono\u201d applicando un +1 o + 2 alle alte luci, cos\u00ec da aver un bel punto di bianco nelle pozioni illuminate delle mie foto, e un +3 o un +4 alle ombre cos\u00ec da enfatizzare il contrasto tra le aree differentemente illuminate.&#8221;<\/p>\n\n\n\n<div class=\"wp-block-columns has-spacing-none has-no-design is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_08.jpg?width=682&#038;height=1024\" alt=\"\" class=\"wp-image-349718\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_08.jpg?width=682&amp;height=1024 682w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_08.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_08.jpg?width=365&amp;height=548 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_08.jpg?width=600&amp;height=900 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_08.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_08.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_09.jpg?width=682&#038;height=1024\" alt=\"\" class=\"wp-image-349719\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_09.jpg?width=682&amp;height=1024 682w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_09.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_09.jpg?width=365&amp;height=548 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_09.jpg?width=600&amp;height=900 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_09.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_09.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p>&#8220;Immagini con neri profondi e alte luci dettagliate, che contribuiscono ad una grande sensazione di tridimensionalit\u00e0 ma allo stesso tempo con una gradazione tonale estremamente ricca in ogni sfumatura.<\/p>\n\n\n\n<p>FUJIFILM X-E5, FUJINON XF23mmF2.8, la Simulazione Pellicola ACROS G, e la ricetta Metaphysical Noir rappresentano la combinazione perfetta per trasformare momenti ordinari in metafore visive e sogni ad occhi aperti.&#8221;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_10.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-349720\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_10.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_10.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_10.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_10.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_10.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_10.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_10.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/02\/IT_Alex-Liverani_ACROS_10.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>ACROS, sogni ad occhi aperti &#8220;Credo non ci sia cosa che ami di pi\u00f9 della fotografia, ma in questo legame viscerale, totalizzante\u00a0 e indissolubile, l\u2019aspetto che meno apprezzo di questa professione, \u00e8 certamente la fase della post-produzione. Sono fotografo di professione da oltre 20 anni ma, nei ritagli di tempo tra un lavoro commissionato e [&hellip;]<\/p>\n","protected":false},"author":269,"featured_media":349711,"template":"","category":[13930,2084,1006,1202,13607,1055,3211,3309,320,3162,1986,565,13898,13899],"post_tag":[],"class_list":["post-355260","story","type-story","status-publish","has-post-thumbnail","hentry","category-acros-g-filter","category-be-inspired","category-cameras","category-category","category-film-simulation","category-lenses","category-x-series-mirrorless","category-x-mount-prime","category-products","category-x-mount","category-x-series","category-stories","category-x-e5","category-xf23mmf28-r-wr"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 14:55:35","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/story\/355260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/story"}],"about":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/types\/story"}],"author":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/users\/269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media\/349711"}],"wp:attachment":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media?parent=355260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/category?post=355260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/post_tag?post=355260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":355213,"date":"2026-04-14T08:57:22","date_gmt":"2026-04-14T08:57:22","guid":{"rendered":"https:\/\/www.fujifilm-x.com\/?post_type=story&#038;p=355213"},"modified":"2026-04-14T08:57:28","modified_gmt":"2026-04-14T08:57:28","slug":"classic-neg-fs-recipe-x-dustin-hendarlim","status":"publish","type":"story","link":"https:\/\/www.fujifilm-x.com\/it-it\/stories\/classic-neg-fs-recipe-x-dustin-hendarlim\/","title":{"rendered":"CLASSIC Neg. FS RECIPE x Dustin Hendarlim"},"content":{"rendered":"\n<p>\u201cLa fotografia \u00e8 sempre stata il mio modo per rallentare i ritmi. Con CLASSIC Neg. mi sembra di attingere a una tavolozza d&#8217;altri tempi, un&#8217;epoca in cui le mattine non erano frenetiche e i colori respiravano al proprio ritmo.\u201d<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_02.jpg?width=682&#038;height=1024\" alt=\"\" class=\"wp-image-344195\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_02.jpg?width=682&amp;height=1024 682w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_02.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_02.jpg?width=365&amp;height=548 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_02.jpg?width=600&amp;height=900 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_02.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_02.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p>Cilincing \u00e8 un piccolo villaggio di pescatori situato all&#8217;estremit\u00e0 settentrionale di Giacarta. \u00c8 il tipo di posto dove la vita scorre senza fretta; le barche scricchiolano dolcemente sull&#8217;acqua, i bambini corrono a piedi nudi sul cemento consumato dal tempo e l&#8217;aria profuma vagamente di salsedine. Di prima mattina, la luce \u00e8 morbida e avvolgente, e avvolge ogni angolo in un&#8217;atmosfera di tranquillit\u00e0.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_03.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-344196\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_03.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_03.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_03.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_03.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_03.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_03.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_03.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_03.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_04.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-344197\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_04.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_04.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_04.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_04.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_04.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_04.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_04.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_04.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p>\u00c8 l\u00ec che ho deciso di portare con me <a href=\"https:\/\/eshop.fujifilm-x.com\/it\/fujifilm-x-e5.html\" data-type=\"link\" data-id=\"https:\/\/eshop.fujifilm-x.com\/it\/fujifilm-x-e5.html\">FUJIFILM X-E5<\/a> con il nuovo obiettivo<a href=\"https:\/\/eshop.fujifilm-x.com\/it\/fujinon-xf23mm-f28-r-wr.html\" data-type=\"link\" data-id=\"https:\/\/eshop.fujifilm-x.com\/it\/fujinon-xf23mm-f28-r-wr.html\"> XF23 mm F2.8 R WR<\/a> per il mio servizio fotografico CLASSIC Neg. Sono stato attratto dal momento, dai colori e dal minimalismo che quella scena offriva. Non stavo cercando i volti delle persone o eventi drammatici, ma solo l&#8217;essenza stessa di trovarmi l\u00ec.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_05.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-344199\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_05.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_05.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_05.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_05.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_05.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_05.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_05.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_05.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p>A mio avviso, la pellicola CLASSIC Neg. possiede quel calore vintage che ti trasporta immediatamente in un&#8217;altra epoca. Non si tratta solo dei colori, ma anche del ritmo dell&#8217;immagine, di quella sensazione di lentezza che trasmette. I verdi sono tenui, i rossi evocano una dolce nostalgia e ogni tonalit\u00e0 sembra appartenere a un ricordo piuttosto che a un file.<\/p>\n\n\n\n<p>Per questo servizio fotografico, ho scelto un look ben definito:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>BILANCIAMENTO DEL BIANCO: AUTO con R +1 \/ B -1, per evitare che le ombre assumessero una tonalit\u00e0 troppo verde.<\/li>\n\n\n\n<li>CURVA DI TONALIT\u00c0: H -1,5 \/ S -1,5, per attenuare il contrasto e ricreare la morbida atmosfera analogica.<\/li>\n\n\n\n<li>EFFETTO GRANULOSIT\u00c0: DEBOLE, PICCOLO \u2014 quanto basta per richiamare alla mente la texture della pellicola.<\/li>\n\n\n\n<li>COLORE: +2, per ridare vita a determinati toni senza alterare l&#8217;atmosfera.<\/li>\n<\/ul>\n\n\n\n<p>Il risultato \u00e8 un diario visivo della tranquilla bellezza di Cilincing. Luce soffusa che si riflette sulla vernice scrostata, sentieri sabbiosi che conducono al mare e il movimento senza fretta delle persone che iniziano la loro giornata. CLASSIC Neg. non si \u00e8 limitato a documentare la scena, ma ne ha preservato il ritmo.<\/p>\n\n\n\n<p>Quando ripenso a quelle immagini, \u00e8 come se avessi tra le mani una serie di cartoline di un periodo pi\u00f9 semplice della mia vita. Ecco perch\u00e9 CLASSIC Neg. mi colpisce cos\u00ec tanto: non si limita a mostrare ci\u00f2 che ho visto, ma mi riporta l\u00ec.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_06.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-344200\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_06.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_06.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_06.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_06.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_06.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_06.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_06.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/ID_Dustin-Hendarlim_Stories_06.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u201cLa fotografia \u00e8 sempre stata il mio modo per rallentare i ritmi. Con CLASSIC Neg. mi sembra di attingere a una tavolozza d&#8217;altri tempi, un&#8217;epoca in cui le mattine non erano frenetiche e i colori respiravano al proprio ritmo.\u201d Cilincing \u00e8 un piccolo villaggio di pescatori situato all&#8217;estremit\u00e0 settentrionale di Giacarta. \u00c8 il tipo di [&hellip;]<\/p>\n","protected":false},"author":269,"featured_media":344194,"template":"","category":[1006,13924,13607,1055,3211,3309,320,3162,1986,13898,13899],"post_tag":[],"class_list":["post-355213","story","type-story","status-publish","has-post-thumbnail","hentry","category-cameras","category-classic-neg","category-film-simulation","category-lenses","category-x-series-mirrorless","category-x-mount-prime","category-products","category-x-mount","category-x-series","category-x-e5","category-xf23mmf28-r-wr"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 14:55:35","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/story\/355213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/story"}],"about":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/types\/story"}],"author":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/users\/269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media\/344194"}],"wp:attachment":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media?parent=355213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/category?post=355213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/post_tag?post=355213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":355222,"date":"2026-04-14T08:55:17","date_gmt":"2026-04-14T08:55:17","guid":{"rendered":"https:\/\/www.fujifilm-x.com\/?post_type=story&#038;p=355222"},"modified":"2026-04-14T08:55:23","modified_gmt":"2026-04-14T08:55:23","slug":"classic-chrome-fs-recipe-x-thomas-b-jones","status":"publish","type":"story","link":"https:\/\/www.fujifilm-x.com\/it-it\/stories\/classic-chrome-fs-recipe-x-thomas-b-jones\/","title":{"rendered":"\u00a0CLASSIC CHROME FS RECIPE x Thomas B. Jones"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>Salty Skipper \u2013 Con CLASSIC CHROME tra il banco da lavoro e la linea d&#8217; acqua<\/strong><\/h2>\n\n\n\n<p>Ci sono luoghi in cui la fotografia va oltre la semplice immortalazione di un momento: diventa un\u2019esperienza condivisa. Per me, i laboratori artigianali sono proprio questo tipo di luoghi. Il profumo del legno, la lunga tradizione, gli attrezzi, la concentrazione nei movimenti \u2013 e soprattutto le persone che danno vita a tutto questo. Persone che hanno imparato alla perfezione il proprio mestiere, lavorano con dedizione e hanno storie da raccontare. Tutto questo racconta una storia \u2013 ben prima che si prema il pulsante di scatto.<\/p>\n\n\n\n<p>Da anni CLASSIC CHROME \u00e8 la mia prima scelta per questo tipo di reportage. Il look pulito e documentaristico mette a fuoco ci\u00f2 che \u00e8 importante: niente filtri, niente abbellimenti. Ed \u00e8 proprio questo che rende CLASSIC CHROME cos\u00ec speciale per me.<\/p>\n\n\n\n<p>Allo stesso tempo, CLASSIC CHROME \u00e8 incredibilmente flessibile: che sia per strada, in riva al lago o nel bel mezzo di un laboratorio, la simulazione pellicola gestisce con facilit\u00e0 il passaggio tra diverse condizioni di luce e colore. Quando passo dalla fotografia di strada al reportage spontaneo, come faccio qui, offre sempre risultati affidabili.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_2-1.jpg?width=682&#038;height=1024\" alt=\"\" class=\"wp-image-339951\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_2-1.jpg?width=682&amp;height=1024 682w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_2-1.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_2-1.jpg?width=365&amp;height=548 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_2-1.jpg?width=600&amp;height=900 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_2-1.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_2-1.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Cosa rende CLASSIC CHROME cos\u00ec speciale<\/strong><\/h3>\n\n\n\n<p>CLASSIC CHROME \u00e8 una Simulazione Pellicola che non si basa su un modello analogico specifico, ed \u00e8 proprio questo che la rende cos\u00ec speciale. La stessa Fujifilm la descrive come una \u00absimulazione pellicola immaginaria\u00bb ispirata all\u2019estetica delle classiche riviste di fotogiornalismo del XX secolo.<br>A differenza di PROVIA o PRO Neg., noti per i loro colori puliti e chiari, CLASSIC CHROME punta sulla sobriet\u00e0: toni tenui, ombre fredde e un effetto magenta ridotto. Il risultato \u00e8 un profilo cromatico che non si impone in primo piano, ma lascia spazio al momento.<\/p>\n\n\n\n<p>Questa sobriet\u00e0 conferisce a CLASSIC CHROME un senso di seriet\u00e0 e calma. Soprattutto con soggetti in stile documentario o reportage, questo crea un look che non appare in posa, ma autentico e concentrato.<\/p>\n\n\n\n<p>Eppure, per quanto la simulazione possa sembrare sottile a prima vista, conferisce alle immagini una profondit\u00e0 e un carattere che si possono percepire. Proprio perch\u00e9 non sembra mai invadente, mi affido a CLASSIC CHROME quando si tratta di raccontare storie in modo autentico.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_3-1.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-339952\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_3-1.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_3-1.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_3-1.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_3-1.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_3-1.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_3-1.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_3-1.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_3-1.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>La mia FS Recipe: Salty Skipper<\/strong><\/h3>\n\n\n\n<p>Ho chiamato la mia CLASSIC CHROME FS RECIPE \u201cSalty Skipper\u201d, un sottile riferimento ai marinai dal carattere rude, ma anche al carattere stesso del look: grezzo, genuino, marittimo.<\/p>\n\n\n\n<p>Questa FS RECIPE \u00e8 ideale per ambienti ad alto contrasto, come la luce solare diretta all&#8217;aperto, ma anche per situazioni di illuminazione soffusa con un mix di luce naturale e artificiale nei laboratori. Lavoro con DR200 per preservare maggiori dettagli nelle luci, mantenendo al contempo una profondit\u00e0 sufficiente nelle ombre.<\/p>\n\n\n\n<p>I colori sono volutamente marittimi: COLOR CHROME FX BLUE impostato su \u201cSTRONG\u201d intensifica le caratteristiche tonalit\u00e0 blu di CLASSIC CHROME \u2013 cielo, acqua, zone d&#8217;ombra \u2013 senza che appaiano innaturali. A questo si aggiunge un bilanciamento del bianco leggermente pi\u00f9 caldo, che garantisce un contrasto arrotondato e armonioso, soprattutto con il legno, le tonalit\u00e0 della pelle e i piccoli dettagli cromatici.<\/p>\n\n\n\n<p>+4 COLOR enfatizza questo effetto senza perdere la classica sobriet\u00e0 di CLASSIC CHROME. Il look rimane realistico, ma con carattere.<br>Una grana fine e delicata (EFFETTO GRANA: DEBOLE, PICCOLA) aggiunge all&#8217;immagine una sottile texture vintage e una sensazione tangibile. Conferisce all&#8217;immagine una qualit\u00e0 tattile che si abbina bene alle scene di artigianato senza risultare invadente.<\/p>\n\n\n\n<p>La CURVA DI TONALIT\u00c0 \u00e8 regolata in modo tale che le luci siano leggermente attenuate (LUCI: -1) e le ombre siano accentuate (OMBRE: +2). Ci\u00f2 garantisce una maggiore definizione nelle luci e una maggiore densit\u00e0 nelle ombre \u2013 ideale sia per le riprese all\u2019aperto alla luce del sole che in interni.<\/p>\n\n\n\n<p>Il BILANCIAMENTO DEL BIANCO viene deliberatamente corretto con moderazione (AUTO \/ R: 0, B: -3) \u2013 questo conferisce alle immagini un sottile calore e aggiunge un po\u2019 pi\u00f9 di profondit\u00e0 alle tonalit\u00e0 del legno. Insieme a +1 di NITIDEZZA e alla funzione di smussatura disattivata, l\u2019immagine rimane nitida ma non esagerata.<\/p>\n\n\n\n<p>\u201cSalty Skipper\u201d \u00e8 quindi una RICETTA FS flessibile e robusta per reportage con condizioni di luce variabili e una vasta gamma di soggetti. Mostra il colore, ma mai in modo eccessivo. Si trattiene, eppure dice cos\u00ec tanto.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_4-1.jpg?width=682&#038;height=1024\" alt=\"\" class=\"wp-image-339953\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_4-1.jpg?width=682&amp;height=1024 682w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_4-1.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_4-1.jpg?width=365&amp;height=548 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_4-1.jpg?width=600&amp;height=900 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_4-1.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_4-1.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_5-1.jpg?width=682&#038;height=1024\" alt=\"\" class=\"wp-image-339954\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_5-1.jpg?width=682&amp;height=1024 682w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_5-1.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_5-1.jpg?width=365&amp;height=548 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_5-1.jpg?width=600&amp;height=900 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_5-1.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_5-1.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B-.Jones-_Stories_6.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-339955\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B-.Jones-_Stories_6.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B-.Jones-_Stories_6.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B-.Jones-_Stories_6.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B-.Jones-_Stories_6.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B-.Jones-_Stories_6.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B-.Jones-_Stories_6.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B-.Jones-_Stories_6.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B-.Jones-_Stories_6.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>In azione \u2013 tra luce e ombra<\/strong><\/h3>\n\n\n\n<p>Il passaggio dal sole splendente di mezzogiorno sul lungomare all&#8217;interno dell&#8217;officina, decisamente pi\u00f9 buio, \u00e8 stato particolarmente emozionante. Laddove altre impostazioni falliscono o richiedono regolazioni complesse, \u00abSalty Skipper\u00bb offre risultati affidabili e ben definiti grazie al profilo DR200 e alla curva di tono moderata.<\/p>\n\n\n\n<p>Nell&#8217;officina, i toni blu hanno creato un piacevole effetto di freschezza, mentre i toni caldi del legno hanno mantenuto una presenza sufficiente nonostante l&#8217;effetto generale di desaturazione. E anche con i toni della pelle \u2013 come lo sguardo concentrato del costruttore di barche che attraversa lo scafo \u2013 l\u2019effetto \u00e8 rimasto autentico ma non piatto.<\/p>\n\n\n\n<p>Questa stabilit\u00e0 nell\u2019interazione tra luce, materiale e soggetto rende questa FS RECIPE uno strumento affidabile nei progetti documentaristici.<\/p>\n\n\n\n<p>Ci\u00f2 che mi colpisce sempre di CLASSIC CHROME \u00e8 questo equilibrio tra moderazione ed espressivit\u00e0. Soprattutto in ambienti come la costruzione navale, dove precisione, materiali e atmosfera si fondono, \u00e8 necessaria una simulazione pellicola che non esageri, ma piuttosto esalti ci\u00f2 che \u00e8 gi\u00e0 presente.<\/p>\n\n\n\n<p>CLASSIC CHROME fa proprio questo: in modo discreto, affidabile ed elegante. Non ti costringe a raccontare una storia chiassosa. Ti permette semplicemente di vedere, sentire e catturare il momento cos\u00ec com&#8217;\u00e8.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_7.jpg?width=682&#038;height=1024\" alt=\"\" class=\"wp-image-339957\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_7.jpg?width=682&amp;height=1024 682w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_7.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_7.jpg?width=365&amp;height=548 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_7.jpg?width=600&amp;height=900 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_7.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_7.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_8.jpg?width=682&#038;height=1024\" alt=\"\" class=\"wp-image-339958\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_8.jpg?width=682&amp;height=1024 682w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_8.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_8.jpg?width=365&amp;height=548 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_8.jpg?width=600&amp;height=900 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_8.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_8.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Scattare foto con CLASSIC CHROME<\/strong><\/h3>\n\n\n\n<p>Nel corso degli anni, CLASSIC CHROME ha esercitato un&#8217;influenza notevole sul mio stile fotografico. La tavolozza di colori ridotta mi costringe a guardare in modo pi\u00f9 consapevole: non a cercare soggetti vivaci, ma profondit\u00e0, luce e struttura.<\/p>\n\n\n\n<p>Spesso scatto in JPEG con una FS RECIPE fissa perch\u00e9 mi aiuta a prendere decisioni durante lo scatto. Non voglio passare ore davanti al computer, ma piuttosto vivere il momento: osservare, creare, lasciarmi andare.<\/p>\n\n\n\n<p>\u201cSalty Skipper\u201d \u00e8 fatto proprio per questo: \u00e8 abbastanza minimalista da lasciare spazio, e abbastanza distintivo da dare all&#8217;immagine una chiara impronta.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_9.jpg?width=682&#038;height=1024\" alt=\"\" class=\"wp-image-339960\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_9.jpg?width=682&amp;height=1024 682w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_9.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_9.jpg?width=365&amp;height=548 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_9.jpg?width=600&amp;height=900 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_9.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2025\/12\/DE_Thomas-B.Jones_Stories_9.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Salty Skipper \u2013 Con CLASSIC CHROME tra il banco da lavoro e la linea d&#8217; acqua Ci sono luoghi in cui la fotografia va oltre la semplice immortalazione di un momento: diventa un\u2019esperienza condivisa. Per me, i laboratori artigianali sono proprio questo tipo di luoghi. Il profumo del legno, la lunga tradizione, gli attrezzi, la [&hellip;]<\/p>\n","protected":false},"author":269,"featured_media":339946,"template":"","category":[2084,1006,1202,13607,1055,3211,3309,320,13915,3162,1986,565,13898,8258],"post_tag":[],"class_list":["post-355222","story","type-story","status-publish","has-post-thumbnail","hentry","category-be-inspired","category-cameras","category-category","category-film-simulation","category-lenses","category-x-series-mirrorless","category-x-mount-prime","category-products","category-provia","category-x-mount","category-x-series","category-stories","category-x-e5","category-xf23mmf14-r-lm-wr"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 14:55:35","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/story\/355222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/story"}],"about":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/types\/story"}],"author":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/users\/269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media\/339946"}],"wp:attachment":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media?parent=355222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/category?post=355222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/post_tag?post=355222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":354231,"date":"2026-04-10T05:00:00","date_gmt":"2026-04-10T05:00:00","guid":{"rendered":"https:\/\/www.fujifilm-x.com\/?post_type=story&#038;p=354231"},"modified":"2026-04-08T00:27:40","modified_gmt":"2026-04-08T00:27:40","slug":"velvia-fs-recipe-x-dominic-stone","status":"publish","type":"story","link":"https:\/\/www.fujifilm-x.com\/it-it\/stories\/velvia-fs-recipe-x-dominic-stone\/","title":{"rendered":"Velvia FS RECIPE x Dominic Stone"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>FS RECIPE for rich, impactful results in the outdoors<\/strong><\/h2>\n\n\n\n<p>For traveling outdoor photographer Dominic Stone, photography is a way to \u2018engage with the mystery of life\u2019 that surrounds him. Dominic\u2019s work, which puts him in the heart of the action at major surfing and running competitions, is a reflection of his own deepest passions. It\u2019s an exchange with the natural world \u2013 one he\u2019s been having since long before he ever picked up a camera.<\/p>\n\n\n\n<p>Recently, Dom created a custom FS RECIPE on FUJIFILM X-E5, using the famously saturated Velvia as his foundation. The process was an exploration of tension that blended Velvia\u2019s vibrancy with a softer, more subtle mood to create images that feel beautiful and impactful. The result is a genuinely personal take on color.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_01.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-354233\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_01.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_01.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_01.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_01.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_01.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_01.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_01.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_01.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\">Photo 2025 \u00a9 Dominic Stone | FUJIFILM X-E5 and FUJINON XF500mmF5.6 R LM OIS WR, 1\/800 sec at F6.4, ISO 200<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>An Intuitive Leap into Photography<\/strong><\/h2>\n\n\n\n<p>Dominic admits that he used to despise the beach, associating it with hot sand and long family car rides. But that changed when a 1940s-era beach cottage joined his family, providing a foundation for a relationship with the ocean. It was there that his love for surfing began. \u201cOnce I stood on a surfboard for the first time, I never looked back,\u201d he says.<\/p>\n\n\n\n<p>Yet, it wasn\u2019t until he was 26 years old that a camera found its way into his hands. With a bit of money saved and a few weeks to spare before starting a master\u2019s program, he walked into a camera store.<\/p>\n\n\n\n<p>Dominic began documenting surf photography, and a chance encounter at a local longboard contest led to a sponsorship for a waterproof housing. Suddenly, he was in the water, creating the perspectives he had grown up romanticizing in magazines.<\/p>\n\n\n\n<p>\u201cI remember the first session I swam out with my camera; I don\u2019t think I\u2019ll ever forget it,\u201d he says.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_02.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-354234\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_02.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_02.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_02.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_02.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_02.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_02.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_02.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_02.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\">Photo 2025 \u00a9 Dominic Stone | FUJIFILM X-E5 and FUJINON XF500mmF5.6 R LM OIS WR, 1\/640 sec at F6.4, ISO 160<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_03.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-354235\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_03.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_03.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_03.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_03.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_03.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_03.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_03.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_03.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\">Photo 2025 \u00a9 Dominic Stone | FUJIFILM X-E5 and FUJINON XF500mmF5.6 R LM OIS WR, 1\/800 sec at F5.6, ISO 200<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Crafting a Softer Velvia Film Simulation<\/strong><\/h2>\n\n\n\n<p>Dominic\u2019s creative style has an appreciation for color, so he was excited to build a FS RECIPE from Velvia\u2019s base with X-E5.<\/p>\n\n\n\n<p>While he was confident that it would work perfectly for landscapes, he was curious to see how it would render the blues of the ocean. His goal was to balance the Film Simulation\u2019s intensity with a gentle touch, letting its personality shine through without creating an \u2018overcooked\u2019 image.<\/p>\n\n\n\n<p>He describes his FS RECIPE choices.<\/p>\n\n\n\n<p>\u201cTo bring a bit of softness to an image that I expected to have stronger contrast than I\u2019m used to, I knew I wanted to reduce the CLARITY in my FS RECIPE.<\/p>\n\n\n\n<p>\u201cI lifted the blacks just a touch to really lean into that softness, sort of working in tension with Velvia\u2019s character.\u201d<\/p>\n\n\n\n<p>Finally, he reduced the overall saturation slightly while adding a strong COLOR CHROME EFFECT for the blues. The aim was to create a FS RECIPE that was \u2018subtle yet steadfast in its impact\u2019.<\/p>\n\n\n\n<p>Dominic views his finished photos as a kind of Trojan horse, \u2018being pretty and easy on the eyes at first, but unleashing something with a bit more impact once we\u2019ve softened enough to receive it\u2019.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_04.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-354236\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_04.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_04.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_04.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_04.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_04.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_04.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_04.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_04.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\">Photo 2025 \u00a9 Dominic Stone | FUJIFILM X-E5 and FUJINON XF56mmF1.2 R, 1\/500 sec at F6.4, ISO 100<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_05.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-354237\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_05.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_05.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_05.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_05.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_05.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_05.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_05.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_05.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\">Photo 2025 \u00a9 Dominic Stone | FUJIFILM X-E5 and FUJINON XF56mmF1.2 R, 1\/800 sec at F5.6, ISO 320<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Straight-Out-of-Camera Freedom<\/strong><\/h2>\n\n\n\n<p>Creating a finished look in-camera was an engaging and freeing experience for Dominic. \u201cAs soon as I decided on my FS RECIPE, I made sure my camera was only making a single image at a time,\u201d he notes, compared to his usual burst mode preference.<\/p>\n\n\n\n<p>The entire process, the feel of the camera, the view through the EVF, and his custom FS RECIPE encouraged him to slow down and be intentional with his composition.<\/p>\n\n\n\n<p>This approach stands in contrast to his typical workflow of creating with RAW files and pulling details from the shadows in post-production. Dominic found the process of creating a straight-out-of-camera image he was happy with \u2018really liberating\u2019.<\/p>\n\n\n\n<p>\u201cI love editing, but it was nice just to transfer a photo to my phone wirelessly and have it ready to go,\u201d he says. It\u2019s a method Dominic sees lending itself to photojournalism, travel, and even providing real-time turnaround at competitions using X-E5.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_06.jpg?width=682&#038;height=1024\" alt=\"\" class=\"wp-image-354240\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_06.jpg?width=682&amp;height=1024 682w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_06.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_06.jpg?width=365&amp;height=548 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_06.jpg?width=600&amp;height=900 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_06.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_06.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\">Photo 2025 \u00a9 Dominic Stone | FUJIFILM X-E5 and FUJINON XF56mmF1.2 R, 1\/1000 sec at F3.6, ISO 125<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Going Beyond the Image<\/strong><\/h2>\n\n\n\n<p>What keeps Dominic inspired is a perspective that life and art are a \u2018conversation with the unseen and unknowable\u2019. For him, every moment is an expression of something flowing through us.<\/p>\n\n\n\n<p>Dominic\u2019s goal is not just to make a picture, but \u2018to create imagery which will somehow translate the ineffable and transcend our concepts of self, to strike us deeply at our core\u2019. The only way to achieve that, he believes, is to continue the dialogue with nature.<\/p>\n\n\n\n<p>That\u2019s what keeps him going.<\/p>\n\n\n\n<p>By taking the legendary look of Velvia and carefully molding it to fit his vision, Dominic crafted a look uniquely his. Creating a finished image directly in-camera gave him the freedom to stay in the moment and focus on the story he wanted to tell, one frame at a time.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_07.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-354238\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_07.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_07.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_07.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_07.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_07.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_07.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_07.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/US_Dominic-Stone_Stories_07.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\">Photo 2025 \u00a9 Dominic Stone | FUJIFILM X-E5 and FUJINON XF8mmF3.5 R WR, 1\/320 sec at F6.4, ISO 200<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Dominic Stone\u2019s \u201cPacifica 100\u201d FS RECIPE<\/strong><\/h2>\n\n\n\n<p><strong>FILM SIMULAITON: <\/strong>Velvia<br><strong>MONOCHROMATIC COLOR: <\/strong>N\/A<br><strong>GRAIN EFFECT: <\/strong>STRONG, SMALL<br><strong>COLOR CHROME EFFECT: <\/strong>WEAK<br><strong>COLOR CHROME FX BLUE: <\/strong>STRONG<br><strong>SMOOTH SKIN EFFECT: <\/strong>OFF<br><strong>WHITE BALANCE: <\/strong>AUTO \/ R +2, B -2<br><strong>DYNAMIC RANGE: <\/strong>DR100<br><strong>D RANGE PRIORITY: <\/strong>OFF<br><strong>TONE CURVE: <\/strong>H 0, S +2.5<br><strong>COLOR: <\/strong>-1<br><strong>SHARPNESS: <\/strong>0<br><strong>HIGH ISO NR: <\/strong>+1<br><strong>CLARITY: <\/strong>-2<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FS RECIPE for rich, impactful results in the outdoors For traveling outdoor photographer Dominic Stone, photography is a way to \u2018engage with the mystery of life\u2019 that surrounds him. Dominic\u2019s work, which puts him in the heart of the action at major surfing and running competitions, is a reflection of his own deepest passions. It\u2019s [&hellip;]<\/p>\n","protected":false},"author":135,"featured_media":354241,"template":"","category":[2084,1006,1202,13607,1055,3211,3309,320,13922,3162,1986,565,13898,13836],"post_tag":[],"class_list":["post-354231","story","type-story","status-publish","has-post-thumbnail","hentry","category-be-inspired","category-cameras","category-category","category-film-simulation","category-lenses","category-x-series-mirrorless","category-x-mount-prime","category-products","category-velvia","category-x-mount","category-x-series","category-stories","category-x-e5","category-xf500mmf5-6-r-lm-ois-wr"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 14:55:35","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/story\/354231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/story"}],"about":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/types\/story"}],"author":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/users\/135"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media\/354241"}],"wp:attachment":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media?parent=354231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/category?post=354231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/post_tag?post=354231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":354218,"date":"2026-04-10T05:00:00","date_gmt":"2026-04-10T05:00:00","guid":{"rendered":"https:\/\/www.fujifilm-x.com\/?post_type=story&#038;p=354218"},"modified":"2026-04-07T08:33:19","modified_gmt":"2026-04-07T08:33:19","slug":"velvia-fs-recipe-x-rommelbundalian","status":"publish","type":"story","link":"https:\/\/www.fujifilm-x.com\/it-it\/stories\/velvia-fs-recipe-x-rommelbundalian\/","title":{"rendered":"Velvia FS RECIPE x Rommel Bundalian"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>\u201cKanto Khromatiks\u201d: My Velvia FS RECIPE<\/strong><\/h2>\n\n\n\n<p>I\u2019ve been shooting long enough to remember Velvia in its original form, a roll of film with colors so rich and saturated it could make a cloudy day look like a postcard. When Fujifilm brought it into the digital age, I was hooked all over again. The colors still had that punch, the contrast still had that drama.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_01.jpg?width=682&#038;height=1024\" alt=\"\" class=\"wp-image-354220\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_01.jpg?width=682&amp;height=1024 682w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_01.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_01.jpg?width=365&amp;height=548 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_01.jpg?width=600&amp;height=900 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_01.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_01.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p>But Velvia is a strong character. Left untamed, it can run away with your highlights, sink your shadows, and push colors a little too far. I wanted to keep its soul but give it a touch of restraint, something I could trust in any light, from the quiet countryside to the vibrant streets of the Philippines. That is how \u201cKanto Khromatiks\u201d came to be.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_02.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-354221\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_02.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_02.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_02.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_02.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_02.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_02.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_02.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_02.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p>The name comes from two words: <em>kanto<\/em>, the Filipino word for \u201cstreet corner,\u201d and <em>Khromatics<\/em>, meaning \u201ccolors.\u201d Together, it means \u201cstreet corner colors,\u201d a nod to the life, movement, and vibrance you find in everyday scenes, whether it is a busy market, a quiet alley, or the glow of streetlights at night.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_03.jpg?width=682&#038;height=1024\" alt=\"\" class=\"wp-image-354222\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_03.jpg?width=682&amp;height=1024 682w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_03.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_03.jpg?width=365&amp;height=548 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_03.jpg?width=600&amp;height=900 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_03.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_03.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p>I keep the Film Simulation on Velvia with DYNAMIC RANGE on AUTO. Highlights are pulled<br>back just half a step to save the bright spots, shadows lifted a notch to keep depth without losing detail. Color sits at +2, lively but not exaggerated. Noise reduction stays at 0 so the fine textures stay intact. SHARPNESS is at +1, CLARITY at +2 for that crisp, tactile feel that makes an image come alive.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_04.jpg?width=682&#038;height=1024\" alt=\"\" class=\"wp-image-354223\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_04.jpg?width=682&amp;height=1024 682w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_04.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_04.jpg?width=365&amp;height=548 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_04.jpg?width=600&amp;height=900 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_04.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_04.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p>GRAIN EFFECT is WEAK and SMALL, just enough to whisper back to my film days without getting in the way. COLOR CHROME EFFECT and COLOR CHROME FX BLUE are both on WEAK, keeping the colors full but not heavy-handed. WHITE BALANCE stays on AUTO, as Fujifilm gets it right more often than not, whether I am in midday sun, shade, or under warm caf\u00e9 lights.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_05.jpg?width=1024&#038;height=682\" alt=\"\" class=\"wp-image-354224\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_05.jpg?width=1024&amp;height=682 1024w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_05.jpg?width=300&amp;height=200 300w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_05.jpg?width=768&amp;height=512 768w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_05.jpg?width=400&amp;height=267 400w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_05.jpg?width=365&amp;height=243 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_05.jpg?width=600&amp;height=400 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_05.jpg?width=717&amp;height=478 717w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_05.jpg?width=936&amp;height=624 936w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p>Out in the field, this setup keeps Velvia\u2019s drama but reins it in just enough. Midday shots hold detail in the highlights. Golden hour turns the skies deep and painterly while the greens stay rich. At night, high ISO paired with that subtle grain gives me clean, cinematic frames without harsh noise.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_06.jpg?width=682&#038;height=1024\" alt=\"\" class=\"wp-image-354225\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_06.jpg?width=682&amp;height=1024 682w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_06.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_06.jpg?width=365&amp;height=548 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_06.jpg?width=600&amp;height=900 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_06.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_06.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<p>The result is still Velvia: bold, colorful, alive, but with a balance that makes it work anywhere. From bustling street markets to quiet coastal roads, \u201cKanto Khromatiks\u201d carries the same magic I fell in love with decades ago, now with the control I have learned to appreciate over the years<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_07.jpg?width=682&#038;height=1024\" alt=\"\" class=\"wp-image-354226\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_07.jpg?width=682&amp;height=1024 682w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_07.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_07.jpg?width=365&amp;height=548 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_07.jpg?width=600&amp;height=900 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_07.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/04\/PH_Rommel-Bundalian_Stories_07.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u201cKanto Khromatiks\u201d: My Velvia FS RECIPE I\u2019ve been shooting long enough to remember Velvia in its original form, a roll of film with colors so rich and saturated it could make a cloudy day look like a postcard. When Fujifilm brought it into the digital age, I was hooked all over again. The colors still [&hellip;]<\/p>\n","protected":false},"author":135,"featured_media":354247,"template":"","category":[2084,1006,1202,13607,1055,3211,3309,320,13922,3162,1986,565,13898,7866],"post_tag":[],"class_list":["post-354218","story","type-story","status-publish","has-post-thumbnail","hentry","category-be-inspired","category-cameras","category-category","category-film-simulation","category-lenses","category-x-series-mirrorless","category-x-mount-prime","category-products","category-velvia","category-x-mount","category-x-series","category-stories","category-x-e5","category-xf50mmf2-r-wr"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 14:55:35","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/story\/354218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/story"}],"about":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/types\/story"}],"author":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/users\/135"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media\/354247"}],"wp:attachment":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media?parent=354218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/category?post=354218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/post_tag?post=354218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":354371,"date":"2026-04-08T00:32:00","date_gmt":"2026-04-08T00:32:00","guid":{"rendered":"https:\/\/www.fujifilm-x.com\/?post_type=story&#038;p=354371"},"modified":"2026-04-08T00:32:05","modified_gmt":"2026-04-08T00:32:05","slug":"classic-chrome-film-simulation-recipe-x-alicia-cooper","status":"publish","type":"story","link":"https:\/\/www.fujifilm-x.com\/it-it\/stories\/classic-chrome-film-simulation-recipe-x-alicia-cooper\/","title":{"rendered":"CLASSIC CHROME\u00a0FILM SIMULATION RECIPE\u00a0x\u00a0Alicia Cooper"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Wanderlight: una ricetta personalizzata per FS di Alicia Cooper<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">La fotografa di viaggi Alicia Cooper crea una \u00abFilm Simulation RECIPE\u00bb versatile che racchiude il suo stile unico<\/h3>\n\n\n\n<p>Per Alicia Cooper, la carriera nella fotografia di viaggio \u00e8 iniziata durante i lockdown della pandemia globale.<br>\u00ab\u00c8 successo per caso\u00bb, esordisce. \u00abVivevo a Bath, nel Regno Unito \u2013 una citt\u00e0 incantevole, ma molto turistica \u2013 e grazie alla pandemia ho avuto la fortuna di fotografarla quando era deserta\u00bb.<br>\u00abHo iniziato a pubblicare le foto online, alla gente sono piaciute e da l\u00ec le cose si sono evolute\u00bb, racconta. \u00abQuando le restrizioni sono state revocate e ho ricominciato a viaggiare e a condividere altre foto, ho iniziato a ricevere incarichi. \u00c8 strano dire che \u00e8 stato grazie alla pandemia, ma mi ha dato l\u2019opportunit\u00e0 di vedere la citt\u00e0 a cui ero cos\u00ec abituata in un modo diverso\u00bb.<br>Ora, Alicia viaggia per il mondo offrendo i suoi servizi fotografici ad alberghi e enti turistici, oltre a creare contenuti per il suo blog di viaggi, The Chaos Diaries.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_02.jpg?width=682&#038;height=1024\" alt=\"\" class=\"wp-image-341793\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_02.jpg?width=682&amp;height=1024 682w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_02.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_02.jpg?width=365&amp;height=548 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_02.jpg?width=600&amp;height=900 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_02.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_02.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\">Foto 2025 \u00a9 Alicia Cooper | FUJIFILM X-T50, FUJINON XF16-55mmF2.8 R LM WR II, 1\/640 sec F2.8, ISO 800, \u2018Wanderlight\u2019<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Developing a style<\/h3>\n\n\n\n<p>Per Alicia Cooper, la carriera nella fotografia di viaggio \u00e8 iniziata durante i lockdown della pandemia globale.<br>\u00ab\u00c8 successo per caso\u00bb, esordisce. \u00abVivevo a Bath, nel Regno Unito \u2013 una citt\u00e0 incantevole, ma molto turistica \u2013 e grazie alla pandemia ho avuto la fortuna di fotografarla quando era deserta\u00bb.<br>\u00abHo iniziato a pubblicare le foto online, alla gente sono piaciute e da l\u00ec le cose si sono evolute\u00bb, racconta. \u00abQuando le restrizioni sono state revocate e ho ricominciato a viaggiare e a condividere altre foto, ho iniziato a ricevere incarichi. \u00c8 strano dire che \u00e8 stato grazie alla pandemia, ma mi ha dato l\u2019opportunit\u00e0 di vedere la citt\u00e0 a cui ero cos\u00ec abituata in un modo diverso\u00bb.<br>Ora, Alicia viaggia per il mondo offrendo i suoi servizi fotografici ad alberghi e enti turistici, oltre a creare contenuti per il suo blog di viaggi, The Chaos Diaries.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_03.jpg?width=682&#038;height=1024\" alt=\"\" class=\"wp-image-341794\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_03.jpg?width=682&amp;height=1024 682w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_03.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_03.jpg?width=365&amp;height=548 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_03.jpg?width=600&amp;height=900 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_03.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_03.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\">Foto 2025 \u00a9 Alicia Cooper | FUJIFILM X-T50, FUJINON XF16-55mmF2.8 R LM WR II, 1\/2500 sec, F3.6, ISO 500, \u2018Wanderlight\u2019<\/figcaption><\/figure>\n\n\n\n<p>Alicia ora si impegna a conoscere a fondo i luoghi prima di cercare nuovi modi per rappresentarli. \u00abSe visito un posto famoso, ne mostro i diversi aspetti, compresi i piccoli dettagli\u00bb, spiega.<br>Questo approccio \u00e8 reso possibile dalla sua filosofia di viaggio senza fretta. \u00abCerchiamo di viaggiare il pi\u00f9 lentamente possibile\u00bb, spiega. \u00abIl nostro obiettivo \u00e8 trascorrere almeno un mese in ogni luogo in cui soggiorniamo. Mi piace cos\u00ec perch\u00e9 possiamo entrare davvero in sintonia con ogni posto\u00bb.<br>\u00abNon ci limitiamo a spuntare le attrazioni turistiche pi\u00f9 famose prima di passare alla destinazione successiva. Questo significa anche che non ci sentiamo esausti per il fatto di vivere costantemente con la valigia in mano \u2013 e a volte ci concediamo persino delle serate a casa!\u00bb<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_04.jpg?width=682&#038;height=1024\" alt=\"\" class=\"wp-image-341795\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_04.jpg?width=682&amp;height=1024 682w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_04.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_04.jpg?width=365&amp;height=548 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_04.jpg?width=600&amp;height=900 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_04.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_04.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\">Foto 2025 \u00a9 Alicia Cooper | FUJIFILM X-T50, FUJINON XF16-55mmF2.8 R LM WR II, 1\/800 sec F3.2, ISO 2500, \u2018Wanderlight\u2019<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Film Simulations per la Fotografia di Viaggio <\/h3>\n\n\n\n<p>Alicia, che scatta con una fotocamera della serie X, \u00e8 una convinta sostenitrice delle modalit\u00e0 di simulazione pellicola integrate nelle fotocamere Fujifilm. \u00abDa quando ho una fotocamera Fujifilm, le uso sempre, specialmente la funzione FS RECIPE personalizzata\u00bb, racconta entusiasta.<br>\u00abAl momento sto usando la FUJIFILM X-T50, che adoro. Ne sono ossessionata. Recentemente ho acquistato anche il FUJINON XF16-55mmF2.8 R LM WR II ed \u00e8 incredibilmente nitido. \u00c8 la combinazione perfetta perch\u00e9 \u00e8 molto compatta\u201d, sottolinea Alicia. \u201cViaggio a tempo pieno, quindi ho pochissimo spazio per portare con me l\u2019attrezzatura\u201d.<br>FUJIFILM X-T50 \u00e8 dotata di tutte e 20 le modalit\u00e0 di Simulazione Pellicola esclusive di Fujifilm. Regolando ulteriori impostazioni di qualit\u00e0 dell\u2019immagine, gli utenti possono poi modificare queste simulazioni di base per creare profili estremamente caratteristici.<br>\u201cQuando ho visto per la prima volta la funzione FS RECIPE personalizzata, ero pi\u00f9 proattiva. Provavo a caricarne il maggior numero possibile per diverse situazioni e sceglievo quella pi\u00f9 adatta\u201d, ricorda Alicia.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_05.jpg?width=682&#038;height=1024\" alt=\"\" class=\"wp-image-341796\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_05.jpg?width=682&amp;height=1024 682w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_05.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_05.jpg?width=365&amp;height=548 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_05.jpg?width=600&amp;height=900 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_05.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_05.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\">Foto 2025 \u00a9 Alicia Cooper | FUJIFILM X-T50, FUJINON XF16-55mmF2.8 R LM WR II, 1\/400 sec F2.8, ISO 125, \u2018Wanderlight\u2019<\/figcaption><\/figure>\n\n\n\n<p>\u00abMa poi sono arrivata a un punto in cui volevo semplicemente un modello adatto a tutto. \u00c8 una richiesta impegnativa da fare a FS RECIPE, ma quello che ho creato \u00e8 proprio cos\u00ec. In ogni situazione in cui l\u2019ho usato, \u00e8 stato fantastico.\u00bb<br>\u00abHo un paio di altri modelli versatili. Per chi lavora nel settore dei viaggi, questo \u00e8 importante: passo da grandi citt\u00e0 come Seul alle escursioni su un vulcano. \u00c8 utile avere opzioni che funzionino bene in ogni situazione.\u201d<br>\u201cAiutare a creare un corpus di lavori con un look e una sensazione coerenti \u00e8 un altro vantaggio, spiega. \u201cPer me \u00e8 importante poter guardare le mie foto e vedere che hanno uno stile distintamente mio. Questo deriva dal modo in cui mi piace inquadrare le mie foto, ma anche dall\u2019avere i colori sincronizzati in tutto il mio lavoro: crea un portfolio solido.\u201d<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_06.jpg?width=682&#038;height=1024\" alt=\"\" class=\"wp-image-341798\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_06.jpg?width=682&amp;height=1024 682w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_06.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_06.jpg?width=365&amp;height=548 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_06.jpg?width=600&amp;height=900 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_06.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_06.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\">Foto 2025 \u00a9 Alicia Cooper | FUJIFILM X-T50, FUJINON XF16-55mmF2.8 R LM WR II, 1\/200 sec at F2.8, ISO 125, \u2018Wanderlight\u2019<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Wanderlight: la mia ricetta Fujifilm<\/h3>\n\n\n\n<p>Fujifilm ha sfidato Alicia a creare una nuova FS RECIPE personalizzata che si adattasse bene al suo stile di fotografia di viaggio. Partendo dalla base CLASSIC CHROME, ha creato Wanderlight, che ha testato a Seul e sull\u2019isola di Jeju, in Corea del Sud.<br>\u00abMi piacciono le immagini che trasmettono un\u2019atmosfera nostalgica dal punto di vista cromatico; mi piace che abbiano un tocco un po\u2019 analogico e cinematografico\u00bb, osserva Alicia. \u201cAdoro i toni caldi e creare qualcosa che chi guarda possa potenzialmente associare a un\u2019 emozione.\u201d<br>\u201cIl mio obiettivo era creare qualcosa che si adattasse al mio stile di editing. Volevo un look sognante\u201d, aggiunge.<br>\u201cPer me, CLASSIC CHROME \u00e8 un\u2019ottima base perch\u00e9 offre un buon contrasto. Ha un aspetto piuttosto documentaristico, quasi come le vecchie diapositive.\u201d<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_07.jpg?width=682&#038;height=1024\" alt=\"\" class=\"wp-image-341799\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_07.jpg?width=682&amp;height=1024 682w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_07.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_07.jpg?width=365&amp;height=548 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_07.jpg?width=600&amp;height=900 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_07.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_07.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\">Foto 2025 \u00a9 Alicia Cooper | FUJIFILM X-T50, FUJINON XF16-55mmF2.8 R LM WR II, 1\/2000 sec  F8, ISO 6400, \u2018Wanderlight\u2019<\/figcaption><\/figure>\n\n\n\n<p>\u00abDa l\u00ec, preferisco un\u2019immagine pi\u00f9 morbida, ed \u00e8 per questo che ho ridotto la nitidezza e la riduzione del rumore. Mi piacciono anche i toni pi\u00f9 caldi, quindi ho accentuato i rossi, attenuato i blu e aggiunto un po\u2019 di grana.\u00bb<br>Wanderlight \u00e8 per me una ricetta multiuso, progettata per garantire prestazioni eccellenti nelle diverse localit\u00e0 in cui un viaggiatore pu\u00f2 trovarsi.<br>\u201cIl mio obiettivo era creare una Film Simulation recipe che fosse perfetta in quasi tutte le situazioni\u201d, spiega Alicia. \u201cAdoro come appare negli ambienti naturali, in particolare come risaltano i verdi in Wanderlight. Se state per partire per un viaggio, che sia in citt\u00e0 o in montagna, sar\u00e0 un\u2019ottima scelta da avere nel vostro set. Ma per me \u00e8 particolarmente efficace nella natura.\u201d<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_08.jpg?width=682&#038;height=1024\" alt=\"\" class=\"wp-image-341800\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_08.jpg?width=682&amp;height=1024 682w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_08.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_08.jpg?width=365&amp;height=548 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_08.jpg?width=600&amp;height=900 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_08.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_08.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\">Foto 2025 \u00a9 Alicia Cooper | FUJIFILM X-T50, FUJINON XF16-55mmF2.8 R LM WR II, 1\/1000 sec F2.8, ISO 500, \u2018Wanderlight\u2019<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Take it in<\/h3>\n\n\n\n<p>Il consiglio di Alicia per i creatori di contenuti di viaggio che cercano di trovare il proprio modo unico di fotografare i luoghi \u00e8 semplicemente quello di fermarsi e respirare.<br>\u201cSe ti trovi in un luogo famoso per le foto, spesso ti capita di guardarti intorno e vedere altre persone che scattano foto, concentrate su un unico aspetto\u201d, descrive.<br>\u201cFermati solo per un momento. Non hai fretta. Guardati semplicemente intorno e non sentirti in dovere di scattare un milione di foto di un posto. Dedica pi\u00f9 tempo all\u2019osservazione. \u00c8 cos\u00ec che ho scoperto angolazioni diverse anche in luoghi molto famosi per le foto.\u201d<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_09.jpg?width=682&#038;height=1024\" alt=\"\" class=\"wp-image-342034\" srcset=\"https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_09.jpg?width=682&amp;height=1024 682w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_09.jpg?width=200&amp;height=300 200w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_09.jpg?width=365&amp;height=548 365w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_09.jpg?width=600&amp;height=900 600w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_09.jpg?width=390&amp;height=585 390w, https:\/\/fujifilm-x.b-cdn.net\/wp-content\/uploads\/2026\/01\/UK_Alicia-Cooper_Stories_09.jpg?width=480&amp;height=720 480w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><figcaption class=\"wp-element-caption\">Foto 2025 \u00a9 Alicia Cooper | FUJIFILM X-T50, FUJINON XF16-55mmF2.8 R LM WR II, 1\/640 sec F2.8, ISO 125, \u2018Wanderlight\u2019<\/figcaption><\/figure>\n\n\n\n<p>\u00abCapita spesso di vedere tanti fotografi in piedi con i treppiedi puntati tutti verso lo stesso soggetto. Lasciati ispirare dagli altri, ma non sentirti in dovere di copiarli solo perch\u00e9 \u00e8 quello che fanno gli altri fotografi. Il segreto sta nel non aver paura di voltarti e guardare altrove.\u00bb<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Wanderlight <\/strong><\/h3>\n\n\n\n<p><strong>FILM SIMULATION: <\/strong>CLASSIC CHROME<br><strong>MONOCHROMATIC COLOR: <\/strong>N\/A<br><strong>GRAIN EFFECT: <\/strong>WEAK, SMALL<br><strong>COLOR CHROME EFFECT: <\/strong>STRONG<br><strong>COLOR CHROME FX BLUE:<\/strong> STRONG<br><strong>SMOOTH SKIN EFFECT: <\/strong>OFF<br><strong>WHITE BALANCE: <\/strong>AUTO, +3 RED, -6 BLUE<br><strong>DYNAMIC RANGE<\/strong>: AUTO<br><strong>D RANGE PRIORITY:<\/strong> OFF<br><strong>TONE CURVE: <\/strong>H -2, S -0.5<br><strong>COLOR: <\/strong>+4<br><strong>SHARPNESS:<\/strong> -2<br><strong>HIGH ISO NR:<\/strong> -3<br><strong>CLARITY: <\/strong>0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wanderlight: una ricetta personalizzata per FS di Alicia Cooper La fotografa di viaggi Alicia Cooper crea una \u00abFilm Simulation RECIPE\u00bb versatile che racchiude il suo stile unico Per Alicia Cooper, la carriera nella fotografia di viaggio \u00e8 iniziata durante i lockdown della pandemia globale.\u00ab\u00c8 successo per caso\u00bb, esordisce. \u00abVivevo a Bath, nel Regno Unito \u2013 [&hellip;]<\/p>\n","protected":false},"author":269,"featured_media":341802,"template":"","category":[2084,1006,1202,13917,13607,1055,3211,320,3162,1986,565,13393,13835,3358],"post_tag":[],"class_list":["post-354371","story","type-story","status-publish","has-post-thumbnail","hentry","category-be-inspired","category-cameras","category-category","category-classic-chrome","category-film-simulation","category-lenses","category-x-series-mirrorless","category-products","category-x-mount","category-x-series","category-stories","category-x-t50","category-xf16-55mmf2-8-r-lm-wr-ii","category-zoom"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 14:55:35","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/story\/354371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/story"}],"about":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/types\/story"}],"author":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/users\/269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media\/341802"}],"wp:attachment":[{"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/media?parent=354371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/category?post=354371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fujifilm-x.com\/it-it\/wp-json\/wp\/v2\/post_tag?post=354371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}]